{"id":17871,"date":"2014-06-11T13:03:38","date_gmt":"2014-06-11T12:03:38","guid":{"rendered":"https:\/\/www.solopress.com\/blog\/?p=17871"},"modified":"2023-04-28T14:29:06","modified_gmt":"2023-04-28T13:29:06","slug":"broschure-entwerfen-photoshop-video-tutorial","status":"publish","type":"post","link":"https:\/\/www.solopress.com\/blog\/de\/tutorials\/brochure-design-photoshop-video-tutorial\/","title":{"rendered":"Photoshop-Videotutorials - Gestaltung einer Brosch\u00fcre oder Brosch\u00fcre"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p><!--more--><\/p>\n<h3><em>Lernen Sie, wie man <strong>Entwurf einer <a title=\"Brosch\u00fcrendruck bei Solopress\" href=\"https:\/\/www.solopress.com\/blog\/de\/broschuren-und-hefte\/\">Brosch\u00fcre<\/a><\/strong> in <strong>Adobe Photoshop<\/strong> mit unserem fachkundigen, leicht zu verstehenden <strong>Video-Tutorial<\/strong>...<\/em><\/h3>\n<p>Dieses Video ist Teil unserer Adobe Creative-Lehrgangsreihe f\u00fcr Design. Bitte stellen Sie sicher, dass Sie <a href=\"https:\/\/www.youtube.com\/solopress\"><strong>abonnieren<\/strong><\/a> zum YouTube-Kanal von Solopress, damit du keine weiteren Anleitungen verpasst!<\/p>\n<div class=\"youtube-embed\" data-video_id=\"GaFHDsW4CcE\"><iframe loading=\"lazy\" title=\"Wie man eine Brosch\u00fcre oder Brosch\u00fcre in Photoshop gestaltet | Design Tutorial\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/GaFHDsW4CcE?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/div>\n<h2>Wie man eine Brosch\u00fcre gestaltet<\/h2>\n<p>Klicken Sie auf der Solopress-Website im Abschnitt \"Kostenlose Vorlagen\" unter \"A4-Briefb\u00f6gen\" auf das Symbol (<a title=\"Hier ist der direkte Link zu dieser Photoshop-Datei\" href=\"https:\/\/www.solopress.com\/blog\/de\/downloads\/6639\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">PS<\/a>) Photoshop-Vorlage 297mm x 210mm.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17875\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/how-to-design-a-brochure-in-photoshop-image-1.png\" alt=\"Wie man eine Brosch\u00fcre in Photoshop gestaltet Bild 1\" width=\"650\" height=\"395\" \/><\/p>\n<p><strong>Anschnitt, Beschnitt, sicherer Bereich<\/strong><\/p>\n<p>\u00d6ffnen Sie die Photoshop-Datei. Wir haben eine Hilfsebene erstellt, die Ihnen bei der Gestaltung Ihrer Brosch\u00fcre helfen wird - dazu geh\u00f6ren der Beschnittbereich, der Anschnitt und der sichere Bereich.<\/p>\n<p>Beschnittbereich - Alles, was sich hier befindet, wird abgeschnitten, aber denken Sie daran, alle Farben oder Bilder in diesen 3 mm breiten Beschnittbereich zu verl\u00e4ngern, um zu vermeiden, dass bei der Druckweiterverarbeitung wei\u00dfe Linien entstehen.<\/p>\n<p>Beschneiden - Ihr Auftrag wird an der durchgehenden schwarzen Linie geschnitten. Alle Bilder oder Texte, die sich in diesem 3 mm breiten Bereich befinden, werden m\u00f6glicherweise nicht korrekt abgeschnitten.<\/p>\n<p>Sicherer Bereich - Halten Sie alle Ihre Informationen innerhalb des wei\u00dfen Bereichs. Denken Sie daran, hochaufl\u00f6sende Bilder (300dpi) zu verwenden, um ein optimales Ergebnis zu erzielen.<\/p>\n<p>Erstellen Sie eine neue Hilfslinie, indem Sie auf das vertikale und horizontale Lineal klicken und ziehen (wenn Ihr Lineal in Photoshop nicht angezeigt wird, dr\u00fccken Sie Befehlstaste + R). Erstellen Sie 4 neue Hilfslinien auf der Linie des sicheren Bereichs.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17876\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/how-to-design-a-brochure-in-photoshop-image-2.png\" alt=\"Video-Tutorial Bild 2\" width=\"650\" height=\"395\" \/><\/p>\n<p><strong>Seite 1 (Titelseite\/Umschlag)<\/strong><\/p>\n<p>Blenden Sie im Ebenenfenster die Hilfsebene aus. Beziehen Sie sich nur auf diese Ebene, um zu pr\u00fcfen, ob Ihr Entwurf in den sicheren Bereich passt, und vergewissern Sie sich, dass alle Farben oder Bilder \u00fcber den Beschnittbereich hinausgehen.<\/p>\n<p>Um Ihren Hintergrund zu importieren, gehen Sie in der oberen Men\u00fcleiste auf Datei, Eingebettetes platzieren, suchen Sie Ihre Datei(en) und w\u00e4hlen Sie Platzieren. Passen Sie die Gr\u00f6\u00dfe und Position an. W\u00e4hlen Sie das H\u00e4kchen, um die Aktion zu best\u00e4tigen.<\/p>\n<p>Um das Hintergrundbild zu erstellen, importieren Sie es und passen die Gr\u00f6\u00dfe an. Gehen Sie in der oberen Men\u00fcleiste auf Ebenen, Neue Einstellungsebene und w\u00e4hlen Sie Farbton und S\u00e4ttigung. Es wird ein Eigenschaftsfenster angezeigt, in dem Sie Farbton, S\u00e4ttigung und Helligkeit einstellen k\u00f6nnen. Sie k\u00f6nnen das Bild auch einf\u00e4rben. W\u00e4hlen Sie die Option Einf\u00e4rben, und ziehen Sie die S\u00e4ttigung auf 11 herunter. \u00c4ndern Sie die Helligkeit auf -21 und passen Sie den Farbton auf 210 an. Passen Sie die Einstellungen an Ihr Design an; wir haben uns f\u00fcr ein graues Blau entschieden, da wir das Design einfach halten wollen, damit es nicht auff\u00e4llt.<\/p>\n<p>Keep It Simple - In Anbetracht der neuesten Designtrends wird Ihre Brosch\u00fcre durch ein einfaches und minimales Design mit thematischen Farben elegant und professionell aussehen. Speichern Sie jetzt Ihren Entwurf und beginnen Sie auf der n\u00e4chsten Seite.<\/p>\n<p>W\u00e4hlen Sie das Rechteck-Werkzeug, ziehen Sie es und erstellen Sie eine Kopfzeile f\u00fcr Ihren Text. (Wir haben die Farbe des Rechtecks bereits vorausgew\u00e4hlt. Vergewissern Sie sich, dass das Rechteck-Werkzeug ausgew\u00e4hlt ist, und im oberen Men\u00fc erscheinen Optionen zum \u00c4ndern der Farbe). W\u00e4hlen Sie im Ebenenfenster die Deckkraft aus und stellen Sie sie auf 80%, das Rechteck wird nun leicht transparent.<\/p>\n<p>W\u00e4hlen Sie das Textwerkzeug und \u00e4ndern Sie die Schrifteinstellung im oberen Men\u00fc. Geben Sie den Brosch\u00fcrennamen ein und passen Sie die Position und Gr\u00f6\u00dfe des Textes an, ggf. auch den Kopfbereich.<\/p>\n<p>Jetzt importieren wir unser Logo auf die Titelseite. Verwenden Sie die gleichen Schritte wie zuvor, platzieren und betten Sie das Logo ein und passen Sie die Gr\u00f6\u00dfe und Positionierung an. Wir haben unser Logo in der oberen rechten Ecke positioniert.<\/p>\n<p>Wir werden nun die Seite duplizieren. Dies ist hilfreich, wenn Sie ein \u00e4hnliches Bild erstellen wollen, da alle Ebenen so bleiben, wie sie im vorherigen Bild waren. Vergessen Sie nicht, Ihr Dokument zu speichern, indem Sie im oberen Men\u00fc auf Datei Speichern unter gehen und das Dokument an dem von Ihnen gew\u00fcnschten Ort speichern. W\u00e4hlen Sie alle Ebenen im Ebenenfenster aus und gehen Sie im oberen Men\u00fc auf Ebene und w\u00e4hlen Sie Ebenen duplizieren. Es erscheint ein Pop-up-Fenster mit der Frage, wohin Sie die Ebenen verschieben m\u00f6chten. W\u00e4hlen Sie unter dem Dokument die Option Neu, benennen Sie die neue Seite und w\u00e4hlen Sie OK.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17877\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/how-to-design-a-brochure-in-photoshop-image-3.png\" alt=\"Video-Tutorial Bild 3\" width=\"650\" height=\"395\" \/><\/p>\n<p><strong>Seite 2<\/strong><\/p>\n<p>Wenden Sie die gleichen Hilfslinien an wie zuvor; blenden Sie alle zus\u00e4tzlichen Ebenen aus, indem Sie das Augensymbol im Ebenenfenster deaktivieren. Importieren Sie Ihren Hintergrund (wir haben f\u00fcr diese Seite eine Volltonfarbe gew\u00e4hlt).<\/p>\n<p>Aktivieren Sie im Ebenenfenster die Ebene \"Rechteck\". Schreiben Sie mit dem Textwerkzeug Ihre Informationen in das orangefarbene Feld und passen Sie die Gr\u00f6\u00dfe und Position der Schrift an. Der Text, den wir verwenden, hei\u00dft <a href=\"https:\/\/www.solopress.com\/blog\/de\/copywriting-typografie\/was-ist-lorem-ipsum-und-warum-ist-es-verwendet\/\">Lorem Ipsum<\/a>. Loren Ipsum ist ein F\u00fclltext, der zur Veranschaulichung der Grafik verwendet wird und es dem Betrachter erm\u00f6glicht, sich auf grafische Aspekte wie Schriftart, Typografie und Seitenlayout zu konzentrieren.<\/p>\n<p>Speichern und duplizieren Sie das Bild und erstellen Sie eine neue Seite.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17878\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/how-to-design-a-brochure-in-photoshop-image-4.png\" alt=\"Video-Tutorial Bild 4\" width=\"650\" height=\"395\" \/><\/p>\n<p><strong>Seite 3<\/strong><\/p>\n<p>Wenden Sie die gleichen Hilfslinien wie zuvor an und importieren Sie den Hintergrund. Schalten Sie im Ebenenfenster die Ebene Rechteck ein und vergr\u00f6\u00dfern Sie das Rechteck. Ziehen Sie bei ausgew\u00e4hltem Rechteck eine Hilfslinie aus dem Lineal und positionieren Sie die Hilfslinie in der Mitte; die Hilfslinie sollte am Ankerpunkt des Rahmens einrasten. Wenn Ihre Hilfslinie nicht einrastet, w\u00e4hlen Sie im oberen Men\u00fc Ansicht und vergewissern Sie sich, dass alle Einstellungen f\u00fcr das Einrasten auf \"Ein\" (H\u00e4kchen) gesetzt sind. Auf diese Weise k\u00f6nnen Sie Ihren Text auf dem Dokument ausrichten.<\/p>\n<p>Geben Sie mit dem Textwerkzeug Ihre Informationen in das orangefarbene Feld ein und passen Sie die Gr\u00f6\u00dfe und Position der Schrift an. Erstellen Sie ein neues Feld und f\u00fcgen Sie die Informationen zur Inhaltsseite hinzu.<\/p>\n<p>Speichern und duplizieren Sie das Bild und erstellen Sie eine neue Seite.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17879\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/how-to-design-a-brochure-in-photoshop-image-5.png\" alt=\"Video-Tutorial Bild 5\" width=\"650\" height=\"395\" \/><\/p>\n<p><strong>Seite 4<\/strong><\/p>\n<p>Wenden Sie die gleichen Hilfslinien an wie zuvor; blenden Sie die zus\u00e4tzlichen Ebenen aus, indem Sie das Augensymbol im Ebenenfenster deaktivieren. Importieren Sie Ihren Hintergrund (wir haben f\u00fcr diese Seite eine Volltonfarbe gew\u00e4hlt).<\/p>\n<p>Legen Sie ein neues Rechteck an und erstellen Sie eine kleine Kopfzeile, die am oberen Rand des Bildes positioniert wird. Stellen Sie sicher, dass die Deckkraft auf 80% eingestellt ist.<\/p>\n<p>Geben Sie mit dem Textwerkzeug den Namen der Kopfzeile in das orangefarbene Feld ein und passen Sie die Gr\u00f6\u00dfe und Position der Schrift an. Geben Sie Ihre Informationen erneut mit dem Textwerkzeug unter dem orangefarbenen Feld ein und passen Sie die Gr\u00f6\u00dfe und Position der Schrift an.<\/p>\n<p>Importieren Sie ein neues Bild, wir haben eine Weltkarte gew\u00e4hlt. Wir haben daf\u00fcr gesorgt, dass alle unsere Symbole und Vektorbilder auf PNG eingestellt sind. Bei diesem Dateiformat kann der Hintergrund (der bei JPEG-Bildern normalerweise wei\u00df ist) transparent sein.<\/p>\n<p>Speichern Sie und gehen Sie zur\u00fcck zur Seite 3 (Inhaltsseite), duplizieren Sie die Ebenen und erstellen Sie eine neue Seite.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17880\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/how-to-design-a-brochure-in-photoshop-image-6.png\" alt=\"Video-Tutorial Bild 6\" width=\"650\" height=\"395\" \/><\/p>\n<p><strong>Seite 5<\/strong><\/p>\n<p>Wenden Sie die gleichen Einrichtungshilfen wie zuvor an und importieren Sie Ihren Hintergrund.<\/p>\n<p>Schalten Sie die Rechteck-Ebene ein. Geben Sie mit dem Textwerkzeug Ihre Informationen in das orangefarbene Feld ein und passen Sie die Schriftgr\u00f6\u00dfe und -position an.<\/p>\n<p>Speichern und duplizieren Sie das Bild und erstellen Sie eine neue Seite.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17881\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/how-to-design-a-brochure-in-photoshop-image-7.png\" alt=\"Video-Tutorial Bild 7\" width=\"650\" height=\"395\" \/><\/p>\n<p><strong>Seite 6<\/strong><\/p>\n<p>Wenden Sie die gleichen Einrichtungshilfen wie zuvor an und importieren Sie Ihren Hintergrund.<\/p>\n<p>Legen Sie ein neues Rechteck an und erstellen Sie eine kleine Kopfzeile, die am oberen Rand des Bildes positioniert wird. Stellen Sie sicher, dass die Deckkraft auf 80% eingestellt ist. Geben Sie mit dem Textwerkzeug den Namen der Kopfzeile in das orangefarbene Feld ein und passen Sie die Gr\u00f6\u00dfe und Position der Schrift an.<\/p>\n<p>Erstellen Sie ein neues Rechteck und einen neuen Hintergrundrahmen auf der rechten Seite des Bildschirms. Verwenden Sie die Hilfslinien, um den Text zu positionieren. Platzieren und betten Sie ein Bild mit dem zus\u00e4tzlichen Platz ein.<\/p>\n<p>Speichern und duplizieren Sie das Bild und erstellen Sie eine neue Seite.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17883\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/how-to-design-a-brochure-in-photoshop-image-8.png\" alt=\"Video-Tutorial Bild 8\" width=\"650\" height=\"395\" \/><\/p>\n<p><strong>Seite 7<\/strong><\/p>\n<p>Wenden Sie die gleichen Einrichtungshilfen wie zuvor an und erstellen Sie das gleiche Layout wie auf der vorherigen Seite. Verschieben Sie das gro\u00dfe Feld in Richtung der linken Seite des Bildschirms. F\u00fcgen Sie alle Ihre Informationen in die K\u00e4stchen ein. Verwenden Sie die Hilfslinien, um den Text zu positionieren. Das Endergebnis ist, dass diese Seite und die vorherige Seite beim Druck zusammenpassen.<\/p>\n<p>Speichern Sie und gehen Sie zur\u00fcck zur Seite 1 (Titelseite), duplizieren Sie das Bild und erstellen Sie eine neue Seite.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17884\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/how-to-design-a-brochure-in-photoshop-image-9.png\" alt=\"Video-Tutorial Bild 9\" width=\"650\" height=\"395\" \/><\/p>\n<p><strong>Seite 8<\/strong><\/p>\n<p>Wenden Sie dieselben Einrichtungshilfen an wie zuvor und erstellen Sie dasselbe Layout wie f\u00fcr das Titelblatt. F\u00fcgen Sie mit dem Textwerkzeug Ihre Kontaktinformationen in das orangefarbene Feld ein.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17885\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/how-to-design-a-brochure-in-photoshop-image-10.png\" alt=\"Video-Tutorial Bild 10\" width=\"650\" height=\"395\" \/><\/p>\n<p>Sie haben nun Ihre Brosch\u00fcre erstellt. Ein weiterer n\u00fctzlicher Tipp: Versuchen Sie, alle oder die meisten Ihrer Informationen bereit zu haben, bevor Sie mit der Brosch\u00fcre beginnen, das wird Ihnen bei der Wahl der Schriftgr\u00f6\u00dfe und der Abst\u00e4nde helfen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17886\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/how-to-design-a-brochure-in-photoshop-image-11.png\" alt=\"Video-Tutorial Bild 11\" width=\"650\" height=\"395\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17887\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/how-to-design-a-brochure-in-photoshop-image-12.png\" alt=\"Wie man eine Brosch\u00fcre in Photoshop gestaltet Bild 12\" width=\"650\" height=\"395\" \/><\/p>\n<p>Und so gestalten Sie eine Brosch\u00fcre in Adobe Photoshop!<\/p>\n<p>Wenn Sie Anmerkungen oder Fragen zur Gestaltung einer Brosch\u00fcre haben, nutzen Sie bitte den unten stehenden Kommentarbereich. Wir werden unser Bestes tun, um Ihre Fragen zu beantworten.<\/p>\n<p>Vielen Dank, dass Sie sich unser Video-Tutorial angesehen haben.<\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":23,"featured_media":64595,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[555],"tags":[707,905],"class_list":{"0":"post-17871","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tutorials","8":"tag-brochures-booklets","9":"tag-photoshop"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>How To Design A Brochure or Booklet In Photoshop | Solopress<\/title>\n<meta name=\"description\" content=\"Solopress Adobe Creative Tips &amp; Tutorials - Learn how to create a brochure using Adobe Photoshop with our expert, easy-to-follow video tutorial.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solopress.com\/blog\/de\/tutorials\/broschure-entwerfen-photoshop-video-tutorial\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How To Design A Brochure or Booklet In Photoshop | Solopress\" \/>\n<meta property=\"og:description\" content=\"Solopress Adobe Creative Tips &amp; Tutorials - Learn how to create a brochure using Adobe Photoshop with our expert, easy-to-follow video tutorial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solopress.com\/blog\/de\/tutorials\/broschure-entwerfen-photoshop-video-tutorial\/\" \/>\n<meta property=\"og:site_name\" content=\"The Latest Print and Design News | Solopress\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Solopress\" \/>\n<meta property=\"article:published_time\" content=\"2014-06-11T12:03:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-28T13:29:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/designing_brochure_in_photoshop.png\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Solopress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@solopress\" \/>\n<meta name=\"twitter:site\" content=\"@solopress\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Solopress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"9\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/brochure-design-photoshop-video-tutorial\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/brochure-design-photoshop-video-tutorial\\\/\"},\"author\":{\"name\":\"Solopress\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/f8531403c74fe1b3ef14bcaeec1c8c41\"},\"headline\":\"Photoshop video tutorials &#8211; how to design a brochure or booklet\",\"datePublished\":\"2014-06-11T12:03:38+00:00\",\"dateModified\":\"2023-04-28T13:29:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/brochure-design-photoshop-video-tutorial\\\/\"},\"wordCount\":1385,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/brochure-design-photoshop-video-tutorial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/designing_brochure_in_photoshop.png\",\"keywords\":[\"Brochures &amp; Booklets\",\"Photoshop\"],\"articleSection\":[\"Design Tutorials\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/brochure-design-photoshop-video-tutorial\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/brochure-design-photoshop-video-tutorial\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/brochure-design-photoshop-video-tutorial\\\/\",\"name\":\"How To Design A Brochure or Booklet In Photoshop | Solopress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/brochure-design-photoshop-video-tutorial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/brochure-design-photoshop-video-tutorial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/designing_brochure_in_photoshop.png\",\"datePublished\":\"2014-06-11T12:03:38+00:00\",\"dateModified\":\"2023-04-28T13:29:06+00:00\",\"description\":\"Solopress Adobe Creative Tips & Tutorials - Learn how to create a brochure using Adobe Photoshop with our expert, easy-to-follow video tutorial.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/brochure-design-photoshop-video-tutorial\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/brochure-design-photoshop-video-tutorial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/brochure-design-photoshop-video-tutorial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/designing_brochure_in_photoshop.png\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/designing_brochure_in_photoshop.png\",\"width\":900,\"height\":675,\"caption\":\"Designing A Brochure In Photoshop\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/brochure-design-photoshop-video-tutorial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Photoshop video tutorials &#8211; how to design a brochure or booklet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"name\":\"The Latest Print and Design News | Solopress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\",\"name\":\"Solopress\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"width\":428,\"height\":88,\"caption\":\"Solopress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Solopress\",\"https:\\\/\\\/x.com\\\/solopress\",\"https:\\\/\\\/instagram.com\\\/solopress\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/solopress\",\"https:\\\/\\\/uk.pinterest.com\\\/solopress\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/solopress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/f8531403c74fe1b3ef14bcaeec1c8c41\",\"name\":\"Solopress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g\",\"caption\":\"Solopress\"},\"sameAs\":[\"https:\\\/\\\/www.solopress.com\\\/\"],\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/de\\\/author\\\/solopress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wie man eine Brosch\u00fcre oder ein Booklet in Photoshop gestaltet | Solopress","description":"Solopress Adobe Creative Tips &amp; Tutorials - Lernen Sie mit unserem leicht verst\u00e4ndlichen Video-Tutorial, wie Sie mit Adobe Photoshop eine Brosch\u00fcre erstellen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solopress.com\/blog\/de\/tutorials\/broschure-entwerfen-photoshop-video-tutorial\/","og_locale":"de_DE","og_type":"article","og_title":"How To Design A Brochure or Booklet In Photoshop | Solopress","og_description":"Solopress Adobe Creative Tips & Tutorials - Learn how to create a brochure using Adobe Photoshop with our expert, easy-to-follow video tutorial.","og_url":"https:\/\/www.solopress.com\/blog\/de\/tutorials\/broschure-entwerfen-photoshop-video-tutorial\/","og_site_name":"The Latest Print and Design News | Solopress","article_publisher":"https:\/\/www.facebook.com\/Solopress","article_published_time":"2014-06-11T12:03:38+00:00","article_modified_time":"2023-04-28T13:29:06+00:00","og_image":[{"width":900,"height":675,"url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/designing_brochure_in_photoshop.png","type":"image\/png"}],"author":"Solopress","twitter_card":"summary_large_image","twitter_creator":"@solopress","twitter_site":"@solopress","twitter_misc":{"Verfasst von":"Solopress","Gesch\u00e4tzte Lesezeit":"9\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.solopress.com\/blog\/tutorials\/brochure-design-photoshop-video-tutorial\/#article","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/brochure-design-photoshop-video-tutorial\/"},"author":{"name":"Solopress","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/f8531403c74fe1b3ef14bcaeec1c8c41"},"headline":"Photoshop video tutorials &#8211; how to design a brochure or booklet","datePublished":"2014-06-11T12:03:38+00:00","dateModified":"2023-04-28T13:29:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/brochure-design-photoshop-video-tutorial\/"},"wordCount":1385,"commentCount":4,"publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/brochure-design-photoshop-video-tutorial\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/designing_brochure_in_photoshop.png","keywords":["Brochures &amp; Booklets","Photoshop"],"articleSection":["Design Tutorials"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.solopress.com\/blog\/tutorials\/brochure-design-photoshop-video-tutorial\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.solopress.com\/blog\/tutorials\/brochure-design-photoshop-video-tutorial\/","url":"https:\/\/www.solopress.com\/blog\/tutorials\/brochure-design-photoshop-video-tutorial\/","name":"Wie man eine Brosch\u00fcre oder ein Booklet in Photoshop gestaltet | Solopress","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/brochure-design-photoshop-video-tutorial\/#primaryimage"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/brochure-design-photoshop-video-tutorial\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/designing_brochure_in_photoshop.png","datePublished":"2014-06-11T12:03:38+00:00","dateModified":"2023-04-28T13:29:06+00:00","description":"Solopress Adobe Creative Tips &amp; Tutorials - Lernen Sie mit unserem leicht verst\u00e4ndlichen Video-Tutorial, wie Sie mit Adobe Photoshop eine Brosch\u00fcre erstellen.","breadcrumb":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/brochure-design-photoshop-video-tutorial\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solopress.com\/blog\/tutorials\/brochure-design-photoshop-video-tutorial\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.solopress.com\/blog\/tutorials\/brochure-design-photoshop-video-tutorial\/#primaryimage","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/designing_brochure_in_photoshop.png","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/designing_brochure_in_photoshop.png","width":900,"height":675,"caption":"Designing A Brochure In Photoshop"},{"@type":"BreadcrumbList","@id":"https:\/\/www.solopress.com\/blog\/tutorials\/brochure-design-photoshop-video-tutorial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.solopress.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Photoshop video tutorials &#8211; how to design a brochure or booklet"}]},{"@type":"WebSite","@id":"https:\/\/www.solopress.com\/blog\/#website","url":"https:\/\/www.solopress.com\/blog\/","name":"Die neuesten Nachrichten aus Druck und Design | Solopress","description":"","publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solopress.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.solopress.com\/blog\/#organization","name":"Solopress","url":"https:\/\/www.solopress.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","width":428,"height":88,"caption":"Solopress"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Solopress","https:\/\/x.com\/solopress","https:\/\/instagram.com\/solopress\/","https:\/\/www.linkedin.com\/company\/solopress","https:\/\/uk.pinterest.com\/solopress\/","https:\/\/www.youtube.com\/user\/solopress"]},{"@type":"Person","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/f8531403c74fe1b3ef14bcaeec1c8c41","name":"Solopress","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g","caption":"Solopress"},"sameAs":["https:\/\/www.solopress.com\/"],"url":"https:\/\/www.solopress.com\/blog\/de\/author\/solopress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/designing_brochure_in_photoshop.png","_links":{"self":[{"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/posts\/17871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/comments?post=17871"}],"version-history":[{"count":5,"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/posts\/17871\/revisions"}],"predecessor-version":[{"id":73790,"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/posts\/17871\/revisions\/73790"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/media\/64595"}],"wp:attachment":[{"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/media?parent=17871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/categories?post=17871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/tags?post=17871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}