{"id":27025,"date":"2014-11-21T10:38:20","date_gmt":"2014-11-21T10:38:20","guid":{"rendered":"https:\/\/www.solopress.com\/blog\/?p=27025"},"modified":"2019-06-25T16:51:14","modified_gmt":"2019-06-25T15:51:14","slug":"rollenbanner-selbst-gestalten","status":"publish","type":"post","link":"https:\/\/www.solopress.com\/blog\/de\/tutorials\/designing-your-own-roller-banner\/","title":{"rendered":"Tipps f\u00fcr die Gestaltung Ihres eigenen Rollbanners"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p><!--more--><\/p>\n<p>Haben Sie Lust, Ihr eigenes Rollbanner zu entwerfen? Vielleicht bereiten Sie sich auf eine Messe oder ein Networking-Event vor und m\u00f6chten jedem Aspekt Ihres Auftritts Ihre eigene Note verleihen. Die meisten Druckereien bieten im Rahmen der Produktion Ihres Rollbanners einen Design-Service an, aber manche Leute ziehen es vor, die Gestaltung selbst zu \u00fcbernehmen. Wenn das auf Sie zutrifft - nur zu! Entwickeln Sie neue F\u00e4higkeiten, haben Sie Erfolg mit <strong>Gestalten Sie Ihr eigenes Rollbanner<\/strong>\u00a0und Sie werden ein gro\u00dfes Erfolgserlebnis haben.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Auswahl der Software<\/strong><\/h2>\n<p>Der wichtigste Aspekt zu Beginn des Entwurfsprozesses ist die Frage, welche Software verwendet werden soll. Die meisten von uns haben Microsoft Word auf ihren Computern, und f\u00fcr viele scheint es eine geeignete Wahl zu sein, ein \"Allzweckprogramm\". H\u00fcten Sie sich davor, in diese Falle zu tappen. Sie k\u00f6nnen zwar Entw\u00fcrfe in Word erstellen, aber das hei\u00dft nicht, dass Sie das auch tun sollten. Sie werden viel weniger M\u00f6glichkeiten haben, um ein beeindruckendes Design zu erstellen. Das Schlimmste aber ist, dass Sie mit dem Programm keine Grafiken in einer Qualit\u00e4t erstellen k\u00f6nnen, die f\u00fcr den Druck geeignet ist.<\/p>\n<p>Adobe Photoshop oder Illustrator sind die beste Wahl und eine lohnende Investition, wenn Sie in Zukunft wieder mit Design oder Fotografie arbeiten m\u00f6chten. Wenn Ihr Budget es jedoch nicht zul\u00e4sst, sollten Sie eine der vielen ausgezeichneten, kostenlosen Alternativen in Betracht ziehen, wie die, die wir in diesem Tutorial-Video vorstellen:<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/xszwt19AyGA\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>F\u00fcr neue Benutzer von Photoshop und Illustrator kann die Lernkurve auch etwas entmutigend sein; wenn das auf Sie zutrifft, finden Sie vielleicht auch eine kostenlose Alternative als zug\u00e4nglichere Option.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Planung Layout<\/strong><\/h2>\n<p>Nachdem Sie sich nun f\u00fcr eine Software entschieden haben, mit der Sie <strong>Gestalten Sie Ihr eigenes Rollbanner<\/strong>ist es an der Zeit, das Banner zu gestalten. Beginnen Sie mit der Unterteilung Ihres Banners in Abschnitte. Der obere Bereich eines Rollbanners enth\u00e4lt in der Regel das Firmenlogo sowie den Firmennamen, falls dieser nicht im Logo enthalten ist. Es ist auch ein guter Platz, um eine Kernbotschaft, einen Firmenslogan oder eine Tagline zu platzieren. Da er sich auf Augenh\u00f6he befindet, wird er die meiste Aufmerksamkeit auf sich ziehen. Der obere Bereich ist der Ort, an dem Sie sofort deutlich machen wollen, was Ihr Unternehmen ist und tut. In der Mitte des <a title=\"solopress billige Rollbanner \" href=\"https:\/\/www.solopress.com\/blog\/de\/rollbanner\/\">Rollbanner<\/a>k\u00f6nnen Sie das Wesentliche Ihrer Botschaft oder Ihres Entwurfs einf\u00fcgen. Es ist der richtige Ort, um den Inhalt zu vertiefen; allerdings muss ein Gleichgewicht zwischen Wortreichtum und Vagheit gefunden werden.<\/p>\n<p>Wenn <strong>Gestalten Sie Ihr eigenes Rollbanner<\/strong>Sie wollen ihn nicht mit zu viel Lesestoff \u00fcberfrachten oder ihn zu leer und zweideutig lassen. Schlie\u00dflich ist der untere Bereich Ihres Rollbanners der ideale Platz f\u00fcr kurze Kontaktinformationen. Ideal sind hier die Adresse Ihrer Website und Icons f\u00fcr soziale Medien. Auch hier gilt: Geben Sie die grundlegenden Informationen an, die Ihre Kunden ben\u00f6tigen, um Sie zu erreichen, aber nicht so viele, dass sie \u00fcberfordert sind. Wenn Sie zus\u00e4tzliche Hilfe bei der Erstellung Ihres Rollbanners ben\u00f6tigen, haben wir dieses Tutorial-Video zusammengestellt, das Sie Schritt f\u00fcr Schritt durch die Gestaltung eines Rollbanners in Photoshop f\u00fchrt:<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/ubV-MBbKwbI?list=UUiBjCqxJJ5SfMswdSddI3dA\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Ber\u00fccksichtigung von Designelementen<\/strong><\/h2>\n<p>Achten Sie darauf, dass Sie in Ihrem Rollbanner-Layout nicht nur Worte, sondern auch Bilder von hoher Qualit\u00e4t verwenden. Es sollten hochaufl\u00f6sende Bilder sein - idealerweise mit mindestens 300 dpi. Au\u00dferdem verwenden Sie am besten <a title=\"cmyk vs. rgb-Farben\" href=\"http:\/\/en.wikipedia.org\/wiki\/CMYK_color_model\" target=\"_blank\" rel=\"noopener noreferrer\">CMYK-Farben, im Vergleich zu RGB<\/a>da sie druckfertig sind. Computerbildschirme zeigen die Farben in RGB an, und die beiden unterscheiden sich leicht. Es ist ratsam, darauf zu achten, dass die von Ihnen verwendeten Farben und Schriftarten gut mit dem Logo Ihres Unternehmens und dem gesamten Branding abgestimmt sind, damit es erkennbar und konsistent ist.<\/p>\n<p>Schlie\u00dflich sollten Sie nicht mehr als 3 Schriftarten f\u00fcr Ihr Gesamtdesign w\u00e4hlen, da jede weitere un\u00fcbersichtlich aussehen k\u00f6nnte. Der gesamte Text sollte vor dem Hintergrund der von Ihnen gew\u00e4hlten Farben und des Designs gut lesbar sein. Denken Sie daran, dass die Menschen in einer belebten Messehalle oder Konferenzeinrichtung schnell einen Blick auf das Rollbanner werfen werden, so dass sie die wichtigsten Informationen aufnehmen k\u00f6nnen, ohne daf\u00fcr \"arbeiten\" oder zu lange verweilen zu m\u00fcssen.<\/p>\n<p>Mit diesen Richtlinien im Hinterkopf sind Sie auf dem besten Weg, ein Rollbanner zu kreieren, das ganz Ihren Vorstellungen entspricht. Nat\u00fcrlich k\u00f6nnen wir Ihnen auch dabei helfen, wenn Sie die Grafik gegen etwas anderes austauschen m\u00f6chten:<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/hNjejdcJnZc?list=UUiBjCqxJJ5SfMswdSddI3dA\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":23,"featured_media":27034,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[555],"tags":[766],"class_list":{"0":"post-27025","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tutorials","8":"tag-roller-banners"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tips For Designing Your Own Roller Banner | Solopress<\/title>\n<meta name=\"description\" content=\"Keen to try your hand at designing your own roller banner? Check out our handy guide and make it easy with these useful ideas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solopress.com\/blog\/de\/tutorials\/rollenbanner-selbst-gestalten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tips For Designing Your Own Roller Banner | Solopress\" \/>\n<meta property=\"og:description\" content=\"Keen to try your hand at designing your own roller banner? Check out our handy guide and make it easy with these useful ideas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solopress.com\/blog\/de\/tutorials\/rollenbanner-selbst-gestalten\/\" \/>\n<meta property=\"og:site_name\" content=\"The Latest Print and Design News | Solopress\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Solopress\" \/>\n<meta property=\"article:published_time\" content=\"2014-11-21T10:38:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-25T15:51:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/11\/348_2l.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"355\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Solopress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@solopress\" \/>\n<meta name=\"twitter:site\" content=\"@solopress\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Solopress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/designing-your-own-roller-banner\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/designing-your-own-roller-banner\\\/\"},\"author\":{\"name\":\"Solopress\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/f8531403c74fe1b3ef14bcaeec1c8c41\"},\"headline\":\"Tips for designing your own roller banner\",\"datePublished\":\"2014-11-21T10:38:20+00:00\",\"dateModified\":\"2019-06-25T15:51:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/designing-your-own-roller-banner\\\/\"},\"wordCount\":730,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/designing-your-own-roller-banner\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/348_2l.jpg\",\"keywords\":[\"Roller Banners\"],\"articleSection\":[\"Design Tutorials\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/designing-your-own-roller-banner\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/designing-your-own-roller-banner\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/designing-your-own-roller-banner\\\/\",\"name\":\"Tips For Designing Your Own Roller Banner | Solopress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/designing-your-own-roller-banner\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/designing-your-own-roller-banner\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/348_2l.jpg\",\"datePublished\":\"2014-11-21T10:38:20+00:00\",\"dateModified\":\"2019-06-25T15:51:14+00:00\",\"description\":\"Keen to try your hand at designing your own roller banner? Check out our handy guide and make it easy with these useful ideas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/designing-your-own-roller-banner\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/designing-your-own-roller-banner\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/designing-your-own-roller-banner\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/348_2l.jpg\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/348_2l.jpg\",\"width\":450,\"height\":355,\"caption\":\"designing your own roller banner with solopress\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/designing-your-own-roller-banner\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tips for designing your own roller banner\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"name\":\"The Latest Print and Design News | Solopress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\",\"name\":\"Solopress\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"width\":428,\"height\":88,\"caption\":\"Solopress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Solopress\",\"https:\\\/\\\/x.com\\\/solopress\",\"https:\\\/\\\/instagram.com\\\/solopress\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/solopress\",\"https:\\\/\\\/uk.pinterest.com\\\/solopress\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/solopress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/f8531403c74fe1b3ef14bcaeec1c8c41\",\"name\":\"Solopress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g\",\"caption\":\"Solopress\"},\"sameAs\":[\"https:\\\/\\\/www.solopress.com\\\/\"],\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/de\\\/author\\\/solopress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tipps f\u00fcr die Gestaltung Ihres eigenen Rollbanners | Solopress","description":"Haben Sie Lust, Ihr eigenes Rollbanner zu entwerfen? Schauen Sie sich unseren praktischen Leitfaden an und machen Sie es sich mit diesen n\u00fctzlichen Ideen leicht.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solopress.com\/blog\/de\/tutorials\/rollenbanner-selbst-gestalten\/","og_locale":"de_DE","og_type":"article","og_title":"Tips For Designing Your Own Roller Banner | Solopress","og_description":"Keen to try your hand at designing your own roller banner? Check out our handy guide and make it easy with these useful ideas.","og_url":"https:\/\/www.solopress.com\/blog\/de\/tutorials\/rollenbanner-selbst-gestalten\/","og_site_name":"The Latest Print and Design News | Solopress","article_publisher":"https:\/\/www.facebook.com\/Solopress","article_published_time":"2014-11-21T10:38:20+00:00","article_modified_time":"2019-06-25T15:51:14+00:00","og_image":[{"width":450,"height":355,"url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/11\/348_2l.jpg","type":"image\/jpeg"}],"author":"Solopress","twitter_card":"summary_large_image","twitter_creator":"@solopress","twitter_site":"@solopress","twitter_misc":{"Verfasst von":"Solopress","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.solopress.com\/blog\/tutorials\/designing-your-own-roller-banner\/#article","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/designing-your-own-roller-banner\/"},"author":{"name":"Solopress","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/f8531403c74fe1b3ef14bcaeec1c8c41"},"headline":"Tips for designing your own roller banner","datePublished":"2014-11-21T10:38:20+00:00","dateModified":"2019-06-25T15:51:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/designing-your-own-roller-banner\/"},"wordCount":730,"commentCount":2,"publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/designing-your-own-roller-banner\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/11\/348_2l.jpg","keywords":["Roller Banners"],"articleSection":["Design Tutorials"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.solopress.com\/blog\/tutorials\/designing-your-own-roller-banner\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.solopress.com\/blog\/tutorials\/designing-your-own-roller-banner\/","url":"https:\/\/www.solopress.com\/blog\/tutorials\/designing-your-own-roller-banner\/","name":"Tipps f\u00fcr die Gestaltung Ihres eigenen Rollbanners | Solopress","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/designing-your-own-roller-banner\/#primaryimage"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/designing-your-own-roller-banner\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/11\/348_2l.jpg","datePublished":"2014-11-21T10:38:20+00:00","dateModified":"2019-06-25T15:51:14+00:00","description":"Haben Sie Lust, Ihr eigenes Rollbanner zu entwerfen? Schauen Sie sich unseren praktischen Leitfaden an und machen Sie es sich mit diesen n\u00fctzlichen Ideen leicht.","breadcrumb":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/designing-your-own-roller-banner\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solopress.com\/blog\/tutorials\/designing-your-own-roller-banner\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.solopress.com\/blog\/tutorials\/designing-your-own-roller-banner\/#primaryimage","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/11\/348_2l.jpg","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/11\/348_2l.jpg","width":450,"height":355,"caption":"designing your own roller banner with solopress"},{"@type":"BreadcrumbList","@id":"https:\/\/www.solopress.com\/blog\/tutorials\/designing-your-own-roller-banner\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.solopress.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Tips for designing your own roller banner"}]},{"@type":"WebSite","@id":"https:\/\/www.solopress.com\/blog\/#website","url":"https:\/\/www.solopress.com\/blog\/","name":"Die neuesten Nachrichten aus Druck und Design | Solopress","description":"","publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solopress.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.solopress.com\/blog\/#organization","name":"Solopress","url":"https:\/\/www.solopress.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","width":428,"height":88,"caption":"Solopress"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Solopress","https:\/\/x.com\/solopress","https:\/\/instagram.com\/solopress\/","https:\/\/www.linkedin.com\/company\/solopress","https:\/\/uk.pinterest.com\/solopress\/","https:\/\/www.youtube.com\/user\/solopress"]},{"@type":"Person","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/f8531403c74fe1b3ef14bcaeec1c8c41","name":"Solopress","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g","caption":"Solopress"},"sameAs":["https:\/\/www.solopress.com\/"],"url":"https:\/\/www.solopress.com\/blog\/de\/author\/solopress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/11\/348_2l.jpg","_links":{"self":[{"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/posts\/27025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/comments?post=27025"}],"version-history":[{"count":5,"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/posts\/27025\/revisions"}],"predecessor-version":[{"id":61217,"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/posts\/27025\/revisions\/61217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/media\/27034"}],"wp:attachment":[{"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/media?parent=27025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/categories?post=27025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/tags?post=27025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}