{"id":72299,"date":"2022-05-25T09:05:24","date_gmt":"2022-05-25T08:05:24","guid":{"rendered":"https:\/\/www.solopress.com\/blog\/?p=72299"},"modified":"2023-10-07T11:15:31","modified_gmt":"2023-10-07T10:15:31","slug":"ancoats-guitars-goes-to-the-guitar-show","status":"publish","type":"post","link":"https:\/\/www.solopress.com\/blog\/de\/entrepreneurs\/ancoats-guitars-goes-to-the-guitar-show\/","title":{"rendered":"Start-Up Geschichten: Ancoats Guitars geht zur Gitarrenmesse"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p><span data-contrast=\"none\">Die Guitar Show in Birmingham war die zweite Fachveranstaltung, auf der der Geigenbauer Dave Roberts ausstellen konnte<\/span><span data-contrast=\"none\">\u00a0<a href=\"https:\/\/www.ancoatsguitars.co.uk\/\" target=\"_blank\" rel=\"noopener\">Ancoats Gitarren<\/a>. Dieses Mal war Dave mit einer zweiten Runde von Drucksachen und Merchandising-Artikeln bewaffnet, um seine Marke gro\u00df herauszubringen. Wir haben die Geschicke von Ancoats Guitars in unserem <\/span><a href=\"https:\/\/www.solopress.com\/blog\/de\/start-up-stories\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">Blog-Serie Start-up Stories<\/span><\/a><span data-contrast=\"none\">Deshalb waren wir sehr gespannt, wie es bei der zweiten Gitarrenmesse lief. Wir haben uns mit Dave getroffen, um herauszufinden, ob er einige der Messegeheimnisse, die er beim ersten Mal gelernt hat, in die Praxis umsetzen konnte.<\/span><\/p>\n<h2><b><span data-contrast=\"none\">Druckvorbereitung<\/span><\/b><\/h2>\n<p><span data-contrast=\"none\">Eine Sache, die dieses Mal anders war, war das erweiterte Angebot an gedrucktem Material, das Dave zur Verf\u00fcgung stand. F\u00fcr seinen Besuch auf der North East Guitar Show, \u00fcber die wir in unserem letzten<\/span><span data-contrast=\"none\">\u00a0<a href=\"https:\/\/www.solopress.com\/blog\/de\/start-up-stories\/start-up-stories-ancoats-guitars-at-the-north-east-guitar-show\/\" target=\"_blank\" rel=\"noopener\">Blog-Eintrag Start Up Stories<\/a>hatte Dave bereits mit Solopress zusammengearbeitet, um die <\/span><a href=\"https:\/\/www.solopress.com\/blog\/de\/rollbanner\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">Rollbanner<\/span><\/a><span data-contrast=\"none\"> und eine <\/span><a href=\"https:\/\/www.solopress.com\/blog\/de\/tablecloths\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">Bedrucktes Tischtuch<\/span><\/a><span data-contrast=\"none\"> um seinen Stand zu verbessern, zus\u00e4tzlich zu <\/span><a href=\"https:\/\/www.solopress.com\/blog\/de\/flugblatter-prospekte\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">Flugbl\u00e4tter<\/span><\/a><span data-contrast=\"none\">, <\/span><a href=\"https:\/\/www.solopress.com\/blog\/de\/visitenkarten\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">Visitenkarte<\/span><\/a><span data-contrast=\"none\"> und <\/span><a href=\"https:\/\/www.solopress.com\/blog\/de\/geschaftsdrucksachen\/compliment-slips\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">Verg\u00fctungsbelege<\/span><\/a><span data-contrast=\"none\">.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Seit der letzten Veranstaltung waren wir wieder flei\u00dfig dabei, neue Elemente zu entwickeln. Auf der North East Guitar Show improvisierte Dave Produktetiketten aus den von uns produzierten Comp-Slips. F\u00fcr eine ausgefeiltere L\u00f6sung konnten wir Markenetiketten entwerfen und drucken. <\/span><a href=\"https:\/\/www.solopress.com\/blog\/de\/schlagworter\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">Swing-Tags<\/span><\/a><span data-contrast=\"none\"> an den Instrumenten selbst zu h\u00e4ngen.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559739&quot;:300,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h2><b><span data-contrast=\"none\">Beute f\u00fcr die Messe<\/span><\/b><\/h2>\n<p><span data-contrast=\"none\">Als Werbegeschenke haben wir folgende Produkte hergestellt <\/span><a href=\"https:\/\/www.solopress.com\/blog\/de\/poster\/a3\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">A3-Plakate<\/span><\/a> <span data-contrast=\"none\">mit einer stilisierten Darstellung des Ancoats Guitars-Logos in einem modernen Blockmuster-Design. Die Plakate enthielten auch eine <\/span><a href=\"https:\/\/www.solopress.com\/blog\/de\/business-marketing\/sie-sind-zuruck-ein-leitfaden-fur-vermarkter-zum-knacken-des-qr-codes\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">QR-Code<\/span><\/a><span data-contrast=\"none\"> so dass jeder, der sie betrachtet, den Code scannen und direkt zur Website navigieren kann.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559739&quot;:300,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-72307\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/05\/MerchGroup.jpg\" alt=\"\" width=\"805\" height=\"593\" \/><\/p>\n<p><span data-contrast=\"none\">Wir haben uns auch f\u00fcr ein neues Produkt von Solopress entschieden: <\/span><a href=\"https:\/\/www.solopress.com\/blog\/de\/aufkleber-etiketten\/custom-shape-sticker-sheets\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">Benutzerdefinierte Form Aufkleber<\/span><\/a><span data-contrast=\"none\">. Diese aufregende neue Option nutzt unsere hochmoderne Motioncutter 23-Maschine, \u00fcber die Sie mehr in unserem Blog erfahren k\u00f6nnen, in dem wir unsere<\/span><a href=\"https:\/\/www.solopress.com\/blog\/de\/solopress-nachrichten\/neue-laser-schneidetechnik-von-solopress\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\"> M\u00f6glichkeiten des Laserschneidens<\/span><\/a><span data-contrast=\"none\">. Die Aufkleber, die wir f\u00fcr Ancoats Guitars produzierten, enthielten verschiedene ausgeschnittene Varianten der Wortmarke und des Logos sowie ein erfreulich d\u00fcsteres Bild von Daves Schiffscontainer-Werkstatt und einen Aufkleber mit dem stolzen Hinweis \"Made in Manchester\".<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h2><b><span data-contrast=\"none\">Authentisch spielen<\/span><\/b><\/h2>\n<p><span data-contrast=\"none\">Bei der Herstellung von Echtheitszertifikaten, die Dave jedem Kauf einer Ancoats-Gitarre beif\u00fcgt, konnten wir eine weitere spezielle Druckveredelungstechnik zum Einsatz bringen. Die Verwendung von Goldfolie auf diesen Zertifikaten verleiht ihnen ein hochwertiges Gef\u00fchl und tr\u00e4gt dazu bei, dass die Kunden ihr ma\u00dfgefertigtes Instrument in Empfang nehmen k\u00f6nnen. Diese Technik dient auch einem praktischen Zweck, denn <a href=\"https:\/\/www.solopress.com\/blog\/de\/foil\/\">Folierung<\/a> macht das Zertifikat schwieriger zu f\u00e4lschen.<\/span><\/p>\n<figure id=\"attachment_72312\" aria-describedby=\"caption-attachment-72312\" style=\"width: 900px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/05\/Cert.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-72312\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/05\/Cert.jpg\" alt=\"\" width=\"900\" height=\"698\" \/><\/a><figcaption id=\"caption-attachment-72312\" class=\"wp-caption-text\">dav<\/figcaption><\/figure>\n<h2><b><span data-contrast=\"none\">Wenn die Kappe passt<\/span><\/b><\/h2>\n<p><span data-contrast=\"none\">Neben den Papier- und Gro\u00dfformatelementen haben wir auch bei der Produktion von bedruckten T-Shirts und bestickten Caps zusammengearbeitet. Die T-Shirts haben ein \u00e4hnliches Design wie die A3-Poster, und die 6-Panel-Baseball-Caps sind in klassischem Schwarz gehalten und mit dem Ancoats Guitars-Wortzeichen in Wei\u00df bestickt. Sie dienten nicht nur als Markenuniform f\u00fcr Dave selbst, als er den Stand besetzte, sondern auch als perfekte Preise f\u00fcr Wettbewerbe in den sozialen Medien.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-72306\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/05\/Merch.jpg\" alt=\"\" width=\"900\" height=\"675\" \/><\/p>\n<h2><b><span data-contrast=\"none\">Wieder auf der Stra\u00dfe<\/span><\/b><\/h2>\n<p><span data-contrast=\"none\">Mit frischem Druck und neuem Merchandise war es f\u00fcr Dave an der Zeit, seine Sachen zu packen und die M6 hinunter zur New Bingley Hall in Birmingham zu fahren.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559739&quot;:300,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.theguitarshow.co.uk\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">Die Gitarrenausstellung<\/span><\/a><span data-contrast=\"none\"> ist die gr\u00f6\u00dfte Veranstaltung im Vereinigten K\u00f6nigreich, die sich mit Gitarren, Gitarristen und Ausr\u00fcstung besch\u00e4ftigt. Sie wird von der Veranstaltungsfirma Torn and Frayed Ltd. organisiert, die ihren Namen treffend nach dem gleichnamigen Song der Rolling Stones gew\u00e4hlt hat. Nach dem Niedergang einer fr\u00fcheren Fachveranstaltung namens Music Live sahen einige der Organisatoren die Gelegenheit, eine Veranstaltung ins Leben zu rufen, die ganz den Gitarren gewidmet war, und die Guitar Show war geboren.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h2><b><span data-contrast=\"none\">Gro\u00dfe Namen<\/span><\/b><\/h2>\n<p><span data-contrast=\"none\">Die diesj\u00e4hrige Messe war Gastgeber f\u00fcr eine Vielzahl hochkar\u00e4tiger Aussteller. Die globalen Supermarken Ibanez, Danelectro und Dunlop waren ebenso anwesend wie die f\u00fcnf absoluten Titanen der britischen Verst\u00e4rkerindustrie: Marshall, Laney, Orange, Ashdown und Blackstar. Innovative Technikmarken wie Focusrite\/Novation, Zoom und Eventide pr\u00e4sentierten ihre neuesten Gadgets, und Hersteller von Premium-Teilen wie Lollar und Bare Knuckle Pickups boten die M\u00f6glichkeit, Ihr Instrument zu verbessern.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559739&quot;:300,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/05\/amps.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-72310\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/05\/amps.png\" alt=\"\" width=\"2152\" height=\"116\" \/><\/a><\/p>\n<h2><b><span data-contrast=\"none\">Hergestellt in Gro\u00dfbritannien<\/span><\/b><\/h2>\n<p><span data-contrast=\"none\">Ancoats Guitars war in guter Gesellschaft, sur<\/span><span data-contrast=\"none\">von britischen Herstellern, die sich auf hochwertige, handgefertigte E-Gitarren spezialisiert haben. Andere kleine britische Gitarrenbauer wie Stonewolf, Reiver und Maybury hatten St\u00e4nde, ebenso wie etablierte Namen im britischen E-Gitarrenbau wie Gordon Smith und Patrick James Eggle.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559739&quot;:300,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h2><b><span data-contrast=\"none\">Unter dem Einfluss<\/span><\/b><\/h2>\n<p><span data-contrast=\"none\">Neben den Herstellern von Instrumenten und Zubeh\u00f6r gab es auch Aussteller aus den Bereichen Einzelhandel, Medien, Verlagswesen und Musikunterricht. Von zunehmender Bedeutung bei solchen Veranstaltungen ist jedoch die Pr\u00e4senz von Online-Influencern. Auch wenn sie nicht unbedingt mit eigenen St\u00e4nden vertreten waren, machten sie sich auf der Messe bemerkbar. Viele bekannte Namen wie Chris Buck, Dave Simpson, Dan und Mick von der That Pedal Show und Danish Pete von Andertons TV drehten ihre Runden, trafen und begr\u00fc\u00dften Fans und informierten sich \u00fcber die Neuheiten in der Gitarrenszene.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559739&quot;:300,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/05\/279149288_2541386252663018_687153710488767799_n.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-72311\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/05\/279149288_2541386252663018_687153710488767799_n.jpeg\" alt=\"\" width=\"600\" height=\"600\" \/><\/a><\/p>\n<h2><b><span data-contrast=\"none\">Aufdrehen, aufstellen, Flagge zeigen<\/span><\/b><\/h2>\n<p><span data-contrast=\"none\">Nach einem sehr fr\u00fchen Start kam Dave rechtzeitig vor Ort an, um sich einzurichten und sich auf den bevorstehenden Tag vorzubereiten. Die ersten Eindr\u00fccke vom Standort seines Standes lie\u00dfen Dave jedoch etwas ratlos zur\u00fcck:<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559739&quot;:300,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"none\">\"Als ich unseren Stand ausfindig machte, war ich ein wenig entt\u00e4uscht, dass er etwas versteckt in der Ecke lag. Wenn ich das n\u00e4chste Mal auf einer Messe ausstellen m\u00f6chte, werde ich auf jeden Fall genau auf den Lageplan achten und sicherstellen, dass ich einen Stand buche, der nicht zu weit abseits der \u00fcblichen Wege liegt!<\/span><\/b><span data-contrast=\"none\">\u202f\u202f<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/05\/PXL_20220507_075655355.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-72304\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/05\/PXL_20220507_075655355.png\" alt=\"\" width=\"900\" height=\"675\" \/><\/a><\/p>\n<p><span data-contrast=\"none\">Hilfe kam in Form der <\/span><a href=\"https:\/\/www.solopress.com\/blog\/de\/flags\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">Gedruckte Flagge<\/span><\/a><span data-contrast=\"none\"> die wir zuvor geliefert hatten. Dave hatte die Flagge zur North East Guitar Show mitgenommen, aber sie war einfach zu gro\u00df, um sie an diesem kleineren Veranstaltungsort zu verwenden. Hier in der New Bingley Hall sah die Fahne nicht nur gut aus, sie half auch dabei, die Pr\u00e4senz des Ancoats Guitars Standes den Besuchern zu signalisieren, die ihn sonst vielleicht nicht unbedingt bemerkt h\u00e4tten.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559739&quot;:300,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h2><b><span data-contrast=\"none\">Sich von der Masse abheben<\/span><\/b><\/h2>\n<p><span data-contrast=\"none\">Der Gesamteffekt des Materials mit dem Markenzeichen von Ancoats Guitars bestand darin, den Eindruck eines Unternehmens zu erwecken, das es ernst meint. Dave sp\u00fcrte den Nutzen seines standardisierten Marketingmaterials sowohl in Bezug auf die Attraktivit\u00e4t des Standes f\u00fcr Besucher als auch in Bezug auf die Wahrnehmung des Unternehmens:<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559739&quot;:300,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"none\">\"Viele Leute waren \u00fcberrascht, dass ich erst seit relativ kurzer Zeit dabei bin, weil das Branding so professionell aussah. Die Aufkleber kamen besonders gut an. Ich habe einige der B\u00f6gen zerschnitten und verstreut, aber viele Leute waren froh, einen ganzen Bogen zu bekommen.<\/span><\/b><span data-contrast=\"none\">\u202f<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-72308\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/05\/Stand3.jpg\" alt=\"\" width=\"798\" height=\"625\" \/><\/p>\n<h2><b><span data-contrast=\"none\">Fliegende Farben<\/span><\/b><\/h2>\n<p><span data-contrast=\"none\">Dave hatte starke Vorstellungen vom Branding f\u00fcr Ancoats Guitars, lange bevor er mit Solopress und dem hauseigenen Designer Matt Bruty zu arbeiten begann. Seine Vision einer Marke, die sich \u00fcber bestimmte Normen in der Gitarrenwelt hinwegsetzt, scheint sich auszuzahlen:<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"none\">\"Ich hatte den buntesten Stand. Im Moment scheint es einen Trend zu 50 Braunt\u00f6nen bei Gitarren zu geben!\"<\/span><\/b><span data-contrast=\"none\">\u202f<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">In der gesch\u00e4ftigen Umgebung einer Messe zahlt es sich aus, hervorzustechen, und die k\u00fchne und unverwechselbare Markenidentit\u00e4t von Ancoats Guitars tut genau das.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559739&quot;:300,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-72309\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/05\/Stand4.jpg\" alt=\"\" width=\"900\" height=\"674\" \/><\/p>\n<h2><b><span data-contrast=\"none\">Vielversprechende Kontakte<\/span><\/b><\/h2>\n<p><span data-contrast=\"none\">Das Kn\u00fcpfen wertvoller Branchenkontakte ist ein wichtiger Teil der Messeerfahrung. Die Live-B\u00fchne auf der Veranstaltung wurde von Reverb.com gesponsert, einer bekannten und hoch angesehenen Website f\u00fcr den Handel mit Musikger\u00e4ten. W\u00e4hrend Reverb seinen Ruf mit Verk\u00e4ufen von Verbraucher zu Verbraucher, einer Art eBay f\u00fcr Musiker, aufgebaut hat, ist es jetzt ein etablierter Einzelh\u00e4ndler f\u00fcr brandneue Musikger\u00e4te. Die Beschaffungsspezialisten von Reverb interessierten sich sehr f\u00fcr den Stand von Ancoats Guitars, und Dave ist jetzt in Gespr\u00e4chen, um seine Instrumente \u00fcber die Website zu verkaufen.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559739&quot;:300,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"none\">\"Ich habe mich auch mit Matt von Fidelity, Joe von Guitar Nerds und dem Brand Relations Manager von Reverb auf einen Drink getroffen. Es war alles ein bisschen surreal, aber ich fand es toll und konnte viele hilfreiche Informationen sammeln. Reverb wird versuchen, mir beim internationalen Vertrieb zu helfen.\"<\/span><\/b><span data-contrast=\"none\">\u202f<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h2><b><span data-contrast=\"none\">Dave x Dave<\/span><\/b><\/h2>\n<p><span data-contrast=\"none\">W\u00e4hrend der Show kn\u00fcpfte Dave Roberts auch eine Verbindung mit dem beliebten Youtuber Dave Simpson. Dave S. hat sich mit seiner lockeren und zug\u00e4nglichen Art, \u00fcber Gitarrenausr\u00fcstung zu diskutieren, einen Namen gemacht. Heute hat er auch regelm\u00e4\u00dfige Gastauftritte auf dem Andertons TV-Kanal, der an seine 770.000 Abonnenten gesendet wird. In einem Bereich, der sich manchmal etwas elit\u00e4r anf\u00fchlt, scheut sich Simpson nie, f\u00fcr erschwingliche Produkte zu werben und kommt immer als \u00e4u\u00dferst sympathischer Typ r\u00fcber.<\/span><\/p>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/05\/Dave-Simpson.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-72313\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/05\/Dave-Simpson.png\" alt=\"\" width=\"900\" height=\"619\" \/><\/a><\/p>\n<p><span data-contrast=\"none\">Die beiden Daves verstanden sich pr\u00e4chtig und tauschten ihre Kontaktdaten aus. Wir hoffen, Dave Simpson bald einmal mit einer Ancoats-Gitarre in einem Vlog zu sehen. Ein solches Treffen zeigt, dass man dabei sein muss, um zu gewinnen, und es zeigt, dass die Teilnahme an diesen Fachveranstaltungen und die Werbung f\u00fcr sich selbst unerwartete und wertvolle Ergebnisse bringen kann.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559739&quot;:300,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h2><b><span data-contrast=\"none\">Die Quintessenz<\/span><\/b><\/h2>\n<p><span data-contrast=\"none\">Die Verbreitung des Markenbewusstseins, das Kn\u00fcpfen von Branchenkontakten und die Anbahnung von Kontakten zu Influencern, Einzelh\u00e4ndlern und Kunden sind f\u00fcr jedes Unternehmen, das an einer Messe teilnimmt, \u00e4u\u00dferst wertvolle Ziele. <\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559739&quot;:300,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Aber wie sieht es mit dem Verkauf aus? Dave war nicht unbedingt darauf aus, seine Instrumente auf Anhieb zu verkaufen, aber es gab gute Neuigkeiten an dieser Front...<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559739&quot;:300,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"none\">\"Die Entscheidung \u00fcber alle Spezifikationen und die Auftragsvergabe f\u00fcr ein ma\u00dfgefertigtes Instrument ist eine gro\u00dfe Verpflichtung, daher blieb ich realistisch, was die Aussicht auf Auftr\u00e4ge auf der Messe selbst anging. Ich war jedoch sehr erfreut, dass ich an meinem Stand gleich einen Verkauf abschlie\u00dfen konnte. Und nicht nur das: Einer der Besucher, mit dem ich gesprochen habe, hat sich bereits eine Woche sp\u00e4ter gemeldet und eine Bestellung aufgegeben!\"<\/span><\/b><span data-contrast=\"none\">\u202f<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Wir sind wirklich ermutigt durch die Art und Weise, wie Ancoats Guitars nach so kurzer Zeit im Gesch\u00e4ft weiter w\u00e4chst und sich in der Branche etabliert. Diese Messeauftritte, zusammen mit den gedruckten Waren und Display-Materialien, an denen wir gemeinsam gearbeitet haben, scheinen Ancoats Guitars auf einen erfolgreichen Weg zu bringen!<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>The Guitar Show in Birmingham was the second trade event where luthier Dave Roberts has had a chance to exhibit\u00a0Ancoats Guitars. This time Dave was armed with a second round of printed material and merchandise to help big up his brand. We\u2019ve been following the fortunes of Ancoats Guitars in our Start-up Stories blog series, [&hellip;]<\/p>\n","protected":false},"author":134,"featured_media":72303,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[955,960],"tags":[757,899],"class_list":{"0":"post-72299","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-entrepreneurs","8":"category-exhibitions-trade-shows","9":"tag-exhibition-stands","10":"tag-exhibitions"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Start-Up Stories: Ancoats Guitars Goes to The Guitar Show - Solopress UK<\/title>\n<meta name=\"description\" content=\"In our latest blog, we follow Dave Roberts as he exhibits Ancoats Guitars at The Guitar Show armed with fresh printed material &amp; merchandise.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solopress.com\/blog\/de\/unternehmer\/ancoats-guitars-goes-to-the-guitar-show\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Start-Up Stories: Ancoats Guitars Goes to The Guitar Show - Solopress UK\" \/>\n<meta property=\"og:description\" content=\"In our latest blog, we follow Dave Roberts as he exhibits Ancoats Guitars at The Guitar Show armed with fresh printed material &amp; merchandise.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solopress.com\/blog\/de\/unternehmer\/ancoats-guitars-goes-to-the-guitar-show\/\" \/>\n<meta property=\"og:site_name\" content=\"The Latest Print and Design News | Solopress\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Solopress\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-25T08:05:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-07T10:15:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/05\/Blog-ancoats-Birmingham.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Danny Powell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@solopress\" \/>\n<meta name=\"twitter:site\" content=\"@solopress\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Danny Powell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"9\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/ancoats-guitars-goes-to-the-guitar-show\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/ancoats-guitars-goes-to-the-guitar-show\\\/\"},\"author\":{\"name\":\"Danny Powell\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/0937555a256c22f94400f4b7e2329c09\"},\"headline\":\"Start-Up Stories: Ancoats Guitars goes to The Guitar Show\",\"datePublished\":\"2022-05-25T08:05:24+00:00\",\"dateModified\":\"2023-10-07T10:15:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/ancoats-guitars-goes-to-the-guitar-show\\\/\"},\"wordCount\":1635,\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/ancoats-guitars-goes-to-the-guitar-show\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Blog-ancoats-Birmingham.jpg\",\"keywords\":[\"Exhibition Stands\",\"Exhibitions\"],\"articleSection\":[\"Entrepreneurs\",\"Events, Exhibitions &amp; Trade Shows\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/ancoats-guitars-goes-to-the-guitar-show\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/ancoats-guitars-goes-to-the-guitar-show\\\/\",\"name\":\"Start-Up Stories: Ancoats Guitars Goes to The Guitar Show - Solopress UK\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/ancoats-guitars-goes-to-the-guitar-show\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/ancoats-guitars-goes-to-the-guitar-show\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Blog-ancoats-Birmingham.jpg\",\"datePublished\":\"2022-05-25T08:05:24+00:00\",\"dateModified\":\"2023-10-07T10:15:31+00:00\",\"description\":\"In our latest blog, we follow Dave Roberts as he exhibits Ancoats Guitars at The Guitar Show armed with fresh printed material & merchandise.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/ancoats-guitars-goes-to-the-guitar-show\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/ancoats-guitars-goes-to-the-guitar-show\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/ancoats-guitars-goes-to-the-guitar-show\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Blog-ancoats-Birmingham.jpg\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Blog-ancoats-Birmingham.jpg\",\"width\":900,\"height\":675,\"caption\":\"Ancoats Guitars Birmingham Blog\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/ancoats-guitars-goes-to-the-guitar-show\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Start-Up Stories: Ancoats Guitars goes to The Guitar Show\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"name\":\"The Latest Print and Design News | Solopress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\",\"name\":\"Solopress\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"width\":428,\"height\":88,\"caption\":\"Solopress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Solopress\",\"https:\\\/\\\/x.com\\\/solopress\",\"https:\\\/\\\/instagram.com\\\/solopress\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/solopress\",\"https:\\\/\\\/uk.pinterest.com\\\/solopress\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/solopress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/0937555a256c22f94400f4b7e2329c09\",\"name\":\"Danny Powell\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"caption\":\"Danny Powell\"},\"description\":\"With over two decades in marketing, Danny Powell is a Senior Copywriter at Solopress, one of the UK\u2019s leading online printers. Having worked on the print buying, agency and sales sides of the industry, he brings a well-rounded perspective to his writing on print, design and sustainability.\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/de\\\/author\\\/danny-powell\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Start-Up Geschichten: Ancoats Guitars geht zur Gitarrenmesse - Solopress UK","description":"In unserem neuesten Blog folgen wir Dave Roberts, wie er Ancoats Guitars auf der Guitar Show mit frischem Druckmaterial und Merchandise ausstellt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solopress.com\/blog\/de\/unternehmer\/ancoats-guitars-goes-to-the-guitar-show\/","og_locale":"de_DE","og_type":"article","og_title":"Start-Up Stories: Ancoats Guitars Goes to The Guitar Show - Solopress UK","og_description":"In our latest blog, we follow Dave Roberts as he exhibits Ancoats Guitars at The Guitar Show armed with fresh printed material & merchandise.","og_url":"https:\/\/www.solopress.com\/blog\/de\/unternehmer\/ancoats-guitars-goes-to-the-guitar-show\/","og_site_name":"The Latest Print and Design News | Solopress","article_publisher":"https:\/\/www.facebook.com\/Solopress","article_published_time":"2022-05-25T08:05:24+00:00","article_modified_time":"2023-10-07T10:15:31+00:00","og_image":[{"width":900,"height":675,"url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/05\/Blog-ancoats-Birmingham.jpg","type":"image\/jpeg"}],"author":"Danny Powell","twitter_card":"summary_large_image","twitter_creator":"@solopress","twitter_site":"@solopress","twitter_misc":{"Verfasst von":"Danny Powell","Gesch\u00e4tzte Lesezeit":"9\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/ancoats-guitars-goes-to-the-guitar-show\/#article","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/ancoats-guitars-goes-to-the-guitar-show\/"},"author":{"name":"Danny Powell","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/0937555a256c22f94400f4b7e2329c09"},"headline":"Start-Up Stories: Ancoats Guitars goes to The Guitar Show","datePublished":"2022-05-25T08:05:24+00:00","dateModified":"2023-10-07T10:15:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/ancoats-guitars-goes-to-the-guitar-show\/"},"wordCount":1635,"publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/ancoats-guitars-goes-to-the-guitar-show\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/05\/Blog-ancoats-Birmingham.jpg","keywords":["Exhibition Stands","Exhibitions"],"articleSection":["Entrepreneurs","Events, Exhibitions &amp; Trade Shows"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/ancoats-guitars-goes-to-the-guitar-show\/","url":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/ancoats-guitars-goes-to-the-guitar-show\/","name":"Start-Up Geschichten: Ancoats Guitars geht zur Gitarrenmesse - Solopress UK","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/ancoats-guitars-goes-to-the-guitar-show\/#primaryimage"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/ancoats-guitars-goes-to-the-guitar-show\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/05\/Blog-ancoats-Birmingham.jpg","datePublished":"2022-05-25T08:05:24+00:00","dateModified":"2023-10-07T10:15:31+00:00","description":"In unserem neuesten Blog folgen wir Dave Roberts, wie er Ancoats Guitars auf der Guitar Show mit frischem Druckmaterial und Merchandise ausstellt.","breadcrumb":{"@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/ancoats-guitars-goes-to-the-guitar-show\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solopress.com\/blog\/entrepreneurs\/ancoats-guitars-goes-to-the-guitar-show\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/ancoats-guitars-goes-to-the-guitar-show\/#primaryimage","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/05\/Blog-ancoats-Birmingham.jpg","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/05\/Blog-ancoats-Birmingham.jpg","width":900,"height":675,"caption":"Ancoats Guitars Birmingham Blog"},{"@type":"BreadcrumbList","@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/ancoats-guitars-goes-to-the-guitar-show\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.solopress.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Start-Up Stories: Ancoats Guitars goes to The Guitar Show"}]},{"@type":"WebSite","@id":"https:\/\/www.solopress.com\/blog\/#website","url":"https:\/\/www.solopress.com\/blog\/","name":"Die neuesten Nachrichten aus Druck und Design | Solopress","description":"","publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solopress.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.solopress.com\/blog\/#organization","name":"Solopress","url":"https:\/\/www.solopress.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","width":428,"height":88,"caption":"Solopress"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Solopress","https:\/\/x.com\/solopress","https:\/\/instagram.com\/solopress\/","https:\/\/www.linkedin.com\/company\/solopress","https:\/\/uk.pinterest.com\/solopress\/","https:\/\/www.youtube.com\/user\/solopress"]},{"@type":"Person","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/0937555a256c22f94400f4b7e2329c09","name":"Danny Powell","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","caption":"Danny Powell"},"description":"Danny Powell ist seit \u00fcber zwei Jahrzehnten im Marketing t\u00e4tig und arbeitet als Senior Copywriter bei Solopress, einer der f\u00fchrenden britischen Online-Druckereien. Da er in der Druckbranche auf der Einkaufs-, Agentur- und Vertriebsseite gearbeitet hat, bringt er in seine Texte \u00fcber Druck, Design und Nachhaltigkeit eine abgerundete Perspektive ein.","url":"https:\/\/www.solopress.com\/blog\/de\/author\/danny-powell\/"}]}},"jetpack_featured_media_url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/05\/Blog-ancoats-Birmingham.jpg","_links":{"self":[{"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/posts\/72299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/comments?post=72299"}],"version-history":[{"count":5,"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/posts\/72299\/revisions"}],"predecessor-version":[{"id":72993,"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/posts\/72299\/revisions\/72993"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/media\/72303"}],"wp:attachment":[{"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/media?parent=72299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/categories?post=72299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/de\/wp-json\/wp\/v2\/tags?post=72299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}