{"id":17445,"date":"2014-06-03T11:45:19","date_gmt":"2014-06-03T10:45:19","guid":{"rendered":"https:\/\/www.solopress.com\/blog\/?p=17445"},"modified":"2020-02-27T12:33:51","modified_gmt":"2020-02-27T12:33:51","slug":"32-copas-del-mundo-carteles-artista-brasileno-cristiano-siqueira","status":"publish","type":"post","link":"https:\/\/www.solopress.com\/blog\/es\/print-inspiration\/32-world-cup-posters-brazilian-artist-cristiano-siqueira\/","title":{"rendered":"32 carteles de la Copa del Mundo del artista brasile\u00f1o Cristiano Siqueira"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p><!--more--><\/p>\n<h3><strong>ESPN<\/strong> encargado <strong>Artista brasile\u00f1o<\/strong> y <strong>dise\u00f1ador gr\u00e1fico Cristiano Siqueira<\/strong> para crear estos incre\u00edbles <strong>Carteles de la Copa Mundial de la FIFA 2014<\/strong>.<\/h3>\n<p><strong>ESPN<\/strong> quer\u00eda capturar a los h\u00e9roes del f\u00fatbol en rugidos, v\u00edtores y triunfos mientras compiten en el mayor acontecimiento futbol\u00edstico cada 4 a\u00f1os.<\/p>\n<p>De Wayne Rooney a Alexis S\u00e1nchez <a href=\"https:\/\/www.solopress.com\/blog\/es\/carteles\/\">carteles<\/a> \u00a1hacen que las estrellas del f\u00fatbol parezcan h\u00e9roes de c\u00f3mic!<\/p>\n<figure id=\"attachment_17446\" aria-describedby=\"caption-attachment-17446\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17446\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E38155F00000578-523_634x948.jpg\" alt=\"FIFA-Copa del Mundo-2014-Wayne-Rooney-The-Three-Lions-Poster\" width=\"634\" height=\"948\" \/><figcaption id=\"caption-attachment-17446\" class=\"wp-caption-text\">Wayne Rooney ruge en el p\u00f3ster de Siqueira \"Los Tres Leones\" para el Mundial<\/figcaption><\/figure>\n<figure id=\"attachment_17447\" aria-describedby=\"caption-attachment-17447\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17447\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E3815D400000578-390_634x948.jpg\" alt=\"Copa Mundial de la FIFA 2014 - Luis Su\u00e1rez - Uruguay - F\u00fatbol - Cartel - Soccor\" width=\"634\" height=\"948\" \/><figcaption id=\"caption-attachment-17447\" class=\"wp-caption-text\">Luis Su\u00e1rez patea un bal\u00f3n de oro para la victoria de Uruguay en 'La Celeste<\/figcaption><\/figure>\n<figure id=\"attachment_17448\" aria-describedby=\"caption-attachment-17448\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17448\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E3815D000000578-441_634x948.jpg\" alt=\"Copa Mundial de la FIFA-2014-USA-Yanks-Football-Soccor-Clint-Dempsey-Micheal-Bradley-Tim-Howard\" width=\"634\" height=\"948\" \/><figcaption id=\"caption-attachment-17448\" class=\"wp-caption-text\">Clint Dempsey, Micheal Bradley y Tim Howard en el p\u00f3ster de \"The Yanks\" para Estados Unidos<\/figcaption><\/figure>\n<figure id=\"attachment_17449\" aria-describedby=\"caption-attachment-17449\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17449\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E3815C800000578-142_634x948.jpg\" alt=\"Copa Mundial de la FIFA 2014-Suiza-centrocampista-Napoli-Gokhan-Inler-Poster\" width=\"634\" height=\"948\" \/><figcaption id=\"caption-attachment-17449\" class=\"wp-caption-text\">El centrocampista del N\u00e1poles juega con Suiza en \"La Mati<\/figcaption><\/figure>\n<figure id=\"attachment_17450\" aria-describedby=\"caption-attachment-17450\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17450\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E3815BF00000578-726_634x950.jpg\" alt=\"FIFA-2014-Copa del Mundo-Espa\u00f1a-Iker-Casillas-Xavi-Andr\u00e9s-Iniesta-Trofeo-Espa\u00f1a-Poster\" width=\"634\" height=\"950\" \/><figcaption id=\"caption-attachment-17450\" class=\"wp-caption-text\">Iker Casillas, Xavi y Andr\u00e9s Iniesta levantan el trofeo de la Copa del Mundo en el p\u00f3ster espa\u00f1ol \"La Furiaroja<\/figcaption><\/figure>\n<figure id=\"attachment_17451\" aria-describedby=\"caption-attachment-17451\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17451\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E3815C300000578-128_634x948.jpg\" alt=\"Copa Mundial de la FIFA-2014-Lee-Chung-Young-Bolton-Wanderers-Mediocampista-Corea del Sur-F\u00fatbol-Soccor-Poster\" width=\"634\" height=\"948\" \/><figcaption id=\"caption-attachment-17451\" class=\"wp-caption-text\">Corea del Sur presenta a Lee Chung-Young, centrocampista del Bolton Wanderers, en el cartel de \"Taeguk Warriors<\/figcaption><\/figure>\n<figure id=\"attachment_17452\" aria-describedby=\"caption-attachment-17452\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17452\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E3815B600000578-560_634x890.jpg\" alt=\"FIFA-World-Cup-Poster-Igor-Akinfeev-Russian-Goalkeeper-CSKA-Moscow-Poster-Football-Soccor\" width=\"634\" height=\"890\" \/><figcaption id=\"caption-attachment-17452\" class=\"wp-caption-text\">El guardameta del CSKA de Mosc\u00fa despliega sus alas por Rusia<\/figcaption><\/figure>\n<figure id=\"attachment_17453\" aria-describedby=\"caption-attachment-17453\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17453\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E3815B100000578-948_634x950.jpg\" alt=\"FIFA-Copa del Mundo-2014-Cristiano-Ronaldo-Portugal-Football-Soccor-Poster\" width=\"634\" height=\"950\" \/><figcaption id=\"caption-attachment-17453\" class=\"wp-caption-text\">Cristiano Ronaldo se se\u00f1ala el pecho con orgullo en la \"Sele\u00e7\u00e3o das Quinas\" de Portugal<\/figcaption><\/figure>\n<figure id=\"attachment_17454\" aria-describedby=\"caption-attachment-17454\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17454\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E3815A300000578-380_634x948.jpg\" alt=\"FIFA-Copa del Mundo-2014-Nigeria-Football-Soccor-Team-Vincent-Enyeama-Obi-Mikel-Joel-Obi-Poster\" width=\"634\" height=\"948\" \/><figcaption id=\"caption-attachment-17454\" class=\"wp-caption-text\">Vincent Enyeama, Obi Mikel y Joel Obi representan a Nigeria en \"Las S\u00faper \u00c1guilas<\/figcaption><\/figure>\n<figure id=\"attachment_17455\" aria-describedby=\"caption-attachment-17455\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17455\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E3815AC00000578-88_634x948.jpg\" alt=\"Copa Mundial de la FIFA-2014-Holanda-Pa\u00edses Bajos-F\u00fatbol-Robin-van-Persie-Arjen-Robben-Wesley-Sneijder-Poster\" width=\"634\" height=\"948\" \/><figcaption id=\"caption-attachment-17455\" class=\"wp-caption-text\">Holanda brilla en el p\u00f3ster \"Oranje\" con Robin van Persie, Wesley Sneijder y Arjen Robben<\/figcaption><\/figure>\n<figure id=\"attachment_17456\" aria-describedby=\"caption-attachment-17456\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17456\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E38159E00000578-978_634x948.jpg\" alt=\"FIFA-Copa del Mundo-2014-Javier-Hern\u00e1ndez-M\u00e9xico-Manchester-United-F\u00fatbol-F\u00fatbol-Brasil-P\u00f3ster\" width=\"634\" height=\"948\" \/><figcaption id=\"caption-attachment-17456\" class=\"wp-caption-text\">Javier Hern\u00e1ndez, del Manchester United, destaca en el cartel de \"El Tri\" de M\u00e9xico<\/figcaption><\/figure>\n<figure id=\"attachment_17457\" aria-describedby=\"caption-attachment-17457\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17457\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E38158A00000578-417_634x948.jpg\" alt=\"Copa Mundial de la FIFA 2014-Jap\u00f3n-AC-Milan-Keisuke-Honda-Manchester-United-Shinji-Kagawa-Poster\" width=\"634\" height=\"948\" \/><figcaption id=\"caption-attachment-17457\" class=\"wp-caption-text\">Jap\u00f3n est\u00e1 representado con Shinji Kagawa, jugador del Manchester United, y Keisuke Honda, del AC Milan, en el cartel de \"Samurai Blue\".<\/figcaption><\/figure>\n<figure id=\"attachment_17458\" aria-describedby=\"caption-attachment-17458\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17458\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E38159500000578-335_634x950.jpg\" alt=\"FIFA-Copa del Mundo-2014-Didier-Drogba-Yaya-Toure-Ivory-Coast-Football-Soccer-Poster\" width=\"634\" height=\"950\" \/><figcaption id=\"caption-attachment-17458\" class=\"wp-caption-text\">Didier Drogba y Yaya Tour\u00e9 se dan la mano para defender a Costa de Marfil en \"Los Elefantes\".<\/figcaption><\/figure>\n<figure id=\"attachment_17459\" aria-describedby=\"caption-attachment-17459\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17459\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E38158300000578-814_634x949.jpg\" alt=\"FIFA-Copa del Mundo-2014-Italia-Mario-Balotelli-Football-Soccer-Poster\" width=\"634\" height=\"949\" \/><figcaption id=\"caption-attachment-17459\" class=\"wp-caption-text\">Mario Balotelli tensa los m\u00fasculos por Italia en el p\u00f3ster de la \"Azzurra<\/figcaption><\/figure>\n<figure id=\"attachment_17460\" aria-describedby=\"caption-attachment-17460\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17460\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E38157A00000578-194_634x948.jpg\" alt=\"Copa Mundial de la FIFA-2014-Jalai-Hosseini-Charlton-delantero-Reza-Ghoochannejhad-capit\u00e1n-Javad-Nekounam-Ir\u00e1n-f\u00fatbol-f\u00fatbol-p\u00f3ster\" width=\"634\" height=\"948\" \/><figcaption id=\"caption-attachment-17460\" class=\"wp-caption-text\">Jalai Hosseini, Reza Ghoochannejhad y Javad Nekounam se dan la mano por Ir\u00e1n<\/figcaption><\/figure>\n<figure id=\"attachment_17461\" aria-describedby=\"caption-attachment-17461\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17461\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E38157600000578-807_634x950.jpg\" alt=\"Copa Mundial de la FIFA 2014-Honduras-Wilson-Palacois-Stoke-Midfielder-New-England-Revolution-Poster\" width=\"634\" height=\"950\" \/><figcaption id=\"caption-attachment-17461\" class=\"wp-caption-text\">Honduras ve c\u00f3mo el centrocampista del Stoke Wilson Palacios y el delantero del New England Revolution aplauden al p\u00fablico en 'Los Catrachos<\/figcaption><\/figure>\n<figure id=\"attachment_17462\" aria-describedby=\"caption-attachment-17462\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17462\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E38156D00000578-977_634x950.jpg\" alt=\"FIFA-Copa del Mundo-Giorgos-Karagounis-Grecia-Football-Soccer-Poster\" width=\"634\" height=\"950\" \/><figcaption id=\"caption-attachment-17462\" class=\"wp-caption-text\">Giorgos Karagounis corre por Grecia en el cartel de \"\u03a3\u03c4\u03b7\u03bd\u03b9\u03ba\u03b9<\/figcaption><\/figure>\n<figure id=\"attachment_17463\" aria-describedby=\"caption-attachment-17463\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17463\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E38157100000578-241_634x948.jpg\" alt=\"Copa Mundial de la FIFA 2014-Ghana-Micheal-Essien-Asamoah-Gyan-Kevin-Prince-Boateng-Poster\" width=\"634\" height=\"948\" \/><figcaption id=\"caption-attachment-17463\" class=\"wp-caption-text\">The Black Stars\" presenta a Micheal Essien, Asamoah Gyan y Kevin-Prince Boateng bailando por Ghana<\/figcaption><\/figure>\n<figure id=\"attachment_17464\" aria-describedby=\"caption-attachment-17464\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17464\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E38156400000578-900_634x948.jpg\" alt=\"Copa Mundial de la FIFA 2014-Alemania-Mesut-Ozil-Phillipp-Lahm-Bastian-Schweinsteiger-Poster\" width=\"634\" height=\"948\" \/><figcaption id=\"caption-attachment-17464\" class=\"wp-caption-text\">La \"Die Mannschaft\" alemana cuenta con Mesut Ozil, Phillipp Lahm y Bastian Schweinsteiger<\/figcaption><\/figure>\n<figure id=\"attachment_17465\" aria-describedby=\"caption-attachment-17465\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17465\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E38156900000578-86_634x950.jpg\" alt=\"FIFA-Copa del Mundo-2014-Francia-Franck-Ribery-Karim-Benzema-Poster\" width=\"634\" height=\"950\" \/><figcaption id=\"caption-attachment-17465\" class=\"wp-caption-text\">Franck Rib\u00e9ry y Karim Benzema, los Bleus de Francia<\/figcaption><\/figure>\n<figure id=\"attachment_17467\" aria-describedby=\"caption-attachment-17467\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17467\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E38161D00000578-102_634x948.jpg\" alt=\"Copa Mundial de la FIFA 2014-Ecuador-Antonio-Valencia-Delantero del Manchester United\" width=\"634\" height=\"948\" \/><figcaption id=\"caption-attachment-17467\" class=\"wp-caption-text\">Ecuador presenta a Antonio Valencia, extremo del Manchester United, en la Tricolor<\/figcaption><\/figure>\n<figure id=\"attachment_17469\" aria-describedby=\"caption-attachment-17469\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17469\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E38161100000578-380_634x948.jpg\" alt=\"FIFA-Copa del Mundo-2014-Croacia-Real-Madrid-Luka-Modric-Bayern-Munich-Mario-Mandzukic-Poster\" width=\"634\" height=\"948\" \/><figcaption id=\"caption-attachment-17469\" class=\"wp-caption-text\">Luka Modric y Mario Mandzukic celebran a lo grande con Croacia<\/figcaption><\/figure>\n<figure id=\"attachment_17470\" aria-describedby=\"caption-attachment-17470\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17470\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E38161800000578-972_634x948.jpg\" alt=\"FIFA-Copa del Mundo-2014-Croacia-Joel-Campbell-Arsenal-jugador-f\u00fatbol-f\u00fatbol-p\u00f3ster\" width=\"634\" height=\"948\" \/><figcaption id=\"caption-attachment-17470\" class=\"wp-caption-text\">Joel Campbell, jugador del Arsenal y representante de Costa Rica en \"Los Ticos<\/figcaption><\/figure>\n<figure id=\"attachment_17471\" aria-describedby=\"caption-attachment-17471\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17471\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E38160A00000578-419_634x948.jpg\" alt=\"FIFA-Copa del Mundo-2014-Croacia-y-M\u00f3naco-jugador-James-Rodr\u00edguez-p\u00f3ster\" width=\"634\" height=\"948\" \/><figcaption id=\"caption-attachment-17471\" class=\"wp-caption-text\">El colombiano James Rodr\u00edguez grita de rodillas en el cartel de 'Los Cafeteros<\/figcaption><\/figure>\n<figure id=\"attachment_17472\" aria-describedby=\"caption-attachment-17472\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17472\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E38160300000578-468_634x948.jpg\" alt=\"FIFA-Copa del Mundo-2014-Chile-y-Barcelona-futbolista-Alexis-S\u00e1nchez-corre-con-el-bal\u00f3n-p\u00f3ster\" width=\"634\" height=\"948\" \/><figcaption id=\"caption-attachment-17472\" class=\"wp-caption-text\">La estrella del Barcelona y representante de Chile es Alexis S\u00e1nchez corriendo r\u00e1pido con el bal\u00f3n<\/figcaption><\/figure>\n<figure id=\"attachment_17473\" aria-describedby=\"caption-attachment-17473\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17473\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E3815F600000578-93_634x948.jpg\" alt=\"Copa Mundial de la FIFA 2014: Camer\u00fan y Chelsea: el delantero Samuel Eto baila alrededor de una bandera de f\u00fatbol.\" width=\"634\" height=\"948\" \/><figcaption id=\"caption-attachment-17473\" class=\"wp-caption-text\">Samuel Eto, delantero del Chelsea y jugador de Camer\u00fan, baila alrededor de una bandera en el cartel de \"Los Leones Indomables<\/figcaption><\/figure>\n<figure id=\"attachment_17474\" aria-describedby=\"caption-attachment-17474\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17474\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E3815FE00000578-66_634x948.jpg\" alt=\"FIFA-Copa del Mundo-2014-Brasil-Neymar-f\u00fatbol-soccer-poster\" width=\"634\" height=\"948\" \/><figcaption id=\"caption-attachment-17474\" class=\"wp-caption-text\">Brasil se representa con Neymar se\u00f1alando a las estrellas en el p\u00f3ster de la \"Sele\u00e7\u00e3o<\/figcaption><\/figure>\n<figure id=\"attachment_17475\" aria-describedby=\"caption-attachment-17475\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17475\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E3815F200000578-971_634x948.jpg\" alt=\"Copa Mundial de la FIFA-2014: Edin-Dzeko, delantero del Manchester City, para Bosnia y Herzegovina.\" width=\"634\" height=\"948\" \/><figcaption id=\"caption-attachment-17475\" class=\"wp-caption-text\">El cartel de Bosnia y Herzegovina muestra al delantero del Manchester City Edin Dzeko sosteniendo su bandera<\/figcaption><\/figure>\n<figure id=\"attachment_17476\" aria-describedby=\"caption-attachment-17476\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17476\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E3815EC00000578-817_634x950.jpg\" alt=\"FIFA-Copa del Mundo-2014-B\u00e9lgica-Eden-Hazard-Chelsea-jugador-f\u00fatbol-f\u00fatbol-p\u00f3ster\" width=\"634\" height=\"950\" \/><figcaption id=\"caption-attachment-17476\" class=\"wp-caption-text\">Eden Hazard, estrella del Chelsea y jugador de B\u00e9lgica, nos mira fijamente en el p\u00f3ster de \"Los Diablos Rojos<\/figcaption><\/figure>\n<figure id=\"attachment_17477\" aria-describedby=\"caption-attachment-17477\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17477\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E3815E100000578-99_634x948.jpg\" alt=\"FIFA-Copa del Mundo-2014-Australia-Tim-Cahill-ex-jugador-del-Everton-y-Millwall-f\u00fatbol-f\u00fatbol-p\u00f3ster\" width=\"634\" height=\"948\" \/><figcaption id=\"caption-attachment-17477\" class=\"wp-caption-text\">El p\u00f3ster de 'The Socceroos' para Australia te da un pu\u00f1etazo en la cara de Tim Cahill, ex jugador del Everton y del Millwall<\/figcaption><\/figure>\n<figure id=\"attachment_17478\" aria-describedby=\"caption-attachment-17478\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17478\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E3815DB00000578-150_634x954.jpg\" alt=\"FIFA-Copa del Mundo-2014-Lionel-Messi-Argentina-f\u00fatbol-f\u00fatbol-p\u00f3ster\" width=\"634\" height=\"954\" \/><figcaption id=\"caption-attachment-17478\" class=\"wp-caption-text\">El cartel de \"La Albiceleste\" presenta a Lionel Messi con Argentina<\/figcaption><\/figure>\n<figure id=\"attachment_17479\" aria-describedby=\"caption-attachment-17479\" style=\"width: 634px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17479\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E3815E500000578-556_634x948.jpg\" alt=\"Copa Mundial de la FIFA 2014-Argelia-Valencia-El extremo Sofiane-Feghouli-abre el p\u00f3ster\" width=\"634\" height=\"948\" \/><figcaption id=\"caption-attachment-17479\" class=\"wp-caption-text\">Los carteles de Argelia muestran a un Sofiane Feghouli bramando<\/figcaption><\/figure>\n<h2>Sobre Cristiano Siqueira<\/h2>\n<ul>\n<li>Dise\u00f1ado para Gillette, Master Card, NIKE, Wall Street Journal Playboy, XXL, Inked y Ethos, por nombrar algunos.<\/li>\n<li>Destacado en las revistas Digital Arts, Adobe Master Class Illustrator, Advanced Photoshop y Portraits<\/li>\n<li>Ganador del premio \"Print:Public Services\" en los Clio Awards 2011<\/li>\n<li>Trabaja principalmente en vector<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/es\/carteles\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-65312\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2013\/03\/poster-strip.jpg\" alt=\"Impresi\u00f3n de carteles\" width=\"696\" height=\"195\" \/><\/a><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":13,"featured_media":17446,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[544],"tags":[805],"class_list":{"0":"post-17445","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-print-inspiration","8":"tag-posters"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>32 World Cup Posters By Brazilian Artist Cristiano Siqueira | Solopress<\/title>\n<meta name=\"description\" content=\"ESPN commissioned Brazilian artist and graphic designer Cristiano Siqueira to create these amazing 2014 FIFA World Cup posters.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solopress.com\/blog\/es\/inspiracion-para-imprimir\/32-copas-del-mundo-carteles-artista-brasileno-cristiano-siqueira\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"32 World Cup Posters By Brazilian Artist Cristiano Siqueira | Solopress\" \/>\n<meta property=\"og:description\" content=\"ESPN commissioned Brazilian artist and graphic designer Cristiano Siqueira to create these amazing 2014 FIFA World Cup posters.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solopress.com\/blog\/es\/inspiracion-para-imprimir\/32-copas-del-mundo-carteles-artista-brasileno-cristiano-siqueira\/\" \/>\n<meta property=\"og:site_name\" content=\"The Latest Print and Design News | Solopress\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Solopress\" \/>\n<meta property=\"article:published_time\" content=\"2014-06-03T10:45:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-27T12:33:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E38155F00000578-523_634x948.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"634\" \/>\n\t<meta property=\"og:image:height\" content=\"948\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Aron Priest\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@solopress\" \/>\n<meta name=\"twitter:site\" content=\"@solopress\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aron Priest\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/print-inspiration\\\/32-world-cup-posters-brazilian-artist-cristiano-siqueira\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/print-inspiration\\\/32-world-cup-posters-brazilian-artist-cristiano-siqueira\\\/\"},\"author\":{\"name\":\"Aron Priest\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/48b967ba047cb36781b5820a5bc366a2\"},\"headline\":\"32 World Cup Posters By Brazilian Artist Cristiano Siqueira\",\"datePublished\":\"2014-06-03T10:45:19+00:00\",\"dateModified\":\"2020-02-27T12:33:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/print-inspiration\\\/32-world-cup-posters-brazilian-artist-cristiano-siqueira\\\/\"},\"wordCount\":747,\"commentCount\":5,\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/print-inspiration\\\/32-world-cup-posters-brazilian-artist-cristiano-siqueira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/article-2639538-1E38155F00000578-523_634x948.jpg\",\"keywords\":[\"Posters\"],\"articleSection\":[\"Print Inspiration\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/print-inspiration\\\/32-world-cup-posters-brazilian-artist-cristiano-siqueira\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/print-inspiration\\\/32-world-cup-posters-brazilian-artist-cristiano-siqueira\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/print-inspiration\\\/32-world-cup-posters-brazilian-artist-cristiano-siqueira\\\/\",\"name\":\"32 World Cup Posters By Brazilian Artist Cristiano Siqueira | Solopress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/print-inspiration\\\/32-world-cup-posters-brazilian-artist-cristiano-siqueira\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/print-inspiration\\\/32-world-cup-posters-brazilian-artist-cristiano-siqueira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/article-2639538-1E38155F00000578-523_634x948.jpg\",\"datePublished\":\"2014-06-03T10:45:19+00:00\",\"dateModified\":\"2020-02-27T12:33:51+00:00\",\"description\":\"ESPN commissioned Brazilian artist and graphic designer Cristiano Siqueira to create these amazing 2014 FIFA World Cup posters.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/print-inspiration\\\/32-world-cup-posters-brazilian-artist-cristiano-siqueira\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/print-inspiration\\\/32-world-cup-posters-brazilian-artist-cristiano-siqueira\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/print-inspiration\\\/32-world-cup-posters-brazilian-artist-cristiano-siqueira\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/article-2639538-1E38155F00000578-523_634x948.jpg\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/article-2639538-1E38155F00000578-523_634x948.jpg\",\"width\":634,\"height\":948,\"caption\":\"Wayne Rooney roars on Siqueira's 'The Three Lions' World Cup poster\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/print-inspiration\\\/32-world-cup-posters-brazilian-artist-cristiano-siqueira\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"32 World Cup Posters By Brazilian Artist Cristiano Siqueira\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"name\":\"The Latest Print and Design News | Solopress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\",\"name\":\"Solopress\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"width\":428,\"height\":88,\"caption\":\"Solopress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Solopress\",\"https:\\\/\\\/x.com\\\/solopress\",\"https:\\\/\\\/instagram.com\\\/solopress\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/solopress\",\"https:\\\/\\\/uk.pinterest.com\\\/solopress\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/solopress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/48b967ba047cb36781b5820a5bc366a2\",\"name\":\"Aron Priest\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/380b785e9e4ce1b2368342be7627087cb9a650c2580eead22bbb5722b18ec622?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/380b785e9e4ce1b2368342be7627087cb9a650c2580eead22bbb5722b18ec622?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/380b785e9e4ce1b2368342be7627087cb9a650c2580eead22bbb5722b18ec622?s=96&r=g\",\"caption\":\"Aron Priest\"},\"description\":\"I have been in the print trade since 1988 and started my first printing company in 1999. Solopress went from just a few employees in the first year up to over 150 staff at present. I am fully trained in every department of my company and love coming to work.\",\"sameAs\":[\"https:\\\/\\\/www.solopress.com\"],\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/es\\\/author\\\/aron-priest\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"32 carteles de la Copa del Mundo del artista brasile\u00f1o Cristiano Siqueira | Solopress","description":"ESPN encarg\u00f3 al artista y dise\u00f1ador gr\u00e1fico brasile\u00f1o Cristiano Siqueira la creaci\u00f3n de estos incre\u00edbles carteles de la Copa Mundial de la FIFA 2014.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solopress.com\/blog\/es\/inspiracion-para-imprimir\/32-copas-del-mundo-carteles-artista-brasileno-cristiano-siqueira\/","og_locale":"es_ES","og_type":"article","og_title":"32 World Cup Posters By Brazilian Artist Cristiano Siqueira | Solopress","og_description":"ESPN commissioned Brazilian artist and graphic designer Cristiano Siqueira to create these amazing 2014 FIFA World Cup posters.","og_url":"https:\/\/www.solopress.com\/blog\/es\/inspiracion-para-imprimir\/32-copas-del-mundo-carteles-artista-brasileno-cristiano-siqueira\/","og_site_name":"The Latest Print and Design News | Solopress","article_publisher":"https:\/\/www.facebook.com\/Solopress","article_published_time":"2014-06-03T10:45:19+00:00","article_modified_time":"2020-02-27T12:33:51+00:00","og_image":[{"width":634,"height":948,"url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E38155F00000578-523_634x948.jpg","type":"image\/jpeg"}],"author":"Aron Priest","twitter_card":"summary_large_image","twitter_creator":"@solopress","twitter_site":"@solopress","twitter_misc":{"Escrito por":"Aron Priest","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.solopress.com\/blog\/print-inspiration\/32-world-cup-posters-brazilian-artist-cristiano-siqueira\/#article","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/print-inspiration\/32-world-cup-posters-brazilian-artist-cristiano-siqueira\/"},"author":{"name":"Aron Priest","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/48b967ba047cb36781b5820a5bc366a2"},"headline":"32 World Cup Posters By Brazilian Artist Cristiano Siqueira","datePublished":"2014-06-03T10:45:19+00:00","dateModified":"2020-02-27T12:33:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/print-inspiration\/32-world-cup-posters-brazilian-artist-cristiano-siqueira\/"},"wordCount":747,"commentCount":5,"publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/print-inspiration\/32-world-cup-posters-brazilian-artist-cristiano-siqueira\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E38155F00000578-523_634x948.jpg","keywords":["Posters"],"articleSection":["Print Inspiration"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.solopress.com\/blog\/print-inspiration\/32-world-cup-posters-brazilian-artist-cristiano-siqueira\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.solopress.com\/blog\/print-inspiration\/32-world-cup-posters-brazilian-artist-cristiano-siqueira\/","url":"https:\/\/www.solopress.com\/blog\/print-inspiration\/32-world-cup-posters-brazilian-artist-cristiano-siqueira\/","name":"32 carteles de la Copa del Mundo del artista brasile\u00f1o Cristiano Siqueira | Solopress","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/print-inspiration\/32-world-cup-posters-brazilian-artist-cristiano-siqueira\/#primaryimage"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/print-inspiration\/32-world-cup-posters-brazilian-artist-cristiano-siqueira\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E38155F00000578-523_634x948.jpg","datePublished":"2014-06-03T10:45:19+00:00","dateModified":"2020-02-27T12:33:51+00:00","description":"ESPN encarg\u00f3 al artista y dise\u00f1ador gr\u00e1fico brasile\u00f1o Cristiano Siqueira la creaci\u00f3n de estos incre\u00edbles carteles de la Copa Mundial de la FIFA 2014.","breadcrumb":{"@id":"https:\/\/www.solopress.com\/blog\/print-inspiration\/32-world-cup-posters-brazilian-artist-cristiano-siqueira\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solopress.com\/blog\/print-inspiration\/32-world-cup-posters-brazilian-artist-cristiano-siqueira\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.solopress.com\/blog\/print-inspiration\/32-world-cup-posters-brazilian-artist-cristiano-siqueira\/#primaryimage","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E38155F00000578-523_634x948.jpg","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E38155F00000578-523_634x948.jpg","width":634,"height":948,"caption":"Wayne Rooney roars on Siqueira's 'The Three Lions' World Cup poster"},{"@type":"BreadcrumbList","@id":"https:\/\/www.solopress.com\/blog\/print-inspiration\/32-world-cup-posters-brazilian-artist-cristiano-siqueira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.solopress.com\/blog\/"},{"@type":"ListItem","position":2,"name":"32 World Cup Posters By Brazilian Artist Cristiano Siqueira"}]},{"@type":"WebSite","@id":"https:\/\/www.solopress.com\/blog\/#website","url":"https:\/\/www.solopress.com\/blog\/","name":"\u00daltimas noticias sobre impresi\u00f3n y dise\u00f1o | Solopress","description":"","publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solopress.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.solopress.com\/blog\/#organization","name":"Solopress","url":"https:\/\/www.solopress.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","width":428,"height":88,"caption":"Solopress"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Solopress","https:\/\/x.com\/solopress","https:\/\/instagram.com\/solopress\/","https:\/\/www.linkedin.com\/company\/solopress","https:\/\/uk.pinterest.com\/solopress\/","https:\/\/www.youtube.com\/user\/solopress"]},{"@type":"Person","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/48b967ba047cb36781b5820a5bc366a2","name":"Aron Priest","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/380b785e9e4ce1b2368342be7627087cb9a650c2580eead22bbb5722b18ec622?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/380b785e9e4ce1b2368342be7627087cb9a650c2580eead22bbb5722b18ec622?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/380b785e9e4ce1b2368342be7627087cb9a650c2580eead22bbb5722b18ec622?s=96&r=g","caption":"Aron Priest"},"description":"Llevo en el sector de la impresi\u00f3n desde 1988 y fund\u00e9 mi primera imprenta en 1999. Solopress pas\u00f3 de tener unos pocos empleados el primer a\u00f1o a tener m\u00e1s de 150 en la actualidad. He recibido formaci\u00f3n completa en todos los departamentos de mi empresa y me encanta venir a trabajar.","sameAs":["https:\/\/www.solopress.com"],"url":"https:\/\/www.solopress.com\/blog\/es\/author\/aron-priest\/"}]}},"jetpack_featured_media_url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/article-2639538-1E38155F00000578-523_634x948.jpg","_links":{"self":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts\/17445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/comments?post=17445"}],"version-history":[{"count":5,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts\/17445\/revisions"}],"predecessor-version":[{"id":67127,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts\/17445\/revisions\/67127"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/media\/17446"}],"wp:attachment":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/media?parent=17445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/categories?post=17445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/tags?post=17445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}