{"id":22494,"date":"2014-08-07T12:37:22","date_gmt":"2014-08-07T11:37:22","guid":{"rendered":"https:\/\/www.solopress.com\/blog\/?p=22494"},"modified":"2022-06-17T22:26:25","modified_gmt":"2022-06-17T21:26:25","slug":"luz-y-sombra-blanco-y-negro","status":"publish","type":"post","link":"https:\/\/www.solopress.com\/blog\/es\/photography\/light-and-shadow-black-and-white\/","title":{"rendered":"Fotograf\u00eda en blanco y negro con luces y sombras de Rupert Vandervell"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p><!--more--><\/p>\n<h3><em><strong>Fot\u00f3grafo<\/strong> <a title=\"Rupert Vandervell | Inicio\" href=\"http:\/\/www.rupertvandervell.co.uk\/\" target=\"_blank\" rel=\"noopener\">Rupert Vandervell<\/a> tom\u00f3 estas <strong>llamativo<\/strong><strong>\u00a0fotos en blanco y negro<\/strong>\u00a0jugando con<strong> luces y sombras<\/strong> en su serie titulada '<strong>Geometrix<\/strong>\u2018.<\/em><\/h3>\n<p>Rupert Vandervell naci\u00f3 y creci\u00f3 en Londres. <strong>fot\u00f3grafo<\/strong> especializada en <strong>bellas artes<\/strong> y <strong>fotograf\u00eda digital<\/strong>. La mayor\u00eda de sus <strong>cartera<\/strong> se centra en <em>l\u00edneas n\u00edtidas<\/em> y <em>llamativos contrastes crom\u00e1ticos<\/em>.<\/p>\n<p>Vandervell describe su serie como,<\/p>\n<blockquote><p><em>\"Una combinaci\u00f3n de luz, sombra y forma humana que se une en armon\u00eda est\u00e9tica, creando una relaci\u00f3n geom\u00e9trica especial. Estos cuadros tratan de l\u00edneas limpias, \u00e1ngulos, formas, texturas y su colaboraci\u00f3n abstracta. La luz brilla sobre el paisaje urbano, tejiendo su telara\u00f1a\".<\/em><\/p><\/blockquote>\n<p>Vandervell sigue describiendo su estilo fotogr\u00e1fico como <em>\"altamente representativo\"<\/em> de su personalidad. Describe su pasi\u00f3n por las l\u00edneas n\u00edtidas y la fotograf\u00eda en blanco y negro como una obsesi\u00f3n. Dice,<\/p>\n<blockquote><p><em>\"A trav\u00e9s del objetivo encuentro cautivadoras a las personas y mi trabajo explora nuestra relaci\u00f3n con el mundo y c\u00f3mo interactuamos con nuestro entorno\".<\/em><\/p><\/blockquote>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-22500\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/08\/7171bfaaf343302ab40e489bd10cee95.jpg\" alt=\"Fotograf\u00eda en blanco y negro de luces y sombras que muestra a una mujer sentada en un banco largo de forma rectangular, de espaldas a nosotros. Lleva una camiseta y un pantal\u00f3n blancos y mira hacia un edificio oscuro de bloques. El suelo es de madera.\" width=\"600\" height=\"450\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-22502\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/08\/a8f1c70d401801b618038e4e7b2b39f1.jpg\" alt=\"Fotograf\u00eda en blanco y negro que utiliza sombras claras y oscuras y muestra a un hombre en la distancia vestido con camisa blanca y pantalones negros. El \u00e1ngulo se sit\u00faa sobre unos bloques de hormig\u00f3n con llamativas l\u00edneas creadas por la sombra\" width=\"600\" height=\"456\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-22504\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/08\/3c28c51626131409c9c2aa904842ded3.jpg\" alt=\"Fotograf\u00eda clara y oscura que muestra un \u00e1ngulo agudo de un edificio cuadrado de madera y un hombre con camisa blanca y pantalones negros que pasea por el suelo con un libro en la cara.\" width=\"600\" height=\"800\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-22506\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/08\/fc6610331a732a7b08294450ed73422f.jpg\" alt=\"Fotograf\u00eda en blanco y negro con efecto de luces y sombras - muestra a una mujer caminando por un sendero inclinado de ladrillo iluminado por los rayos del sol y rodeada de fuertes muros de hormig\u00f3n negro que se entrecruzan por encima de ella.\" width=\"600\" height=\"450\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-22508\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/08\/6e229b273390047c59ff3dccd814ea1c.jpg\" alt=\"Fotograf\u00eda en blanco y negro, con efecto de luces y sombras, de un edificio blanco brillante con ventanas ennegrecidas y la silueta negra de un hombre que pasa caminando.\" width=\"600\" height=\"802\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-22511\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/08\/71861e5bcd7ca280a8a4b03d8c75064e.jpg\" alt=\"Fotograf\u00eda en blanco y negro, de luces y sombras, tomada en un \u00e1ngulo llamativo que muestra el cielo iluminado todo de blanco, un hombre delgado que camina ligeramente m\u00e1s alto que el fot\u00f3grafo en el fondo y una gran losa de hormig\u00f3n encima que podr\u00eda ser un puente de carretera.\" width=\"600\" height=\"450\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-22513\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/08\/61ee7670f514a493ef01fda7efd2ee21.jpg\" alt=\"Fotograf\u00eda de paisaje en blanco y negro de una mujer al otro lado de la calle vestida con un odio blanco, blusa negra y pantalones blancos mirando a la c\u00e1mara. Ella est\u00e1 de pie delante de un edificio de hormig\u00f3n blanco y negro\" width=\"600\" height=\"450\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-22515\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/08\/b87447c03a28cd7a47a5c1986c9d60db.jpg\" alt=\"Fotograf\u00eda en blanco y negro tomada desde arriba y mirando al sujeto. El sujeto viste un traje negro y lleva una maleta o bolsa de trabajo negra. Camina por un sendero plateado junto a una carretera en la que se reflejan las ventanas del edificio de al lado.\" width=\"600\" height=\"450\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-22517\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/08\/light-shadow-photograph.jpg\" alt=\"Fotograf\u00eda de luces y sombras con \u00e1ngulos abstractos. Muestra a un hombre caminando aparentemente lejos de la c\u00e1mara por un camino luminoso en el exterior y tomada desde un lugar interior ligeramente confuso con m\u00faltiples capas\" width=\"600\" height=\"800\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-22519\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/08\/d0876c592e1b4ed8d4f016b1ed0d43c3.jpg\" alt=\"Fotograf\u00eda con efecto de luces y sombras que muestra el cuerpo de un hombre (menos la cabeza) caminando por debajo de la c\u00e1mara por una escalera de caracol.\" width=\"600\" height=\"450\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-22521\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/08\/light-and-shadow-photograph-2.jpg\" alt=\"Fotograf\u00eda en blanco y negro de un hombre que camina por un sendero muy iluminado de espaldas a la c\u00e1mara, vestido con un abrigo largo y pantalones negros. El \u00e1ngulo est\u00e1 tomado justo antes de que se junten dos esquinas de un edificio de cristal.\" width=\"600\" height=\"776\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-22523\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/08\/f39c2f95782a15f7d1fc92d52277659a.jpg\" alt=\"Foto en blanco y negro tomada con una llamativa sombra negra a trav\u00e9s de un sendero de 4 niveles - s\u00f3lo se ven las piernas de una persona caminando hacia la parte superior izquierda del encuadre.\" width=\"600\" height=\"450\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-22525\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/08\/d8477ddc283dc2e5c7b099c28ea80bfe.jpg\" alt=\"Fotograf\u00eda tomada con un bloque de hormig\u00f3n texturizado mirando hacia abajo sobre sondeos de hormig\u00f3n\" width=\"600\" height=\"450\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-22527\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/08\/9f841ab2f4fc4056455e62f56c5afa3b.jpg\" alt=\"Llamativa fotograf\u00eda en blanco y negro de una mujer caminando por un extenso camino de losas de hormig\u00f3n con botas de tac\u00f3n.\" width=\"600\" height=\"450\" \/><\/p>\n<h2>C\u00f3mo hacer tus propias fotos de luces y sombras<\/h2>\n<ul>\n<li>C\u00e9ntrate en la luz dura y directa para crear un efecto de sombra profunda con bordes n\u00edtidos. La regla b\u00e1sica de utilizar diferentes tipos de luz en las fotos (es decir, luz suave, luz dura, luz amplia y luz puntual) es casi id\u00e9ntica a la hora de crear efectos de sombra.<\/li>\n<li>Utiliza la profundidad de campo: los efectos de sombra pueden resultar realmente impactantes cuando se toman desde distintas distancias. Encuentra una profundidad que realmente alargue el efecto de sombra.<\/li>\n<li>Mueve el objeto que est\u00e1 creando la sombra, recuerda que no es un objeto inm\u00f3vil. Si el \u00e1ngulo de la sombra no es el correcto, mu\u00e9velo hasta que est\u00e9s satisfecho.<\/li>\n<li>Aprovecha las luces y las sombras para resaltar la forma del paisaje en tus im\u00e1genes.<\/li>\n<\/ul>\n<h2>Imprima sus fotograf\u00edas en un calendario<\/h2>\n<p>\u00bfTe sientes inspirado? Sal y prueba tambi\u00e9n a jugar con los \u00e1ngulos. Te sorprender\u00e1 la cantidad de lugares que esperan a ser fotografiados justo delante de tu puerta. Cuando tengas una buena colecci\u00f3n de estas im\u00e1genes, \u00bfpor qu\u00e9 no <a title=\"Imprimir un calendario | Solopress\" href=\"https:\/\/www.solopress.com\/blog\/es\/calendars\/\">imprimirlos en un calendario<\/a> como regalo para un ser querido?\u00a0<!--\/codes_iframe--><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":13,"featured_media":22500,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[546],"tags":[],"class_list":{"0":"post-22494","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-photography"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Light And Shadow Photography By Rupert Vandervall | Solopress<\/title>\n<meta name=\"description\" content=\"Striking light and shadow, black and white photography by digital photographer Rupert Vandervall focuses on strong angles, concrete and people.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solopress.com\/blog\/es\/fotografia\/luz-y-sombra-blanco-y-negro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Light And Shadow Photography By Rupert Vandervall | Solopress\" \/>\n<meta property=\"og:description\" content=\"Striking light and shadow, black and white photography by digital photographer Rupert Vandervall focuses on strong angles, concrete and people.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solopress.com\/blog\/es\/fotografia\/luz-y-sombra-blanco-y-negro\/\" \/>\n<meta property=\"og:site_name\" content=\"The Latest Print and Design News | Solopress\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Solopress\" \/>\n<meta property=\"article:published_time\" content=\"2014-08-07T11:37:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-17T21:26:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/08\/7171bfaaf343302ab40e489bd10cee95.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Aron Priest\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@solopress\" \/>\n<meta name=\"twitter:site\" content=\"@solopress\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aron Priest\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/photography\\\/light-and-shadow-black-and-white\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/photography\\\/light-and-shadow-black-and-white\\\/\"},\"author\":{\"name\":\"Aron Priest\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/48b967ba047cb36781b5820a5bc366a2\"},\"headline\":\"Light And Shadow Black And White Photography By Rupert Vandervell\",\"datePublished\":\"2014-08-07T11:37:22+00:00\",\"dateModified\":\"2022-06-17T21:26:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/photography\\\/light-and-shadow-black-and-white\\\/\"},\"wordCount\":348,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/photography\\\/light-and-shadow-black-and-white\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/7171bfaaf343302ab40e489bd10cee95.jpg\",\"articleSection\":[\"Photography\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/photography\\\/light-and-shadow-black-and-white\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/photography\\\/light-and-shadow-black-and-white\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/photography\\\/light-and-shadow-black-and-white\\\/\",\"name\":\"Light And Shadow Photography By Rupert Vandervall | Solopress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/photography\\\/light-and-shadow-black-and-white\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/photography\\\/light-and-shadow-black-and-white\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/7171bfaaf343302ab40e489bd10cee95.jpg\",\"datePublished\":\"2014-08-07T11:37:22+00:00\",\"dateModified\":\"2022-06-17T21:26:25+00:00\",\"description\":\"Striking light and shadow, black and white photography by digital photographer Rupert Vandervall focuses on strong angles, concrete and people.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/photography\\\/light-and-shadow-black-and-white\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/photography\\\/light-and-shadow-black-and-white\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/photography\\\/light-and-shadow-black-and-white\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/7171bfaaf343302ab40e489bd10cee95.jpg\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/7171bfaaf343302ab40e489bd10cee95.jpg\",\"width\":600,\"height\":450,\"caption\":\"Light and shadow, black and white photograph showing a woman perched on a rectangular shaped , long bench with her back facing us. She is wearing a white hate and white t-shirt and trousers, looking at a dark, block building . The floor is made of wood.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/photography\\\/light-and-shadow-black-and-white\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Light And Shadow Black And White Photography By Rupert Vandervell\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"name\":\"The Latest Print and Design News | Solopress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\",\"name\":\"Solopress\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"width\":428,\"height\":88,\"caption\":\"Solopress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Solopress\",\"https:\\\/\\\/x.com\\\/solopress\",\"https:\\\/\\\/instagram.com\\\/solopress\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/solopress\",\"https:\\\/\\\/uk.pinterest.com\\\/solopress\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/solopress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/48b967ba047cb36781b5820a5bc366a2\",\"name\":\"Aron Priest\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/380b785e9e4ce1b2368342be7627087cb9a650c2580eead22bbb5722b18ec622?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/380b785e9e4ce1b2368342be7627087cb9a650c2580eead22bbb5722b18ec622?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/380b785e9e4ce1b2368342be7627087cb9a650c2580eead22bbb5722b18ec622?s=96&r=g\",\"caption\":\"Aron Priest\"},\"description\":\"I have been in the print trade since 1988 and started my first printing company in 1999. Solopress went from just a few employees in the first year up to over 150 staff at present. I am fully trained in every department of my company and love coming to work.\",\"sameAs\":[\"https:\\\/\\\/www.solopress.com\"],\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/es\\\/author\\\/aron-priest\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fotograf\u00eda de luces y sombras por Rupert Vandervall | Solopress","description":"Llamativas luces y sombras, la fotograf\u00eda en blanco y negro del fot\u00f3grafo digital Rupert Vandervall se centra en los \u00e1ngulos fuertes, el hormig\u00f3n y las personas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solopress.com\/blog\/es\/fotografia\/luz-y-sombra-blanco-y-negro\/","og_locale":"es_ES","og_type":"article","og_title":"Light And Shadow Photography By Rupert Vandervall | Solopress","og_description":"Striking light and shadow, black and white photography by digital photographer Rupert Vandervall focuses on strong angles, concrete and people.","og_url":"https:\/\/www.solopress.com\/blog\/es\/fotografia\/luz-y-sombra-blanco-y-negro\/","og_site_name":"The Latest Print and Design News | Solopress","article_publisher":"https:\/\/www.facebook.com\/Solopress","article_published_time":"2014-08-07T11:37:22+00:00","article_modified_time":"2022-06-17T21:26:25+00:00","og_image":[{"width":600,"height":450,"url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/08\/7171bfaaf343302ab40e489bd10cee95.jpg","type":"image\/jpeg"}],"author":"Aron Priest","twitter_card":"summary_large_image","twitter_creator":"@solopress","twitter_site":"@solopress","twitter_misc":{"Escrito por":"Aron Priest","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.solopress.com\/blog\/photography\/light-and-shadow-black-and-white\/#article","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/photography\/light-and-shadow-black-and-white\/"},"author":{"name":"Aron Priest","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/48b967ba047cb36781b5820a5bc366a2"},"headline":"Light And Shadow Black And White Photography By Rupert Vandervell","datePublished":"2014-08-07T11:37:22+00:00","dateModified":"2022-06-17T21:26:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/photography\/light-and-shadow-black-and-white\/"},"wordCount":348,"commentCount":3,"publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/photography\/light-and-shadow-black-and-white\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/08\/7171bfaaf343302ab40e489bd10cee95.jpg","articleSection":["Photography"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.solopress.com\/blog\/photography\/light-and-shadow-black-and-white\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.solopress.com\/blog\/photography\/light-and-shadow-black-and-white\/","url":"https:\/\/www.solopress.com\/blog\/photography\/light-and-shadow-black-and-white\/","name":"Fotograf\u00eda de luces y sombras por Rupert Vandervall | Solopress","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/photography\/light-and-shadow-black-and-white\/#primaryimage"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/photography\/light-and-shadow-black-and-white\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/08\/7171bfaaf343302ab40e489bd10cee95.jpg","datePublished":"2014-08-07T11:37:22+00:00","dateModified":"2022-06-17T21:26:25+00:00","description":"Llamativas luces y sombras, la fotograf\u00eda en blanco y negro del fot\u00f3grafo digital Rupert Vandervall se centra en los \u00e1ngulos fuertes, el hormig\u00f3n y las personas.","breadcrumb":{"@id":"https:\/\/www.solopress.com\/blog\/photography\/light-and-shadow-black-and-white\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solopress.com\/blog\/photography\/light-and-shadow-black-and-white\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.solopress.com\/blog\/photography\/light-and-shadow-black-and-white\/#primaryimage","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/08\/7171bfaaf343302ab40e489bd10cee95.jpg","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/08\/7171bfaaf343302ab40e489bd10cee95.jpg","width":600,"height":450,"caption":"Light and shadow, black and white photograph showing a woman perched on a rectangular shaped , long bench with her back facing us. She is wearing a white hate and white t-shirt and trousers, looking at a dark, block building . The floor is made of wood."},{"@type":"BreadcrumbList","@id":"https:\/\/www.solopress.com\/blog\/photography\/light-and-shadow-black-and-white\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.solopress.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Light And Shadow Black And White Photography By Rupert Vandervell"}]},{"@type":"WebSite","@id":"https:\/\/www.solopress.com\/blog\/#website","url":"https:\/\/www.solopress.com\/blog\/","name":"\u00daltimas noticias sobre impresi\u00f3n y dise\u00f1o | Solopress","description":"","publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solopress.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.solopress.com\/blog\/#organization","name":"Solopress","url":"https:\/\/www.solopress.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","width":428,"height":88,"caption":"Solopress"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Solopress","https:\/\/x.com\/solopress","https:\/\/instagram.com\/solopress\/","https:\/\/www.linkedin.com\/company\/solopress","https:\/\/uk.pinterest.com\/solopress\/","https:\/\/www.youtube.com\/user\/solopress"]},{"@type":"Person","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/48b967ba047cb36781b5820a5bc366a2","name":"Aron Priest","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/380b785e9e4ce1b2368342be7627087cb9a650c2580eead22bbb5722b18ec622?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/380b785e9e4ce1b2368342be7627087cb9a650c2580eead22bbb5722b18ec622?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/380b785e9e4ce1b2368342be7627087cb9a650c2580eead22bbb5722b18ec622?s=96&r=g","caption":"Aron Priest"},"description":"Llevo en el sector de la impresi\u00f3n desde 1988 y fund\u00e9 mi primera imprenta en 1999. Solopress pas\u00f3 de tener unos pocos empleados el primer a\u00f1o a tener m\u00e1s de 150 en la actualidad. He recibido formaci\u00f3n completa en todos los departamentos de mi empresa y me encanta venir a trabajar.","sameAs":["https:\/\/www.solopress.com"],"url":"https:\/\/www.solopress.com\/blog\/es\/author\/aron-priest\/"}]}},"jetpack_featured_media_url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/08\/7171bfaaf343302ab40e489bd10cee95.jpg","_links":{"self":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts\/22494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/comments?post=22494"}],"version-history":[{"count":5,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts\/22494\/revisions"}],"predecessor-version":[{"id":72400,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts\/22494\/revisions\/72400"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/media\/22500"}],"wp:attachment":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/media?parent=22494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/categories?post=22494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/tags?post=22494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}