{"id":65993,"date":"2020-01-14T08:42:45","date_gmt":"2020-01-14T08:42:45","guid":{"rendered":"https:\/\/www.solopress.com\/blog\/?p=65993"},"modified":"2021-02-24T12:47:54","modified_gmt":"2021-02-24T12:47:54","slug":"como-redimensionar-una-imagen-en-photoshop","status":"publish","type":"post","link":"https:\/\/www.solopress.com\/blog\/es\/tutorials\/how-to-resize-an-image-in-photoshop\/","title":{"rendered":"C\u00f3mo cambiar el tama\u00f1o de una imagen en Photoshop"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p>He aqu\u00ed c\u00f3mo escalar una imagen en Photoshop. Mediante el uso de objetos inteligentes, se mantendr\u00e1 la resoluci\u00f3n de la imagen, lo que resulta en un trabajo terminado de mayor calidad.<\/p>\n<ol>\n<li>Seleccione la imagen y haga clic con el bot\u00f3n derecho en la capa<\/li>\n<li>Seleccione \"Convertir en objeto inteligente\" en el men\u00fa emergente<\/li>\n<li>Utiliza Ctrl+T en PC o Cmd+T en Mac para activar Transformaci\u00f3n libre.<\/li>\n<li>Localice los campos Establecer escala horizontal (marcado W:) o Establecer escala vertical (marcado H:) en la barra de selecci\u00f3n<\/li>\n<li>Marque la casilla \"Mantener relaci\u00f3n de aspecto\" (el s\u00edmbolo del eslab\u00f3n entre los campos A: y A:) para limitar las proporciones.<\/li>\n<li>Introduzca un valor porcentual en cualquiera de los campos W: o H: (por encima de 100% para aumentar el tama\u00f1o y por debajo de 100&amp; para reducirlo).<\/li>\n<\/ol>\n<p>Nuestro v\u00eddeo te muestra con m\u00e1s detalle c\u00f3mo y por qu\u00e9 \u00e9sta es la mejor manera de redimensionar una imagen sin perder calidad en Photoshop. Pero si ya est\u00e1s listo para imprimir, o si prefieres que nuestro equipo de dise\u00f1o se encargue del material gr\u00e1fico, dir\u00edgete a <a href=\"https:\/\/www.solopress.com\/blog\/es\/\">Solopress<\/a>.<\/p>\n<h3><strong>Tutorial de v\u00eddeo: C\u00f3mo cambiar el tama\u00f1o de una imagen en Photoshop<\/strong><\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/PLovpSfX0PI?rel=0\" width=\"675\" height=\"378\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Esta serie de tutoriales en v\u00eddeo est\u00e1 repleta de consejos para sacar el m\u00e1ximo partido a los programas de dise\u00f1o de Adobe. Si quieres estar al d\u00eda de la serie, suscr\u00edbete a nuestro canal de YouTube.<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/solopress?sub_confirmation=1\" target=\"_blank\" rel=\"https:\/\/www.youtube.com\/solopress?sub_confirmation=1 noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-66137\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2020\/01\/subscribe.png\" alt=\"bot\u00f3n de suscripci\u00f3n\" width=\"157\" height=\"48\" \/><\/a><\/p>\n<h3><strong>Transcripci\u00f3n en v\u00eddeo<\/strong><\/h3>\n<p>Hola a todos,<\/p>\n<p>Mi nombre es Dan de Solopress, y bienvenidos a nuestro tutorial sobre c\u00f3mo cambiar el tama\u00f1o de una imagen en Photoshop como parte de nuestra serie de tutoriales de Dise\u00f1o Gr\u00e1fico. Vamos a crear un mont\u00f3n de contenido gratuito para usted, as\u00ed que aseg\u00farese de hacer clic en suscribirse y el icono de la campana para ser notificado de cuando subimos. Hoy utilizaremos la funci\u00f3n llamada \"Objetos inteligentes\". Los objetos inteligentes han estado en Photoshop desde 2005, as\u00ed que a menos que todav\u00eda est\u00e9s ejecutando Windows XP con Photoshop 7.0, tendr\u00e1s esta funci\u00f3n.<\/p>\n<p>As\u00ed que aqu\u00ed tengo un lienzo b\u00e1sico con dos fotos id\u00e9nticas en \u00e9l, una es simplemente un duplicado de la otra. S\u00f3lo como un atajo de teclado adicional para usted, usted puede duplicar cualquier elemento en Photoshop seleccionando la capa y pulsando Ctrl o Cmd + J.<\/p>\n<p>Ahora puedes estar pensando que cambiar el tama\u00f1o de una imagen en Photoshop es intr\u00ednsecamente f\u00e1cil. Simplemente activa la Transformaci\u00f3n Libre pulsando Ctrl o Cmd T, y luego arrastra los pines de las esquinas al tama\u00f1o que quieras que tenga la imagen. O si est\u00e1s en una versi\u00f3n antigua de Photoshop, puede que tengas que mantener pulsada la tecla May\u00fas para asegurarte de que Photoshop restringe las proporciones de la imagen para que no termines con una imagen aplastada.<\/p>\n<p>El problema del cambio de tama\u00f1o convencional es que es destructivo. La imagen se compone de p\u00edxeles y, una vez redimensionada, esos p\u00edxeles no se reducen. La imagen se habr\u00e1 encogido y s\u00f3lo habr\u00e1 conservado los p\u00edxeles suficientes para la imagen redimensionada.<\/p>\n<p>As\u00ed que voy a ejecutar a trav\u00e9s de un ejemplo de esto utilizando par\u00e1metros controlados. Aqu\u00ed tenemos una imagen de un coche atravesando un charco. Hay una cantidad decente de detalle en esto, un mont\u00f3n de gotas de agua y objetos enfocados. Haremos el cambio de tama\u00f1o convencional en la imagen de la izquierda. En primer lugar, vamos a activar la transformaci\u00f3n libre, ya sea seleccionando la capa aqu\u00ed, luego ir a la pesta\u00f1a Editar, e ir a Transformaci\u00f3n Libre. Alternativamente, como antes, podemos pulsar Ctrl o Cmd T. Ver\u00e1 el cuadro delimitador de la imagen y las asas de agarre, pero en la barra de selecci\u00f3n, ahora hay diferentes par\u00e1metros que podemos ajustar con precisi\u00f3n.<\/p>\n<p>Cambiaremos el valor porcentual de 100% a 10%. Pero antes, comprobemos que la casilla \"Mantener relaci\u00f3n de aspecto\" est\u00e1 seleccionada. Esto significar\u00e1 que al cambiar uno de los valores, tambi\u00e9n cambiar\u00e1 el otro. A continuaci\u00f3n, pulsaremos la tecla intro que est\u00e1 m\u00e1s a la derecha en el teclado, o la marca aqu\u00ed. Esto confirmar\u00e1 estos cambios en el objeto que acaba de cambiar. Y vamos a dejar eso ah\u00ed por ahora.<\/p>\n<p>La otra capa, vamos a convertirla en un objeto inteligente. Este es un proceso no destructivo, y la mejor manera en que puedo describirlo es que mantiene la imagen en su tama\u00f1o original, pero act\u00faa como si estuviera siendo redimensionada. El beneficio de esto se har\u00e1 evidente en breve. Para convertirlo en un objeto inteligente, seleccione la capa, haga clic derecho y seleccione \"convertir en objeto inteligente\". A continuaci\u00f3n, seguiremos los mismos pasos que antes. Asegur\u00e1ndonos de que la capa est\u00e1 seleccionada, activaremos la transformaci\u00f3n libre pulsando Ctrl o Cmd T, asegur\u00e1ndonos de que la casilla mantener relaci\u00f3n de aspecto est\u00e1 seleccionada, y luego cambiando la escala de 100% a 10%.<\/p>\n<p>Como la imagen de la izquierda est\u00e1 ahora \"rasterizada\" a 10% de su tama\u00f1o original, eso significa que ha perdido 90% de su informaci\u00f3n, mientras que el objeto inteligente la ha conservado toda. Es mucho m\u00e1s f\u00e1cil ver la diferencia si la volvemos a escalar, as\u00ed que cambiaremos el valor de la imagen de la izquierda a 100%.<\/p>\n<p>Pero espere: la imagen aparece ahora a escala 100%. Esto se debe a que, al rasterizar la imagen, este tama\u00f1o de 10% se convirti\u00f3 en la imagen completa. Y cuando la reescalamos a 1000%, podemos ver que la peque\u00f1a cantidad de informaci\u00f3n que queda deja la imagen con un aspecto muy cuadriculado. Cuando confirmamos los cambios haciendo clic en la marca, Photoshop intenta suavizar la imagen para crear detalles, pero estamos demasiado lejos para que parezca plausible.<\/p>\n<p>Transversalmente, cuando nos fijamos en las opciones de escala para el objeto inteligente, todav\u00eda se muestra en 10%. As\u00ed que cuando lo cambiamos de nuevo a 100%, la imagen se escala de nuevo a su tama\u00f1o original - y lo m\u00e1s importante, sin p\u00e9rdida de detalle. Si comparamos las dos im\u00e1genes, vemos que en la de la izquierda han desaparecido todos los detalles. La nitidez de las gotas de agua ha desaparecido por completo, hasta el punto de que casi parece humo. Apenas se distinguen los radios de las ruedas y las rocas han perdido toda definici\u00f3n.<\/p>\n<p>Y ah\u00ed lo tienes, la mejor forma de redimensionar im\u00e1genes en Photoshop. Si has encontrado este v\u00eddeo \u00fatil, por favor deja un like. Y si tienes alguna pregunta o sugerencia, no dudes en comentarla.<\/p>\n<p>Estamos creando todo tipo de tutoriales para los programas de Adobe, as\u00ed que suscr\u00edbete y disfruta de nuestro contenido.<\/p>\n<p>Mi nombre es Dan, gracias por mirar.<\/p>","protected":false},"excerpt":{"rendered":"<p>Here\u2019s how to scale an image in Photoshop. By using Smart Objects, you\u2019ll maintain image resolution, resulting in higher quality finished work. Select the image and right click on the layer Select \u201cConvert to Smart Object\u201d from the pop-up menu Use Ctrl+T on PC or Cmd+T on Mac to enable Free Transform Locate the Set [&hellip;]<\/p>\n","protected":false},"author":134,"featured_media":68602,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[555],"tags":[905],"class_list":{"0":"post-65993","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tutorials","8":"tag-photoshop"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>How to Resize an Image in Photoshop | Adobe Tutorial | Solopress UK<\/title>\n<meta name=\"description\" content=\"In this video tutorial, we present a step-by-step guide on how to resize an image in photoshop without compromising on resolution.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solopress.com\/blog\/es\/tutoriales\/como-redimensionar-una-imagen-en-photoshop\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How to Resize an Image in Photoshop | Adobe Tutorial | Solopress UK\" \/>\n<meta property=\"og:description\" content=\"In this video tutorial, we present a step-by-step guide on how to resize an image in photoshop without compromising on resolution.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solopress.com\/blog\/es\/tutoriales\/como-redimensionar-una-imagen-en-photoshop\/\" \/>\n<meta property=\"og:site_name\" content=\"The Latest Print and Design News | Solopress\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Solopress\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-14T08:42:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-24T12:47:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2020\/07\/Resize.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Danny Powell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@solopress\" \/>\n<meta name=\"twitter:site\" content=\"@solopress\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Danny Powell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-resize-an-image-in-photoshop\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-resize-an-image-in-photoshop\\\/\"},\"author\":{\"name\":\"Danny Powell\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/0937555a256c22f94400f4b7e2329c09\"},\"headline\":\"How to resize an image in Photoshop\",\"datePublished\":\"2020-01-14T08:42:45+00:00\",\"dateModified\":\"2021-02-24T12:47:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-resize-an-image-in-photoshop\\\/\"},\"wordCount\":1076,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-resize-an-image-in-photoshop\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Resize.jpg\",\"keywords\":[\"Photoshop\"],\"articleSection\":[\"Design Tutorials\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-resize-an-image-in-photoshop\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-resize-an-image-in-photoshop\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-resize-an-image-in-photoshop\\\/\",\"name\":\"How to Resize an Image in Photoshop | Adobe Tutorial | Solopress UK\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-resize-an-image-in-photoshop\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-resize-an-image-in-photoshop\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Resize.jpg\",\"datePublished\":\"2020-01-14T08:42:45+00:00\",\"dateModified\":\"2021-02-24T12:47:54+00:00\",\"description\":\"In this video tutorial, we present a step-by-step guide on how to resize an image in photoshop without compromising on resolution.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-resize-an-image-in-photoshop\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-resize-an-image-in-photoshop\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-resize-an-image-in-photoshop\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Resize.jpg\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Resize.jpg\",\"width\":800,\"height\":600,\"caption\":\"How to resize an image in PS header image\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-resize-an-image-in-photoshop\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How to resize an image in Photoshop\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"name\":\"The Latest Print and Design News | Solopress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\",\"name\":\"Solopress\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"width\":428,\"height\":88,\"caption\":\"Solopress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Solopress\",\"https:\\\/\\\/x.com\\\/solopress\",\"https:\\\/\\\/instagram.com\\\/solopress\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/solopress\",\"https:\\\/\\\/uk.pinterest.com\\\/solopress\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/solopress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/0937555a256c22f94400f4b7e2329c09\",\"name\":\"Danny Powell\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"caption\":\"Danny Powell\"},\"description\":\"With over two decades in marketing, Danny Powell is a Senior Copywriter at Solopress, one of the UK\u2019s leading online printers. Having worked on the print buying, agency and sales sides of the industry, he brings a well-rounded perspective to his writing on print, design and sustainability.\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/es\\\/author\\\/danny-powell\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo cambiar el tama\u00f1o de una imagen en Photoshop | Adobe Tutorial | Solopress ES","description":"En este video tutorial, presentamos una gu\u00eda paso a paso sobre c\u00f3mo cambiar el tama\u00f1o de una imagen en photoshop sin comprometer la resoluci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solopress.com\/blog\/es\/tutoriales\/como-redimensionar-una-imagen-en-photoshop\/","og_locale":"es_ES","og_type":"article","og_title":"How to Resize an Image in Photoshop | Adobe Tutorial | Solopress UK","og_description":"In this video tutorial, we present a step-by-step guide on how to resize an image in photoshop without compromising on resolution.","og_url":"https:\/\/www.solopress.com\/blog\/es\/tutoriales\/como-redimensionar-una-imagen-en-photoshop\/","og_site_name":"The Latest Print and Design News | Solopress","article_publisher":"https:\/\/www.facebook.com\/Solopress","article_published_time":"2020-01-14T08:42:45+00:00","article_modified_time":"2021-02-24T12:47:54+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2020\/07\/Resize.jpg","type":"image\/jpeg"}],"author":"Danny Powell","twitter_card":"summary_large_image","twitter_creator":"@solopress","twitter_site":"@solopress","twitter_misc":{"Escrito por":"Danny Powell","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-resize-an-image-in-photoshop\/#article","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-resize-an-image-in-photoshop\/"},"author":{"name":"Danny Powell","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/0937555a256c22f94400f4b7e2329c09"},"headline":"How to resize an image in Photoshop","datePublished":"2020-01-14T08:42:45+00:00","dateModified":"2021-02-24T12:47:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-resize-an-image-in-photoshop\/"},"wordCount":1076,"commentCount":4,"publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-resize-an-image-in-photoshop\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2020\/07\/Resize.jpg","keywords":["Photoshop"],"articleSection":["Design Tutorials"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.solopress.com\/blog\/tutorials\/how-to-resize-an-image-in-photoshop\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-resize-an-image-in-photoshop\/","url":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-resize-an-image-in-photoshop\/","name":"C\u00f3mo cambiar el tama\u00f1o de una imagen en Photoshop | Adobe Tutorial | Solopress ES","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-resize-an-image-in-photoshop\/#primaryimage"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-resize-an-image-in-photoshop\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2020\/07\/Resize.jpg","datePublished":"2020-01-14T08:42:45+00:00","dateModified":"2021-02-24T12:47:54+00:00","description":"En este video tutorial, presentamos una gu\u00eda paso a paso sobre c\u00f3mo cambiar el tama\u00f1o de una imagen en photoshop sin comprometer la resoluci\u00f3n.","breadcrumb":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-resize-an-image-in-photoshop\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solopress.com\/blog\/tutorials\/how-to-resize-an-image-in-photoshop\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-resize-an-image-in-photoshop\/#primaryimage","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2020\/07\/Resize.jpg","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2020\/07\/Resize.jpg","width":800,"height":600,"caption":"How to resize an image in PS header image"},{"@type":"BreadcrumbList","@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-resize-an-image-in-photoshop\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.solopress.com\/blog\/"},{"@type":"ListItem","position":2,"name":"How to resize an image in Photoshop"}]},{"@type":"WebSite","@id":"https:\/\/www.solopress.com\/blog\/#website","url":"https:\/\/www.solopress.com\/blog\/","name":"\u00daltimas noticias sobre impresi\u00f3n y dise\u00f1o | Solopress","description":"","publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solopress.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.solopress.com\/blog\/#organization","name":"Solopress","url":"https:\/\/www.solopress.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","width":428,"height":88,"caption":"Solopress"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Solopress","https:\/\/x.com\/solopress","https:\/\/instagram.com\/solopress\/","https:\/\/www.linkedin.com\/company\/solopress","https:\/\/uk.pinterest.com\/solopress\/","https:\/\/www.youtube.com\/user\/solopress"]},{"@type":"Person","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/0937555a256c22f94400f4b7e2329c09","name":"Danny Powell","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","caption":"Danny Powell"},"description":"Con m\u00e1s de dos d\u00e9cadas de experiencia en marketing, Danny Powell es redactor jefe de Solopress, una de las principales imprentas en l\u00ednea del Reino Unido. Tras haber trabajado en los departamentos de compras, agencias y ventas del sector de la impresi\u00f3n, aporta una perspectiva muy completa a sus escritos sobre impresi\u00f3n, dise\u00f1o y sostenibilidad.","url":"https:\/\/www.solopress.com\/blog\/es\/author\/danny-powell\/"}]}},"jetpack_featured_media_url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2020\/07\/Resize.jpg","_links":{"self":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts\/65993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/comments?post=65993"}],"version-history":[{"count":5,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts\/65993\/revisions"}],"predecessor-version":[{"id":67001,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts\/65993\/revisions\/67001"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/media\/68602"}],"wp:attachment":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/media?parent=65993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/categories?post=65993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/tags?post=65993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}