{"id":70633,"date":"2021-03-26T11:24:58","date_gmt":"2021-03-26T11:24:58","guid":{"rendered":"https:\/\/www.solopress.com\/blog\/?p=70633"},"modified":"2021-06-24T16:16:28","modified_gmt":"2021-06-24T15:16:28","slug":"el-panfleto-electoral-perfecto","status":"publish","type":"post","link":"https:\/\/www.solopress.com\/blog\/es\/print-inspiration\/the-perfect-election-leaflet\/","title":{"rendered":"C\u00f3mo dise\u00f1ar el folleto electoral perfecto que los votantes no puedan ignorar"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p>Los folletos electorales son una parte importante de cualquier campa\u00f1a pol\u00edtica; nosotros lo sabemos, hemos impreso uno o dos en nuestra vida.<\/p>\n<p>Pero, \u00bfqu\u00e9 hace que unas campa\u00f1as sean m\u00e1s eficaces que otras?Nos intrigaba conocer la opini\u00f3n de la gente al respecto, as\u00ed que realizamos una encuesta entre 878 votantes para descubrir qu\u00e9 piensan realmente cuando reciben un folleto electoral. Estas son nuestras conclusiones...<\/p>\n<h2 style=\"text-align: center;\"><b><u>Titulares pol\u00edticos<\/u><\/b><\/h2>\n<p>La primera serie de preguntas de nuestra encuesta se refer\u00eda al titular. Qu\u00e9 tipo de mensaje prefieren ver los ciudadanos en la portada de un folleto electoral?<\/p>\n<h3><strong>1. \u00bfQu\u00e9 tipo de titular preferir\u00eda ver en la portada de un folleto electoral? <\/strong><em>\u00bfUn eslogan del partido, una pol\u00edtica concreta o una cita del candidato?<\/em><\/h3>\n<p>Hemos descubierto que la mayor\u00eda de nuestros encuestados prefieren ver un titular centrado en un \u00e1rea pol\u00edtica espec\u00edfica en lugar de una declaraci\u00f3n de intenciones m\u00e1s general. 56% de los encuestados dijeron que prefer\u00edan ver un titular espec\u00edfico. 25% prefer\u00edan un eslogan del partido y s\u00f3lo 19% quer\u00edan ver una cita del candidato. Esto est\u00e1 en desacuerdo con la tendencia predominante que vemos de titulares m\u00e1s generalizados, como \"Liderazgo fuerte y estable en el inter\u00e9s nacional\" (Conservador, 2017). Tal vez los grandes partidos deber\u00edan optar por titulares m\u00e1s espec\u00edficos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-70726 aligncenter\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2021\/03\/5968d039-6ee0-4483-bd4f-54d10c7325bc.jpg\" alt=\"\" width=\"527\" height=\"480\" \/><\/p>\n<h3><strong>2. \u00bfEn qu\u00e9 debe centrarse el mensaje principal del anverso de un folleto electoral? <\/strong><em>\u00bfUna cuesti\u00f3n principal o varias?<\/em><\/h3>\n<p>Si se opta por un titular centrado en una pol\u00edtica, \u00bfdeber\u00eda centrarse m\u00e1s en un tema o abarcar un abanico m\u00e1s amplio de pol\u00edticas? 56 % de los encuestados dijeron que prefer\u00edan ver un titular centrado en una cuesti\u00f3n principal, mientras que los 44% restantes preferir\u00edan ver un mensaje m\u00e1s general centrado, por lo que el titular centrado en una sola pol\u00edtica gana por un estrecho margen.<\/p>\n<h3><strong>3. \u00bfQu\u00e9 preferir\u00eda aprender del titular? <\/strong><em>\u00bfQu\u00e9 defiende o contra qu\u00e9 est\u00e1 el candidato?<\/em><\/h3>\n<p>Los titulares pueden destacar una postura positiva en nombre del candidato, o pueden centrarse en algo a lo que se oponga. Cuando preguntamos a la gente qu\u00e9 prefer\u00eda, una abrumadora mayor\u00eda de 88% se decant\u00f3 por un titular que explicara lo que defiende el candidato, y solo 12% prefirieron uno que se centrara en aquello a lo que el candidato se opone.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-70723 aligncenter\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2021\/03\/01b0135d-6f82-4c93-b696-d20160a54c27.jpg\" alt=\"\" width=\"420\" height=\"480\" \/><\/p>\n<h3><strong>4. \u00bfQu\u00e9 debe decir el titular? <\/strong><em>\u00bfPor qu\u00e9 hay que votar al candidato o por qu\u00e9 no hay que votar a la oposici\u00f3n?<\/em><\/h3>\n<p>Del mismo modo, el titular puede ser una oportunidad para la autopromoci\u00f3n o para desprestigiar a la oposici\u00f3n. Sin embargo, seg\u00fan nuestra encuesta, la gran mayor\u00eda de la gente prefiere ver c\u00f3mo defiendes tu liderazgo a ver c\u00f3mo lanzas lodo contra tus oponentes, y el 96% prefiere un mensaje positivo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-70720 aligncenter\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2021\/03\/f59b2cf6-fe75-4a0a-af66-139fe35c67f7.jpg\" alt=\"\" width=\"601\" height=\"414\" \/><\/p>\n<h2 style=\"text-align: center;\"><b><u>Oportunidades fotogr\u00e1ficas<\/u><\/b><\/h2>\n<p>Una foto del candidato es un elemento fundamental de los folletos de campa\u00f1a. Sin embargo, hay que decidir d\u00f3nde se toma la foto, qui\u00e9n aparece en ella, c\u00f3mo se recorta e incluso qu\u00e9 expresi\u00f3n facial adoptar.<\/p>\n<h3 class=\"sm-questiontitle\" title=\"\u00bfQu\u00e9 tipo de fotograf\u00eda preferir\u00eda ver en el anverso de un folleto electoral?\"><strong>5. \u00bfQu\u00e9 tipo de fotograf\u00eda preferir\u00eda ver en la portada? <\/strong><em>\u00bfUna foto del candidato o de un tema de inter\u00e9s para la circunscripci\u00f3n?<\/em><\/h3>\n<p class=\"sm-questiontitle\" title=\"\u00bfQu\u00e9 tipo de fotograf\u00eda preferir\u00eda ver en el anverso de un folleto electoral?\">Los encuestados se dividieron casi mitad y mitad cuando se les pregunt\u00f3 sobre d\u00f3nde deber\u00eda aparecer realmente el candidato, con 52% prefiriendo una foto del candidato y 48% prefiriendo ver una foto que represente un tema en la circunscripci\u00f3n o distrito. As\u00ed que, al menos en lo que se refiere a la portada, \u00a1quiz\u00e1 no sea tan obvio como pens\u00e1bamos que deb\u00eda ser!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-70717 aligncenter\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2021\/03\/74c7a796-f92a-4971-a541-191df665404f.jpg\" alt=\"\" width=\"537\" height=\"448\" \/><\/p>\n<h3><strong>6. \u00bfQu\u00e9 tipo de fotograf\u00eda del candidato preferir\u00eda ver? <\/strong><em>\u00bfCabeza y hombros o cuerpo entero?<\/em><\/h3>\n<p>\u00bfQu\u00e9 parte del candidato quiere ver realmente la gente? 74% de los encuestados prefieren ver una foto recortada por la cabeza y los hombros, y solo 26% prefieren una foto de cuerpo entero.<\/p>\n<h3 class=\"sm-questiontitle\" title=\"\u00bfC\u00f3mo prefiere ver retratado al candidato?\"><strong>7. \u00bfC\u00f3mo preferir\u00eda que se retratara el candidato? <\/strong><em>\u00bfEn su circunscripci\u00f3n, con el l\u00edder de su partido o profesionalmente en un estudio?<\/em><\/h3>\n<p>Tambi\u00e9n preguntamos a los encuestados si prefer\u00edan ver al candidato retratado en su comunidad, junto al l\u00edder de su partido, o fotografiado en un estudio por un profesional. Un abrumador 82% de los encuestados prefiri\u00f3 ver a su candidato en la circunscripci\u00f3n o barrio que esperaba representar. 11% prefer\u00edan una foto junto al l\u00edder del partido y s\u00f3lo 7% prefer\u00edan ver una foto de estudio profesional.<\/p>\n<h3><strong><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2021\/03\/d20afe03-3546-403f-84b4-6e804bcc69e2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-70714 aligncenter\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2021\/03\/d20afe03-3546-403f-84b4-6e804bcc69e2.jpg\" alt=\"\" width=\"331\" height=\"379\" \/><\/a>8. \u00bfC\u00f3mo debe ser la expresi\u00f3n facial del candidato? <\/strong><em>\u00bfFeliz y alegre? \u00bfO serio y formal?<\/em><\/h3>\n<p>Cuando preguntamos a los votantes si prefer\u00edan ver a su candidato de buen humor y alegre o con una expresi\u00f3n facial seria y de negocios, 68 % prefirieron una sonrisa y s\u00f3lo 32% una expresi\u00f3n severa, as\u00ed que vale la pena animarse.<\/p>\n<h2 style=\"text-align: center;\"><b><u>Preguntas ret\u00f3ricas<\/u><\/b><\/h2>\n<h3><strong>9. \u00bfC\u00f3mo prefiere que se redacte un folleto electoral? <\/strong><em>\u00bfPor el candidato en 1\u00aa persona, o sobre el candidato en 3\u00aa persona?<\/em><\/h3>\n<p>La encuesta prosegu\u00eda con una pregunta sobre el estilo de redacci\u00f3n de un folleto electoral. Preguntamos si prefer\u00edan un folleto escrito en primera persona (por ejemplo, \"Yo soy la mujer para el puesto\") o si lo prefer\u00edan en tercera persona (por ejemplo, \"Ella es la mujer para su puesto\"). Una gran mayor\u00eda de 90% prefiri\u00f3 leer un folleto escrito en primera persona.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-70711 aligncenter\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2021\/03\/a44a9a62-5f5a-4c56-93dd-ae340e61382e.jpg\" alt=\"\" width=\"601\" height=\"480\" \/><\/p>\n<h3><strong>10. \u00bfQu\u00e9 tono de voz prefiere en un folleto electoral?<\/strong> <em>\u00bfApasi\u00f3n y empat\u00eda? \u00bfO directo y objetivo?<\/em><\/h3>\n<p>En cuanto al tono del lenguaje utilizado en el folleto, preguntamos a los encuestados si prefer\u00edan un tono de voz apasionado y emp\u00e1tico o uno muy directo y objetivo. El resultado estuvo muy re\u00f1ido: s\u00f3lo 54% prefirieron el lenguaje directo y objetivo al apasionado y emp\u00e1tico. Esta igualdad puede sugerir que un compromiso entre los dos enfoques podr\u00eda ser el m\u00e1s eficaz.<\/p>\n<h2 style=\"text-align: center;\"><b><u>Panorama general<\/u><\/b><\/h2>\n<h3 class=\"sm-questiontitle\" title=\"\u00bfSobre cu\u00e1l preferir\u00eda aprender m\u00e1s?\"><strong>11. \u00bfSobre cu\u00e1l preferir\u00eda aprender m\u00e1s? <\/strong><em>\u00bfLos objetivos comunes del partido o las prioridades personales del candidato?<\/em><\/h3>\n<p>Nuestra siguiente pregunta se centraba en si los encuestados prefer\u00edan saber m\u00e1s sobre los objetivos generales del partido o si prefer\u00edan conocer las opiniones y prioridades personales del candidato. Mientras que 52% prefieren conocer las prioridades personales del candidato, 48% est\u00e1n dispuestos a saber m\u00e1s sobre el manifiesto del partido.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-70708 aligncenter\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2021\/03\/515955b1-1587-42da-94cb-83dbeb5ca3f1.jpg\" alt=\"\" width=\"481\" height=\"454\" \/><\/p>\n<h3 class=\"sm-questiontitle\" title=\"\u00bfLe interesa leer sobre la vida personal y los intereses del candidato?\"><strong>12. \u00bfLe interesa conocer la vida personal y los intereses del candidato?<\/strong><\/h3>\n<p>Los candidatos suelen dar informaci\u00f3n personal sobre sus intereses, aficiones y vida familiar, quiz\u00e1 para hacerse una idea m\u00e1s amplia de su personalidad. Sin embargo, s\u00f3lo 44% de las personas a las que preguntamos esperaban o\u00edr este tipo de informaci\u00f3n, y 56% declararon que no les interesaba espec\u00edficamente o\u00edr hablar de la vida personal del candidato.<\/p>\n<h3 class=\"sm-questiontitle\" title=\"\u00bfLe interesa conocer el historial profesional y pol\u00edtico del candidato?\"><strong>13. \u00bfLe interesa conocer el historial profesional y pol\u00edtico del candidato?<\/strong><\/h3>\n<p class=\"sm-questiontitle\" title=\"\u00bfLe interesa conocer el historial profesional y pol\u00edtico del candidato?\">Preguntamos a los encuestados si les interesaba conocer la trayectoria pol\u00edtica o profesional de los candidatos, y en esta ocasi\u00f3n un enorme 80% de los encuestados se declar\u00f3 interesado. Estas dos preguntas demuestran que, si se va a incluir informaci\u00f3n sobre el candidato como individuo, puede ser mejor inclinarse por los detalles profesionales m\u00e1s que por los personales.<\/p>\n<h2 style=\"text-align: center;\"><b><u>Datos y cifras<\/u><\/b><\/h2>\n<h3 class=\"sm-questiontitle\" title=\"\u00bfEspera que el folleto ofrezca informaci\u00f3n sobre la fecha, hora y lugar de votaci\u00f3n?\"><strong>14. \u00bfEspera que el folleto contenga informaci\u00f3n sobre la fecha, la hora y el lugar de votaci\u00f3n?<\/strong><\/h3>\n<p>Preguntamos a los lectores si esperaban que el folleto incluyera informaci\u00f3n sobre la hora, la fecha y el lugar de votaci\u00f3n para las propias elecciones, y un significativo 85% dijo que efectivamente esperaban que se imprimiera esta informaci\u00f3n. Est\u00e1 claro que es una buena idea asegurarse de que esta informaci\u00f3n se incluye en el folleto.<\/p>\n<h3 class=\"sm-questiontitle\" title=\"\u00bfC\u00f3mo prefiere que se presenten las estad\u00edsticas?\"><strong>15. \u00bfC\u00f3mo prefiere que se presenten las estad\u00edsticas? <\/strong><em>\u00bfEn forma de declaraciones escritas? \u00bfO gr\u00e1ficos y diagramas?<\/em><\/h3>\n<p>Un folleto electoral suele presentar estad\u00edsticas e informaci\u00f3n al lector, por lo que preguntamos si la gente prefer\u00eda declaraciones escritas o gr\u00e1ficos y diagramas para ilustrar los hechos y las cifras. Parece que la mayor\u00eda de la gente, 77% de hecho, encuentra la informaci\u00f3n m\u00e1s f\u00e1cil de digerir en forma de gr\u00e1ficos y diagramas, y s\u00f3lo 23% prefiere una declaraci\u00f3n escrita. No cabe duda de que merece la pena considerar una representaci\u00f3n gr\u00e1fica siempre que se quiera presentar informaci\u00f3n estad\u00edstica.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-70705 aligncenter\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2021\/03\/00b45b0b-9c04-4ee9-b996-751f0d073605.jpg\" alt=\"\" width=\"555\" height=\"442\" \/><\/p>\n<h3 class=\"sm-questiontitle\" title=\"\u00bfC\u00f3mo prefiere que se presente la informaci\u00f3n?\"><strong>16. 16. \u00bfC\u00f3mo prefiere que se presente la informaci\u00f3n? <\/strong><em>\u00bfEn p\u00e1rrafos o vi\u00f1etas?<\/em><\/h3>\n<p>En cuanto a los puntos concretos que los candidatos desean exponer en su contenido escrito, a menudo se presentan como p\u00e1rrafos de texto o separados en vi\u00f1etas. Preguntamos a nuestros encuestados qu\u00e9 prefer\u00edan, y dos tercios (67%) se decantaron por las vi\u00f1etas. Por lo tanto, si quieres exponer tu punto de vista de forma clara y sencilla, los lectores prefieren que tu contenido escrito est\u00e9 separado en distintos fragmentos.<\/p>\n<h2 style=\"text-align: center;\"><b><u>Buena \u00f3ptica<\/u><\/b><\/h2>\n<h3 class=\"sm-questiontitle\" title=\"\u00bfQu\u00e9 estilo gr\u00e1fico de los folletos electorales le parece m\u00e1s atractivo?\"><strong>17. \u00bfQu\u00e9 estilo gr\u00e1fico de los folletos electorales le parece m\u00e1s atractivo? <\/strong><em>\u00bfInclinada o no inclinada?<\/em><\/h3>\n<p>Al examinar el material de campa\u00f1a de las \u00faltimas elecciones, hemos observado una tendencia en el dise\u00f1o de gr\u00e1ficos y textos inclinados, que casi recuerdan a la propaganda sovi\u00e9tica de mediados de siglo. Quer\u00edamos saber si los encuestados prefer\u00edan este enfoque a las pancartas de texto horizontales m\u00e1s tradicionales. A pesar de las tendencias actuales, 64% prefirieron las versiones no inclinadas, por lo que podr\u00eda ser que un enfoque de dise\u00f1o gr\u00e1fico vanguardista en realidad puede perjudicar la forma en que se percibe su campa\u00f1a.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-70696 aligncenter\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2021\/03\/715215e2-740f-4d82-a223-b1844f196cbf.jpg\" alt=\"\" width=\"485\" height=\"360\" \/><\/p>\n<h3 class=\"sm-questiontitle\" title=\"\u00bfAyuda la inclusi\u00f3n de un gr\u00e1fico electoral, como una urna o una roseta, a comunicar la finalidad del folleto?\"><strong>18. \u00bfLa inclusi\u00f3n de un gr\u00e1fico electoral, como una urna o una roseta, ayuda a comunicar el objetivo del folleto?<\/strong><\/h3>\n<p>Siguiendo con los dispositivos de dise\u00f1o tradicionales, tambi\u00e9n ten\u00edamos curiosidad por saber si motivos tradicionales como la escarapela y la urna siguen teniendo cabida a la hora de se\u00f1alar el objetivo de unas elecciones.\u00a0<a href=\"https:\/\/www.solopress.com\/blog\/es\/folletos-volantes\/\">folleto<\/a>. Cuando preguntamos a la gente si prefer\u00edan ver una urna o una roseta como parte del dise\u00f1o, 64% dijeron que s\u00ed. La lecci\u00f3n parece ser que no hay que dejar que la b\u00fasqueda de la originalidad o el deseo de evitar clich\u00e9s nos alejen de ciertos tropos de dise\u00f1o que los lectores esperan y agradecen cuando se trata de material de campa\u00f1a.<\/p>\n<h3 class=\"sm-questiontitle\" title=\"\u00bfUn folleto electoral bien dise\u00f1ado aumenta las probabilidades de leer su contenido?\"><strong>19. \u00bfEs m\u00e1s probable que lea el contenido de un folleto electoral bien dise\u00f1ado?<\/strong><\/h3>\n<p>Pero, \u00bfes importante el dise\u00f1o a la hora de transmitir un mensaje pol\u00edtico? Preguntamos si un folleto electoral bien dise\u00f1ado aumentaba las probabilidades de que la gente leyera el contenido, y 95% estuvieron de acuerdo en que s\u00ed. Parece que merece la pena invertir tiempo y esfuerzo en el dise\u00f1o de los folletos si quieres que tu mensaje se escuche.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-70702 aligncenter\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2021\/03\/bf3a637f-8c6d-47d3-98dd-bcf96bb01a1f.jpg\" alt=\"\" width=\"429\" height=\"369\" \/><\/p>\n<h2 style=\"text-align: center;\"><b><u>Crear el folleto electoral perfecto<\/u><\/b><\/h2>\n<div>Bas\u00e1ndonos en los resultados de nuestra encuesta, decidimos crear nuestro propio folleto electoral perfecto. Cada una de nuestras decisiones de dise\u00f1o basadas en datos est\u00e1 numerada, para que puedas ver cu\u00e1les de nuestras conclusiones influyeron en cada elemento del folleto. \u00a1A ver cu\u00e1ntas puedes incorporar cuando crees tu propia campa\u00f1a convincente!<\/div>\n<div><\/div>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2021\/03\/Perfect-Election-Leaflet-Front.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-70888 size-full\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2021\/03\/Perfect-Election-Leaflet-Front.jpg\" alt=\"\" width=\"1754\" height=\"2480\" \/><\/a><br \/>\n<a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2021\/03\/Perfect-Election-Leaflet-Back.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-70885\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2021\/03\/Perfect-Election-Leaflet-Back.jpg\" alt=\"\" width=\"1754\" height=\"2480\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><b><u>El pueblo ha hablado<\/u><\/b><\/h2>\n<p>Esperamos que estas ideas le resulten tan fascinantes como a nosotros, y que le sean \u00fatiles a la hora de crear su folleto electoral.<\/p>\n<p>Los folletos y octavillas son s\u00f3lo una parte del equipo de campa\u00f1a de un candidato. nuestro\u00a0<a href=\"https:\/\/www.solopress.com\/blog\/es\/elections\/\"><span data-contrast=\"none\">Impresi\u00f3n electoral<\/span><\/a> re\u00fane toda nuestra valiosa gama de material impreso de campa\u00f1a con entrega gratuita al d\u00eda siguiente.<\/p>","protected":false},"excerpt":{"rendered":"<p>Election Leaflets are a big part of any political campaign \u2014 we should know, we&#8217;ve printed one or two\u00a0in our time. But what makes\u202fsome\u00a0campaigns\u00a0more effective than others?\u202fWe\u00a0were intrigued to hear people&#8217;s opinions on the issue, so we carried out a\u00a0survey of 878 voters to\u00a0discover what\u00a0they\u00a0really think when they\u00a0receive\u00a0an\u00a0election\u00a0leaflet. Here are our findings\u2026 Political headlines The [&hellip;]<\/p>\n","protected":false},"author":134,"featured_media":70648,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[544],"tags":[634],"class_list":{"0":"post-70633","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-print-inspiration","8":"tag-flyers-leaflets"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>How To Design The Perfect Election Leaflet That Voters Can\u2019t Ignore! | Solopress UK<\/title>\n<meta name=\"description\" content=\"We asked you what makes the perfect Election Leaflet. Our survey results provide unmissable insight for anyone hoping to bring voters onside\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solopress.com\/blog\/es\/inspiracion-para-imprimir\/el-panfleto-electoral-perfecto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How To Design The Perfect Election Leaflet That Voters Can\u2019t Ignore! | Solopress UK\" \/>\n<meta property=\"og:description\" content=\"We asked you what makes the perfect Election Leaflet. Our survey results provide unmissable insight for anyone hoping to bring voters onside\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solopress.com\/blog\/es\/inspiracion-para-imprimir\/el-panfleto-electoral-perfecto\/\" \/>\n<meta property=\"og:site_name\" content=\"The Latest Print and Design News | Solopress\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Solopress\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-26T11:24:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-24T15:16:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2021\/03\/Blog-tile-election-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Danny Powell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@solopress\" \/>\n<meta name=\"twitter:site\" content=\"@solopress\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Danny Powell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/print-inspiration\\\/the-perfect-election-leaflet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/print-inspiration\\\/the-perfect-election-leaflet\\\/\"},\"author\":{\"name\":\"Danny Powell\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/0937555a256c22f94400f4b7e2329c09\"},\"headline\":\"How to design the perfect Election Leaflet that voters can\u2019t ignore!\",\"datePublished\":\"2021-03-26T11:24:58+00:00\",\"dateModified\":\"2021-06-24T15:16:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/print-inspiration\\\/the-perfect-election-leaflet\\\/\"},\"wordCount\":1792,\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/print-inspiration\\\/the-perfect-election-leaflet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Blog-tile-election-01.jpg\",\"keywords\":[\"Flyers &amp; Leaflets\"],\"articleSection\":[\"Print Inspiration\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/print-inspiration\\\/the-perfect-election-leaflet\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/print-inspiration\\\/the-perfect-election-leaflet\\\/\",\"name\":\"How To Design The Perfect Election Leaflet That Voters Can\u2019t Ignore! | Solopress UK\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/print-inspiration\\\/the-perfect-election-leaflet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/print-inspiration\\\/the-perfect-election-leaflet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Blog-tile-election-01.jpg\",\"datePublished\":\"2021-03-26T11:24:58+00:00\",\"dateModified\":\"2021-06-24T15:16:28+00:00\",\"description\":\"We asked you what makes the perfect Election Leaflet. Our survey results provide unmissable insight for anyone hoping to bring voters onside\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/print-inspiration\\\/the-perfect-election-leaflet\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/print-inspiration\\\/the-perfect-election-leaflet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/print-inspiration\\\/the-perfect-election-leaflet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Blog-tile-election-01.jpg\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Blog-tile-election-01.jpg\",\"width\":900,\"height\":675,\"caption\":\"Perfect Election Leaflet\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/print-inspiration\\\/the-perfect-election-leaflet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How to design the perfect Election Leaflet that voters can\u2019t ignore!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"name\":\"The Latest Print and Design News | Solopress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\",\"name\":\"Solopress\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"width\":428,\"height\":88,\"caption\":\"Solopress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Solopress\",\"https:\\\/\\\/x.com\\\/solopress\",\"https:\\\/\\\/instagram.com\\\/solopress\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/solopress\",\"https:\\\/\\\/uk.pinterest.com\\\/solopress\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/solopress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/0937555a256c22f94400f4b7e2329c09\",\"name\":\"Danny Powell\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"caption\":\"Danny Powell\"},\"description\":\"With over two decades in marketing, Danny Powell is a Senior Copywriter at Solopress, one of the UK\u2019s leading online printers. Having worked on the print buying, agency and sales sides of the industry, he brings a well-rounded perspective to his writing on print, design and sustainability.\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/es\\\/author\\\/danny-powell\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo dise\u00f1ar el folleto electoral perfecto que los votantes no puedan ignorar | Solopress Espa\u00f1a","description":"Le hemos preguntado cu\u00e1l es el folleto electoral perfecto. Los resultados de nuestra encuesta ofrecen una visi\u00f3n imperdible para cualquiera que desee atraer a los votantes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solopress.com\/blog\/es\/inspiracion-para-imprimir\/el-panfleto-electoral-perfecto\/","og_locale":"es_ES","og_type":"article","og_title":"How To Design The Perfect Election Leaflet That Voters Can\u2019t Ignore! | Solopress UK","og_description":"We asked you what makes the perfect Election Leaflet. Our survey results provide unmissable insight for anyone hoping to bring voters onside","og_url":"https:\/\/www.solopress.com\/blog\/es\/inspiracion-para-imprimir\/el-panfleto-electoral-perfecto\/","og_site_name":"The Latest Print and Design News | Solopress","article_publisher":"https:\/\/www.facebook.com\/Solopress","article_published_time":"2021-03-26T11:24:58+00:00","article_modified_time":"2021-06-24T15:16:28+00:00","og_image":[{"width":900,"height":675,"url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2021\/03\/Blog-tile-election-01.jpg","type":"image\/jpeg"}],"author":"Danny Powell","twitter_card":"summary_large_image","twitter_creator":"@solopress","twitter_site":"@solopress","twitter_misc":{"Escrito por":"Danny Powell","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.solopress.com\/blog\/print-inspiration\/the-perfect-election-leaflet\/#article","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/print-inspiration\/the-perfect-election-leaflet\/"},"author":{"name":"Danny Powell","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/0937555a256c22f94400f4b7e2329c09"},"headline":"How to design the perfect Election Leaflet that voters can\u2019t ignore!","datePublished":"2021-03-26T11:24:58+00:00","dateModified":"2021-06-24T15:16:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/print-inspiration\/the-perfect-election-leaflet\/"},"wordCount":1792,"publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/print-inspiration\/the-perfect-election-leaflet\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2021\/03\/Blog-tile-election-01.jpg","keywords":["Flyers &amp; Leaflets"],"articleSection":["Print Inspiration"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.solopress.com\/blog\/print-inspiration\/the-perfect-election-leaflet\/","url":"https:\/\/www.solopress.com\/blog\/print-inspiration\/the-perfect-election-leaflet\/","name":"C\u00f3mo dise\u00f1ar el folleto electoral perfecto que los votantes no puedan ignorar | Solopress Espa\u00f1a","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/print-inspiration\/the-perfect-election-leaflet\/#primaryimage"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/print-inspiration\/the-perfect-election-leaflet\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2021\/03\/Blog-tile-election-01.jpg","datePublished":"2021-03-26T11:24:58+00:00","dateModified":"2021-06-24T15:16:28+00:00","description":"Le hemos preguntado cu\u00e1l es el folleto electoral perfecto. Los resultados de nuestra encuesta ofrecen una visi\u00f3n imperdible para cualquiera que desee atraer a los votantes.","breadcrumb":{"@id":"https:\/\/www.solopress.com\/blog\/print-inspiration\/the-perfect-election-leaflet\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solopress.com\/blog\/print-inspiration\/the-perfect-election-leaflet\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.solopress.com\/blog\/print-inspiration\/the-perfect-election-leaflet\/#primaryimage","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2021\/03\/Blog-tile-election-01.jpg","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2021\/03\/Blog-tile-election-01.jpg","width":900,"height":675,"caption":"Perfect Election Leaflet"},{"@type":"BreadcrumbList","@id":"https:\/\/www.solopress.com\/blog\/print-inspiration\/the-perfect-election-leaflet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.solopress.com\/blog\/"},{"@type":"ListItem","position":2,"name":"How to design the perfect Election Leaflet that voters can\u2019t ignore!"}]},{"@type":"WebSite","@id":"https:\/\/www.solopress.com\/blog\/#website","url":"https:\/\/www.solopress.com\/blog\/","name":"\u00daltimas noticias sobre impresi\u00f3n y dise\u00f1o | Solopress","description":"","publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solopress.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.solopress.com\/blog\/#organization","name":"Solopress","url":"https:\/\/www.solopress.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","width":428,"height":88,"caption":"Solopress"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Solopress","https:\/\/x.com\/solopress","https:\/\/instagram.com\/solopress\/","https:\/\/www.linkedin.com\/company\/solopress","https:\/\/uk.pinterest.com\/solopress\/","https:\/\/www.youtube.com\/user\/solopress"]},{"@type":"Person","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/0937555a256c22f94400f4b7e2329c09","name":"Danny Powell","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","caption":"Danny Powell"},"description":"Con m\u00e1s de dos d\u00e9cadas de experiencia en marketing, Danny Powell es redactor jefe de Solopress, una de las principales imprentas en l\u00ednea del Reino Unido. Tras haber trabajado en los departamentos de compras, agencias y ventas del sector de la impresi\u00f3n, aporta una perspectiva muy completa a sus escritos sobre impresi\u00f3n, dise\u00f1o y sostenibilidad.","url":"https:\/\/www.solopress.com\/blog\/es\/author\/danny-powell\/"}]}},"jetpack_featured_media_url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2021\/03\/Blog-tile-election-01.jpg","_links":{"self":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts\/70633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/comments?post=70633"}],"version-history":[{"count":5,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts\/70633\/revisions"}],"predecessor-version":[{"id":71371,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts\/70633\/revisions\/71371"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/media\/70648"}],"wp:attachment":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/media?parent=70633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/categories?post=70633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/tags?post=70633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}