{"id":71826,"date":"2022-01-20T09:15:52","date_gmt":"2022-01-20T09:15:52","guid":{"rendered":"https:\/\/www.solopress.com\/blog\/?p=71826"},"modified":"2023-10-07T11:11:41","modified_gmt":"2023-10-07T10:11:41","slug":"guitarras-ancoats","status":"publish","type":"post","link":"https:\/\/www.solopress.com\/blog\/es\/entrepreneurs\/ancoats-guitars\/","title":{"rendered":"Historias de empresas emergentes: Presentaci\u00f3n de Ancoats Guitars"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p>La impresi\u00f3n es una herramienta eficaz para las empresas en sus comienzos. Les ayuda a decir al mundo que han llegado, a establecer su identidad y a cultivar un sentido de profesionalidad y validez en torno a su marca. Para 2022, decidimos que quer\u00edamos seguir a una nueva empresa para ver c\u00f3mo la impresi\u00f3n pod\u00eda apoyar sus esfuerzos en los primeros d\u00edas. Nos pusimos en contacto con Ancoats Guitars, fabricante de guitarras el\u00e9ctricas artesanales de Manchester.<\/p>\n<h2><strong>Presentaci\u00f3n de Ancoats Guitars<\/strong><\/h2>\n<p>Ancoats Guitars es el nombre comercial de Dave Roberts, que empez\u00f3 a juguetear con las guitarras como hobby hace casi 25 a\u00f1os. Desde hace seis a\u00f1os, construye guitarras desde cero. Ahora que ha reunido los conocimientos, el equipo y el espacio de trabajo necesarios para fabricar instrumentos de gama alta a medida, Dave puede por fin poner en marcha su sue\u00f1o y fabricar sus guitarras.<br \/>\n<a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/01\/Ancoats-Guitars-New-Islington.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-71830 aligncenter\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/01\/Ancoats-Guitars-New-Islington.jpg\" alt=\"\" width=\"280\" height=\"383\" \/><\/a><br \/>\n2022 ser\u00e1 el a\u00f1o en que Ancoats Guitars se convierta en una empresa manufacturera de pleno derecho, y Solopress seguir\u00e1 cada paso del camino, informando sobre los altibajos de la puesta en marcha de una nueva marca, y transmitiendo multitud de consejos sobre c\u00f3mo la impresi\u00f3n puede dar el pistoletazo de salida a una nueva marca.<\/p>\n<h3><strong>\u00bfPor qu\u00e9 Ancoats?<\/strong><\/h3>\n<p>Dave ha decidido bautizar la empresa con el nombre de la zona de Manchester donde tiene su taller. Ancoats es un antiguo centro de la industria textil de la ciudad, que surgi\u00f3 durante la revoluci\u00f3n industrial y prosper\u00f3 hasta bien entrado el siglo pasado.<a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/01\/Ancoats-Buildings.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-71833 aligncenter\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/01\/Ancoats-Buildings.jpg\" alt=\"\" width=\"303\" height=\"415\" \/><\/a><\/p>\n<p>La zona es famosa por sus imponentes molinos de ladrillo rojo, aunque en la actualidad la mayor\u00eda se han convertido en pisos de lujo y modernos apartamentos tipo loft. El taller de Dave es un contenedor de transporte reutilizado, muy acorde con el pasado industrial de la zona.<br \/>\n<a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/01\/Ancoats-Guitars-Workshop.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-71831 aligncenter\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/01\/Ancoats-Guitars-Workshop.jpg\" alt=\"\" width=\"303\" height=\"416\" \/><\/a><\/p>\n<p>Las propias guitarras tambi\u00e9n llevar\u00e1n nombres que hacen referencia a zonas de la ciudad. La New Islington es el primer modelo que se ofrecer\u00e1 con la NQ, que representa el Northern Quarter de Manchester, a punto de finalizar su desarrollo.<\/p>\n<h2><strong>Retos para una nueva marca de guitarras<\/strong><\/h2>\n<p>Una pregunta importante al inicio de cualquier empresa comercial es: \u00bfqu\u00e9 diferencia a este producto de la competencia?<\/p>\n<p>Cuando se trata de establecer una nueva marca de guitarras el\u00e9ctricas, hay dos elefantes muy imponentes en la habitaci\u00f3n.<\/p>\n<p>La primera es que las guitarras el\u00e9ctricas de Extremo Oriente, que siempre han sido mucho m\u00e1s baratas que las nacionales, se est\u00e1n poniendo al d\u00eda en t\u00e9rminos de calidad.<\/p>\n<p>La segunda es que los guitarristas el\u00e9ctricos, a pesar de sus posturas de rock and roll, son un grupo sorprendentemente conservador. Los dise\u00f1os y las marcas que se hicieron populares en los a\u00f1os 50 siguen dominando el mercado.<\/p>\n<h2><strong>La respuesta de Ancoats<\/strong><\/h2>\n<p>Ancoats Guitars es capaz de superar estos retos con un pu\u00f1ado de argumentos de venta \u00fanicos que diferencian el producto y atraen fuertemente al mercado objetivo. Entre ellos se encuentran la calidad de fabricaci\u00f3n, el dise\u00f1o exclusivo, la personalizaci\u00f3n y un esp\u00edritu empresarial respetuoso con el medio ambiente.<\/p>\n<h3><strong>Calidad de construcci\u00f3n<\/strong><\/h3>\n<p>Lo primero y m\u00e1s importante es la calidad de los instrumentos. Aunque las guitarras fabricadas en serie han avanzado mucho en los \u00faltimos a\u00f1os, la calidad de la construcci\u00f3n artesanal sigue siendo insuperable. Solo los constructores expertos, ya sea con sus propias marcas o construyendo modelos Custom Shop de gama alta para las grandes marcas, pueden dar este nivel de cuidado y atenci\u00f3n a cada instrumento.<br \/>\n<a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/01\/Ancoats-Guitars-Bench.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-71836 aligncenter\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/01\/Ancoats-Guitars-Bench.jpg\" alt=\"\" width=\"618\" height=\"305\" \/><\/a><br \/>\nAdem\u00e1s del minucioso trabajo en madera que se realiza en Ancoats Guitars, Dave utiliza los tipos de madera, herrajes, componentes el\u00e9ctricos y acabados de la m\u00e1xima calidad que los guitarristas valoran.<\/p>\n<h3><strong>Dise\u00f1o atrevido, anclado en la tradici\u00f3n<\/strong><\/h3>\n<p>Pero, \u00bfqu\u00e9 pasa con los compradores de guitarras conservadores y su fidelidad a los dise\u00f1os originales estadounidenses? \u00bfC\u00f3mo puede alguien innovar y seguir apelando a esa est\u00e9tica?<\/p>\n<p>Sin duda es un reto complicado, pero las guitarras Ancoats caminan sobre una l\u00ednea perfecta entre los estilos moderno y retro, dando como resultado dise\u00f1os \u00fanicos y llamativos que a\u00fan se sientan c\u00f3modamente entre los grandes del pasado.<br \/>\n<a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/01\/Ancoats-3-guitars.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-71838 aligncenter\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/01\/Ancoats-3-guitars.png\" alt=\"\" width=\"1299\" height=\"735\" \/><\/a>Los dise\u00f1os de Dave mezclan la est\u00e9tica de la edad de oro de la producci\u00f3n de guitarras americanas con las influencias europeas de los movimientos Art D\u00e9co y Bauhaus. El resultado puede verse en el modelo debut de Ancoats Guitars, la New Islington. Mientras que los aficionados a la guitarra pueden encontrar un toque de Rickenbacker en los cuernos, de Gibson en el cuerpo inferior, de Fender en los contornos de la caja y de Gretsch en los herrajes, las guitarras Ancoats tienen un car\u00e1cter distinto, con motivos Art Dec\u00f3 en el golpeador y las formas de la pala.<\/p>\n<h3><strong>Personalizaci\u00f3n - no est\u00e1ndar como est\u00e1ndar<\/strong><\/h3>\n<p>Los guitarristas pueden ser muy exigentes con todos los aspectos de sus guitarras. La forma del m\u00e1stil y el contorno del cuerpo influyen en el tacto del instrumento. Los herrajes, como las clavijas de afinaci\u00f3n (o \"clavijeros\") y la disposici\u00f3n del puente, donde las cuerdas se anclan al cuerpo, afectan a la fiabilidad y el rendimiento. Los tipos de madera y las pastillas (dispositivos magn\u00e9ticos que convierten las vibraciones de las cuerdas en una se\u00f1al el\u00e9ctrica) influyen mucho en el sonido.<\/p>\n<p>Aunque puede resultar dif\u00edcil para un guitarrista quisquilloso encontrar la guitarra perfecta en el mercado, el proceso de pedido en ancoatsguitars.co.uk permite al comprador especificar hasta el \u00faltimo detalle, lo que garantiza la entrega de la guitarra de sus sue\u00f1os. Adem\u00e1s de los tipos de personalizaci\u00f3n que ofrecen la mayor\u00eda de los constructores, Dave tambi\u00e9n ofrece la opci\u00f3n poco frecuente del \"tallado alem\u00e1n\". Se trata de un chafl\u00e1n curvado alrededor del borde del cuerpo, recuperado recientemente por el constructor de guitarras estadounidense Fano.<\/p>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/01\/Ancoats-Guitars-German-Carve.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-71839 aligncenter\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/01\/Ancoats-Guitars-German-Carve.jpg\" alt=\"\" width=\"633\" height=\"476\" \/><\/a><\/p>\n<p>Los acabados que se ofrecen van m\u00e1s all\u00e1 de la gama tradicional de colores de guitarra. Si encuentra un tono que le gusta y que ofrece <a href=\"https:\/\/www.littlegreene.eu\/paint\/colour\" target=\"_blank\" rel=\"noopener noreferrer\">Peque\u00f1a empresa de pintura verde<\/a> o como tinte para madera de <a href=\"https:\/\/www.crimsonguitars.com\/products\/stunning-stains\" target=\"_blank\" rel=\"noopener noreferrer\">Guitarras Crimson<\/a>Ancoats Guitars acabar\u00e1 su guitarra en ese color.<\/p>\n<h3><strong>Valores ecol\u00f3gicos<\/strong><\/h3>\n<p>Dave es un apasionado del medio ambiente, por lo que cada guitarra Ancoats se construye con madera sostenible. Dado que en el siglo pasado la construcci\u00f3n de guitarras se basaba en maderas tropicales como el palisandro y la caoba, la madera de origen responsable se ha convertido en un factor importante para los constructores y compradores de guitarras. Dave trabaja con G&amp;S Specialist Timber, en el Distrito de los Lagos, para conseguir las maderas de mejor calidad minimizando el impacto sobre el planeta.<\/p>\n<p>La industria de la guitarra tampoco tiene un gran historial en lo que respecta a los materiales de acabado. Los tradicionales y codiciados acabados de nitrocelulosa pueden ser especialmente perjudiciales. A partir de los a\u00f1os setenta, los fabricantes se pasaron a los acabados de poliuretano. Aunque son m\u00e1s baratos y m\u00e1s seguros de aplicar, son esencialmente pl\u00e1sticos, as\u00ed que no son perfectos.<\/p>\n<p>Sin embargo, los acabados utilizados en Ancoats Guitars son todos al agua, lo que significa que son m\u00e1s respetuosos con el medio ambiente y m\u00e1s f\u00e1ciles de retocar si la guitarra recibe un golpe.<\/p>\n<p>Dave tambi\u00e9n ha hecho todo lo posible para asegurarse de que todos sus proveedores sean locales, con el fin de reducir al m\u00ednimo las distancias de entrega. Y, por supuesto, si pides tu guitarra en el Reino Unido, \u00a1no tendr\u00e1 que recorrer medio mundo para llegar hasta ti!<\/p>\n<h2><strong>Contar al mundo<\/strong><\/h2>\n<p>Del mismo modo que una guitarra el\u00e9ctrica necesita un amplificador para transmitir su m\u00fasica, una nueva marca con un mont\u00f3n de puntos de venta incre\u00edbles necesita una estrategia de marketing armoniosa si quiere hacerse o\u00edr.<\/p>\n<figure id=\"attachment_71832\" aria-describedby=\"caption-attachment-71832\" style=\"width: 900px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.youtube.com\/channel\/UCzmX-Up6zWUahmkH1qLkVhQ\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-71832 size-full\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/01\/Dave-Roberts-Ancoats-Guitars-YouTube.jpg\" alt=\"\" width=\"900\" height=\"600\" \/><\/a><figcaption id=\"caption-attachment-71832\" class=\"wp-caption-text\">Puedes ver la demostraci\u00f3n de Dave Ancoats Guitars en su canal de YouTube<\/figcaption><\/figure>\n<p>Adem\u00e1s de un <a href=\"https:\/\/www.ancoatsguitars.co.uk\/\" target=\"_blank\" rel=\"noopener noreferrer\">sitio web muy atractivo<\/a> una red en constante expansi\u00f3n <a href=\"https:\/\/www.youtube.com\/channel\/UCzmX-Up6zWUahmkH1qLkVhQ\" target=\"_blank\" rel=\"noopener noreferrer\">Canal YouTube<\/a> y una creciente variedad de contenidos en las redes sociales, Dave trabajar\u00e1 en estrecha colaboraci\u00f3n con Solopress para crear un impresionante conjunto de material impreso para promocionar Ancoats Guitars.<\/p>\n<h2><strong>Nuevo: Preparar un logotipo para su lanzamiento<\/strong><\/h2>\n<p>Antes de poner en marcha nuestros primeros proyectos de impresi\u00f3n, Dave quer\u00eda trabajar en el logotipo de Ancoats Guitars. Le parec\u00eda importante perfeccionar el dise\u00f1o de la marca antes de lanzarse a una actividad a largo plazo. Esta es una t\u00e1ctica inteligente para cualquier empresa en la c\u00faspide de un gran impulso de marketing, y los artistas de Solopress est\u00e1n siempre aqu\u00ed para ayudar si usted necesita un logotipo desarrollado, ajustado o renderizado en un formato diferente.<\/p>\n<p>Dado que el dise\u00f1o constituye una parte tan importante de la identidad de Ancoats Guitars, era importante que el dise\u00f1o del logotipo cumpliera el mismo est\u00e1ndar. Dave trabaj\u00f3 con nuestro dise\u00f1ador para desarrollar el logotipo de Ancoats Guitars conservando su visi\u00f3n original. El resultado es un conjunto de iteraciones del logotipo que funcionar\u00e1n en pantalla, en papel y en los propios instrumentos, incluida una marca denominativa, un c\u00edrculo para las redes sociales y una calcoman\u00eda para el clavijero de la guitarra.<br \/>\n<a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/01\/Ancoats-Guitars-Logos.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-71829 aligncenter\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/01\/Ancoats-Guitars-Logos.jpg\" alt=\"\" width=\"900\" height=\"248\" \/><\/a><\/p>\n<p>Si su logotipo necesita un poco de trabajo, el primer paso es ponerse en contacto con nosotros a trav\u00e9s de <a href=\"https:\/\/www.solopress.com\/blog\/es\/contact-us\/\" target=\"_blank\" rel=\"noopener noreferrer\">Chat en directo<\/a>Correo electr\u00f3nico <a href=\"mailto:info@solopress.com\" target=\"_blank\" rel=\"noopener noreferrer\">info@solopress.com<\/a> o llame al 01702 7460047, y le pondremos en contacto con un artista de nuestro equipo de dise\u00f1o.<\/p>\n<h2><strong>Un a\u00f1o apasionante<\/strong><\/h2>\n<p>Con Dave a bordo y el nuevo logotipo luciendo genial en <a href=\"https:\/\/www.ancoatsguitars.co.uk\/\" target=\"_blank\" rel=\"noopener noreferrer\">ancoatsguitars.es<\/a>Estamos impacientes por ponernos manos a la obra y asegurarnos de que la impresi\u00f3n desempe\u00f1e un papel eficaz en la consolidaci\u00f3n de Ancoats Guitars como marca emergente. Siga esta historia del blog en <a href=\"https:\/\/www.solopress.com\/blog\/es\/start-up-stories\/\" target=\"_blank\" rel=\"noopener noreferrer\">solopress.com\/blog\/start-up-stories<\/a> para recibir actualizaciones peri\u00f3dicas a medida que avance el a\u00f1o.<\/p>","protected":false},"excerpt":{"rendered":"<p>Print provides an effective toolkit for businesses when they first start out. It helps them tell the world they have arrived, establish their identity and cultivate a sense of professionalism and validity around their brand. For 2022, we decided we wanted to follow a new business to see how print could support their efforts through [&hellip;]<\/p>\n","protected":false},"author":134,"featured_media":71834,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[955],"tags":[],"class_list":{"0":"post-71826","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-entrepreneurs"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Start-up Stories: Introducing Ancoats Guitars - Solopress UK<\/title>\n<meta name=\"description\" content=\"This year, we\u2019re following Ancoats Guitars, a new electric guitar brand. We\u2019ll report on the first year in business &amp; share tips on print.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solopress.com\/blog\/es\/emprendedores\/guitarras-ancoats\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Start-up Stories: Introducing Ancoats Guitars - Solopress UK\" \/>\n<meta property=\"og:description\" content=\"This year, we\u2019re following Ancoats Guitars, a new electric guitar brand. We\u2019ll report on the first year in business &amp; share tips on print.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solopress.com\/blog\/es\/emprendedores\/guitarras-ancoats\/\" \/>\n<meta property=\"og:site_name\" content=\"The Latest Print and Design News | Solopress\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Solopress\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-20T09:15:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-07T10:11:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/01\/Ancoats-Guitars-Header.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Danny Powell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@solopress\" \/>\n<meta name=\"twitter:site\" content=\"@solopress\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Danny Powell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/ancoats-guitars\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/ancoats-guitars\\\/\"},\"author\":{\"name\":\"Danny Powell\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/0937555a256c22f94400f4b7e2329c09\"},\"headline\":\"Start-up Stories: Introducing Ancoats Guitars\",\"datePublished\":\"2022-01-20T09:15:52+00:00\",\"dateModified\":\"2023-10-07T10:11:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/ancoats-guitars\\\/\"},\"wordCount\":1437,\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/ancoats-guitars\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Ancoats-Guitars-Header.jpg\",\"articleSection\":[\"Entrepreneurs\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/ancoats-guitars\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/ancoats-guitars\\\/\",\"name\":\"Start-up Stories: Introducing Ancoats Guitars - Solopress UK\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/ancoats-guitars\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/ancoats-guitars\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Ancoats-Guitars-Header.jpg\",\"datePublished\":\"2022-01-20T09:15:52+00:00\",\"dateModified\":\"2023-10-07T10:11:41+00:00\",\"description\":\"This year, we\u2019re following Ancoats Guitars, a new electric guitar brand. We\u2019ll report on the first year in business & share tips on print.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/ancoats-guitars\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/ancoats-guitars\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/ancoats-guitars\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Ancoats-Guitars-Header.jpg\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Ancoats-Guitars-Header.jpg\",\"width\":900,\"height\":675,\"caption\":\"Ancoats Guitars. Part 2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/ancoats-guitars\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Start-up Stories: Introducing Ancoats Guitars\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"name\":\"The Latest Print and Design News | Solopress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\",\"name\":\"Solopress\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"width\":428,\"height\":88,\"caption\":\"Solopress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Solopress\",\"https:\\\/\\\/x.com\\\/solopress\",\"https:\\\/\\\/instagram.com\\\/solopress\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/solopress\",\"https:\\\/\\\/uk.pinterest.com\\\/solopress\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/solopress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/0937555a256c22f94400f4b7e2329c09\",\"name\":\"Danny Powell\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"caption\":\"Danny Powell\"},\"description\":\"With over two decades in marketing, Danny Powell is a Senior Copywriter at Solopress, one of the UK\u2019s leading online printers. Having worked on the print buying, agency and sales sides of the industry, he brings a well-rounded perspective to his writing on print, design and sustainability.\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/es\\\/author\\\/danny-powell\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Historias de empresas emergentes: Presentaci\u00f3n de Ancoats Guitars - Solopress Espa\u00f1a","description":"Este a\u00f1o seguimos a Ancoats Guitars, una nueva marca de guitarras el\u00e9ctricas. Informaremos sobre su primer a\u00f1o de actividad y compartiremos consejos sobre impresi\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solopress.com\/blog\/es\/emprendedores\/guitarras-ancoats\/","og_locale":"es_ES","og_type":"article","og_title":"Start-up Stories: Introducing Ancoats Guitars - Solopress UK","og_description":"This year, we\u2019re following Ancoats Guitars, a new electric guitar brand. We\u2019ll report on the first year in business & share tips on print.","og_url":"https:\/\/www.solopress.com\/blog\/es\/emprendedores\/guitarras-ancoats\/","og_site_name":"The Latest Print and Design News | Solopress","article_publisher":"https:\/\/www.facebook.com\/Solopress","article_published_time":"2022-01-20T09:15:52+00:00","article_modified_time":"2023-10-07T10:11:41+00:00","og_image":[{"width":900,"height":675,"url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/01\/Ancoats-Guitars-Header.jpg","type":"image\/jpeg"}],"author":"Danny Powell","twitter_card":"summary_large_image","twitter_creator":"@solopress","twitter_site":"@solopress","twitter_misc":{"Escrito por":"Danny Powell","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/ancoats-guitars\/#article","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/ancoats-guitars\/"},"author":{"name":"Danny Powell","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/0937555a256c22f94400f4b7e2329c09"},"headline":"Start-up Stories: Introducing Ancoats Guitars","datePublished":"2022-01-20T09:15:52+00:00","dateModified":"2023-10-07T10:11:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/ancoats-guitars\/"},"wordCount":1437,"publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/ancoats-guitars\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/01\/Ancoats-Guitars-Header.jpg","articleSection":["Entrepreneurs"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/ancoats-guitars\/","url":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/ancoats-guitars\/","name":"Historias de empresas emergentes: Presentaci\u00f3n de Ancoats Guitars - Solopress Espa\u00f1a","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/ancoats-guitars\/#primaryimage"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/ancoats-guitars\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/01\/Ancoats-Guitars-Header.jpg","datePublished":"2022-01-20T09:15:52+00:00","dateModified":"2023-10-07T10:11:41+00:00","description":"Este a\u00f1o seguimos a Ancoats Guitars, una nueva marca de guitarras el\u00e9ctricas. Informaremos sobre su primer a\u00f1o de actividad y compartiremos consejos sobre impresi\u00f3n.","breadcrumb":{"@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/ancoats-guitars\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solopress.com\/blog\/entrepreneurs\/ancoats-guitars\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/ancoats-guitars\/#primaryimage","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/01\/Ancoats-Guitars-Header.jpg","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/01\/Ancoats-Guitars-Header.jpg","width":900,"height":675,"caption":"Ancoats Guitars. Part 2"},{"@type":"BreadcrumbList","@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/ancoats-guitars\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.solopress.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Start-up Stories: Introducing Ancoats Guitars"}]},{"@type":"WebSite","@id":"https:\/\/www.solopress.com\/blog\/#website","url":"https:\/\/www.solopress.com\/blog\/","name":"\u00daltimas noticias sobre impresi\u00f3n y dise\u00f1o | Solopress","description":"","publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solopress.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.solopress.com\/blog\/#organization","name":"Solopress","url":"https:\/\/www.solopress.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","width":428,"height":88,"caption":"Solopress"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Solopress","https:\/\/x.com\/solopress","https:\/\/instagram.com\/solopress\/","https:\/\/www.linkedin.com\/company\/solopress","https:\/\/uk.pinterest.com\/solopress\/","https:\/\/www.youtube.com\/user\/solopress"]},{"@type":"Person","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/0937555a256c22f94400f4b7e2329c09","name":"Danny Powell","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","caption":"Danny Powell"},"description":"Con m\u00e1s de dos d\u00e9cadas de experiencia en marketing, Danny Powell es redactor jefe de Solopress, una de las principales imprentas en l\u00ednea del Reino Unido. Tras haber trabajado en los departamentos de compras, agencias y ventas del sector de la impresi\u00f3n, aporta una perspectiva muy completa a sus escritos sobre impresi\u00f3n, dise\u00f1o y sostenibilidad.","url":"https:\/\/www.solopress.com\/blog\/es\/author\/danny-powell\/"}]}},"jetpack_featured_media_url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/01\/Ancoats-Guitars-Header.jpg","_links":{"self":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts\/71826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/comments?post=71826"}],"version-history":[{"count":5,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts\/71826\/revisions"}],"predecessor-version":[{"id":71851,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts\/71826\/revisions\/71851"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/media\/71834"}],"wp:attachment":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/media?parent=71826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/categories?post=71826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/tags?post=71826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}