{"id":74268,"date":"2023-07-17T10:12:28","date_gmt":"2023-07-17T09:12:28","guid":{"rendered":"https:\/\/www.solopress.com\/blog\/?p=74268"},"modified":"2023-07-17T10:12:28","modified_gmt":"2023-07-17T09:12:28","slug":"historias-de-clientes-solopress-design-serves-chris-a-winner","status":"publish","type":"post","link":"https:\/\/www.solopress.com\/blog\/es\/customer-stories\/customer-stories-solopress-design-serves-chris-a-winner\/","title":{"rendered":"Historias de clientes: Solopress Design sirve a Chris un ganador"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p>Chris Phillips utiliz\u00f3 <a href=\"https:\/\/www.solopress.com\/blog\/es\/design\/\" target=\"_blank\" rel=\"noopener\">Dise\u00f1o Solopress<\/a> para ayudarle a superar su objetivo de recaudaci\u00f3n de fondos para organizaciones ben\u00e9ficas dedicadas a la salud mental.<\/p>\n<p>Tras soportar un his <a href=\"https:\/\/www.echo-news.co.uk\/sport\/23629913.tennis-ace-chris-raises-14k-mind-playing-11-hours\/\" target=\"_blank\" rel=\"noopener\">Partido de tenis de 11 horas<\/a>Chris recaud\u00f3 la incre\u00edble cifra de 14.000 libras esterlinas para la organizaci\u00f3n ben\u00e9fica MIND, dedicada a la salud mental.<\/p>\n<p>Con Wimbledon en marcha, Chris se inspir\u00f3 en el hist\u00f3rico <a href=\"https:\/\/olympics.com\/en\/news\/longest-tennis-match-history-grand-slam-record\" target=\"_blank\" rel=\"noopener\">el partido de tenis m\u00e1s largo de la historia<\/a>, disputado en la pista de hierba en 2010, entre Nicolas Mahut y John Isner. Se jug\u00f3 durante tres d\u00edas con un marcador final de 6-4,3-6,6-7,7-6,70-68.<\/p>\n<h2><strong>Punto de ruptura<\/strong><\/h2>\n<p>Para este reto, quer\u00eda un poco de impresi\u00f3n para impulsar su evento y reconocer a sus patrocinadores.<\/p>\n<p>Sin embargo, sin ninguna experiencia en la creaci\u00f3n de material gr\u00e1fico para impresi\u00f3n, Chris se puso en contacto con nuestro equipo de dise\u00f1o de Solopress para que le dieran una soluci\u00f3n ganadora.<\/p>\n<p>dijo Chris: \"No ten\u00eda ni idea del dise\u00f1o de nuestro <a href=\"https:\/\/www.solopress.com\/blog\/es\/banners\/\" target=\"_blank\" rel=\"noopener\">Banner<\/a> o <a href=\"https:\/\/www.solopress.com\/blog\/es\/folletos-volantes\/\" target=\"_blank\" rel=\"noopener\">Folletos<\/a>. Lo \u00fanico que sab\u00eda era que necesit\u00e1bamos una pancarta con nuestros patrocinadores.<\/p>\n<p>\"Le expliqu\u00e9 para qu\u00e9 era mi impresi\u00f3n y qu\u00e9 necesit\u00e1bamos, luego le envi\u00e9 a Glenn algunas fotos para que \u00e9l hiciera el resto\".<\/p>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/07\/358122874_10160700240893584_243847431872458396_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-74273\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/07\/358122874_10160700240893584_243847431872458396_n.jpg\" alt=\"\" width=\"900\" height=\"675\" \/><\/a><\/p>\n<h2><strong>Gran servicio<\/strong><\/h2>\n<p>Chris trabaj\u00f3 en su obra de arte con nuestro talentoso dise\u00f1ador interno, Glenn. El proceso fue sencillo.<\/p>\n<p>En primer lugar, se conect\u00f3 a Solopress Design y rellen\u00f3 el formulario en l\u00ednea. A continuaci\u00f3n, carg\u00f3 todos los archivos relevantes que ten\u00eda para ayudar a Glenn a iniciar el dise\u00f1o.<\/p>\n<p>Con el proceso de dise\u00f1o en marcha, Glenn y Chris desarrollaron sus ideas por correo electr\u00f3nico. Sin embargo, los clientes tambi\u00e9n pueden solicitar hablar con un dise\u00f1ador por tel\u00e9fono si as\u00ed lo prefieren.<\/p>\n<p>dijo Chris: \"Ten\u00eda un logotipo para el evento y los logotipos de todos mis patrocinadores que pas\u00e9 por Solopress Design. El plazo de entrega para recibir mi Banner fue rapid\u00edsimo\".<\/p>\n<p>La creaci\u00f3n de material gr\u00e1fico a trav\u00e9s de Solopress Design le da acceso a nuestro equipo interno especializado. Chris trabaj\u00f3 estrechamente con Glenn para crear algo que realmente elevara su recaudaci\u00f3n de fondos.<\/p>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/07\/358097904_10160700240578584_1308242705040929179_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-74275\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/07\/358097904_10160700240578584_1308242705040929179_n.jpg\" alt=\"\" width=\"900\" height=\"473\" \/><\/a><\/p>\n<p>Glenn a\u00f1adi\u00f3: \"Fue incre\u00edblemente f\u00e1cil tratar con Chris. Le hice algunas preguntas para aclarar lo que quer\u00eda y asegurarme de que est\u00e1bamos de acuerdo.<\/p>\n<p>\"Dise\u00f1amos la pancarta y los folletos de Chris completamente desde cero. Le pregunt\u00e9 por sus objetivos y su visi\u00f3n de los productos finales y a partir de ah\u00ed trabajamos.<\/p>\n<p>\"Confi\u00f3 plenamente en nuestro servicio y le gust\u00f3 tanto el primer borrador que lo mand\u00f3 imprimir\".<\/p>\n<p>Solopress Design dispone de cinco niveles de asistencia para que sus ilustraciones est\u00e9n listas para imprimir. Los cinco niveles son:<\/p>\n<ul>\n<li>Modificaciones: Ya tiene su dise\u00f1o y necesita peque\u00f1os cambios.<\/li>\n<li>Maquetaci\u00f3n: Sabe lo que quiere pero necesita ayuda para producirlo.<\/li>\n<li>Recrear: Nuestro equipo de dise\u00f1o recrear\u00e1 lo que ha perdido.<\/li>\n<li>Dise\u00f1o: Acons\u00e9jenos sobre sus necesidades de dise\u00f1o y nosotros haremos el resto.<\/li>\n<li>Dise\u00f1o Plus: Un servicio integral de dise\u00f1o, desde el concepto hasta la impresi\u00f3n.<\/li>\n<\/ul>\n<p>Glenn a\u00f1ade: \"Solopress Design puede ayudar a los clientes de muchas maneras.<\/p>\n<p>\"Por ejemplo, si un cliente elige Dise\u00f1o Plus, lo \u00fanico que necesitar\u00edamos de \u00e9l es un objetivo general del producto final y entonces empezar\u00edamos el dise\u00f1o desde cero. Esa opci\u00f3n permite a los clientes dar una idea b\u00e1sica de lo que quieren y para qu\u00e9 sirve y luego partir\u00edamos de ah\u00ed\".<\/p>\n<h2><strong>Un golpe de brillantez<\/strong><\/h2>\n<p>Chris hab\u00eda propuesto a sus patrocinadores que su marca recibir\u00eda cobertura televisiva en ITV, cobertura en prensa a trav\u00e9s del Southend Echo y una mayor exposici\u00f3n a trav\u00e9s de las redes sociales.<\/p>\n<p>Esto significaba que el Banner ten\u00eda que difundir claramente a los patrocinadores para que pudieran ser vistos durante todo el gran d\u00eda.<\/p>\n<p>Como reportero del Southend Echo, Chris sab\u00eda que programar el partido antes de Wimbledon y de la temporada de f\u00fatbol ser\u00eda un gran acierto.<\/p>\n<p>Chris consigui\u00f3 que nombres como Kevin Maher, Neil Harris y Steve Tilson saltaran a la cancha en nombre de la salud mental.<\/p>\n<p>Cambiando de pareja cada 30 minutos, Chris confi\u00f3 en la generosidad de muchos voluntarios para superar la l\u00ednea de meta.<\/p>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/07\/358129696_10160700239443584_154591227692812643_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-74272\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/07\/358129696_10160700239443584_154591227692812643_n.jpg\" alt=\"\" width=\"900\" height=\"675\" \/><\/a><\/p>\n<h2><strong>\u00bfC\u00f3mo impuls\u00f3 Solopress Design la recaudaci\u00f3n de fondos de Chris?<\/strong><\/h2>\n<p>Los folletos y las pancartas contribuyen sin duda a que su campa\u00f1a de recaudaci\u00f3n de fondos sea un \u00e9xito, pero la impresi\u00f3n de Chris realmente ayud\u00f3 a que la pelota siguiera rodando.<\/p>\n<p>Con la temporada de tenis ya en pleno apogeo, Chris asisti\u00f3 a las competiciones hermanas de Wimbledon, Queen's y el Abierto de Eastbourne, para ayudar a recabar apoyos.<\/p>\n<p>Chris a\u00f1adi\u00f3: \"Nuestro folleto fue fant\u00e1stico, nos permiti\u00f3 dar a la gente informaci\u00f3n en sus manos para que vieran lo que hac\u00edamos.<\/p>\n<p>\"En el Open de Eastbourne conseguimos un fant\u00e1stico premio en la rifa de mi folleto. Uno de los vendedores ofreci\u00f3 como premio cualquier raqueta de su p\u00e1gina web, \u00a1que era bastante cara!\".<\/p>\n<p>Imperdible, Banner tuvo tal acogida en la pista que \u00a1har\u00e1 un bis!<\/p>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/07\/358077544_10160700240878584_1458416757843866132_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-74274\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/07\/358077544_10160700240878584_1458416757843866132_n.jpg\" alt=\"\" width=\"900\" height=\"450\" \/><\/a><\/p>\n<p>dijo Chris: \"Aunque mi Banner se cre\u00f3 exclusivamente para este evento puntual, recibi\u00f3 tantos elogios de la gente que va a volver a la pista\".<\/p>\n<p>En general, el estampado de Chris result\u00f3 ser un acierto.<\/p>\n<p>Y a\u00f1adi\u00f3: \"Mi impresi\u00f3n ayud\u00f3 mucho a la recaudaci\u00f3n de fondos. Los folletos que pod\u00edamos repartir ese d\u00eda y los c\u00f3digos QR que llev\u00e1bamos permit\u00edan a la gente donar con boletos de la rifa si no llevaban dinero en efectivo\".<\/p>\n<p>\"Les dio una verdadera sensaci\u00f3n de profesionalidad ese d\u00eda, lo que satisfizo a nuestros patrocinadores\".<\/p>\n<h2><strong>Punto del campeonato<\/strong><\/h2>\n<p>Al principio, Chris no estaba seguro de cu\u00e1nto recaudar\u00eda este evento. Siendo un recaudador de fondos experimentado, cre\u00eda que su marat\u00f3n de tenis podr\u00eda rondar las 5.000 libras.<\/p>\n<p>Chris ha recaudado un total de 14.000 libras. Gracias a su patrocinador principal, Rickard Luckin, su evento tambi\u00e9n atrajo la atenci\u00f3n del mundo del tenis, ya que Judy Murray, Sue Barker y Ryan Peniston contribuyeron a la recaudaci\u00f3n de fondos.<\/p>\n<p>Martina Navratilova, varias veces campeona de Wimbledon, comparti\u00f3 su apoyo en las redes sociales, mientras que Sir Andy Murray don\u00f3 una pelota de tenis firmada para la subasta.<\/p>\n<p>Chris a\u00f1adi\u00f3: \"El dinero est\u00e1 muy bien y ha sido incre\u00edble recaudar tanto como lo hemos hecho, pero igual de importante ha sido concienciar tanto como lo hemos hecho para una causa tan importante\".<\/p>\n<h2><strong>Juego, set, partido<\/strong><\/h2>\n<p>Un dise\u00f1o gr\u00e1fico experto es esencial para obtener resultados profesionales de su impresi\u00f3n. Si no tiene acceso a esas habilidades, nuestro servicio de dise\u00f1o est\u00e1 aqu\u00ed para ayudarle a producir algo especial.<\/p>\n<p>Desde modificaciones hasta creaciones completas, nuestros cinco niveles de asistencia pueden hacer que su dise\u00f1o supere la l\u00ednea.<\/p>","protected":false},"excerpt":{"rendered":"<p>Chris Phillips used Solopress Design to help smash his fundraising target as he raised money for mental health charities. After enduring an his 11-hour tennis match, Chris raised an incredible \u00a314,000 for the mental health charity, MIND. With Wimbledon underway, Chris was inspired by the historic longest tennis match ever, played on the grass court [&hellip;]<\/p>\n","protected":false},"author":154,"featured_media":74271,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[557],"tags":[],"class_list":{"0":"post-74268","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-customer-stories"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Customer Stories: Solopress Design Serves Chris A Winner!<\/title>\n<meta name=\"description\" content=\"Solopress Design has five tiers of support to get your artwork print ready. If you need help with your design, fill out our online form.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solopress.com\/blog\/es\/historias-de-clientes\/historias-de-clientes-solopress-design-serves-chris-a-winner\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Customer Stories: Solopress Design Serves Chris A Winner!\" \/>\n<meta property=\"og:description\" content=\"Solopress Design has five tiers of support to get your artwork print ready. If you need help with your design, fill out our online form.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solopress.com\/blog\/es\/historias-de-clientes\/historias-de-clientes-solopress-design-serves-chris-a-winner\/\" \/>\n<meta property=\"og:site_name\" content=\"The Latest Print and Design News | Solopress\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Solopress\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-17T09:12:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/07\/design-service-blog-tennis.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jake Ross\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@solopress\" \/>\n<meta name=\"twitter:site\" content=\"@solopress\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jake Ross\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-solopress-design-serves-chris-a-winner\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-solopress-design-serves-chris-a-winner\\\/\"},\"author\":{\"name\":\"Jake Ross\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/86438061b6921d896a81194a55080684\"},\"headline\":\"Customer Stories: Solopress Design serves Chris a winner!\",\"datePublished\":\"2023-07-17T09:12:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-solopress-design-serves-chris-a-winner\\\/\"},\"wordCount\":1029,\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-solopress-design-serves-chris-a-winner\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/design-service-blog-tennis.jpg\",\"articleSection\":[\"Customer Stories\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-solopress-design-serves-chris-a-winner\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-solopress-design-serves-chris-a-winner\\\/\",\"name\":\"Customer Stories: Solopress Design Serves Chris A Winner!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-solopress-design-serves-chris-a-winner\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-solopress-design-serves-chris-a-winner\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/design-service-blog-tennis.jpg\",\"datePublished\":\"2023-07-17T09:12:28+00:00\",\"description\":\"Solopress Design has five tiers of support to get your artwork print ready. If you need help with your design, fill out our online form.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-solopress-design-serves-chris-a-winner\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-solopress-design-serves-chris-a-winner\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-solopress-design-serves-chris-a-winner\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/design-service-blog-tennis.jpg\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/design-service-blog-tennis.jpg\",\"width\":900,\"height\":675,\"caption\":\"Solopress Design\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-solopress-design-serves-chris-a-winner\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Customer Stories: Solopress Design serves Chris a winner!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"name\":\"The Latest Print and Design News | Solopress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\",\"name\":\"Solopress\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"width\":428,\"height\":88,\"caption\":\"Solopress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Solopress\",\"https:\\\/\\\/x.com\\\/solopress\",\"https:\\\/\\\/instagram.com\\\/solopress\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/solopress\",\"https:\\\/\\\/uk.pinterest.com\\\/solopress\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/solopress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/86438061b6921d896a81194a55080684\",\"name\":\"Jake Ross\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97ff332c68b712fc4f6e179f11f1b65fb3ae3d18ec6c0115eb15220bdbbdf414?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97ff332c68b712fc4f6e179f11f1b65fb3ae3d18ec6c0115eb15220bdbbdf414?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97ff332c68b712fc4f6e179f11f1b65fb3ae3d18ec6c0115eb15220bdbbdf414?s=96&r=g\",\"caption\":\"Jake Ross\"},\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/es\\\/author\\\/jake-ross\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Historias de clientes: Solopress Design sirve a Chris \u00a1Un ganador!","description":"Solopress Design cuenta con cinco niveles de asistencia para que sus dise\u00f1os est\u00e9n listos para imprimir. Si necesita ayuda con su dise\u00f1o, rellene nuestro formulario en l\u00ednea.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solopress.com\/blog\/es\/historias-de-clientes\/historias-de-clientes-solopress-design-serves-chris-a-winner\/","og_locale":"es_ES","og_type":"article","og_title":"Customer Stories: Solopress Design Serves Chris A Winner!","og_description":"Solopress Design has five tiers of support to get your artwork print ready. If you need help with your design, fill out our online form.","og_url":"https:\/\/www.solopress.com\/blog\/es\/historias-de-clientes\/historias-de-clientes-solopress-design-serves-chris-a-winner\/","og_site_name":"The Latest Print and Design News | Solopress","article_publisher":"https:\/\/www.facebook.com\/Solopress","article_published_time":"2023-07-17T09:12:28+00:00","og_image":[{"width":900,"height":675,"url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/07\/design-service-blog-tennis.jpg","type":"image\/jpeg"}],"author":"Jake Ross","twitter_card":"summary_large_image","twitter_creator":"@solopress","twitter_site":"@solopress","twitter_misc":{"Escrito por":"Jake Ross","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-solopress-design-serves-chris-a-winner\/#article","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-solopress-design-serves-chris-a-winner\/"},"author":{"name":"Jake Ross","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/86438061b6921d896a81194a55080684"},"headline":"Customer Stories: Solopress Design serves Chris a winner!","datePublished":"2023-07-17T09:12:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-solopress-design-serves-chris-a-winner\/"},"wordCount":1029,"publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-solopress-design-serves-chris-a-winner\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/07\/design-service-blog-tennis.jpg","articleSection":["Customer Stories"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-solopress-design-serves-chris-a-winner\/","url":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-solopress-design-serves-chris-a-winner\/","name":"Historias de clientes: Solopress Design sirve a Chris \u00a1Un ganador!","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-solopress-design-serves-chris-a-winner\/#primaryimage"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-solopress-design-serves-chris-a-winner\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/07\/design-service-blog-tennis.jpg","datePublished":"2023-07-17T09:12:28+00:00","description":"Solopress Design cuenta con cinco niveles de asistencia para que sus dise\u00f1os est\u00e9n listos para imprimir. Si necesita ayuda con su dise\u00f1o, rellene nuestro formulario en l\u00ednea.","breadcrumb":{"@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-solopress-design-serves-chris-a-winner\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-solopress-design-serves-chris-a-winner\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-solopress-design-serves-chris-a-winner\/#primaryimage","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/07\/design-service-blog-tennis.jpg","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/07\/design-service-blog-tennis.jpg","width":900,"height":675,"caption":"Solopress Design"},{"@type":"BreadcrumbList","@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-solopress-design-serves-chris-a-winner\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.solopress.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Customer Stories: Solopress Design serves Chris a winner!"}]},{"@type":"WebSite","@id":"https:\/\/www.solopress.com\/blog\/#website","url":"https:\/\/www.solopress.com\/blog\/","name":"\u00daltimas noticias sobre impresi\u00f3n y dise\u00f1o | Solopress","description":"","publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solopress.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.solopress.com\/blog\/#organization","name":"Solopress","url":"https:\/\/www.solopress.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","width":428,"height":88,"caption":"Solopress"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Solopress","https:\/\/x.com\/solopress","https:\/\/instagram.com\/solopress\/","https:\/\/www.linkedin.com\/company\/solopress","https:\/\/uk.pinterest.com\/solopress\/","https:\/\/www.youtube.com\/user\/solopress"]},{"@type":"Person","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/86438061b6921d896a81194a55080684","name":"Jake Ross","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97ff332c68b712fc4f6e179f11f1b65fb3ae3d18ec6c0115eb15220bdbbdf414?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97ff332c68b712fc4f6e179f11f1b65fb3ae3d18ec6c0115eb15220bdbbdf414?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97ff332c68b712fc4f6e179f11f1b65fb3ae3d18ec6c0115eb15220bdbbdf414?s=96&r=g","caption":"Jake Ross"},"url":"https:\/\/www.solopress.com\/blog\/es\/author\/jake-ross\/"}]}},"jetpack_featured_media_url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/07\/design-service-blog-tennis.jpg","_links":{"self":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts\/74268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/users\/154"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/comments?post=74268"}],"version-history":[{"count":4,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts\/74268\/revisions"}],"predecessor-version":[{"id":74278,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts\/74268\/revisions\/74278"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/media\/74271"}],"wp:attachment":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/media?parent=74268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/categories?post=74268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/tags?post=74268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}