{"id":75689,"date":"2025-09-13T08:16:27","date_gmt":"2025-09-13T07:16:27","guid":{"rendered":"https:\/\/www.solopress.com\/blog\/?p=75689"},"modified":"2025-10-13T09:00:50","modified_gmt":"2025-10-13T08:00:50","slug":"historias-de-clientes-apoyo-al-envio-de-amigos","status":"publish","type":"post","link":"https:\/\/www.solopress.com\/blog\/es\/customer-stories\/customer-stories-building-support-for-send-friends\/","title":{"rendered":"Historias de clientes: apoyo a los amigos de SEND"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p><span style=\"font-weight: 400;\">Cuando se construye algo desde cero sin gran presupuesto ni respaldo, cada detalle cuenta. Para Leanne Thompson, fundadora de <a href=\"https:\/\/www.sendfriends.co.uk\/\" target=\"_blank\" rel=\"noopener\">Amigos de SEND<\/a>Incluso un cartel enrollable bien dise\u00f1ado se ha convertido en un tema de conversaci\u00f3n, atrayendo a la gente para que conozca un proyecto en expansi\u00f3n basado en la experiencia vivida, la empat\u00eda y el apoyo pr\u00e1ctico.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">SEND Friends es una iniciativa de inter\u00e9s comunitario con sede en Grimsby, que ofrece apoyo entre iguales a las familias de ni\u00f1os con necesidades educativas especiales y discapacidades (SEND). Pero empez\u00f3 con una idea mucho m\u00e1s sencilla: un libro infantil.<\/span><\/p>\n<h3><b>Historias que hablan de experiencias reales<\/b><\/h3>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-75690 size-full\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-3-e1758118494237.jpg\" alt=\"\" width=\"1512\" height=\"1193\" srcset=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-3-e1758118494237.jpg 1512w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-3-e1758118494237-300x237.jpg 300w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-3-e1758118494237-1024x808.jpg 1024w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-3-e1758118494237-768x606.jpg 768w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-3-e1758118494237-15x12.jpg 15w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-3-e1758118494237-532x420.jpg 532w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-3-e1758118494237-696x549.jpg 696w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-3-e1758118494237-1068x843.jpg 1068w\" sizes=\"auto, (max-width: 1512px) 100vw, 1512px\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Leanne cre\u00f3 originalmente SEND Friends como una serie de <a href=\"https:\/\/www.sendfriends.co.uk\/the-book-series\/\" target=\"_blank\" rel=\"noopener\">libros infantiles<\/a>. Las alegres historias rimadas presentan a los personajes neurodivergentes de forma que animan a los adultos a replantearse sus expectativas y ajustar el entorno, en lugar de ver al ni\u00f1o como el problema.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\"Escrib\u00ed los libros con la esperanza de que mis hijos y otros como ellos se vieran representados de forma positiva\", explica Leanne. \"Quer\u00eda que pudieran identificarse con los personajes, que se sintieran validados y quiz\u00e1 incluso capacitados para abogar por s\u00ed mismos\".<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los libros empezaron a generar una peque\u00f1a cantidad de ingresos a trav\u00e9s de los derechos de autor, y Leanne vio el potencial para hacer m\u00e1s. Bas\u00e1ndose en la experiencia de su propia familia y en su experiencia profesional en el \u00e1mbito del apoyo a personas con necesidades educativas especiales, ampli\u00f3 SEND Friends para convertirlo en un servicio de apoyo entre iguales para familias que se sent\u00edan abrumadas o abandonadas por el sistema.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\"Hay un enorme vac\u00edo en el apoyo a las familias neurodivergentes\", afirma. \"Los tiempos de espera para la evaluaci\u00f3n son largos, los servicios var\u00edan de una zona a otra e, incluso cuando se est\u00e1 en lista de espera, el apoyo puede ser desigual. Si eres nuevo en el mundo de los SEND, puede resultar abrumador. Intento ofrecer el tipo de apoyo que yo necesitaba pero que no siempre encontraba\".<\/span><\/p>\n<h3><b>Impresi\u00f3n que atrae a la gente<\/b><\/h3>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-75693\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-2.jpg\" alt=\"SEND Roller Banners e impresi\u00f3n\" width=\"2136\" height=\"2226\" srcset=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-2.jpg 2136w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-2-288x300.jpg 288w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-2-983x1024.jpg 983w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-2-768x800.jpg 768w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-2-1474x1536.jpg 1474w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-2-1965x2048.jpg 1965w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-2-12x12.jpg 12w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-2-403x420.jpg 403w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-2-696x725.jpg 696w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-2-1068x1113.jpg 1068w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-2-1920x2001.jpg 1920w\" sizes=\"auto, (max-width: 2136px) 100vw, 2136px\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Para correr la voz, Leanne sab\u00eda que necesitaba algo visual. Trabajando con fondos limitados reinvertidos de los derechos de autor de su libro, recurri\u00f3 a Solopress para obtener una pancarta de un solo rodillo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\"Quer\u00eda dar a conocer mi marca y empezar a ganar reconocimiento. Esperaba que atrajera a la gente para conversar y eso es exactamente lo que ha hecho\", afirma.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La pancarta fue dise\u00f1ada por la propia Leanne e impresa con sus propias ilustraciones y marca.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\"Me impresion\u00f3 lo f\u00e1cil que era hacer pedidos en l\u00ednea. Ya ten\u00eda un dise\u00f1o, as\u00ed que fue estupendo poder cargarlo directamente. El proceso de prueba fue muy claro y la pancarta lleg\u00f3 tan r\u00e1pido que pude llevarla a mi primer evento.\"<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La respuesta ha sido alentadora y esto no ha hecho m\u00e1s que empezar.<\/span><\/p>\n<h3><b>Una pancarta, grandes ambiciones<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Aunque la pancarta ha ayudado a poner en marcha el proyecto, Leanne tiene planes m\u00e1s ambiciosos para el futuro.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\"Ya he utilizado Solopress en un puesto anterior, as\u00ed que s\u00e9 lo bien que est\u00e1n hechos los productos. En cuanto pueda, quiero montar un evento completo. Folletos, octavillas, obsequios promocionales como bol\u00edgrafos o caramelos que ayuden a la gente a recordar qui\u00e9n eres. Con el tiempo, me gustar\u00eda tener un stand de exposici\u00f3n completo donde poder mostrar con orgullo los libros que lo empezaron todo y anunciar los eventos que estoy planeando. Ese ser\u00e1 mi momento 'yo lo hice'\".<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A corto plazo, SEND Friends ofrece apoyo en l\u00ednea y presencial sin coste alguno o a bajo coste para los participantes. Leanne tambi\u00e9n est\u00e1 conectando con organizaciones locales para ampliar su alcance y crear asociaciones duraderas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\"El sue\u00f1o es tener un espacio permanente. Un centro para familias neurodivergentes. Un lugar donde la gente pueda sentirse segura, aprender a entenderse y gustarse a s\u00ed misma, y encontrar orientaci\u00f3n pr\u00e1ctica y un sentimiento de pertenencia. Autismo, ADHD, OCD, ARFID, Tourette y m\u00e1s. Todo bajo un mismo techo de apoyo. Quiz\u00e1 alg\u00fan d\u00eda. Pero por ahora, la pancarta est\u00e1 ayudando a abrir esas primeras conversaciones\".<\/span><\/p>\n<h3><b>Comience su propia historia con Solopress<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Si est\u00e1 lanzando un servicio, promocionando su mensaje o simplemente dando a conocer su nombre, los Roller Banners son una soluci\u00f3n asequible, port\u00e1til y que llama la atenci\u00f3n. Solopress ofrece una amplia gama de <a href=\"https:\/\/www.solopress.com\/blog\/es\/banners\/\" target=\"_blank\" rel=\"noopener\">opciones de banner<\/a>que incluyen dise\u00f1os asequibles, soportes de alta calidad y alternativas ecol\u00f3gicas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Explore toda la gama y encuentre el producto adecuado para su proyecto en <a href=\"https:\/\/www.solopress.com\/blog\/es\/\" target=\"_blank\" rel=\"noopener\">solopress.com<\/a>.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>When you\u2019re building something from the ground up with no big budget or backing, every detail counts. For Leanne Thompson, founder of SEND Friends, even one well-designed roller banner has become a conversation starter, drawing people in to hear about a growing project rooted in lived experience, empathy and practical support. SEND Friends is a [&hellip;]<\/p>\n","protected":false},"author":134,"featured_media":75752,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[557,544],"tags":[],"class_list":{"0":"post-75689","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-customer-stories","8":"category-print-inspiration"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Customer Stories: Building Support For SEND Friends - Solopress<\/title>\n<meta name=\"description\" content=\"Learn how SEND Friends uses print to build awareness and support families navigating the world of special educational needs and disabilities.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solopress.com\/blog\/es\/historias-de-clientes\/historias-de-clientes-apoyo-al-envio-de-amigos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Customer Stories: Building Support For SEND Friends - Solopress\" \/>\n<meta property=\"og:description\" content=\"Learn how SEND Friends uses print to build awareness and support families navigating the world of special educational needs and disabilities.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solopress.com\/blog\/es\/historias-de-clientes\/historias-de-clientes-apoyo-al-envio-de-amigos\/\" \/>\n<meta property=\"og:site_name\" content=\"The Latest Print and Design News | Solopress\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Solopress\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-13T07:16:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-13T08:00:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/10\/SEND-Friends-Customer-Story-Blog-Header.png\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"338\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Danny Powell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@solopress\" \/>\n<meta name=\"twitter:site\" content=\"@solopress\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Danny Powell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-building-support-for-send-friends\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-building-support-for-send-friends\\\/\"},\"author\":{\"name\":\"Danny Powell\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/0937555a256c22f94400f4b7e2329c09\"},\"headline\":\"Customer Stories: building support for SEND Friends\",\"datePublished\":\"2025-09-13T07:16:27+00:00\",\"dateModified\":\"2025-10-13T08:00:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-building-support-for-send-friends\\\/\"},\"wordCount\":708,\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-building-support-for-send-friends\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/SEND-Friends-Customer-Story-Blog-Header.png\",\"articleSection\":[\"Customer Stories\",\"Print Inspiration\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-building-support-for-send-friends\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-building-support-for-send-friends\\\/\",\"name\":\"Customer Stories: Building Support For SEND Friends - Solopress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-building-support-for-send-friends\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-building-support-for-send-friends\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/SEND-Friends-Customer-Story-Blog-Header.png\",\"datePublished\":\"2025-09-13T07:16:27+00:00\",\"dateModified\":\"2025-10-13T08:00:50+00:00\",\"description\":\"Learn how SEND Friends uses print to build awareness and support families navigating the world of special educational needs and disabilities.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-building-support-for-send-friends\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-building-support-for-send-friends\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-building-support-for-send-friends\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/SEND-Friends-Customer-Story-Blog-Header.png\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/SEND-Friends-Customer-Story-Blog-Header.png\",\"width\":450,\"height\":338,\"caption\":\"SEND Friends Header\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-building-support-for-send-friends\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Customer Stories: building support for SEND Friends\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"name\":\"The Latest Print and Design News | Solopress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\",\"name\":\"Solopress\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"width\":428,\"height\":88,\"caption\":\"Solopress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Solopress\",\"https:\\\/\\\/x.com\\\/solopress\",\"https:\\\/\\\/instagram.com\\\/solopress\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/solopress\",\"https:\\\/\\\/uk.pinterest.com\\\/solopress\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/solopress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/0937555a256c22f94400f4b7e2329c09\",\"name\":\"Danny Powell\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"caption\":\"Danny Powell\"},\"description\":\"With over two decades in marketing, Danny Powell is a Senior Copywriter at Solopress, one of the UK\u2019s leading online printers. Having worked on the print buying, agency and sales sides of the industry, he brings a well-rounded perspective to his writing on print, design and sustainability.\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/es\\\/author\\\/danny-powell\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Historias de clientes: Crear apoyo para los amigos de SEND - Solopress","description":"Descubra c\u00f3mo SEND Friends utiliza la impresi\u00f3n para sensibilizar y apoyar a las familias que se enfrentan al mundo de las necesidades educativas especiales y las discapacidades.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solopress.com\/blog\/es\/historias-de-clientes\/historias-de-clientes-apoyo-al-envio-de-amigos\/","og_locale":"es_ES","og_type":"article","og_title":"Customer Stories: Building Support For SEND Friends - Solopress","og_description":"Learn how SEND Friends uses print to build awareness and support families navigating the world of special educational needs and disabilities.","og_url":"https:\/\/www.solopress.com\/blog\/es\/historias-de-clientes\/historias-de-clientes-apoyo-al-envio-de-amigos\/","og_site_name":"The Latest Print and Design News | Solopress","article_publisher":"https:\/\/www.facebook.com\/Solopress","article_published_time":"2025-09-13T07:16:27+00:00","article_modified_time":"2025-10-13T08:00:50+00:00","og_image":[{"width":450,"height":338,"url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/10\/SEND-Friends-Customer-Story-Blog-Header.png","type":"image\/png"}],"author":"Danny Powell","twitter_card":"summary_large_image","twitter_creator":"@solopress","twitter_site":"@solopress","twitter_misc":{"Escrito por":"Danny Powell","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-building-support-for-send-friends\/#article","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-building-support-for-send-friends\/"},"author":{"name":"Danny Powell","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/0937555a256c22f94400f4b7e2329c09"},"headline":"Customer Stories: building support for SEND Friends","datePublished":"2025-09-13T07:16:27+00:00","dateModified":"2025-10-13T08:00:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-building-support-for-send-friends\/"},"wordCount":708,"publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-building-support-for-send-friends\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/10\/SEND-Friends-Customer-Story-Blog-Header.png","articleSection":["Customer Stories","Print Inspiration"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-building-support-for-send-friends\/","url":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-building-support-for-send-friends\/","name":"Historias de clientes: Crear apoyo para los amigos de SEND - Solopress","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-building-support-for-send-friends\/#primaryimage"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-building-support-for-send-friends\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/10\/SEND-Friends-Customer-Story-Blog-Header.png","datePublished":"2025-09-13T07:16:27+00:00","dateModified":"2025-10-13T08:00:50+00:00","description":"Descubra c\u00f3mo SEND Friends utiliza la impresi\u00f3n para sensibilizar y apoyar a las familias que se enfrentan al mundo de las necesidades educativas especiales y las discapacidades.","breadcrumb":{"@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-building-support-for-send-friends\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-building-support-for-send-friends\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-building-support-for-send-friends\/#primaryimage","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/10\/SEND-Friends-Customer-Story-Blog-Header.png","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/10\/SEND-Friends-Customer-Story-Blog-Header.png","width":450,"height":338,"caption":"SEND Friends Header"},{"@type":"BreadcrumbList","@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-building-support-for-send-friends\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.solopress.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Customer Stories: building support for SEND Friends"}]},{"@type":"WebSite","@id":"https:\/\/www.solopress.com\/blog\/#website","url":"https:\/\/www.solopress.com\/blog\/","name":"\u00daltimas noticias sobre impresi\u00f3n y dise\u00f1o | Solopress","description":"","publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solopress.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.solopress.com\/blog\/#organization","name":"Solopress","url":"https:\/\/www.solopress.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","width":428,"height":88,"caption":"Solopress"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Solopress","https:\/\/x.com\/solopress","https:\/\/instagram.com\/solopress\/","https:\/\/www.linkedin.com\/company\/solopress","https:\/\/uk.pinterest.com\/solopress\/","https:\/\/www.youtube.com\/user\/solopress"]},{"@type":"Person","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/0937555a256c22f94400f4b7e2329c09","name":"Danny Powell","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","caption":"Danny Powell"},"description":"Con m\u00e1s de dos d\u00e9cadas de experiencia en marketing, Danny Powell es redactor jefe de Solopress, una de las principales imprentas en l\u00ednea del Reino Unido. Tras haber trabajado en los departamentos de compras, agencias y ventas del sector de la impresi\u00f3n, aporta una perspectiva muy completa a sus escritos sobre impresi\u00f3n, dise\u00f1o y sostenibilidad.","url":"https:\/\/www.solopress.com\/blog\/es\/author\/danny-powell\/"}]}},"jetpack_featured_media_url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/10\/SEND-Friends-Customer-Story-Blog-Header.png","_links":{"self":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts\/75689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/comments?post=75689"}],"version-history":[{"count":7,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts\/75689\/revisions"}],"predecessor-version":[{"id":75753,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts\/75689\/revisions\/75753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/media\/75752"}],"wp:attachment":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/media?parent=75689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/categories?post=75689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/tags?post=75689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}