{"id":76103,"date":"2026-03-31T13:45:18","date_gmt":"2026-03-31T12:45:18","guid":{"rendered":"https:\/\/www.solopress.com\/blog\/?p=76103"},"modified":"2026-04-01T13:03:30","modified_gmt":"2026-04-01T12:03:30","slug":"solopress-invierte-por-primera-vez-en-el-reino-unido-en-una-impresora-de-inyeccion-de-tinta-de-alta-velocidad-ricoh-pro-vc80000","status":"publish","type":"post","link":"https:\/\/www.solopress.com\/blog\/es\/solopress-news\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\/","title":{"rendered":"Una primicia en el Reino Unido: Solopress invierte en la prensa de inyecci\u00f3n de tinta de alta velocidad Ricoh Pro VC80000"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p>Una nueva incorporaci\u00f3n ha llegado a la planta de producci\u00f3n de Solopress. La <a style=\"color: #4db2ec; text-decoration-line: underline;\" href=\"https:\/\/www.ricoh.co.uk\/products\/production-printers\/continuous-feed-printers\/pro-vc80000\/\" target=\"_blank\" rel=\"noopener\">Ricoh Pro VC80000<\/a> se est\u00e1 instalando en nuestra planta de Southend-on-Sea tras varios meses de planificaci\u00f3n, y se espera que aumente nuestra capacidad de producci\u00f3n de impresi\u00f3n digital en 80%.<\/p>\n<p><span style=\"font-weight: 400;\">Esta inversi\u00f3n de m\u00e1s de 2 millones de libras se centra en aumentar la capacidad y mejorar la eficiencia en \u00e1reas clave de nuestra producci\u00f3n digital. A medida que crece la demanda, sobre todo de tiradas digitales m\u00e1s largas, es cada vez m\u00e1s importante mantener una calidad constante y unos plazos de entrega fiables.<\/span><\/p>\n<h2 id=\"why\"><b>Respuesta a la creciente demanda<\/b><\/h2>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Jack-Clifford-and-Andy.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-76104\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Jack-Clifford-and-Andy.png\" alt=\"\" width=\"900\" height=\"675\" srcset=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Jack-Clifford-and-Andy.png 900w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Jack-Clifford-and-Andy-300x225.png 300w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Jack-Clifford-and-Andy-768x576.png 768w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Jack-Clifford-and-Andy-16x12.png 16w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Jack-Clifford-and-Andy-560x420.png 560w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Jack-Clifford-and-Andy-80x60.png 80w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Jack-Clifford-and-Andy-696x522.png 696w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Jack-Clifford-and-Andy-265x198.png 265w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">La demanda de impresi\u00f3n de folletos sigue creciendo en nuestra base de clientes, sobre todo para tiradas digitales m\u00e1s largas que requieren una calidad constante y plazos de entrega fiables.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Estos trabajos suelen implicar mayores cantidades, plazos de entrega m\u00e1s ajustados e ilustraciones detalladas que deben reproducirse de forma coherente desde el primer ejemplar hasta el \u00faltimo. Cumplir estas expectativas exige una configuraci\u00f3n de producci\u00f3n capaz de gestionar tanto el volumen como las variaciones sin introducir retrasos ni incoherencias.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La Ricoh Pro VC80000 ha sido seleccionada para reforzar esa capacidad. Nos permite producir tiradas digitales m\u00e1s largas de forma m\u00e1s eficiente, manteniendo los est\u00e1ndares que nuestros clientes ya esperan de nosotros.<\/span><\/p>\n<p><b>En palabras de Jack Clifford, Director de Operaciones de Solopress:<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">\u201cHemos experimentado un crecimiento fuerte y constante en la impresi\u00f3n de folletos, por lo que aumentar la capacidad en esta \u00e1rea era una prioridad. La Ricoh Pro VC80000 nos permite producir tiradas digitales m\u00e1s largas de forma mucho m\u00e1s eficiente, manteniendo la calidad que esperan nuestros clientes.\u201d<\/span><\/p>\n<h2><b>Qu\u00e9 aporta el Ricoh Pro VC80000<a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Install.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-76107\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Install.png\" alt=\"\" width=\"900\" height=\"675\" srcset=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Install.png 900w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Install-300x225.png 300w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Install-768x576.png 768w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Install-16x12.png 16w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Install-560x420.png 560w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Install-80x60.png 80w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Install-696x522.png 696w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Install-265x198.png 265w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><\/b><\/h2>\n<p><span style=\"font-weight: 400;\">La Ricoh Pro VC80000 es una prensa de inyecci\u00f3n de tinta de alimentaci\u00f3n continua. En lugar de imprimir en hojas individuales, imprime en un rollo de papel en movimiento, lo que permite una producci\u00f3n ininterrumpida y de alta velocidad.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Es capaz de alcanzar velocidades de hasta 150 metros por minuto, con una resoluci\u00f3n de impresi\u00f3n de hasta 1200 \u00d7 1200 ppp. Esto permite un alto rendimiento al tiempo que se mantiene la nitidez de los detalles y la uniformidad del color, especialmente en tiradas largas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La rotativa est\u00e1 dise\u00f1ada para mantener una producci\u00f3n estable durante largos periodos de producci\u00f3n. Sus sistemas de secado y gesti\u00f3n de la temperatura ayudan a mantener unas condiciones constantes durante toda la tirada, lo que es especialmente importante cuando se trabaja con dise\u00f1os con una gran cobertura de tinta o detalles finos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Esto nos permite aumentar la velocidad y la capacidad al tiempo que mantenemos los est\u00e1ndares de calidad que ya aplicamos en todos los trabajos.<\/span><\/p>\n<p><b>David Farnsworth, director de cuentas estrat\u00e9gicas de Ricoh UK Graphic Communications, coment\u00f3:<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">\u201cSolopress es exactamente el tipo de entorno de producci\u00f3n con visi\u00f3n de futuro en el que la tecnolog\u00eda de Ricoh demuestra su valor. La primera instalaci\u00f3n VC80000 del Reino Unido es un hito importante, no s\u00f3lo para Solopress, sino como demostraci\u00f3n de lo que la producci\u00f3n moderna de inyecci\u00f3n de tinta puede lograr comercialmente. Tambi\u00e9n se\u00f1ala la confianza en nuestras soluciones y el valor de los servicios que ofrecemos.\u201d<\/span><\/p>\n<h2 id=\"workflow\"><b>Del papel en blanco al folleto acabado en un solo flujo de trabajo<\/b><\/h2>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Hunkeler-Horizon.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-76108\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Hunkeler-Horizon.png\" alt=\"\" width=\"877\" height=\"436\" srcset=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Hunkeler-Horizon.png 877w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Hunkeler-Horizon-300x149.png 300w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Hunkeler-Horizon-768x382.png 768w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Hunkeler-Horizon-18x9.png 18w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Hunkeler-Horizon-845x420.png 845w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Hunkeler-Horizon-696x346.png 696w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Hunkeler-Horizon-324x160.png 324w\" sizes=\"auto, (max-width: 877px) 100vw, 877px\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">La rotativa se est\u00e1 instalando en l\u00ednea con el equipo de desenrollado y acabado de Hunkeler, incluida la Horizon Mark V Stitchliner. Esto crea un flujo de trabajo continuo desde la impresi\u00f3n hasta el folleto acabado.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A medida que el rollo impreso avanza por el sistema, se corta, recoge, cose y recorta en secuencia. Esto reduce la necesidad de intervenci\u00f3n manual entre etapas y ayuda a mantener la uniformidad en grandes cantidades.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tambi\u00e9n acorta el tiempo entre la impresi\u00f3n y el acabado, lo que permite una entrega m\u00e1s predecible, especialmente en el caso de los folletos de mayor volumen.<\/span><\/p>\n<h2><b>Aumentar la capacidad donde m\u00e1s se necesita<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Se espera que esta inversi\u00f3n <strong>aumentar nuestra capacidad de impresi\u00f3n digital en unas 80%<\/strong>. Y lo que es m\u00e1s importante, nos permite distribuir el trabajo de forma m\u00e1s eficaz entre nuestros departamentos de producci\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Est\u00e1 previsto que m\u00e1s de la mitad de nuestra producci\u00f3n de folletos se realice en esta nueva l\u00ednea cuando est\u00e9 plenamente operativa. Al trasladar este trabajo a un sistema dedicado de gran volumen, podemos reducir la presi\u00f3n sobre otras prensas digitales y mejorar la eficiencia general del flujo de trabajo\".<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El resultado es un margen de producci\u00f3n adicional que ayuda a gestionar los picos de demanda sin comprometer los plazos de entrega ni la calidad.<\/span><\/p>\n<h2 id=\"expertise\"><b>Preparaci\u00f3n del equipo<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Paralelamente a la instalaci\u00f3n, los miembros de nuestro equipo de producci\u00f3n se han estado preparando para utilizar la nueva rotativa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los experimentados operarios de rotativa Tony Sullivan, Jim Wellard, Geoff Holliss y Darren Brown completaron recientemente un programa de formaci\u00f3n de tres d\u00edas en la sede central de Ricoh en Telford, Reino Unido. El curso abarc\u00f3 los procedimientos de seguridad, el transporte del papel a trav\u00e9s de la rotativa, los sistemas de secado y refrigeraci\u00f3n, la gesti\u00f3n de la tinta y los controles en pantalla.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Esta formaci\u00f3n garantiza que el equipo est\u00e9 totalmente preparado para integrar la nueva rotativa en la producci\u00f3n diaria. Como ocurre con cualquier equipo nuevo, es la combinaci\u00f3n de tecnolog\u00eda y experiencia del operario lo que determina su eficacia.<\/span><\/p>\n<h2><b>Una instalaci\u00f3n cuidadosamente gestionada<\/b><\/h2>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Unload.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-76109\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Unload.png\" alt=\"\" width=\"900\" height=\"675\" srcset=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Unload.png 900w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Unload-300x225.png 300w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Unload-768x576.png 768w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Unload-16x12.png 16w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Unload-560x420.png 560w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Unload-80x60.png 80w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Unload-696x522.png 696w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Unload-265x198.png 265w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><span style=\"font-weight: 400;\">La instalaci\u00f3n de una m\u00e1quina de esta envergadura es un proceso minucioso. La Ricoh Pro VC80000 lleg\u00f3 en varias secciones, cada una con un peso de varias toneladas, y requiri\u00f3 una manipulaci\u00f3n cuidadosa para colocarla en el espacio de producci\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Equipos especializados trabajaron junto a nuestros propios ingenieros para descargar e instalar las unidades con precisi\u00f3n. Cada secci\u00f3n se coloc\u00f3 con precisi\u00f3n para garantizar la alineaci\u00f3n en toda la l\u00ednea de producci\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al mismo tiempo, se ha configurado el flujo de trabajo circundante para que sea compatible con el nuevo sistema, desde la manipulaci\u00f3n del material hasta el acabado y la expedici\u00f3n.<\/span><\/p>\n<h2><b>Qu\u00e9 significa esto para su impresi\u00f3n<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">A medida que la nueva l\u00ednea entre en funcionamiento, los clientes empezar\u00e1n a ver las ventajas en la forma en que el trabajo avanza a trav\u00e9s de la producci\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Permite la introducci\u00f3n de un plazo de entrega de 24 horas en folletos A4 y A5 grapados en vertical, ofreciendo una opci\u00f3n m\u00e1s r\u00e1pida para uno de nuestros productos m\u00e1s demandados.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Otros formatos, orientaciones y tipos de papel seguir\u00e1n los plazos de producci\u00f3n adecuados debido a los requisitos de secado y acabado. Sin embargo, el aumento de la capacidad beneficia a todos los trabajos de impresi\u00f3n digital al reducir la presi\u00f3n en todo el programa de producci\u00f3n.<\/span><\/p>\n<h2><b>De cara al futuro<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">La Ricoh Pro VC80000 est\u00e1 siendo instalada y puesta en marcha. En las pr\u00f3ximas semanas, entrar\u00e1 en plena producci\u00f3n a medida que se completen las pruebas y la calibraci\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Esta inversi\u00f3n refleja un enfoque continuo para mejorar nuestra forma de producir impresos. Al aumentar la capacidad y perfeccionar nuestros flujos de trabajo, podemos seguir ofreciendo una calidad constante y responder con mayor eficacia a la evoluci\u00f3n de la demanda. Eche un vistazo a nuestra <a href=\"https:\/\/www.solopress.com\/blog\/es\/stapled-brochures\/\" target=\"_blank\" rel=\"noopener\">Folletos grapados<\/a> para plazos de entrega reducidos e impresi\u00f3n de primera calidad.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>A new addition has arrived on the Solopress production floor. The Ricoh Pro VC80000 is now being installed at our Southend-on-Sea site following several months of planning, and is expected to boost our digital print production capacity by a massive 80%. This \u00a32m+ investment focuses on increasing capacity and improving efficiency in key areas of [&hellip;]<\/p>\n","protected":false},"author":134,"featured_media":76106,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[550,551],"tags":[],"class_list":{"0":"post-76103","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-print-industry-news","8":"category-solopress-news"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Solopress Invests In UK&#039;s First Ricoh Pro VC80000 Inkjet Press<\/title>\n<meta name=\"description\" content=\"Solopress installs Ricoh VC80000 continuous feed press, boosting digital capacity by 80% and improving efficiency in brochure production.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solopress.com\/blog\/es\/noticias-de-solopress\/solopress-invierte-por-primera-vez-en-el-reino-unido-en-una-impresora-de-inyeccion-de-tinta-de-alta-velocidad-ricoh-pro-vc80000\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Solopress Invests In UK&#039;s First Ricoh Pro VC80000 Inkjet Press\" \/>\n<meta property=\"og:description\" content=\"Solopress installs Ricoh VC80000 continuous feed press, boosting digital capacity by 80% and improving efficiency in brochure production.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solopress.com\/blog\/es\/noticias-de-solopress\/solopress-invierte-por-primera-vez-en-el-reino-unido-en-una-impresora-de-inyeccion-de-tinta-de-alta-velocidad-ricoh-pro-vc80000\/\" \/>\n<meta property=\"og:site_name\" content=\"The Latest Print and Design News | Solopress\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Solopress\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-31T12:45:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-01T12:03:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Flat.png\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Danny Powell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@solopress\" \/>\n<meta name=\"twitter:site\" content=\"@solopress\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Danny Powell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/solopress-news\\\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/solopress-news\\\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\\\/\"},\"author\":{\"name\":\"Danny Powell\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/0937555a256c22f94400f4b7e2329c09\"},\"headline\":\"A UK first: Solopress invests in Ricoh Pro VC80000 high speed inkjet press\",\"datePublished\":\"2026-03-31T12:45:18+00:00\",\"dateModified\":\"2026-04-01T12:03:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/solopress-news\\\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\\\/\"},\"wordCount\":966,\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/solopress-news\\\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Ricoh-Flat.png\",\"articleSection\":[\"Print Industry News\",\"Solopress News\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/solopress-news\\\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/solopress-news\\\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\\\/\",\"name\":\"Solopress Invests In UK's First Ricoh Pro VC80000 Inkjet Press\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/solopress-news\\\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/solopress-news\\\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Ricoh-Flat.png\",\"datePublished\":\"2026-03-31T12:45:18+00:00\",\"dateModified\":\"2026-04-01T12:03:30+00:00\",\"description\":\"Solopress installs Ricoh VC80000 continuous feed press, boosting digital capacity by 80% and improving efficiency in brochure production.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/solopress-news\\\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/solopress-news\\\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/solopress-news\\\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Ricoh-Flat.png\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Ricoh-Flat.png\",\"width\":900,\"height\":675,\"caption\":\"The Ricoh VC80000 installed at Solopress\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/solopress-news\\\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A UK first: Solopress invests in Ricoh Pro VC80000 high speed inkjet press\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"name\":\"The Latest Print and Design News | Solopress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\",\"name\":\"Solopress\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"width\":428,\"height\":88,\"caption\":\"Solopress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Solopress\",\"https:\\\/\\\/x.com\\\/solopress\",\"https:\\\/\\\/instagram.com\\\/solopress\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/solopress\",\"https:\\\/\\\/uk.pinterest.com\\\/solopress\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/solopress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/0937555a256c22f94400f4b7e2329c09\",\"name\":\"Danny Powell\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"caption\":\"Danny Powell\"},\"description\":\"With over two decades in marketing, Danny Powell is a Senior Copywriter at Solopress, one of the UK\u2019s leading online printers. Having worked on the print buying, agency and sales sides of the industry, he brings a well-rounded perspective to his writing on print, design and sustainability.\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/es\\\/author\\\/danny-powell\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Solopress invierte en la primera impresora de inyecci\u00f3n de tinta Ricoh Pro VC80000 del Reino Unido","description":"Solopress instala la prensa de alimentaci\u00f3n continua Ricoh VC80000, aumentando la capacidad digital en 80% y mejorando la eficiencia en la producci\u00f3n de folletos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solopress.com\/blog\/es\/noticias-de-solopress\/solopress-invierte-por-primera-vez-en-el-reino-unido-en-una-impresora-de-inyeccion-de-tinta-de-alta-velocidad-ricoh-pro-vc80000\/","og_locale":"es_ES","og_type":"article","og_title":"Solopress Invests In UK's First Ricoh Pro VC80000 Inkjet Press","og_description":"Solopress installs Ricoh VC80000 continuous feed press, boosting digital capacity by 80% and improving efficiency in brochure production.","og_url":"https:\/\/www.solopress.com\/blog\/es\/noticias-de-solopress\/solopress-invierte-por-primera-vez-en-el-reino-unido-en-una-impresora-de-inyeccion-de-tinta-de-alta-velocidad-ricoh-pro-vc80000\/","og_site_name":"The Latest Print and Design News | Solopress","article_publisher":"https:\/\/www.facebook.com\/Solopress","article_published_time":"2026-03-31T12:45:18+00:00","article_modified_time":"2026-04-01T12:03:30+00:00","og_image":[{"width":900,"height":675,"url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Flat.png","type":"image\/png"}],"author":"Danny Powell","twitter_card":"summary_large_image","twitter_creator":"@solopress","twitter_site":"@solopress","twitter_misc":{"Escrito por":"Danny Powell","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.solopress.com\/blog\/solopress-news\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\/#article","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/solopress-news\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\/"},"author":{"name":"Danny Powell","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/0937555a256c22f94400f4b7e2329c09"},"headline":"A UK first: Solopress invests in Ricoh Pro VC80000 high speed inkjet press","datePublished":"2026-03-31T12:45:18+00:00","dateModified":"2026-04-01T12:03:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/solopress-news\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\/"},"wordCount":966,"publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/solopress-news\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Flat.png","articleSection":["Print Industry News","Solopress News"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.solopress.com\/blog\/solopress-news\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\/","url":"https:\/\/www.solopress.com\/blog\/solopress-news\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\/","name":"Solopress invierte en la primera impresora de inyecci\u00f3n de tinta Ricoh Pro VC80000 del Reino Unido","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/solopress-news\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\/#primaryimage"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/solopress-news\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Flat.png","datePublished":"2026-03-31T12:45:18+00:00","dateModified":"2026-04-01T12:03:30+00:00","description":"Solopress instala la prensa de alimentaci\u00f3n continua Ricoh VC80000, aumentando la capacidad digital en 80% y mejorando la eficiencia en la producci\u00f3n de folletos.","breadcrumb":{"@id":"https:\/\/www.solopress.com\/blog\/solopress-news\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solopress.com\/blog\/solopress-news\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.solopress.com\/blog\/solopress-news\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\/#primaryimage","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Flat.png","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Flat.png","width":900,"height":675,"caption":"The Ricoh VC80000 installed at Solopress"},{"@type":"BreadcrumbList","@id":"https:\/\/www.solopress.com\/blog\/solopress-news\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.solopress.com\/blog\/"},{"@type":"ListItem","position":2,"name":"A UK first: Solopress invests in Ricoh Pro VC80000 high speed inkjet press"}]},{"@type":"WebSite","@id":"https:\/\/www.solopress.com\/blog\/#website","url":"https:\/\/www.solopress.com\/blog\/","name":"\u00daltimas noticias sobre impresi\u00f3n y dise\u00f1o | Solopress","description":"","publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solopress.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.solopress.com\/blog\/#organization","name":"Solopress","url":"https:\/\/www.solopress.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","width":428,"height":88,"caption":"Solopress"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Solopress","https:\/\/x.com\/solopress","https:\/\/instagram.com\/solopress\/","https:\/\/www.linkedin.com\/company\/solopress","https:\/\/uk.pinterest.com\/solopress\/","https:\/\/www.youtube.com\/user\/solopress"]},{"@type":"Person","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/0937555a256c22f94400f4b7e2329c09","name":"Danny Powell","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","caption":"Danny Powell"},"description":"Con m\u00e1s de dos d\u00e9cadas de experiencia en marketing, Danny Powell es redactor jefe de Solopress, una de las principales imprentas en l\u00ednea del Reino Unido. Tras haber trabajado en los departamentos de compras, agencias y ventas del sector de la impresi\u00f3n, aporta una perspectiva muy completa a sus escritos sobre impresi\u00f3n, dise\u00f1o y sostenibilidad.","url":"https:\/\/www.solopress.com\/blog\/es\/author\/danny-powell\/"}]}},"jetpack_featured_media_url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Flat.png","_links":{"self":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts\/76103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/comments?post=76103"}],"version-history":[{"count":4,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts\/76103\/revisions"}],"predecessor-version":[{"id":76113,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/posts\/76103\/revisions\/76113"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/media\/76106"}],"wp:attachment":[{"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/media?parent=76103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/categories?post=76103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/es\/wp-json\/wp\/v2\/tags?post=76103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}