{"id":4003,"date":"2012-05-22T17:06:05","date_gmt":"2012-05-22T16:06:05","guid":{"rendered":"https:\/\/www.solopress.com\/blog\/?p=4003"},"modified":"2023-10-29T14:11:37","modified_gmt":"2023-10-29T14:11:37","slug":"comment-eviter-les-fautes-dorthographe-lors-de-limpression","status":"publish","type":"post","link":"https:\/\/www.solopress.com\/blog\/fr\/tutorials\/how-to-avoid-spelling-mistakes-in-your-printing\/","title":{"rendered":"Comment \u00e9viter les fautes d'orthographe dans vos imprim\u00e9s"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p><!--more--><\/p>\n<h3><em>Avec des millions de pages imprim\u00e9es par Solopress.com chaque ann\u00e9e, il est juste de dire que nous avons vu quelques fautes d'orthographe spectaculaires dans notre temps. Mais ces erreurs co\u00fbteuses peuvent \u00eatre \u00e9vit\u00e9es... si vous suivez nos \u00e9tapes simples pour une orthographe r\u00e9ussie !<\/em><\/h3>\n<p><strong>Fautes d'orthographe dans l'impression<\/strong> se produisent. Ce triste constat n'a rien de surprenant. Une enqu\u00eate d\u00e9courageante de Mencap a r\u00e9v\u00e9l\u00e9 aujourd'hui que les Britanniques sont vraiment tr\u00e8s mauvais en orthographe. Il semblerait que 65% d'entre nous ne soient m\u00eame pas capables d'orthographier correctement \"necessary\"... sans l'aide des nouvelles technologies. Avec plus de deux tiers des Britanniques qui doivent d\u00e9sormais compter sur des correcteurs d'orthographe, nous sommes en passe de devenir la g\u00e9n\u00e9ration de l'autocorrection. Toutefois, il convient de rappeler qu'en raison de la complexit\u00e9 de la langue anglaise et d'autres facteurs tels que les noms bizarrement orthographi\u00e9s ou l'utilisation de mots d'argot, les machines n'ont pas toujours raison non plus.<\/p>\n<p>\"Le langage utilis\u00e9 par une entreprise ou une personne est le reflet de son attitude, de ses capacit\u00e9s et de ses comp\u00e9tences\", d\u00e9clare Mark Goldring, directeur g\u00e9n\u00e9ral de Mencap, la plus grande organisation caritative du Royaume-Uni soutenant les personnes souffrant de troubles de l'apprentissage. \"Le climat \u00e9conomique difficile d'aujourd'hui signifie qu'une mauvaise orthographe sur un CV est fatale, car elle indique qu'une personne ne peut pas produire un travail \u00e0 un niveau donn\u00e9, quel que soit son niveau de qualification.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4045\" title=\"\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2012\/05\/no-parking-spelling-mistake.jpg\" alt=\"Faute d&#039;orthographe de No Parking\" width=\"650\" height=\"402\" \/><\/p>\n<p>C'est bien s\u00fbr aussi le cas pour toutes les <a title=\"Impression de cartes de visite chez Solopress\" href=\"https:\/\/www.solopress.com\/blog\/fr\/cartes-daffaires\/\" target=\"_blank\" rel=\"noopener noreferrer\">cartes de visite<\/a>, <a title=\"Impression de flyers chez Solopress\" href=\"https:\/\/www.solopress.com\/blog\/fr\/depliants-depliants\/\" target=\"_blank\" rel=\"noopener noreferrer\">d\u00e9pliants<\/a>, <a title=\"Impression de brochures chez Solopress\" href=\"https:\/\/www.solopress.com\/blog\/fr\/brochures-livrets\/\" target=\"_blank\" rel=\"noopener noreferrer\">brochures<\/a>, <a title=\"Impression d&#039;affiches chez Solopress\" href=\"https:\/\/www.solopress.com\/blog\/fr\/affiches\/\" target=\"_blank\" rel=\"noopener noreferrer\">affiches<\/a>, <a title=\"Impression de banni\u00e8res \u00e0 rouleaux chez Solopress\" href=\"https:\/\/www.solopress.com\/blog\/fr\/bannieres-a-rouleaux\/\" target=\"_blank\" rel=\"noopener noreferrer\">banni\u00e8res<\/a>, <a title=\"Impression de cartes postales chez Solopress\" href=\"https:\/\/www.solopress.com\/blog\/fr\/cartes-postales\/\" target=\"_blank\" rel=\"noopener noreferrer\">cartes postales<\/a>, <a title=\"Impression d&#039;autocollants chez Solopress\" href=\"https:\/\/www.solopress.com\/blog\/fr\/autocollants-etiquettes\/\" target=\"_blank\" rel=\"noopener noreferrer\">autocollants<\/a> et autres imprim\u00e9s que Solopress.com imprime chaque seconde de la journ\u00e9e. C'est pourquoi nous avons pr\u00e9par\u00e9 quelques conseils utiles pour vous aider \u00e0 \u00e9viter les fautes d'orthographe embarrassantes.<\/p>\n<h2>Les 5 meilleurs conseils en orthographe<\/h2>\n<p>1. Utilisez toujours le correcteur orthographique automatique et assurez-vous d'avoir indiqu\u00e9 \u00e0 l'application logicielle que la langue dans laquelle vous \u00e9crivez est l'anglais britannique et non l'anglais am\u00e9ricain. Il suffit de rep\u00e9rer la case \u00e0 cocher ou l'option de menu appropri\u00e9e dans l'\u00e9cran d'options du logiciel. Sinon, ce sera \"color\" au lieu de \"colour\", \"center\" au lieu de \"center\", \"customize\" au lieu de \"customise\", etc. Si le correcteur orthographique ne trouve pas un mot, utilisez Google, Wikipedia ou Wiktionary pour en trouver l'orthographe correcte.<\/p>\n<p>2. S'il vous pla\u00eet ! S'il vous pla\u00eet ! S'il vous pla\u00eet ! Demandez \u00e0 quelqu'un d'autre de v\u00e9rifier votre travail avant de l'envoyer \u00e0 Solopress.com ou \u00e0 tout autre imprimeur commercial pour qu'il soit imprim\u00e9. Vous serez souvent surpris par les choses apparemment \u00e9videntes que vous avez oubli\u00e9es ou mal orthographi\u00e9es. Les erreurs se produisent, nous ne sommes que des \u00eatres humains apr\u00e8s tout. Demander \u00e0 vos amis, \u00e0 votre famille et \u00e0 vos coll\u00e8gues de relire vos imprim\u00e9s est une \u00e9vidence, car il est beaucoup plus facile pour une autre paire d'yeux de rep\u00e9rer les erreurs que si vous essayez de le faire tout seul.<\/p>\n<p>3. Assurez-vous que vous avez correctement orthographi\u00e9 le nom d'une personne dans toute correspondance ou promotion - en particulier s'il s'agit d'un client existant (ou potentiel) ! Il est peu probable qu'un syst\u00e8me automatis\u00e9 tel qu'un correcteur orthographique int\u00e9gr\u00e9 parvienne \u00e0 \u00e9peler correctement le nom d'une personne. \u00c0 moins qu'il n'ait d\u00e9j\u00e0 appris le pr\u00e9nom et le nom de cette personne par le pass\u00e9. C'est aussi quelque chose qui pourrait co\u00fbter cher \u00e0 votre entreprise si vous vous trompez. Pourquoi quelqu'un prendrait-il la peine de faire affaire avec vous alors que vous n'\u00eates m\u00eame pas capable d'orthographier correctement son nom ?<\/p>\n<p>4. Plus qu'une simple faute de frappe, l'utilisation abusive des apostrophes peut \u00eatre tout aussi embarrassante et nuire \u00e0 la r\u00e9putation de votre entreprise. Selon Richard Kemp, l'un de nos concepteurs internes experts, une erreur fr\u00e9quente commise par les clients de Solopress est la confusion entre l'utilisation correcte de \"your\" et de \"you're\".<\/p>\n<p>5. L'introduction d'une feuille de style pour votre entreprise est une id\u00e9e brillante. Les feuilles de style sont l'\u00e9l\u00e9ment de base de tout journal, magazine ou site web professionnel - elles fonctionnent donc. Elles contribueront \u00e0 faire en sorte que toutes les communications \u00e9manant de chacun de vos employ\u00e9s et destin\u00e9es au monde ext\u00e9rieur apparaissent comme un ensemble coh\u00e9rent. Uniques et sp\u00e9cifiquement adapt\u00e9es \u00e0 votre entreprise, les feuilles de style ne prennent que tr\u00e8s peu de temps \u00e0 cr\u00e9er et \u00e0 mettre en \u0153uvre. Une feuille de style bien con\u00e7ue expliquera \u00e0 tous les membres de votre organisation quels mots, orthographes, phrases et abr\u00e9viations ils doivent utiliser dans les lettres, les courriels, les messages texte sur t\u00e9l\u00e9phone portable, les commentaires sur Twitter, etc. Si l'on prend l'exemple de Solopress.com, notre personnel doit-il dire que nous sommes bas\u00e9s \u00e0 Southend ou \u00e0 Southend-on-Sea ?<\/p>\n<h2>Les chocs de l'orthographe<\/h2>\n<p>* La majorit\u00e9 des Britanniques estiment que leur niveau d'orthographe est tr\u00e8s bon ou assez bon. Nous devons tous \u00eatre des imb\u00e9ciles, car seul 1 r\u00e9pondant sur 5 \u00e0 l'enqu\u00eate de Mencap a correctement orthographi\u00e9 tous les mots d'un petit test d'orthographe qui lui a \u00e9t\u00e9 propos\u00e9.<br \/>\n* Les femmes \u00e2g\u00e9es de 65 ans et plus sont les meilleures en orthographe de Grande-Bretagne. C'est vrai. Votre grand-m\u00e8re est plus dou\u00e9e que vous pour l'orthographe.<br \/>\n* Les pires orthographes de Grande-Bretagne sont des hommes \u00e2g\u00e9s de 18 \u00e0 24 ans. Nous sommes toutefois convaincus qu'ils peuvent \u00e9peler PlayStation, Jagerbomb et Kim Kardashian sans probl\u00e8me, ou presque.<br \/>\n* Un quart des Londoniens ont toujours recours \u00e0 un correcteur orthographique - plus que dans n'importe quelle autre r\u00e9gion de Grande-Bretagne. Le prix \u00e0 payer pour \u00eatre la capitale la plus cosmopolite du monde, peut-\u00eatre ?<br \/>\n* Oxford est la ville la plus performante de Grande-Bretagne en mati\u00e8re d'orthographe.<br \/>\n* Hull est la ville la plus mal orthographi\u00e9e de Grande-Bretagne.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4046\" title=\"\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2012\/05\/love-hate-spelling-mistake.jpg\" alt=\"Faute d&#039;orthographe de Love Hate\" width=\"650\" height=\"402\" \/><\/p>\n<h2>Les 20 mots les plus couramment mal orthographi\u00e9s<\/h2>\n<p>20. Remplacer<br \/>\n19. La conscience<br \/>\n18. Un lot<br \/>\n17. Parall\u00e8le<br \/>\n16. Entrepreneur<br \/>\n15. La bureaucratie<br \/>\n14. Le consensus<br \/>\n13. Man\u0153uvre<br \/>\n12. Questionnaire<br \/>\n11. Renvoy\u00e9<br \/>\n10. Occurrence<br \/>\n9. Particuli\u00e8rement<br \/>\n8. Brocoli<br \/>\n7. Embarrasser<br \/>\n6. Connaisseur<br \/>\n5. Acceptables<br \/>\n4. Calendrier<br \/>\n3. N\u00e9cessaire<br \/>\n2. S\u00e9parer<br \/>\n1. Sans aucun doute<\/p>\n<h2>C'est en pratiquant qu'on devient parfait<\/h2>\n<p>Que pouvez-vous faire d'autre pour \u00e9viter les fautes d'orthographe dans vos travaux d'impression ? Le vieux dicton \"c'est en forgeant qu'on devient forgeron\" peut vraiment faire la diff\u00e9rence lorsqu'il s'agit d'am\u00e9liorer son orthographe. Apr\u00e8s tout, Nintendo a fait fortune en faisant travailler nos cerveaux gr\u00e2ce \u00e0 sa c\u00e9l\u00e8bre s\u00e9rie de jeux vid\u00e9o d'entra\u00eenement c\u00e9r\u00e9bral Dr. Trop cher pour vous ? Les mots crois\u00e9s sont un moyen plus rapide et moins co\u00fbteux d'entra\u00eener votre cerveau.<\/p>\n<p>Mencap a \u00e9galement lanc\u00e9 la premi\u00e8re campagne de sensibilisation num\u00e9rique au monde. <a title=\"Spellathon dans le blog de Solopress Printing &amp; Design\" href=\"http:\/\/www.spellathon.net\" target=\"_blank\" rel=\"noopener noreferrer\">Championnat de spellathon<\/a> cette semaine. Les participants peuvent concourir en ligne et via une application t\u00e9l\u00e9chargeable pour leur t\u00e9l\u00e9phone intelligent iPhone, Android ou Blackberry. Les jeux d'orthographe amusants et interactifs de Spellathon sont anim\u00e9s par l'acteur Stephen Fry.<\/p>\n<h2>Donnez votre avis<\/h2>\n<p><strong>Quels sont les mots que VOUS trouvez difficiles \u00e0 orthographier correctement ?<\/strong> Veuillez faire d\u00e9filer cette page jusqu'\u00e0 la case \"Laissez une r\u00e9ponse\" ci-dessous pour poster vos commentaires et partager vos dessins (vous pouvez \u00e9galement commenter via la case Facebook)...<!--\/codes_iframe--><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":23,"featured_media":4045,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[555],"tags":[],"class_list":{"0":"post-4003","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tutorials"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>How To Avoid Spelling Mistakes In Your Printing<\/title>\n<meta name=\"description\" content=\"With millions of pages printed by Solopress.com every year, it\u2019s fair to say we\u2019ve seen some spectacular spelling mistakes in our time\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solopress.com\/blog\/fr\/tutoriels\/comment-eviter-les-fautes-dorthographe-lors-de-limpression\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How To Avoid Spelling Mistakes In Your Printing\" \/>\n<meta property=\"og:description\" content=\"With millions of pages printed by Solopress.com every year, it\u2019s fair to say we\u2019ve seen some spectacular spelling mistakes in our time\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solopress.com\/blog\/fr\/tutoriels\/comment-eviter-les-fautes-dorthographe-lors-de-limpression\/\" \/>\n<meta property=\"og:site_name\" content=\"The Latest Print and Design News | Solopress\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Solopress\" \/>\n<meta property=\"article:published_time\" content=\"2012-05-22T16:06:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-29T14:11:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2012\/05\/no-parking-spelling-mistake.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"402\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Solopress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@solopress\" \/>\n<meta name=\"twitter:site\" content=\"@solopress\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Solopress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-avoid-spelling-mistakes-in-your-printing\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-avoid-spelling-mistakes-in-your-printing\\\/\"},\"author\":{\"name\":\"Solopress\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/f8531403c74fe1b3ef14bcaeec1c8c41\"},\"headline\":\"How to avoid spelling mistakes in your printing\",\"datePublished\":\"2012-05-22T16:06:05+00:00\",\"dateModified\":\"2023-10-29T14:11:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-avoid-spelling-mistakes-in-your-printing\\\/\"},\"wordCount\":1054,\"commentCount\":10,\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-avoid-spelling-mistakes-in-your-printing\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/no-parking-spelling-mistake.jpg\",\"articleSection\":[\"Design Tutorials\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-avoid-spelling-mistakes-in-your-printing\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-avoid-spelling-mistakes-in-your-printing\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-avoid-spelling-mistakes-in-your-printing\\\/\",\"name\":\"How To Avoid Spelling Mistakes In Your Printing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-avoid-spelling-mistakes-in-your-printing\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-avoid-spelling-mistakes-in-your-printing\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/no-parking-spelling-mistake.jpg\",\"datePublished\":\"2012-05-22T16:06:05+00:00\",\"dateModified\":\"2023-10-29T14:11:37+00:00\",\"description\":\"With millions of pages printed by Solopress.com every year, it\u2019s fair to say we\u2019ve seen some spectacular spelling mistakes in our time\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-avoid-spelling-mistakes-in-your-printing\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-avoid-spelling-mistakes-in-your-printing\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-avoid-spelling-mistakes-in-your-printing\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/no-parking-spelling-mistake.jpg\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/no-parking-spelling-mistake.jpg\",\"width\":650,\"height\":402,\"caption\":\"No Parking spelling mistake\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-avoid-spelling-mistakes-in-your-printing\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How to avoid spelling mistakes in your printing\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"name\":\"The Latest Print and Design News | Solopress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\",\"name\":\"Solopress\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"width\":428,\"height\":88,\"caption\":\"Solopress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Solopress\",\"https:\\\/\\\/x.com\\\/solopress\",\"https:\\\/\\\/instagram.com\\\/solopress\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/solopress\",\"https:\\\/\\\/uk.pinterest.com\\\/solopress\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/solopress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/f8531403c74fe1b3ef14bcaeec1c8c41\",\"name\":\"Solopress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g\",\"caption\":\"Solopress\"},\"sameAs\":[\"https:\\\/\\\/www.solopress.com\\\/\"],\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/fr\\\/author\\\/solopress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment \u00e9viter les fautes d'orthographe dans vos impressions ?","description":"Avec des millions de pages imprim\u00e9es par Solopress.com chaque ann\u00e9e, il est juste de dire que nous avons vu quelques fautes d'orthographe spectaculaires dans notre temps.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solopress.com\/blog\/fr\/tutoriels\/comment-eviter-les-fautes-dorthographe-lors-de-limpression\/","og_locale":"fr_FR","og_type":"article","og_title":"How To Avoid Spelling Mistakes In Your Printing","og_description":"With millions of pages printed by Solopress.com every year, it\u2019s fair to say we\u2019ve seen some spectacular spelling mistakes in our time","og_url":"https:\/\/www.solopress.com\/blog\/fr\/tutoriels\/comment-eviter-les-fautes-dorthographe-lors-de-limpression\/","og_site_name":"The Latest Print and Design News | Solopress","article_publisher":"https:\/\/www.facebook.com\/Solopress","article_published_time":"2012-05-22T16:06:05+00:00","article_modified_time":"2023-10-29T14:11:37+00:00","og_image":[{"width":650,"height":402,"url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2012\/05\/no-parking-spelling-mistake.jpg","type":"image\/jpeg"}],"author":"Solopress","twitter_card":"summary_large_image","twitter_creator":"@solopress","twitter_site":"@solopress","twitter_misc":{"\u00c9crit par":"Solopress","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-avoid-spelling-mistakes-in-your-printing\/#article","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-avoid-spelling-mistakes-in-your-printing\/"},"author":{"name":"Solopress","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/f8531403c74fe1b3ef14bcaeec1c8c41"},"headline":"How to avoid spelling mistakes in your printing","datePublished":"2012-05-22T16:06:05+00:00","dateModified":"2023-10-29T14:11:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-avoid-spelling-mistakes-in-your-printing\/"},"wordCount":1054,"commentCount":10,"publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-avoid-spelling-mistakes-in-your-printing\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2012\/05\/no-parking-spelling-mistake.jpg","articleSection":["Design Tutorials"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.solopress.com\/blog\/tutorials\/how-to-avoid-spelling-mistakes-in-your-printing\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-avoid-spelling-mistakes-in-your-printing\/","url":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-avoid-spelling-mistakes-in-your-printing\/","name":"Comment \u00e9viter les fautes d'orthographe dans vos impressions ?","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-avoid-spelling-mistakes-in-your-printing\/#primaryimage"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-avoid-spelling-mistakes-in-your-printing\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2012\/05\/no-parking-spelling-mistake.jpg","datePublished":"2012-05-22T16:06:05+00:00","dateModified":"2023-10-29T14:11:37+00:00","description":"Avec des millions de pages imprim\u00e9es par Solopress.com chaque ann\u00e9e, il est juste de dire que nous avons vu quelques fautes d'orthographe spectaculaires dans notre temps.","breadcrumb":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-avoid-spelling-mistakes-in-your-printing\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solopress.com\/blog\/tutorials\/how-to-avoid-spelling-mistakes-in-your-printing\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-avoid-spelling-mistakes-in-your-printing\/#primaryimage","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2012\/05\/no-parking-spelling-mistake.jpg","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2012\/05\/no-parking-spelling-mistake.jpg","width":650,"height":402,"caption":"No Parking spelling mistake"},{"@type":"BreadcrumbList","@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-avoid-spelling-mistakes-in-your-printing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.solopress.com\/blog\/"},{"@type":"ListItem","position":2,"name":"How to avoid spelling mistakes in your printing"}]},{"@type":"WebSite","@id":"https:\/\/www.solopress.com\/blog\/#website","url":"https:\/\/www.solopress.com\/blog\/","name":"Les derni\u00e8res nouvelles en mati\u00e8re d'impression et de conception | Solopress","description":"","publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solopress.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.solopress.com\/blog\/#organization","name":"Solopress","url":"https:\/\/www.solopress.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","width":428,"height":88,"caption":"Solopress"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Solopress","https:\/\/x.com\/solopress","https:\/\/instagram.com\/solopress\/","https:\/\/www.linkedin.com\/company\/solopress","https:\/\/uk.pinterest.com\/solopress\/","https:\/\/www.youtube.com\/user\/solopress"]},{"@type":"Person","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/f8531403c74fe1b3ef14bcaeec1c8c41","name":"Solopress","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g","caption":"Solopress"},"sameAs":["https:\/\/www.solopress.com\/"],"url":"https:\/\/www.solopress.com\/blog\/fr\/author\/solopress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2012\/05\/no-parking-spelling-mistake.jpg","_links":{"self":[{"href":"https:\/\/www.solopress.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/4003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solopress.com\/blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.solopress.com\/blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/fr\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/fr\/wp-json\/wp\/v2\/comments?post=4003"}],"version-history":[{"count":5,"href":"https:\/\/www.solopress.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/4003\/revisions"}],"predecessor-version":[{"id":74627,"href":"https:\/\/www.solopress.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/4003\/revisions\/74627"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/fr\/wp-json\/wp\/v2\/media\/4045"}],"wp:attachment":[{"href":"https:\/\/www.solopress.com\/blog\/fr\/wp-json\/wp\/v2\/media?parent=4003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/fr\/wp-json\/wp\/v2\/categories?post=4003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/fr\/wp-json\/wp\/v2\/tags?post=4003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}