{"id":69748,"date":"2020-10-09T10:24:11","date_gmt":"2020-10-09T09:24:11","guid":{"rendered":"https:\/\/www.solopress.com\/blog\/?p=69748"},"modified":"2022-04-05T11:23:28","modified_gmt":"2022-04-05T10:23:28","slug":"quest-ce-que-le-dpi","status":"publish","type":"post","link":"https:\/\/www.solopress.com\/blog\/fr\/art-design\/what-is-dpi\/","title":{"rendered":"Qu'est-ce que le DPI ?"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p>Le concept de DPI est relativement simple dans le monde de la conception et de l'impression, mais il devient rapidement confus d\u00e8s que l'on entre dans les d\u00e9tails. Et l'IAP, c'est avant tout une question de d\u00e9tails !<\/p>\n<p>Essentiellement, le DPI est une mesure utilis\u00e9e pour \u00e9valuer le niveau de d\u00e9tail qui peut \u00eatre reproduit par une imprimante. Plus le DPI est \u00e9lev\u00e9, plus la quantit\u00e9 d'informations pouvant \u00eatre captur\u00e9e \u00e0 l'impression est importante. Un DPI \u00e9lev\u00e9 signifie que l'impression r\u00e9sultante devrait avoir une r\u00e9solution plus \u00e9lev\u00e9e, paraissant plus nette et plus d\u00e9taill\u00e9e.<\/p>\n<p>Mais ce n'est pas tout. La qualit\u00e9 de l'image qui sort de l'imprimante est le r\u00e9sultat de bien d'autres facteurs que le nombre de points par pouce de l'imprimante. Ajoutez \u00e0 cela le fait que DPI est souvent confondu avec le terme \"points par pouce\". <em>carr\u00e9<\/em> pouces\", ou \"pixels par pouce\", et il est clair que nous avons des explications \u00e0 donner. Commen\u00e7ons par le commencement.<\/p>\n<h2><strong>Qu'est-ce que le DPI<\/strong> <strong>repr\u00e9sentent-ils ?<\/strong><\/h2>\n<p>DPI signifie \"Dots Per Inch\" (points par pouce) et est utilis\u00e9 pour mesurer le niveau de d\u00e9tail reproduit dans une image ou par une imprimante.<\/p>\n<p>Le terme \"points\" d\u00e9signe les points d'encre appliqu\u00e9s par un dispositif d'impression. Le nombre de points par pouce est une mesure du nombre de ces points d'encre appliqu\u00e9s sur une ligne d'un pouce de long du mat\u00e9riau imprim\u00e9, \u00e9galement appel\u00e9e \"densit\u00e9 de points\". Elle donne une bonne indication de la nettet\u00e9 des d\u00e9tails qui peut \u00eatre obtenue avec ce dispositif d'impression.<\/p>\n<h2><strong>Qu'est-ce que le DPCM ?<\/strong><\/h2>\n<p>DPI signifie \"Dots Per Centimetre\" (points par centim\u00e8tre). Comme on peut s'y attendre, il s'agit de l'\u00e9quivalent m\u00e9trique de DPI. Malgr\u00e9 l'aspect pratique du DPCM, ce terme n'est pas largement adopt\u00e9 et le DPI reste la mesure standard de l'industrie pour la densit\u00e9 des points.<\/p>\n<h2><strong>Comment le DPI affecte-t-il la r\u00e9solution ?<\/strong><\/h2>\n<p>L'impression num\u00e9rique est une illusion d'optique. Pour que l'impression soit r\u00e9ussie, nous devons pr\u00e9senter une matrice de points suffisamment fine pour tromper l'\u0153il humain. Les spectateurs doivent penser qu'ils voient une repr\u00e9sentation de quelque chose qu'ils pourraient voir dans la vie r\u00e9elle. Quelque chose qui consiste en des lignes et des images continues, plut\u00f4t qu'en un motif pointill\u00e9.<\/p>\n<p>Pour ce faire, certaines conditions doivent \u00eatre remplies. La densit\u00e9 des points, la taille de l'image et la distance par rapport \u00e0 l'observateur doivent toutes se situer dans la bonne fourchette pour que notre illusion fonctionne. C'est l\u00e0 que le DPI entre en jeu. Il s'agit d'une mesure pratique qui nous permet d'\u00e9valuer la finesse d'impression n\u00e9cessaire pour que nos images apparaissent lisses et d\u00e9taill\u00e9es dans leur contexte.<\/p>\n<h2><strong>La densit\u00e9 de points est-elle mesur\u00e9e sur une ou deux dimensions ?<\/strong><\/h2>\n<p>Le DPI est parfois pr\u00e9sent\u00e9 sous la forme d'un seul chiffre, comme 1200dpi. Ailleurs, vous pouvez voir la m\u00eame mesure \u00e9crite comme 1200 x 1200dpi.<\/p>\n<p>En effet, le DPI pour l'impression se r\u00e9f\u00e8re au nombre de points qui apparaissent le long d'une ligne d'un pouce de long, et non dans une zone d'un pouce carr\u00e9.<\/p>\n<p>1200 x 1200dpi est une fa\u00e7on plus compl\u00e8te d'exprimer la densit\u00e9 de points, car il s'agit d'une mesure qui se r\u00e9f\u00e8re \u00e0 la surface. La combinaison des deux nombres donne les points par <em>carr\u00e9<\/em> pouce. Nous avons besoin des mesures horizontales et verticales pour comprendre la quantit\u00e9 et la disposition des points dans un carr\u00e9 en 2D.<\/p>\n<p>Toutefois, lorsque les deux valeurs sont identiques, le nombre n'est souvent indiqu\u00e9 qu'une seule fois. 1200dpi devient l'abr\u00e9viation de 1200 x 1200dpi.<\/p>\n<p>Mais ces deux chiffres ne sont pas toujours identiques ! Certains appareils \u00e0 jet d'encre peuvent avoir un nombre de points par pouce (DPI) diff\u00e9rent dans le sens horizontal et dans le sens vertical. Lorsqu'une t\u00eate d'impression se d\u00e9place sur une page, l'imprimante peut appliquer plus de points par pouce sur cet axe. Cela permet de distribuer et de m\u00e9langer plus pr\u00e9cis\u00e9ment le nombre limit\u00e9 d'encres afin de reproduire les couleurs avec plus de pr\u00e9cision. De nombreuses imprimantes de bureau haut de gamme, destin\u00e9es aux particuliers et aux entreprises, qui se targuent d'obtenir des r\u00e9sultats de \"qualit\u00e9 photo\", par exemple, peuvent imprimer \u00e0 5760 x 1440 dpi, 4800 x 2400 dpi ou 9600 x 2400 dpi.<\/p>\n<p>Ainsi, pour donner une image compl\u00e8te de la densit\u00e9 d'impression, une mesure de DPI en deux dimensions doit \u00eatre exprim\u00e9e sous la forme d'une paire de nombres.<\/p>\n<h2><strong>DPI vs PPI<\/strong><\/h2>\n<p>C'est tr\u00e8s bien pour les imprimantes, mais le DPI n'a-t-il pas un rapport avec la conception graphique num\u00e9rique et la taille des fichiers d'image ?<\/p>\n<p>C'est l\u00e0 qu'intervient la confusion avec un concept connexe mais diff\u00e9rent appel\u00e9 PPI, ou \"pixels par pouce\". Le PPI concerne les points d'encre, mais les \u00e9crans \u00e9lectroniques, les fichiers d'images et les capteurs des appareils photo num\u00e9riques fonctionnent tous en pixels. Le PPI est la fa\u00e7on dont nous mesurons la densit\u00e9 des pixels, plut\u00f4t que celle des points d'encre.<\/p>\n<p>Le fait que l'on parle souvent de DPI pour d\u00e9signer une image num\u00e9rique alors qu'il s'agit en r\u00e9alit\u00e9 de PPI n'est pas d'un grand secours.<\/p>\n<p>La plupart des dessins qui aboutissent \u00e0 l'impression commencent sur un ordinateur. Si l'on veut obtenir un r\u00e9sultat imprim\u00e9 en haute r\u00e9solution, il faut commencer par une image num\u00e9rique en haute r\u00e9solution. Le probl\u00e8me de l'imagerie num\u00e9rique \u00e0 haute r\u00e9solution est qu'elle implique une \u00e9norme quantit\u00e9 d'informations. Il en r\u00e9sulte des fichiers volumineux qui prennent de la place, n\u00e9cessitent une puissance de traitement importante pour \u00eatre manipul\u00e9s et sont encombrants \u00e0 d\u00e9placer.<\/p>\n<p>Il s'agit donc de trouver un \u00e9quilibre entre les fichiers d'images qui ne surchargent pas nos ordinateurs et ceux qui permettent d'obtenir une impression de haute qualit\u00e9.<\/p>\n<h2><strong>Quelle doit \u00eatre la taille de mon image num\u00e9rique ?<\/strong><\/h2>\n<p>Lorsque vous vous interrogez sur la \"taille\" de votre image num\u00e9rique, vous tenez compte de l'une des trois caract\u00e9ristiques suivantes :<\/p>\n<ul>\n<li>Le nombre total de pixels dans l'image (qui sera refl\u00e9t\u00e9 dans la taille du fichier)<\/li>\n<li>La r\u00e9solution ou la densit\u00e9 de pixels est mesur\u00e9e en PPI.<\/li>\n<li>Les dimensions physiques de l'image qu'il repr\u00e9sente, c'est-\u00e0-dire le nombre total de pixels divis\u00e9 par le PPI.<\/li>\n<\/ul>\n<p>Le PPI, qui mesure la densit\u00e9 des pixels, n'est qu'un aspect de l'ad\u00e9quation d'une image num\u00e9rique. La densit\u00e9 de pixels d\u00e9crit la relation entre la qualit\u00e9 et la taille, et ces deux facteurs interagissent l'un avec l'autre. Plus la taille augmente, plus la qualit\u00e9 diminue, et inversement.<\/p>\n<p>Imaginez une image compos\u00e9e d'un nombre fini de pixels par pouce. Si vous augmentez la taille de cette image dans un programme de conception, vous \u00e9tirez ce nombre fini de pixels sur une plus grande surface. Le nombre de points par pouce, ainsi que la r\u00e9solution et la qualit\u00e9 de l'image, diminueraient.<\/p>\n<p>Inversement, si vous avez une image au format A4 en 72ppi et que vous la modifiez ensuite en 300ppi, la taille de l'image sera consid\u00e9rablement r\u00e9duite. Les deux \u00e9l\u00e9ments de l'image, la quantit\u00e9 de pixels et la taille globale, d\u00e9pendent enti\u00e8rement l'un de l'autre.<\/p>\n<p>Si votre objectif est d'envoyer une image \u00e0 l'impression et que vous souhaitez pr\u00e9server votre qualit\u00e9 d'image de 300ppi, vous devez vous assurer que votre r\u00e9solution est r\u00e9gl\u00e9e sur 300ppi et que la taille de votre image est r\u00e9gl\u00e9e de mani\u00e8re \u00e0 repr\u00e9senter la taille du produit fini. Il est essentiel que ces param\u00e8tres soient d\u00e9finis au d\u00e9but du processus de conception, car il n'est pas possible d'ajouter des d\u00e9tails par la suite !<\/p>\n<h2><strong>72ppi pour l'\u00e9cran, 300ppi pour l'impression, n'est-ce pas ?<\/strong><\/h2>\n<p>Ce chiffre de 300ppi (souvent appel\u00e9 300 dpi, comme nous l'avons vu) provient du monde de l'\u00e9dition, o\u00f9 nous sommes habitu\u00e9s \u00e0 consid\u00e9rer une image imprim\u00e9e sur un support que l'on peut tenir dans ses mains et observer \u00e0 bout de bras. En r\u00e8gle g\u00e9n\u00e9rale, lorsqu'on envoie des fichiers \u00e0 imprimer, il faut s'assurer qu'ils ont une r\u00e9solution de 300ppi ou plus. Toutefois, pour un \u00e9l\u00e9ment imprim\u00e9 destin\u00e9 \u00e0 \u00eatre regard\u00e9 de loin, vous pouvez vous contenter d'une valeur inf\u00e9rieure.<\/p>\n<p>72ppi est g\u00e9n\u00e9ralement consid\u00e9r\u00e9 comme la r\u00e9solution optimale pour les images qui apparaissent sur l'internet. En effet, elles sont suffisamment grandes pour s'afficher correctement \u00e0 l'\u00e9cran, mais suffisamment compactes pour ne pas ralentir le temps de chargement de vos pages web.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Le DPI est donc une mesure simple, mais dont les implications pour la conception et l'impression sont consid\u00e9rables. Si vous ne savez toujours pas comment vous assurer que vos cr\u00e9ations sont pr\u00eates \u00e0 \u00eatre imprim\u00e9es ou si vous \u00eates pr\u00e9occup\u00e9 par la r\u00e9solution de votre impression, notre \u00e9quipe se tient \u00e0 votre disposition pour discuter de vos besoins. N'h\u00e9sitez pas \u00e0 nous contacter au 01702 460047, via <\/strong><a href=\"mailto:info@solopress.com\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>courriel<\/strong><\/a><strong> ou sur LiveChat.<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>The concept of DPI is a relatively simple one in the worlds of design and print, but it gets confusing quickly once we start diving into the details. And DPI is all about the details! Essentially, DPI is a measurement that&#8217;s used to evaluate the level of detail that can be reproduced by a printer. [&hellip;]<\/p>\n","protected":false},"author":134,"featured_media":69760,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[545],"tags":[],"class_list":{"0":"post-69748","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-art-design"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>What Is DPI &amp; What Does DPI Stand For? | Solopress UK<\/title>\n<meta name=\"description\" content=\"Learn about what DPI is, what it stands for, and the difference between DPI and PPI by reading our easy-to-follow blog post.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solopress.com\/blog\/fr\/design-dart\/quest-ce-que-le-dpi\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"What Is DPI &amp; What Does DPI Stand For? | Solopress UK\" \/>\n<meta property=\"og:description\" content=\"Learn about what DPI is, what it stands for, and the difference between DPI and PPI by reading our easy-to-follow blog post.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solopress.com\/blog\/fr\/design-dart\/quest-ce-que-le-dpi\/\" \/>\n<meta property=\"og:site_name\" content=\"The Latest Print and Design News | Solopress\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Solopress\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-09T09:24:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-05T10:23:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2020\/10\/dpi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Danny Powell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@solopress\" \/>\n<meta name=\"twitter:site\" content=\"@solopress\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Danny Powell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/art-design\\\/what-is-dpi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/art-design\\\/what-is-dpi\\\/\"},\"author\":{\"name\":\"Danny Powell\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/0937555a256c22f94400f4b7e2329c09\"},\"headline\":\"What is DPI?\",\"datePublished\":\"2020-10-09T09:24:11+00:00\",\"dateModified\":\"2022-04-05T10:23:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/art-design\\\/what-is-dpi\\\/\"},\"wordCount\":1324,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/art-design\\\/what-is-dpi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/dpi.jpg\",\"articleSection\":[\"Art &amp; Design\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/art-design\\\/what-is-dpi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/art-design\\\/what-is-dpi\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/art-design\\\/what-is-dpi\\\/\",\"name\":\"What Is DPI & What Does DPI Stand For? | Solopress UK\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/art-design\\\/what-is-dpi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/art-design\\\/what-is-dpi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/dpi.jpg\",\"datePublished\":\"2020-10-09T09:24:11+00:00\",\"dateModified\":\"2022-04-05T10:23:28+00:00\",\"description\":\"Learn about what DPI is, what it stands for, and the difference between DPI and PPI by reading our easy-to-follow blog post.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/art-design\\\/what-is-dpi\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/art-design\\\/what-is-dpi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/art-design\\\/what-is-dpi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/dpi.jpg\",\"width\":900,\"height\":675,\"caption\":\"DPI\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/art-design\\\/what-is-dpi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"What is DPI?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"name\":\"The Latest Print and Design News | Solopress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\",\"name\":\"Solopress\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"width\":428,\"height\":88,\"caption\":\"Solopress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Solopress\",\"https:\\\/\\\/x.com\\\/solopress\",\"https:\\\/\\\/instagram.com\\\/solopress\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/solopress\",\"https:\\\/\\\/uk.pinterest.com\\\/solopress\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/solopress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/0937555a256c22f94400f4b7e2329c09\",\"name\":\"Danny Powell\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"caption\":\"Danny Powell\"},\"description\":\"With over two decades in marketing, Danny Powell is a Senior Copywriter at Solopress, one of the UK\u2019s leading online printers. Having worked on the print buying, agency and sales sides of the industry, he brings a well-rounded perspective to his writing on print, design and sustainability.\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/fr\\\/author\\\/danny-powell\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qu'est-ce que le DPI et que signifie le DPI ? | DPI - Solopress UK","description":"D\u00e9couvrez ce qu'est le DPI, ce qu'il repr\u00e9sente et la diff\u00e9rence entre le DPI et le PPI en lisant notre article de blog facile \u00e0 suivre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solopress.com\/blog\/fr\/design-dart\/quest-ce-que-le-dpi\/","og_locale":"fr_FR","og_type":"article","og_title":"What Is DPI & What Does DPI Stand For? | Solopress UK","og_description":"Learn about what DPI is, what it stands for, and the difference between DPI and PPI by reading our easy-to-follow blog post.","og_url":"https:\/\/www.solopress.com\/blog\/fr\/design-dart\/quest-ce-que-le-dpi\/","og_site_name":"The Latest Print and Design News | Solopress","article_publisher":"https:\/\/www.facebook.com\/Solopress","article_published_time":"2020-10-09T09:24:11+00:00","article_modified_time":"2022-04-05T10:23:28+00:00","og_image":[{"width":900,"height":675,"url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2020\/10\/dpi.jpg","type":"image\/jpeg"}],"author":"Danny Powell","twitter_card":"summary_large_image","twitter_creator":"@solopress","twitter_site":"@solopress","twitter_misc":{"\u00c9crit par":"Danny Powell","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.solopress.com\/blog\/art-design\/what-is-dpi\/#article","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/art-design\/what-is-dpi\/"},"author":{"name":"Danny Powell","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/0937555a256c22f94400f4b7e2329c09"},"headline":"What is DPI?","datePublished":"2020-10-09T09:24:11+00:00","dateModified":"2022-04-05T10:23:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/art-design\/what-is-dpi\/"},"wordCount":1324,"commentCount":0,"publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/art-design\/what-is-dpi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2020\/10\/dpi.jpg","articleSection":["Art &amp; Design"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.solopress.com\/blog\/art-design\/what-is-dpi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.solopress.com\/blog\/art-design\/what-is-dpi\/","url":"https:\/\/www.solopress.com\/blog\/art-design\/what-is-dpi\/","name":"Qu'est-ce que le DPI et que signifie le DPI ? | DPI - Solopress UK","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/art-design\/what-is-dpi\/#primaryimage"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/art-design\/what-is-dpi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2020\/10\/dpi.jpg","datePublished":"2020-10-09T09:24:11+00:00","dateModified":"2022-04-05T10:23:28+00:00","description":"D\u00e9couvrez ce qu'est le DPI, ce qu'il repr\u00e9sente et la diff\u00e9rence entre le DPI et le PPI en lisant notre article de blog facile \u00e0 suivre.","breadcrumb":{"@id":"https:\/\/www.solopress.com\/blog\/art-design\/what-is-dpi\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solopress.com\/blog\/art-design\/what-is-dpi\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.solopress.com\/blog\/art-design\/what-is-dpi\/#primaryimage","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2020\/10\/dpi.jpg","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2020\/10\/dpi.jpg","width":900,"height":675,"caption":"DPI"},{"@type":"BreadcrumbList","@id":"https:\/\/www.solopress.com\/blog\/art-design\/what-is-dpi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.solopress.com\/blog\/"},{"@type":"ListItem","position":2,"name":"What is DPI?"}]},{"@type":"WebSite","@id":"https:\/\/www.solopress.com\/blog\/#website","url":"https:\/\/www.solopress.com\/blog\/","name":"Les derni\u00e8res nouvelles en mati\u00e8re d'impression et de conception | Solopress","description":"","publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solopress.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.solopress.com\/blog\/#organization","name":"Solopress","url":"https:\/\/www.solopress.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","width":428,"height":88,"caption":"Solopress"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Solopress","https:\/\/x.com\/solopress","https:\/\/instagram.com\/solopress\/","https:\/\/www.linkedin.com\/company\/solopress","https:\/\/uk.pinterest.com\/solopress\/","https:\/\/www.youtube.com\/user\/solopress"]},{"@type":"Person","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/0937555a256c22f94400f4b7e2329c09","name":"Danny Powell","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","caption":"Danny Powell"},"description":"Danny Powell, qui travaille depuis plus de vingt ans dans le domaine du marketing, est r\u00e9dacteur principal chez Solopress, l'un des principaux imprimeurs en ligne du Royaume-Uni. Ayant travaill\u00e9 dans les secteurs de l'achat d'imprim\u00e9s, des agences et des ventes, il apporte une perspective bien \u00e9quilibr\u00e9e \u00e0 ses \u00e9crits sur l'impression, le design et le d\u00e9veloppement durable.","url":"https:\/\/www.solopress.com\/blog\/fr\/author\/danny-powell\/"}]}},"jetpack_featured_media_url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2020\/10\/dpi.jpg","_links":{"self":[{"href":"https:\/\/www.solopress.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/69748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solopress.com\/blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.solopress.com\/blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/fr\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/fr\/wp-json\/wp\/v2\/comments?post=69748"}],"version-history":[{"count":4,"href":"https:\/\/www.solopress.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/69748\/revisions"}],"predecessor-version":[{"id":72098,"href":"https:\/\/www.solopress.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/69748\/revisions\/72098"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/fr\/wp-json\/wp\/v2\/media\/69760"}],"wp:attachment":[{"href":"https:\/\/www.solopress.com\/blog\/fr\/wp-json\/wp\/v2\/media?parent=69748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/fr\/wp-json\/wp\/v2\/categories?post=69748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/fr\/wp-json\/wp\/v2\/tags?post=69748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}