{"id":18713,"date":"2019-06-08T11:38:32","date_gmt":"2019-06-08T10:38:32","guid":{"rendered":"https:\/\/www.solopress.com\/blog\/?p=18713"},"modified":"2021-06-26T10:22:27","modified_gmt":"2021-06-26T09:22:27","slug":"cartoline-trendy-cool-design","status":"publish","type":"post","link":"https:\/\/www.solopress.com\/blog\/it\/art-design\/postcards-trendy-cool-design\/","title":{"rendered":"Idee di design per cartoline"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p><!--more--><\/p>\n<p>Il marketing delle cartoline \u00e8 un ottimo modo per far conoscere il vostro marchio. Piccola ma d'impatto, una cartolina ben progettata <a href=\"https:\/\/www.solopress.com\/blog\/it\/cartoline\/\">cartolina<\/a> vi aiuter\u00e0 a catturare l'attenzione dei vostri lettori, e magari a farli ridere, sorridere o ricordare un momento caro del passato.<\/p>\n<p>Date un'occhiata a queste 10 idee di design di cartoline ispiratrici per la vostra azienda.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Ciao da un posto bellissimo<\/strong><\/h2>\n<figure id=\"attachment_18716\" aria-describedby=\"caption-attachment-18716\" style=\"width: 550px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-18716\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/Postcard-Design-Hello-Beautiful.jpg\" alt=\"Cartolina calligrafica bianca fatta a mano\" width=\"550\" height=\"443\" \/><figcaption id=\"caption-attachment-18716\" class=\"wp-caption-text\">Ciao da un posto bellissimo di EmDashPaperCo<\/figcaption><\/figure>\n<p>Il lettore vede il panorama dagli occhi del mittente. In questo modo si cattura la sensazione che l'immagine suscita, acque calme e cieli limpidi, e la si proietta sul lettore.<\/p>\n<p>Il testo scritto a mano aggiunge anche un tocco personale, come se si trattasse semplicemente di un <strong>biglietto scarabocchiato da un amico<\/strong> sopra una foto delle vacanze, forse come ripensamento. Il testo bianco contrasta con l'azzurro dell'acqua e lo fa risaltare sullo sfondo.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Cartolina pop-up Uomo contro Inchiostro<\/strong><\/h2>\n<figure id=\"attachment_18719\" aria-describedby=\"caption-attachment-18719\" style=\"width: 550px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-18719\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/Postcard-Designs-3D.jpg\" alt=\"Cartolina pop-up 3D di Man vs Ink mostra una cartolina disegnata in 3D di Portland\" width=\"550\" height=\"603\" \/><figcaption id=\"caption-attachment-18719\" class=\"wp-caption-text\"><a title=\"Uomo contro inchiostro | Home page\" href=\"http:\/\/manvsink.com\/\">Uomo contro inchiostro<\/a> Cartolina pop-up<\/figcaption><\/figure>\n<p>Questa cartolina popup salta letteralmente agli occhi di chi la riceve. Con un <strong>scheda interattiva \"tirami<\/strong> e un'atmosfera personale e casalinga, questo design cattura perfettamente l'atmosfera creativa di Portland in modo eccentrico e divertente. Il design di questa cartolina ha l'aspetto di uno di questi film indie, con illustrazioni disegnate a mano e colori pastello tenui.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Saluti da Brooklyn<\/strong><\/h2>\n<figure id=\"attachment_18720\" aria-describedby=\"caption-attachment-18720\" style=\"width: 550px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-18720\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/Postcard-Design-Greetings-From-Brooklyn.jpg\" alt=\"Cartolina della mappa di Brooklyn con disegno tipografico. \" width=\"550\" height=\"733\" \/><figcaption id=\"caption-attachment-18720\" class=\"wp-caption-text\">Saluti da Brooklyn di pepperpressny<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h2><strong>Involucri di arance italiane<\/strong><\/h2>\n<figure id=\"attachment_18721\" aria-describedby=\"caption-attachment-18721\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-18721\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/Postcard-Design-Louise-Fili.jpg\" alt=\"Stravagante disegno di cartolina di involucri di arance italiane.\" width=\"600\" height=\"444\" \/><figcaption id=\"caption-attachment-18721\" class=\"wp-caption-text\"><a title=\"Louise Fili Ltd | Home\" href=\"https:\/\/www.louisefili.com\/\">Louise Fili Ltd<\/a>Involucri di arance italiane<\/figcaption><\/figure>\n<p>Questa cartolina gioca con i sensi del pubblico con testi stampati su prelibatezze tradizionali italiane, come arance e cioccolatini. Anche i dettagli delle confezioni increspate e lucide fanno venire voglia di <strong>allungare la mano e prenderne uno<\/strong>come su una bancarella del mercato di Roma.<\/p>\n<p>Guru del design <a href=\"http:\/\/www.philcleaver.com\/the-man.html\">Phil Cleaver<\/a>, vincitore di un prestigioso Yellow Pencil, afferma che i migliori marchi fanno appello ai nostri sensi.<\/p>\n<p>\"Un marchio efficace si rivolge al maggior numero possibile di sensi umani per radicarsi saldamente nella nostra memoria\", spiega Phil.<\/p>\n<p>Questa cartolina retr\u00f2 presenta una mappa di Brooklyn in vecchio stile. Stampata su carta di cellulosa, presenta una <strong>aspetto naturalmente antico <\/strong>- come quelle \"mappe\" macchiate di t\u00e8 che si facevano a scuola.<\/p>\n<p>La scritta rossa si distingue dal resto del testo, attirando sottilmente l'attenzione del lettore. La combinazione di colori marrone, rosso e blu scuro \u00e8 classica, con un'immagine di <a href=\"https:\/\/en.wikipedia.org\/wiki\/Ivy_League\">Ivy League americana<\/a> sentire. Mettete la storia al centro del design della vostra cartolina per evocare ricordi nei vostri lettori e creare un legame.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Naomi<\/strong><\/h2>\n<figure id=\"attachment_18722\" aria-describedby=\"caption-attachment-18722\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-18722\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/Postcard-Design-Naomi.jpg\" alt=\"Cartolina vintage &quot;save the date&quot; che mostra una coppia che fa una passeggiata romantica in campagna.\" width=\"650\" height=\"650\" \/><figcaption id=\"caption-attachment-18722\" class=\"wp-caption-text\">Naomi di NostalgicImprints<\/figcaption><\/figure>\n<p>Questa cartolina tradizionale gioca con la memoria, evocando la vacanza per antonomasia nella campagna inglese, tutta all'insegna della pigrizia e del divertimento. <strong>passeggiate pomeridiane in tranquille stradine di campagna<\/strong>. Il testo in stile antico contribuisce a dare la sensazione di rimpiangere un'epoca passata, raggiungibile solo leggendo questa cartolina.<\/p>\n<p>La curva della strada in questa cartolina attira l'occhio del lettore e lo spinge a seguirla fino all'orizzonte. Si tratta di una tecnica fotografica tradizionale chiamata \"leading line\", scelta per guidare le persone attraverso un'immagine.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Tokyo<\/strong><\/h2>\n<figure id=\"attachment_18738\" aria-describedby=\"caption-attachment-18738\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-18738\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/Postcard-Design-Tokyo.jpg\" alt=\"Pxel a scomparsa nello stile delle cartoline giapponesi dei giochi a premi\" width=\"600\" height=\"429\" \/><figcaption id=\"caption-attachment-18738\" class=\"wp-caption-text\">Tokyo di Sconosciuto<\/figcaption><\/figure>\n<p>Questa cartolina contemporanea giustappone un carattere tipografico in stile fumetto sullo sfondo di una delle strade pi\u00f9 storiche della citt\u00e0, Asakusa Rokku. Equilibra i sentimenti di <strong>modernit\u00e0 e tradizione<\/strong>passato e presente.<\/p>\n<p>Il colorato lavaggio blu porta con s\u00e9 sfumature di psichedelia, catturando la <strong>fermento e vivacit\u00e0<\/strong> I Pok\u00e9mon sono molto diffusi in citt\u00e0, con molte attivit\u00e0 per i fan.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Il paese delle meraviglie<\/strong><\/h2>\n<figure id=\"attachment_18742\" aria-describedby=\"caption-attachment-18742\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-18742\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/Postcard-Design-Wonderland.jpg\" alt=\"Cartolina retrospettiva \" width=\"600\" height=\"825\" \/><figcaption id=\"caption-attachment-18742\" class=\"wp-caption-text\">Il paese delle meraviglie di Atelier Olschinsky<\/figcaption><\/figure>\n<p>Questo design contemporaneo \u00e8 costruito intorno a forme geometriche su diversi livelli. Questo crea <strong>l'illusione della profondit\u00e0<\/strong>che attira il lettore all'interno della cartolina. Il design poco ortodosso \u00e8 bilanciato dai tenui colori autunnali - arancioni, marroni e verdi. Il tutto ricorda il 20<sup>th<\/sup> cinema europeo del secolo scorso. Per un marchio contemporaneo, magari un negozio di souvenir, un bar o un'agenzia creativa, questo design funziona bene.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Oia<\/strong><\/h2>\n<figure id=\"attachment_18732\" aria-describedby=\"caption-attachment-18732\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-18732\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/Postcard-Design-Oliwia-Gajda.jpg\" alt=\"Cartolina romantica con tramonto e giovane uomo che suona la chitarra a una giovane donna affacciata su una splendida baia. \" width=\"600\" height=\"852\" \/><figcaption id=\"caption-attachment-18732\" class=\"wp-caption-text\">Oia di Oliwia Gajda<\/figcaption><\/figure>\n<p>Questa cartolina artistica cattura un momento perfetto sotto forma di disegno. A differenza delle fotografie, le illustrazioni danno la possibilit\u00e0 di adattare l'immagine al meglio al messaggio che si vuole trasmettere. In questo modo, potete scegliere <strong>dove si deve concentrare il lettore<\/strong>e aggiungere qualsiasi altro testo o caratteristica che si ritenga opportuna.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Pizzaland<\/strong><\/h2>\n<figure id=\"attachment_18741\" aria-describedby=\"caption-attachment-18741\" style=\"width: 550px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-18741\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/Postcard-Design-Chris-Rushing.jpg\" alt=\"Cartolina di possibile ispirazione italiana di una fetta di pizza gigante, la cosiddetta &quot;pizzaland&quot;.\" width=\"550\" height=\"825\" \/><figcaption id=\"caption-attachment-18741\" class=\"wp-caption-text\"><a title=\"Chris Rushing | Home Page\" href=\"https:\/\/www.chrisrushing.com\/#Index\">Chris Rushing<\/a>Pizzaland<\/figcaption><\/figure>\n<p>Una nota catena di pizzerie statunitense ha creato questa cartolina in stile infografico che utilizza un layout a mappa per \"mappare\" gli ingredienti principali e gli USP della sua marca di pizza.<\/p>\n<p>Con aree come \"prati di mozzarella\" e \"spiaggia del primo morso\", il lettore viene condotto in un viaggio interattivo verso il paradiso della pizza. Questo approccio unico \u00e8 un ottimo modo per rimanere freschi come l'impasto della pizza di questa mattina nella mente dei vostri lettori.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Alpino<\/strong><\/h2>\n<figure id=\"attachment_18730\" aria-describedby=\"caption-attachment-18730\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-18730\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/Postcard-Design-Alpine.png\" alt=\"Cartolina dall&#039;aspetto mistico e fresco nella natura selvaggia. \" width=\"600\" height=\"388\" \/><figcaption id=\"caption-attachment-18730\" class=\"wp-caption-text\">Alpine di Ashley Earley<\/figcaption><\/figure>\n<p>Un altro design di cartolina semplice, ma questa volta sono le parole ad attirare l'attenzione. Il messaggio in grassetto e in maiuscolo presenta chiaramente una persona che ora \u00e8 sicura di s\u00e9 dopo un periodo di incertezza. Il <strong>il messaggio ispiratore si rivolge al lettore<\/strong> e dice: \"Potresti trovare anche te stesso\". Il carattere tipografico \u00e8 importante: spesso, in grassetto e bianco, porta con s\u00e9 il messaggio pesante delle parole.<\/p>\n<p>Phil dice che \u00e8 fondamentale fare le cose per bene. \"Pensate al messaggio che volete trasmettere e scegliete il carattere tipografico pi\u00f9 adatto\".<\/p>\n<p>&nbsp;<\/p>\n<p>Iniziate a creare la vostra cartolina premium su Solopress con il nostro <a href=\"https:\/\/www.solopress.com\/blog\/it\/free-artwork-templates\/cartoline\/\">modelli facili da usare<\/a>. <a href=\"https:\/\/www.solopress.com\/blog\/it\/cartoline\/\">Acquista oggi le cartoline<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":23,"featured_media":64676,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[545],"tags":[884],"class_list":{"0":"post-18713","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-art-design","8":"tag-postcards"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>10 Inspiring Postcard Design Ideas | Solopress UK<\/title>\n<meta name=\"description\" content=\"Think outside the box with your marketing with an effective postcard design. Check out these inspiring postcard ideas and start designing your own today.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solopress.com\/blog\/it\/design-darte\/cartoline-trendy-cool-design\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 Inspiring Postcard Design Ideas | Solopress UK\" \/>\n<meta property=\"og:description\" content=\"Think outside the box with your marketing with an effective postcard design. Check out these inspiring postcard ideas and start designing your own today.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solopress.com\/blog\/it\/design-darte\/cartoline-trendy-cool-design\/\" \/>\n<meta property=\"og:site_name\" content=\"The Latest Print and Design News | Solopress\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Solopress\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-08T10:38:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-26T09:22:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2019\/06\/Postcard-Design-Alpine.png\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Solopress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@solopress\" \/>\n<meta name=\"twitter:site\" content=\"@solopress\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Solopress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/art-design\\\/postcards-trendy-cool-design\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/art-design\\\/postcards-trendy-cool-design\\\/\"},\"author\":{\"name\":\"Solopress\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/f8531403c74fe1b3ef14bcaeec1c8c41\"},\"headline\":\"Postcard design ideas\",\"datePublished\":\"2019-06-08T10:38:32+00:00\",\"dateModified\":\"2021-06-26T09:22:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/art-design\\\/postcards-trendy-cool-design\\\/\"},\"wordCount\":938,\"commentCount\":10,\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/art-design\\\/postcards-trendy-cool-design\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Postcard-Design-Alpine.png\",\"keywords\":[\"Postcards\"],\"articleSection\":[\"Art &amp; Design\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/art-design\\\/postcards-trendy-cool-design\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/art-design\\\/postcards-trendy-cool-design\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/art-design\\\/postcards-trendy-cool-design\\\/\",\"name\":\"10 Inspiring Postcard Design Ideas | Solopress UK\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/art-design\\\/postcards-trendy-cool-design\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/art-design\\\/postcards-trendy-cool-design\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Postcard-Design-Alpine.png\",\"datePublished\":\"2019-06-08T10:38:32+00:00\",\"dateModified\":\"2021-06-26T09:22:27+00:00\",\"description\":\"Think outside the box with your marketing with an effective postcard design. Check out these inspiring postcard ideas and start designing your own today.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/art-design\\\/postcards-trendy-cool-design\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/art-design\\\/postcards-trendy-cool-design\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/art-design\\\/postcards-trendy-cool-design\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Postcard-Design-Alpine.png\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Postcard-Design-Alpine.png\",\"width\":900,\"height\":675,\"caption\":\"Alpine Postcard Design\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/art-design\\\/postcards-trendy-cool-design\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Postcard design ideas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"name\":\"The Latest Print and Design News | Solopress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\",\"name\":\"Solopress\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"width\":428,\"height\":88,\"caption\":\"Solopress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Solopress\",\"https:\\\/\\\/x.com\\\/solopress\",\"https:\\\/\\\/instagram.com\\\/solopress\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/solopress\",\"https:\\\/\\\/uk.pinterest.com\\\/solopress\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/solopress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/f8531403c74fe1b3ef14bcaeec1c8c41\",\"name\":\"Solopress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g\",\"caption\":\"Solopress\"},\"sameAs\":[\"https:\\\/\\\/www.solopress.com\\\/\"],\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/it\\\/author\\\/solopress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10 idee di design per cartoline ispiratrici | Solopress UK","description":"Pensate fuori dagli schemi per il vostro marketing con un design di cartolina efficace. Date un'occhiata a queste idee di cartoline ispiratrici e iniziate a progettare la vostra oggi stesso.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solopress.com\/blog\/it\/design-darte\/cartoline-trendy-cool-design\/","og_locale":"it_IT","og_type":"article","og_title":"10 Inspiring Postcard Design Ideas | Solopress UK","og_description":"Think outside the box with your marketing with an effective postcard design. Check out these inspiring postcard ideas and start designing your own today.","og_url":"https:\/\/www.solopress.com\/blog\/it\/design-darte\/cartoline-trendy-cool-design\/","og_site_name":"The Latest Print and Design News | Solopress","article_publisher":"https:\/\/www.facebook.com\/Solopress","article_published_time":"2019-06-08T10:38:32+00:00","article_modified_time":"2021-06-26T09:22:27+00:00","og_image":[{"width":900,"height":675,"url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2019\/06\/Postcard-Design-Alpine.png","type":"image\/png"}],"author":"Solopress","twitter_card":"summary_large_image","twitter_creator":"@solopress","twitter_site":"@solopress","twitter_misc":{"Scritto da":"Solopress","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.solopress.com\/blog\/art-design\/postcards-trendy-cool-design\/#article","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/art-design\/postcards-trendy-cool-design\/"},"author":{"name":"Solopress","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/f8531403c74fe1b3ef14bcaeec1c8c41"},"headline":"Postcard design ideas","datePublished":"2019-06-08T10:38:32+00:00","dateModified":"2021-06-26T09:22:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/art-design\/postcards-trendy-cool-design\/"},"wordCount":938,"commentCount":10,"publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/art-design\/postcards-trendy-cool-design\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2019\/06\/Postcard-Design-Alpine.png","keywords":["Postcards"],"articleSection":["Art &amp; Design"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.solopress.com\/blog\/art-design\/postcards-trendy-cool-design\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.solopress.com\/blog\/art-design\/postcards-trendy-cool-design\/","url":"https:\/\/www.solopress.com\/blog\/art-design\/postcards-trendy-cool-design\/","name":"10 idee di design per cartoline ispiratrici | Solopress UK","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/art-design\/postcards-trendy-cool-design\/#primaryimage"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/art-design\/postcards-trendy-cool-design\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2019\/06\/Postcard-Design-Alpine.png","datePublished":"2019-06-08T10:38:32+00:00","dateModified":"2021-06-26T09:22:27+00:00","description":"Pensate fuori dagli schemi per il vostro marketing con un design di cartolina efficace. Date un'occhiata a queste idee di cartoline ispiratrici e iniziate a progettare la vostra oggi stesso.","breadcrumb":{"@id":"https:\/\/www.solopress.com\/blog\/art-design\/postcards-trendy-cool-design\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solopress.com\/blog\/art-design\/postcards-trendy-cool-design\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.solopress.com\/blog\/art-design\/postcards-trendy-cool-design\/#primaryimage","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2019\/06\/Postcard-Design-Alpine.png","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2019\/06\/Postcard-Design-Alpine.png","width":900,"height":675,"caption":"Alpine Postcard Design"},{"@type":"BreadcrumbList","@id":"https:\/\/www.solopress.com\/blog\/art-design\/postcards-trendy-cool-design\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.solopress.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Postcard design ideas"}]},{"@type":"WebSite","@id":"https:\/\/www.solopress.com\/blog\/#website","url":"https:\/\/www.solopress.com\/blog\/","name":"Le ultime notizie su stampa e design | Solopress","description":"","publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solopress.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.solopress.com\/blog\/#organization","name":"Solopress","url":"https:\/\/www.solopress.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","width":428,"height":88,"caption":"Solopress"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Solopress","https:\/\/x.com\/solopress","https:\/\/instagram.com\/solopress\/","https:\/\/www.linkedin.com\/company\/solopress","https:\/\/uk.pinterest.com\/solopress\/","https:\/\/www.youtube.com\/user\/solopress"]},{"@type":"Person","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/f8531403c74fe1b3ef14bcaeec1c8c41","name":"Solopress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g","caption":"Solopress"},"sameAs":["https:\/\/www.solopress.com\/"],"url":"https:\/\/www.solopress.com\/blog\/it\/author\/solopress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2019\/06\/Postcard-Design-Alpine.png","_links":{"self":[{"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/posts\/18713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/comments?post=18713"}],"version-history":[{"count":5,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/posts\/18713\/revisions"}],"predecessor-version":[{"id":71401,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/posts\/18713\/revisions\/71401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/media\/64676"}],"wp:attachment":[{"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/media?parent=18713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/categories?post=18713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/tags?post=18713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}