{"id":18780,"date":"2014-06-27T14:51:32","date_gmt":"2014-06-27T13:51:32","guid":{"rendered":"https:\/\/www.solopress.com\/blog\/?p=18780"},"modified":"2023-04-28T20:53:44","modified_gmt":"2023-04-28T19:53:44","slug":"come-progettare-un-poster","status":"publish","type":"post","link":"https:\/\/www.solopress.com\/blog\/it\/tutorials\/how-to-design-a-poster\/","title":{"rendered":"Video tutorial di Photoshop: come progettare un poster"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p><!--more--><\/p>\n<h3><em>Imparare a <strong>progettare un poster in Adobe Photoshop<\/strong> con il nostro esperto, facile da seguire <strong>video tutorial<\/strong>\u2026<\/em><\/h3>\n<p>Questo video fa parte della serie di esercitazioni sul design di Adobe Creative. Assicuratevi di <strong><a title=\"Iscriviti a Solopress su YouTube\" href=\"https:\/\/www.youtube.com\/solopress?sub_confirmation=1\" target=\"_blank\" rel=\"external nofollow noopener noreferrer\">sottoscrivere<\/a><\/strong> al canale YouTube di Solopress per non perdere le guide future!<\/p>\n<div class=\"youtube-embed\" data-video_id=\"0GKTU-lhH1I\"><iframe loading=\"lazy\" title=\"Come progettare un poster in Photoshop | Tutorial di design\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/0GKTU-lhH1I?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/div>\n<h2>Come progettare un poster<\/h2>\n<p>Visitate il sito web di Solopress (<a href=\"https:\/\/www.solopress.com\/blog\/it\/\">www.solopress.com<\/a>) per scaricare la guida gratuita al modello Photoshop Poster A0 come base per il vostro poster.<\/p>\n<p>Aprite il file di Photoshop, abbiamo creato un livello guida che vi aiuter\u00e0 a progettare la vostra partecipazione di nozze - questo include l'area al vivo, il taglio e l'area di sicurezza.<\/p>\n<p>Area al vivo - Tutto ci\u00f2 che si trova qui verr\u00e0 tagliato, ma ricordate di estendere qualsiasi colorazione o immagine in quest'area al vivo di 3 mm per evitare che appaiano linee bianche durante le fasi di finitura della stampa.<\/p>\n<p>Rifilo - Il lavoro verr\u00e0 tagliato sulla linea nera continua; qualsiasi immagine o testo inserito in quest'area di 3 mm potrebbe essere rifilato in modo errato.<\/p>\n<p>Area sicura - Conservate tutte le informazioni all'interno dell'area bianca. Ricordate di utilizzare immagini ad alta risoluzione (300 dpi) per ottenere i migliori risultati.<\/p>\n<p>Creare una nuova guida facendo clic e trascinando il righello verticale e orizzontale (se il righello non appare in Photoshop, premere Command + R).<\/p>\n<p>Creare 4 nuove guide sulla linea dell'area sicura. In questo video ho creato 2 linee che attraversano il centro in verticale e in orizzontale; \u00e8 possibile impostarle sulla misura esatta facendo clic su Visualizza - Nuova guida e inserendo 420,5 mm per la verticale e 594,5 mm per l'orizzontale.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18786 size-full\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/1.png\" alt=\"1\" width=\"650\" height=\"350\" \/><\/p>\n<p><strong>Iniziamo!<\/strong><\/p>\n<p>Ora che le guide sono state posizionate, possiamo iniziare a lavorare sullo sfondo. Per creare uno sfondo a tinta unita, fare clic su Livelli-Nuovo livello di riempimento-Tinta unita. In questa dimostrazione user\u00f2 un colore di riempimento invece di un'immagine o di un motivo perch\u00e9 aggiunger\u00f2 delle forme per dare profondit\u00e0.<\/p>\n<p>Quando si trascina un'immagine, si ha immediatamente accesso alla possibilit\u00e0 di scalare, ruotare e capovolgere l'immagine. Se si desidera modificare una di queste opzioni dopo che l'immagine \u00e8 stata inserita, selezionare il livello e fare clic su Modifica - Trasformazione. Ho posizionato l'immagine delle mie linee e voglio copiarla per creare un modello. Per copiare un'immagine, fare clic con il pulsante destro del mouse sul livello e selezionare Duplica livello.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18788 size-full\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/3.png\" alt=\"3\" width=\"650\" height=\"350\" \/><\/p>\n<p>Quando ho aggiunto l'immagine del motivo chevron, ho cambiato il colore dell'immagine. Per farlo, fare clic con il pulsante destro del mouse sul livello e selezionare Opzioni di fusione. In questa finestra \u00e8 possibile sovrapporre colori solidi, sfumature e motivi, nonch\u00e9 aggiungere tratti, <a href=\"https:\/\/www.solopress.com\/blog\/it\/tutorial\/come-aggiungere-una-goccia-dombra-in-photoshop\/\">ombre a goccia<\/a> e modificare l'opacit\u00e0 del livello.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18787 size-full\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/2.png\" alt=\"2\" width=\"650\" height=\"350\" \/><\/p>\n<p>Ora \u00e8 il momento di aggiungere il testo; per farlo, selezionare lo strumento Testo nella barra laterale, fare clic su un punto qualsiasi del progetto e iniziare a digitare. \u00c8 possibile modificare il carattere, la dimensione, l'interlinea e altre opzioni utilizzando il Pannello caratteri, accessibile dalla barra delle opzioni di base del testo in alto. \u00c8 possibile ridimensionare (non consiglio di cambiare la dimensione del carattere), ruotare, capovolgere ecc. usando la funzione Modifica - Trasformazione di cui ho parlato prima.<\/p>\n<p>Dopo aver posizionato tutto il testo e le immagini, voglio aggiungere le barre per l'intestazione e il pi\u00e8 di pagina. Ho usato lo strumento Rettangolo nella barra laterale per disegnare la forma necessaria. Poi ho modificato l'aspetto utilizzando le Opzioni di fusione.<\/p>\n<p>Per non perdere il testo bianco nei motivi, ho usato le Opzioni di fusione e ho creato un tratto dello stesso colore dello sfondo, quindi ho ridotto l'opacit\u00e0 per sfumare.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18789 size-full\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/4.png\" alt=\"4\" width=\"650\" height=\"350\" \/><\/p>\n<p>Quando siete soddisfatti del vostro progetto, ricordatevi di eliminare il livello del modello!<\/p>\n<p>Per prepararsi a mandarlo in stampa, salvarlo come PDF utilizzando le opzioni del menu Salva con nome, quindi seguire le istruzioni sul sito web di Solopress.<\/p>\n<p>Ecco quindi un manifesto rock per la stagione dei festival!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18790 size-full\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/5.png\" alt=\"5\" width=\"650\" height=\"350\" \/><\/p>\n<p>Se avete commenti o domande sulla progettazione pronta per <a href=\"https:\/\/www.solopress.com\/blog\/it\/manifesti\/\">stampa di poster<\/a>utilizzate la sezione commenti qui sotto e faremo del nostro meglio per rispondere alle vostre domande.<\/p>\n<p>Grazie per aver guardato il nostro video tutorial!<\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":23,"featured_media":18790,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[555],"tags":[905,805],"class_list":{"0":"post-18780","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tutorials","8":"tag-photoshop","9":"tag-posters"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>How To Design A Poster In Photoshop | Solopress<\/title>\n<meta name=\"description\" content=\"Solopress Adobe Creative Tips &amp; Tutorials - Learn how to create a Poster using Adobe Photoshop with our expert, easy-to-follow video tutorial.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solopress.com\/blog\/it\/tutorial\/come-progettare-un-poster\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How To Design A Poster In Photoshop | Solopress\" \/>\n<meta property=\"og:description\" content=\"Solopress Adobe Creative Tips &amp; Tutorials - Learn how to create a Poster using Adobe Photoshop with our expert, easy-to-follow video tutorial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solopress.com\/blog\/it\/tutorial\/come-progettare-un-poster\/\" \/>\n<meta property=\"og:site_name\" content=\"The Latest Print and Design News | Solopress\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Solopress\" \/>\n<meta property=\"article:published_time\" content=\"2014-06-27T13:51:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-28T19:53:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/5.png\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Solopress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@solopress\" \/>\n<meta name=\"twitter:site\" content=\"@solopress\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Solopress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-design-a-poster\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-design-a-poster\\\/\"},\"author\":{\"name\":\"Solopress\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/f8531403c74fe1b3ef14bcaeec1c8c41\"},\"headline\":\"Photoshop video tutorials &#8211; how to design a Poster\",\"datePublished\":\"2014-06-27T13:51:32+00:00\",\"dateModified\":\"2023-04-28T19:53:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-design-a-poster\\\/\"},\"wordCount\":692,\"commentCount\":6,\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-design-a-poster\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/5.png\",\"keywords\":[\"Photoshop\",\"Posters\"],\"articleSection\":[\"Design Tutorials\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-design-a-poster\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-design-a-poster\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-design-a-poster\\\/\",\"name\":\"How To Design A Poster In Photoshop | Solopress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-design-a-poster\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-design-a-poster\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/5.png\",\"datePublished\":\"2014-06-27T13:51:32+00:00\",\"dateModified\":\"2023-04-28T19:53:44+00:00\",\"description\":\"Solopress Adobe Creative Tips & Tutorials - Learn how to create a Poster using Adobe Photoshop with our expert, easy-to-follow video tutorial.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-design-a-poster\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-design-a-poster\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-design-a-poster\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/5.png\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/5.png\",\"width\":650,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/tutorials\\\/how-to-design-a-poster\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Photoshop video tutorials &#8211; how to design a Poster\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"name\":\"The Latest Print and Design News | Solopress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\",\"name\":\"Solopress\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"width\":428,\"height\":88,\"caption\":\"Solopress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Solopress\",\"https:\\\/\\\/x.com\\\/solopress\",\"https:\\\/\\\/instagram.com\\\/solopress\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/solopress\",\"https:\\\/\\\/uk.pinterest.com\\\/solopress\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/solopress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/f8531403c74fe1b3ef14bcaeec1c8c41\",\"name\":\"Solopress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g\",\"caption\":\"Solopress\"},\"sameAs\":[\"https:\\\/\\\/www.solopress.com\\\/\"],\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/it\\\/author\\\/solopress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come progettare un poster in Photoshop | Solopress","description":"Solopress Adobe Creative Tips &amp; Tutorials - Imparate a creare un poster con Adobe Photoshop con il nostro video tutorial esperto e facile da seguire.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solopress.com\/blog\/it\/tutorial\/come-progettare-un-poster\/","og_locale":"it_IT","og_type":"article","og_title":"How To Design A Poster In Photoshop | Solopress","og_description":"Solopress Adobe Creative Tips & Tutorials - Learn how to create a Poster using Adobe Photoshop with our expert, easy-to-follow video tutorial.","og_url":"https:\/\/www.solopress.com\/blog\/it\/tutorial\/come-progettare-un-poster\/","og_site_name":"The Latest Print and Design News | Solopress","article_publisher":"https:\/\/www.facebook.com\/Solopress","article_published_time":"2014-06-27T13:51:32+00:00","article_modified_time":"2023-04-28T19:53:44+00:00","og_image":[{"width":650,"height":350,"url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/5.png","type":"image\/png"}],"author":"Solopress","twitter_card":"summary_large_image","twitter_creator":"@solopress","twitter_site":"@solopress","twitter_misc":{"Scritto da":"Solopress","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-design-a-poster\/#article","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-design-a-poster\/"},"author":{"name":"Solopress","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/f8531403c74fe1b3ef14bcaeec1c8c41"},"headline":"Photoshop video tutorials &#8211; how to design a Poster","datePublished":"2014-06-27T13:51:32+00:00","dateModified":"2023-04-28T19:53:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-design-a-poster\/"},"wordCount":692,"commentCount":6,"publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-design-a-poster\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/5.png","keywords":["Photoshop","Posters"],"articleSection":["Design Tutorials"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.solopress.com\/blog\/tutorials\/how-to-design-a-poster\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-design-a-poster\/","url":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-design-a-poster\/","name":"Come progettare un poster in Photoshop | Solopress","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-design-a-poster\/#primaryimage"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-design-a-poster\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/5.png","datePublished":"2014-06-27T13:51:32+00:00","dateModified":"2023-04-28T19:53:44+00:00","description":"Solopress Adobe Creative Tips &amp; Tutorials - Imparate a creare un poster con Adobe Photoshop con il nostro video tutorial esperto e facile da seguire.","breadcrumb":{"@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-design-a-poster\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solopress.com\/blog\/tutorials\/how-to-design-a-poster\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-design-a-poster\/#primaryimage","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/5.png","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/5.png","width":650,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/www.solopress.com\/blog\/tutorials\/how-to-design-a-poster\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.solopress.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Photoshop video tutorials &#8211; how to design a Poster"}]},{"@type":"WebSite","@id":"https:\/\/www.solopress.com\/blog\/#website","url":"https:\/\/www.solopress.com\/blog\/","name":"Le ultime notizie su stampa e design | Solopress","description":"","publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solopress.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.solopress.com\/blog\/#organization","name":"Solopress","url":"https:\/\/www.solopress.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","width":428,"height":88,"caption":"Solopress"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Solopress","https:\/\/x.com\/solopress","https:\/\/instagram.com\/solopress\/","https:\/\/www.linkedin.com\/company\/solopress","https:\/\/uk.pinterest.com\/solopress\/","https:\/\/www.youtube.com\/user\/solopress"]},{"@type":"Person","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/f8531403c74fe1b3ef14bcaeec1c8c41","name":"Solopress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g","caption":"Solopress"},"sameAs":["https:\/\/www.solopress.com\/"],"url":"https:\/\/www.solopress.com\/blog\/it\/author\/solopress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/06\/5.png","_links":{"self":[{"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/posts\/18780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/comments?post=18780"}],"version-history":[{"count":5,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/posts\/18780\/revisions"}],"predecessor-version":[{"id":73868,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/posts\/18780\/revisions\/73868"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/media\/18790"}],"wp:attachment":[{"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/media?parent=18780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/categories?post=18780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/tags?post=18780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}