{"id":25099,"date":"2014-09-22T10:53:33","date_gmt":"2014-09-22T09:53:33","guid":{"rendered":"https:\/\/www.solopress.com\/blog\/?p=25099"},"modified":"2020-02-26T17:01:34","modified_gmt":"2020-02-26T17:01:34","slug":"modi-creativi-per-dire-grazie-dopo-il-giorno-del-matrimonio","status":"publish","type":"post","link":"https:\/\/www.solopress.com\/blog\/it\/special-occasions\/creative-ways-to-say-thank-you-after-your-wedding-day\/","title":{"rendered":"Modi creativi per ringraziare dopo il matrimonio"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p><!--more--><\/p>\n<h3><em>Quando si tratta di matrimoni, ci sono tanti modi per ringraziare. Dai biglietti alle targhette, lasciatevi ispirare da queste favolose idee di design creativo.\u00a0<\/em><\/h3>\n<p>Durante l'organizzazione del giorno del matrimonio, da quello pi\u00f9 stravagante a quello pi\u00f9 semplice, un elemento comune \u00e8 il vostro <a href=\"https:\/\/www.solopress.com\/blog\/it\/wedding-stationery\/\">cancelleria per il matrimonio<\/a>. Qualunque sia il vostro budget, lo stile o il tema, l'arte di personalizzare il vostro giorno speciale ha visto molte creazioni ispirate mettere la ciliegina sulla torta, rendendo l'occasione memorabile perfetta.<\/p>\n<h2>Un ringraziamento personalizzato<\/h2>\n<p>Per i festeggiamenti del giorno del matrimonio potete pianificare in anticipo, selezionando una serie particolare di scatti fotografici che saranno utilizzati come modo diretto e puntuale di ringraziare.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-25127 size-full\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/09\/phot-thankyou.jpg\" alt=\"Biglietto di ringraziamento con fotografia di matrimonio\" width=\"600\" height=\"437\" \/><\/p>\n<p>Pu\u00f2 essere utilizzato per <a title=\"Design per la stampa di biglietti d&#039;auguri presso Solopress\" href=\"https:\/\/www.solopress.com\/blog\/it\/biglietti-dauguri\/\">biglietti d'auguri<\/a>\u00a0e cartoline stampate, oppure si pu\u00f2 essere un po' diversi e optare per una <a title=\"Stampa di volantini da Solopress\" href=\"https:\/\/www.solopress.com\/blog\/it\/volantini\/\">volantino o opuscolo<\/a> stile.<\/p>\n<h2>Un ringraziamento memorabile<\/h2>\n<p>Come nel caso delle fotografie, potete mostrare il vostro apprezzamento in modo indimenticabile e toccante.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-25128 size-full\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/09\/mixed-card-thanks.jpg\" alt=\"Cartolina di ringraziamento di matrimonio in stile memorabile\" width=\"600\" height=\"462\" \/>Questo sarebbe perfettamente illustrato in un <a title=\"Solopress offre la stampa di cartoline\" href=\"https:\/\/www.solopress.com\/blog\/it\/cartoline\/\">cartolina<\/a>per dare ai vostri ospiti un'idea concreta della gioia dell'evento.<\/p>\n<h2>Tipografia Gratitudine<\/h2>\n<p>In un modo alternativo, la dimostrazione di apprezzamento nei confronti degli ospiti del vostro matrimonio non deve solo tradursi nel compito puntuale di inviare biglietti di ringraziamento nelle prossime settimane dopo il giorno speciale.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-25130 size-full\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/09\/typed-wedding-thanks.jpg\" alt=\"Poster di ringraziamento per il matrimonio in stile tipografico\" width=\"398\" height=\"600\" \/><\/p>\n<p>Alcuni optano per la dimostrazione di gratitudine il giorno stesso o in \"tempo reale\". Esposti su ogni tavolo per completare le decorazioni, oppure tramite <a href=\"https:\/\/www.solopress.com\/blog\/it\/manifesti\/\">stampa di poster<\/a> In alcuni punti della location, queste eleganti aggiunte all'arredamento del matrimonio aggiungono quel qualcosa di speciale e lanciano un messaggio.<\/p>\n<h2>Aggiunte di bomboniere per il matrimonio<\/h2>\n<p>L'uso di <a title=\"Etichette Swing disponibili presso Solopress\" href=\"https:\/\/www.solopress.com\/blog\/it\/tag-swing\/\">cartellini swing stampati\u00a0<\/a>sono un'aggiunta creativa alle bomboniere di nozze. I disegni possono essere semplicistici, retr\u00f2 o vintage per adattarsi al vostro tema particolare.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-25138 size-full\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/09\/swing-tags.jpg\" alt=\"Bomboniere Swing Tags\" width=\"600\" height=\"600\" \/><\/p>\n<p>L'inclusione di cartellini oscillanti non si limita solo all'allestimento dei tavoli, ma pu\u00f2 essere una caratteristica attraente di un carrello per il buffet di caramelle, che \u00e8 un punto focale di grande successo per qualsiasi celebrazione di matrimonio.  Con molti modi per essere il pi\u00f9 creativi possibile, questa idea completer\u00e0 la giornata in modo perfetto in ogni modo.<\/p>\n<h2>Mantenere la semplicit\u00e0 con un'eleganza sobria<\/h2>\n<p>L'uso tradizionale del biglietto d'auguri, per ringraziare gli ospiti della loro presenza e dei loro regali, \u00e8 ancora una scelta popolare. Alcuni optano per uno stile abbinato al tema scelto, che comprende tutta la cancelleria, dagli inviti ai centro tavola fino al libro degli ospiti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-25146 size-full\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/09\/typogrphic-thankyou.jpg\" alt=\"Un biglietto di ringraziamento per il matrimonio elegante e semplice\" width=\"600\" height=\"450\" \/><\/p>\n<p>I biglietti possono essere semplicemente eleganti, fotografici o tipografici, a seconda delle preferenze personali.<\/p>\n<h2>Avanti, siate creativi e ringraziate!<\/h2>\n<p>In qualsiasi modo decidiate di ringraziare, con la quantit\u00e0 di scelte offerte e le libere capacit\u00e0 creative a vostra disposizione, la dimostrazione di questo sentimento sentito lascer\u00e0 sicuramente ai vostri ospiti un ricordo duraturo del giorno pi\u00f9 speciale della vostra vita.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-25155 size-full\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/09\/themed-card.jpg\" alt=\"Biglietto di ringraziamento a tema matrimonio\" width=\"600\" height=\"400\" \/><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":23,"featured_media":25138,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[553],"tags":[893],"class_list":{"0":"post-25099","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-special-occasions","8":"tag-weddings"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Creative Ways To Say Thank You After Your Wedding | Solopress UK<\/title>\n<meta name=\"description\" content=\"There are many ways to say thank you to your wedding guests using printed cards or even tags. From the unique to the classic, explore and get creative!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solopress.com\/blog\/it\/occasioni-speciali\/modi-creativi-per-dire-grazie-dopo-il-giorno-del-matrimonio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Creative Ways To Say Thank You After Your Wedding | Solopress UK\" \/>\n<meta property=\"og:description\" content=\"There are many ways to say thank you to your wedding guests using printed cards or even tags. From the unique to the classic, explore and get creative!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solopress.com\/blog\/it\/occasioni-speciali\/modi-creativi-per-dire-grazie-dopo-il-giorno-del-matrimonio\/\" \/>\n<meta property=\"og:site_name\" content=\"The Latest Print and Design News | Solopress\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Solopress\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-22T09:53:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-26T17:01:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/09\/swing-tags.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Solopress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@solopress\" \/>\n<meta name=\"twitter:site\" content=\"@solopress\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Solopress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/special-occasions\\\/creative-ways-to-say-thank-you-after-your-wedding-day\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/special-occasions\\\/creative-ways-to-say-thank-you-after-your-wedding-day\\\/\"},\"author\":{\"name\":\"Solopress\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/f8531403c74fe1b3ef14bcaeec1c8c41\"},\"headline\":\"Creative ways to say thank you after your wedding day\",\"datePublished\":\"2014-09-22T09:53:33+00:00\",\"dateModified\":\"2020-02-26T17:01:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/special-occasions\\\/creative-ways-to-say-thank-you-after-your-wedding-day\\\/\"},\"wordCount\":482,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/special-occasions\\\/creative-ways-to-say-thank-you-after-your-wedding-day\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/swing-tags.jpg\",\"keywords\":[\"Weddings\"],\"articleSection\":[\"Special Occasions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/special-occasions\\\/creative-ways-to-say-thank-you-after-your-wedding-day\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/special-occasions\\\/creative-ways-to-say-thank-you-after-your-wedding-day\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/special-occasions\\\/creative-ways-to-say-thank-you-after-your-wedding-day\\\/\",\"name\":\"Creative Ways To Say Thank You After Your Wedding | Solopress UK\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/special-occasions\\\/creative-ways-to-say-thank-you-after-your-wedding-day\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/special-occasions\\\/creative-ways-to-say-thank-you-after-your-wedding-day\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/swing-tags.jpg\",\"datePublished\":\"2014-09-22T09:53:33+00:00\",\"dateModified\":\"2020-02-26T17:01:34+00:00\",\"description\":\"There are many ways to say thank you to your wedding guests using printed cards or even tags. From the unique to the classic, explore and get creative!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/special-occasions\\\/creative-ways-to-say-thank-you-after-your-wedding-day\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/special-occasions\\\/creative-ways-to-say-thank-you-after-your-wedding-day\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/special-occasions\\\/creative-ways-to-say-thank-you-after-your-wedding-day\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/swing-tags.jpg\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/swing-tags.jpg\",\"width\":600,\"height\":600,\"caption\":\"Swing tags weddng favours\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/special-occasions\\\/creative-ways-to-say-thank-you-after-your-wedding-day\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Creative ways to say thank you after your wedding day\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"name\":\"The Latest Print and Design News | Solopress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\",\"name\":\"Solopress\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"width\":428,\"height\":88,\"caption\":\"Solopress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Solopress\",\"https:\\\/\\\/x.com\\\/solopress\",\"https:\\\/\\\/instagram.com\\\/solopress\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/solopress\",\"https:\\\/\\\/uk.pinterest.com\\\/solopress\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/solopress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/f8531403c74fe1b3ef14bcaeec1c8c41\",\"name\":\"Solopress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g\",\"caption\":\"Solopress\"},\"sameAs\":[\"https:\\\/\\\/www.solopress.com\\\/\"],\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/it\\\/author\\\/solopress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Modi creativi per dire grazie dopo il matrimonio | Solopress UK","description":"Ci sono molti modi per ringraziare gli ospiti del vostro matrimonio utilizzando biglietti stampati o tag. Da quelli unici a quelli classici, esplorate e siate creativi!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solopress.com\/blog\/it\/occasioni-speciali\/modi-creativi-per-dire-grazie-dopo-il-giorno-del-matrimonio\/","og_locale":"it_IT","og_type":"article","og_title":"Creative Ways To Say Thank You After Your Wedding | Solopress UK","og_description":"There are many ways to say thank you to your wedding guests using printed cards or even tags. From the unique to the classic, explore and get creative!","og_url":"https:\/\/www.solopress.com\/blog\/it\/occasioni-speciali\/modi-creativi-per-dire-grazie-dopo-il-giorno-del-matrimonio\/","og_site_name":"The Latest Print and Design News | Solopress","article_publisher":"https:\/\/www.facebook.com\/Solopress","article_published_time":"2014-09-22T09:53:33+00:00","article_modified_time":"2020-02-26T17:01:34+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/09\/swing-tags.jpg","type":"image\/jpeg"}],"author":"Solopress","twitter_card":"summary_large_image","twitter_creator":"@solopress","twitter_site":"@solopress","twitter_misc":{"Scritto da":"Solopress","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.solopress.com\/blog\/special-occasions\/creative-ways-to-say-thank-you-after-your-wedding-day\/#article","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/special-occasions\/creative-ways-to-say-thank-you-after-your-wedding-day\/"},"author":{"name":"Solopress","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/f8531403c74fe1b3ef14bcaeec1c8c41"},"headline":"Creative ways to say thank you after your wedding day","datePublished":"2014-09-22T09:53:33+00:00","dateModified":"2020-02-26T17:01:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/special-occasions\/creative-ways-to-say-thank-you-after-your-wedding-day\/"},"wordCount":482,"commentCount":0,"publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/special-occasions\/creative-ways-to-say-thank-you-after-your-wedding-day\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/09\/swing-tags.jpg","keywords":["Weddings"],"articleSection":["Special Occasions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.solopress.com\/blog\/special-occasions\/creative-ways-to-say-thank-you-after-your-wedding-day\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.solopress.com\/blog\/special-occasions\/creative-ways-to-say-thank-you-after-your-wedding-day\/","url":"https:\/\/www.solopress.com\/blog\/special-occasions\/creative-ways-to-say-thank-you-after-your-wedding-day\/","name":"Modi creativi per dire grazie dopo il matrimonio | Solopress UK","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/special-occasions\/creative-ways-to-say-thank-you-after-your-wedding-day\/#primaryimage"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/special-occasions\/creative-ways-to-say-thank-you-after-your-wedding-day\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/09\/swing-tags.jpg","datePublished":"2014-09-22T09:53:33+00:00","dateModified":"2020-02-26T17:01:34+00:00","description":"Ci sono molti modi per ringraziare gli ospiti del vostro matrimonio utilizzando biglietti stampati o tag. Da quelli unici a quelli classici, esplorate e siate creativi!","breadcrumb":{"@id":"https:\/\/www.solopress.com\/blog\/special-occasions\/creative-ways-to-say-thank-you-after-your-wedding-day\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solopress.com\/blog\/special-occasions\/creative-ways-to-say-thank-you-after-your-wedding-day\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.solopress.com\/blog\/special-occasions\/creative-ways-to-say-thank-you-after-your-wedding-day\/#primaryimage","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/09\/swing-tags.jpg","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/09\/swing-tags.jpg","width":600,"height":600,"caption":"Swing tags weddng favours"},{"@type":"BreadcrumbList","@id":"https:\/\/www.solopress.com\/blog\/special-occasions\/creative-ways-to-say-thank-you-after-your-wedding-day\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.solopress.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Creative ways to say thank you after your wedding day"}]},{"@type":"WebSite","@id":"https:\/\/www.solopress.com\/blog\/#website","url":"https:\/\/www.solopress.com\/blog\/","name":"Le ultime notizie su stampa e design | Solopress","description":"","publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solopress.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.solopress.com\/blog\/#organization","name":"Solopress","url":"https:\/\/www.solopress.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","width":428,"height":88,"caption":"Solopress"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Solopress","https:\/\/x.com\/solopress","https:\/\/instagram.com\/solopress\/","https:\/\/www.linkedin.com\/company\/solopress","https:\/\/uk.pinterest.com\/solopress\/","https:\/\/www.youtube.com\/user\/solopress"]},{"@type":"Person","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/f8531403c74fe1b3ef14bcaeec1c8c41","name":"Solopress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g","caption":"Solopress"},"sameAs":["https:\/\/www.solopress.com\/"],"url":"https:\/\/www.solopress.com\/blog\/it\/author\/solopress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2014\/09\/swing-tags.jpg","_links":{"self":[{"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/posts\/25099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/comments?post=25099"}],"version-history":[{"count":5,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/posts\/25099\/revisions"}],"predecessor-version":[{"id":66977,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/posts\/25099\/revisions\/66977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/media\/25138"}],"wp:attachment":[{"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/media?parent=25099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/categories?post=25099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/tags?post=25099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}