{"id":72374,"date":"2022-06-16T10:19:12","date_gmt":"2022-06-16T09:19:12","guid":{"rendered":"https:\/\/www.solopress.com\/blog\/?p=72374"},"modified":"2023-09-15T18:55:51","modified_gmt":"2023-09-15T17:55:51","slug":"compensazione-delle-emissioni-di-carbonio-riciclaggio","status":"publish","type":"post","link":"https:\/\/www.solopress.com\/blog\/it\/eco-friendly\/carbon-offsetting-v-recycling\/","title":{"rendered":"Compensazione delle emissioni di carbonio e riciclaggio: qual \u00e8 la differenza?"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p>Si parla continuamente di compensazione delle emissioni di anidride carbonica e di riciclaggio.<\/p>\n<p>Attraverso la nebbia inquinata, la compensazione delle emissioni di anidride carbonica ha apparentemente sostituito il riciclaggio come l'Everest della vita verde.<\/p>\n<p>La compensazione \u00e8 solo uno schema di greenwashing per migliorare l'immagine pubblica delle grandi imprese?<\/p>\n<p>Inoltre, come azienda e come cliente, a cosa dobbiamo dare la priorit\u00e0?<\/p>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/06\/Polluted-Jakarta.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-72375\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/06\/Polluted-Jakarta.jpg\" alt=\"\" width=\"1920\" height=\"1279\" \/><\/a><\/p>\n<h2><strong><u>Riciclaggio: un ricordo del passato?<\/u><\/strong><\/h2>\n<p>Il riciclaggio \u00e8 il metodo per creare nuovi prodotti a partire da materiali che altrimenti sarebbero stati gettati via come rifiuti. Non \u00e8 affatto una nuova invenzione.<\/p>\n<p>Fin dalla preistoria, gli utensili rotti venivano riutilizzati quando i materiali scarseggiavano.<\/p>\n<p>Il riciclaggio \u00e8 stato notato nella civilt\u00e0 moderna fin dal <a href=\"https:\/\/nerc.org\/news-and-updates\/blog\/nerc-blog\/2019\/11\/19\/a-brief-history-of-recycling\" target=\"_blank\" rel=\"noopener\">9<sup>th<\/sup> secolo Giappone<\/a> ma l'impatto dannoso che i rifiuti hanno su tutta la vita sulla Terra non \u00e8 stato veramente compreso fino ad oggi.<\/p>\n<p>I moderni metodi di riciclaggio hanno reso questo processo irriconoscibile rispetto alle sue umili origini.<\/p>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/06\/Recycling-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-72376\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/06\/Recycling-1.jpg\" alt=\"\" width=\"1920\" height=\"1136\" \/><\/a><\/p>\n<p>Con pi\u00f9 opportunit\u00e0 di riciclaggio che mai, perch\u00e9 solo 9% di rifiuti umani vengono riciclati?<\/p>\n<p>Dalla plastica ai telefoni, dal vetro ai rifiuti organici: c'\u00e8 ben poco che non possa essere smaltito in modo responsabile.<\/p>\n<p>Tuttavia, nonostante questa consapevolezza senza precedenti della necessit\u00e0 di riciclare, sembra che la razza umana non segua il suo stesso consiglio.<\/p>\n<p><a href=\"https:\/\/www.science.org\/doi\/10.1126\/sciadv.1700782\" target=\"_blank\" rel=\"noopener\">Uno studio recente<\/a> ha rivelato che di tutti i rifiuti di plastica prodotti dall'uomo, 79% finiscono in discarica o nell'ambiente naturale, 12% vengono bruciati e, come gi\u00e0 detto, solo 9% vengono riciclati.<\/p>\n<p>Il riciclaggio pu\u00f2 evitare che milioni di tonnellate di materiale vengano gettate in discarica. Una discarica equivale a nascondere il problema sotto il tappeto: seppellire e accumulare quantit\u00e0 enormi di rifiuti sposta semplicemente il problema senza farlo sparire.<\/p>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/06\/Under-the-carpet.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-72377\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/06\/Under-the-carpet.jpg\" alt=\"\" width=\"1920\" height=\"1920\" \/><\/a><\/p>\n<p>Al contrario, il riciclaggio apporta enormi benefici alla societ\u00e0, in molti modi che non si immaginano.<\/p>\n<h2><strong><u>Riciclaggio: Il bene, il male e le discariche<\/u><\/strong><\/h2>\n<p>La conservazione dell'energia \u00e8 il principale vantaggio ambientale del riciclaggio.<\/p>\n<p>Questo perch\u00e9 si risparmiano enormi quantit\u00e0 di energia riutilizzando un prodotto rispetto all'inquinamento causato dalla conversione delle risorse naturali e delle materie prime in nuovi prodotti.<\/p>\n<p>Altri vantaggi del riciclo sono:<\/p>\n<ul>\n<li>Riduzione dell'inquinamento dell'aria e dell'acqua<\/li>\n<li>Riduzione dei gas a effetto serra<\/li>\n<li>Conservazione delle risorse naturali<\/li>\n<li>Terreni boschivi e spazi aperti di maggiori dimensioni<\/li>\n<li>Meno rifiuti e paesaggi naturali pi\u00f9 incontaminati e habitat per la fauna selvatica<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/06\/Natural-landscape.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-72378\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/06\/Natural-landscape.jpg\" alt=\"\" width=\"1920\" height=\"1280\" \/><\/a><\/p>\n<p>Tuttavia, la contaminazione \u00e8 il principale svantaggio del riciclaggio.<\/p>\n<p>\u00c8 causato da noi, i consumatori.<\/p>\n<p>Allo stesso modo, questo dovrebbe significare che \u00e8 un problema che possiamo ribaltare.<\/p>\n<p>Le persone con le migliori intenzioni possono accidentalmente mescolare i rifiuti non riciclabili con quelli usa e getta, il che significa che un intero lotto di materiali riciclabili pu\u00f2 essere contaminato e quindi inutilizzabile.<\/p>\n<p>Come abbiamo discusso nel nostro <a href=\"https:\/\/www.solopress.com\/blog\/it\/ecologico\/la-ultima-guida-al-riciclaggio-della-carta\/\" target=\"_blank\" rel=\"noopener\">Guida definitiva al riciclo della carta<\/a>Una scatola di pizza da asporto usata pu\u00f2 rovinare la vostra settimana di riciclo di carta e cartone.<\/p>\n<p>La contaminazione ha diverse cause:<\/p>\n<ul>\n<li>Educazione minima su ci\u00f2 che pu\u00f2 essere riciclato<\/li>\n<li>Aree diverse in grado di riciclare cose diverse<\/li>\n<li>Riciclaggio di articoli pericolosi: aghi, pannolini e pesticidi.<\/li>\n<li>I rifiuti alimentari e liquidi non sono puliti<\/li>\n<li>Prodotti che non dovrebbero essere riciclati: sacchetti di plastica ecc.<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/06\/Pizza-box.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-72379\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/06\/Pizza-box.jpg\" alt=\"\" width=\"1920\" height=\"1280\" \/><\/a><\/p>\n<p>In media, <a href=\"https:\/\/www.rubicon.com\/blog\/recycling-contamination-facts\/\" target=\"_blank\" rel=\"noopener\">25% del riciclaggio \u00e8 contaminato<\/a>. Quindi, un articolo riciclato su quattro non serve a nulla e viene automaticamente gettato in discarica.<\/p>\n<p>Effetti del riciclaggio contaminato:<\/p>\n<ul>\n<li>Pu\u00f2 mandare in discarica prodotti che sarebbero stati riutilizzati.<\/li>\n<li>La separazione dei rifiuti contaminati richiede pi\u00f9 tempo e rende il riciclaggio una procedura pi\u00f9 costosa.<\/li>\n<li>La contaminazione pu\u00f2 disturbare o addirittura rompere le macchine, il che significa che \u00e8 necessario pi\u00f9 tempo per ripararle, il che rende ancora pi\u00f9 costoso il riciclaggio.<\/li>\n<li>I rifiuti pericolosi possono esporre i lavoratori a condizioni di lavoro pericolose<\/li>\n<\/ul>\n<p>Sfortunatamente, il riciclaggio moderno \u00e8 diventato un termine indorato per il viaggio che la maggior parte della plastica compie verso la sua destinazione di vacanza: la discarica.<\/p>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/06\/Landfill1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-72380\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/06\/Landfill1.jpg\" alt=\"\" width=\"1996\" height=\"1327\" \/><\/a><\/p>\n<h2><strong><u>Neutralit\u00e0 di carbonio - Non stare con le mani in mano<\/u><\/strong><\/h2>\n<p>La neutralit\u00e0 del carbonio \u00e8 salita alla ribalta nel 2006, quando \u00e8 stata dichiarata la parola preferita dagli Oxford Dictionaries negli Stati Uniti.<\/p>\n<p>I prodotti o i servizi caratterizzati come carbon neutral non comportano alcun rilascio netto di CO2 nell'atmosfera.<\/p>\n<p>Per essere etichettato come carbon neutral, un prodotto o un servizio deve fare una delle due cose:<\/p>\n<ul>\n<li>Non richiedono carbonio per essere prodotti<\/li>\n<\/ul>\n<p><strong>O<\/strong><\/p>\n<ul>\n<li>Compensare tutte le emissioni di carbonio durante il suo ciclo di vita in progetti di compensazione.<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.greenpeace.org.uk\/news\/the-biggest-problem-with-carbon-offsetting-is-that-it-doesnt-really-work\/#:~:text=What%20is%20carbon%20offsetting%3F,to%20communities%20in%20developing%20countries.\" target=\"_blank\" rel=\"noopener\">La compensazione \u00e8 un modo per pagare altri per ridurre le emissioni o assorbire CO<sub>2<\/sub> per compensare le proprie emissioni e ridurre l'impronta di carbonio.<\/a><\/p>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/06\/Tree-planting.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-72381\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/06\/Tree-planting.jpg\" alt=\"\" width=\"1920\" height=\"1322\" \/><\/a><\/p>\n<p>Piantare alberi, costruire parchi eolici e ripulire gli oceani dalla plastica sono tipi comuni di progetti di compensazione.<\/p>\n<p>Pensate alla compensazione delle emissioni di anidride carbonica come a una banca a cui pagate il vostro debito.<\/p>\n<p>Invece di indebitarsi, per\u00f2, si ripaga l'anidride carbonica prodotta compensandola da qualche altra parte attraverso un progetto di compensazione, come quelli che sosteniamo a <a href=\"https:\/\/www.solopress.com\/blog\/it\/notizie-solopress\/solopress-offset-100000-kg-di-co2\/\" target=\"_blank\" rel=\"noopener\">Brasile e Nicaragua.<\/a><\/p>\n<p>La compensazione delle emissioni di carbonio assorbir\u00e0 enormi quantit\u00e0 di CO2 prodotte dagli esseri umani, evitando che finiscano nell'atmosfera.<\/p>\n<h2><strong><u>Pi\u00f9 caldo<\/u><\/strong><\/h2>\n<p>La maggior parte dei prodotti passa dal raccolto alla linea di produzione, fino al capolinea: il cliente tramite il servizio di consegna.<\/p>\n<p>Molte aziende faticano a mantenere neutre dal punto di vista delle emissioni di carbonio tutte queste fasi della produzione. Ecco perch\u00e9 i progetti di compensazione delle emissioni di anidride carbonica hanno conosciuto un'ascesa vertiginosa.<\/p>\n<p>L'idea \u00e8 che, per tutti i gas a effetto serra emessi durante la fabbricazione di un prodotto, un peso equivalente di CO2 venga riassorbito grazie ai prodotti di compensazione del carbonio. Idealmente, il riassorbimento avverr\u00e0 entro la durata di vita del prodotto.<\/p>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/05\/Carbon-offset-cycle.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-72210\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/05\/Carbon-offset-cycle.jpg\" alt=\"\" width=\"1920\" height=\"1280\" \/><\/a><\/p>\n<p>La crescente pressione globale per trovare soluzioni per correggere, rallentare e annullare il cambiamento climatico ha senza dubbio portato la compensazione alla ribalta pi\u00f9 rapidamente.<\/p>\n<p>Dopo l'Accordo di Parigi e la COP26, ci si aspetta che tutti i partecipanti raggiungano la neutralit\u00e0 delle emissioni di carbonio per evitare che la temperatura del nostro pianeta aumenti di +1,5 \u00b0C.<\/p>\n<p>I leader mondiali stanno ora cercando di raggiungere gli obiettivi nazionali e internazionali fissati per evitare che la temperatura raggiunga +1,5\u00b0C.<\/p>\n<p>Sono state promesse alcune importanti mosse nel campionato carbon neutral per evitare che ci\u00f2 accada:<\/p>\n<ul>\n<li>Il piano del governo britannico prevede che la Gran Bretagna sia a zero emissioni entro il 2050.<\/li>\n<li>Il Regno Unito ha vietato la produzione e la vendita di nuove auto diesel entro il 2030<\/li>\n<li>Le Nazioni Unite si sono impegnate a ridurre a zero le emissioni entro il 2050.<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/06\/Net-zero.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-72383\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/06\/Net-zero.jpg\" alt=\"\" width=\"1920\" height=\"1280\" \/><\/a><\/p>\n<p>L'impegno dell'ONU per l'azzeramento delle emissioni arriva mentre la ricerca mostra che 68% delle emissioni globali provengono dai dieci Paesi che emettono pi\u00f9 gas serra.<\/p>\n<p>\u00c8 sconcertante che 46% del totale delle emissioni globali provengano da soli tre luoghi:<\/p>\n<ul>\n<li>Cina<\/li>\n<li>Gli Stati Uniti d'America<\/li>\n<li>L'Unione Europea<\/li>\n<\/ul>\n<p>Tuttavia, alcune aziende stanno prendendo in considerazione la situazione.<\/p>\n<p>Apple sostiene di essere gestita in modo neutrale dal punto di vista delle emissioni di anidride carbonica. Entro il 2030, Apple vuole che ogni dispositivo venduto abbia un impatto climatico netto pari a zero.<\/p>\n<p>Google sostiene gi\u00e0 di avere un impatto climatico pari a zero, grazie all'uso della compensazione delle emissioni di carbonio.<\/p>\n<h2><strong><u>Compensare la pace<\/u><\/strong><\/h2>\n<p>La compensazione delle emissioni di carbonio \u00e8 stata definita da Greenpeace come greenwashing aziendale.<\/p>\n<p>Sostengono che i produttori di combustibili fossili, come BP e Shell, nonch\u00e9 gli aeroporti come Heathrow e le compagnie aeree come EasyJet, utilizzano la compensazione pi\u00f9 come una trovata di pubbliche relazioni che come qualcosa di concreto.<\/p>\n<p>Senza ridurre le loro esorbitanti emissioni e il loro impatto sull'ambiente, i loro sforzi di compensazione avranno meno forza nell'affrontare il cambiamento climatico.<\/p>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/06\/Plane-emissions.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-72384\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/06\/Plane-emissions.jpg\" alt=\"\" width=\"1920\" height=\"1236\" \/><\/a><\/p>\n<p>I progetti sono in gran parte localizzati nei Paesi in via di sviluppo.<\/p>\n<p>La realizzazione di progetti di compensazione in comunit\u00e0 meno fortunate comporta una vasta serie di vantaggi per tutti i soggetti coinvolti.<\/p>\n<p>I progetti di compensazione offrono posti di lavoro alle comunit\u00e0 locali, migliorando l'economia. Migliorano risorse vitali come l'accesso all'acqua potabile.<\/p>\n<p>Inoltre, si espandono le infrastrutture locali e preservano la biodiversit\u00e0.<\/p>\n<p>Fattorie eoliche, <a href=\"https:\/\/www.solopress.com\/blog\/it\/notizie-solopress\/solopress-offset-100000-kg-di-co2\/\" target=\"_blank\" rel=\"noopener\">come quello che sosteniamo in Brasile<\/a>compensano centinaia di milioni di CO2 all'anno. Inoltre, contribuiscono ad alimentare vaste aree e a sostenere pi\u00f9 di una comunit\u00e0 locale.<\/p>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/05\/wind-farm.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-72211\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/05\/wind-farm.jpg\" alt=\"\" width=\"1920\" height=\"1193\" \/><\/a><\/p>\n<h2><strong><u>L'impegno di Solopress per la compensazione<\/u><\/strong><\/h2>\n<p>Qui alla Solopress abbiamo appena superato l'obiettivo di compensare 100.000 kg di CO2 in poco pi\u00f9 di un anno. Questo obiettivo \u00e8 stato raggiunto lavorando a fianco di ClimatePartner con tre diversi progetti di compensazione delle emissioni di carbonio che sosteniamo.<\/p>\n<p>Non avremmo potuto farlo senza il vostro supporto nell'acquisto dei prodotti del nostro <a href=\"https:\/\/www.solopress.com\/blog\/it\/green\/\" target=\"_blank\" rel=\"noopener\">Gamma verde Solopress<\/a>.<\/p>\n<p>Siamo orgogliosi di dimostrare che non siamo solo degli spuntatori di scatole verdi. Tutti i prodotti, dai volantini ai biglietti da visita e alle cartoline, vengono acquistati, prodotti e consegnati con una promessa di neutralit\u00e0 rispetto al carbonio.<\/p>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/06\/Carbon-neutral.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-72385\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/06\/Carbon-neutral.jpg\" alt=\"\" width=\"1920\" height=\"1108\" \/><\/a><\/p>\n<p>Tutta la nostra attivit\u00e0 \u00e8 alimentata da 100% di elettricit\u00e0 rinnovabile, grazie alla nostra partnership con TotalEnergies Gas.<\/p>\n<p>Riducendo l'utilizzo di carbonio e compensando quello prodotto, \u00e8 in grado di fornire un servizio di consegna completamente neutrale dal punto di vista del carbonio.<\/p>\n<h2><strong><u>Luci blu e sirene lampeggianti<\/u><\/strong><\/h2>\n<p>Il riciclaggio \u00e8 un modo importante per limitare i danni che stiamo causando ai nostri oceani e agli habitat verdi.<\/p>\n<p>Ridurre i nostri rifiuti aiuter\u00e0 a preservare questi ambienti diversi, consentendo loro di assorbire il carbonio al massimo delle loro potenzialit\u00e0.<\/p>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/06\/Clean-environment.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-72382\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/06\/Clean-environment.jpg\" alt=\"\" width=\"1920\" height=\"1152\" \/><\/a><\/p>\n<p>La compensazione delle emissioni di carbonio \u00e8 il modo per mitigare il cambiamento climatico, insieme a una riduzione globale delle nostre emissioni.<\/p>\n<p>Il tempo \u00e8 fondamentale per evitare un aumento globale della temperatura, quindi non c'\u00e8 una scelta o l'una o l'altra.<\/p>\n<p>Dobbiamo risolvere entrambi i problemi con le luci blu e le sirene accese.<\/p>\n<p>La compensazione \u00e8 un passo positivo per rimediare al nostro impatto sul cambiamento climatico, ma la riduzione dei nostri comportamenti dannosi \u00e8 l'unica risposta a lungo termine che la Terra vuole vedere.<\/p>","protected":false},"excerpt":{"rendered":"<p>We hear about carbon offsetting and recycling constantly. Through the polluted mist, carbon offsetting has seemingly replaced recycling as the Everest of green living. Is offsetting just a greenwashing scheme to finesse the public images of big businesses? Moreover, as a business and as a customer, which should we prioritise? Recycling &#8211; a thing of [&hellip;]<\/p>\n","protected":false},"author":154,"featured_media":72615,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[532],"tags":[],"class_list":{"0":"post-72374","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-eco-friendly"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carbon Offsetting v Recycling: What Is The Difference? - Solopress UK<\/title>\n<meta name=\"description\" content=\"Is carbon offsetting just a greenwashing scheme to finesse the public images of big businesses? As a business and as customers which is best?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solopress.com\/blog\/it\/ecologico\/compensazione-delle-emissioni-di-carbonio-riciclaggio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carbon Offsetting v Recycling: What Is The Difference? - Solopress UK\" \/>\n<meta property=\"og:description\" content=\"Is carbon offsetting just a greenwashing scheme to finesse the public images of big businesses? As a business and as customers which is best?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solopress.com\/blog\/it\/ecologico\/compensazione-delle-emissioni-di-carbonio-riciclaggio\/\" \/>\n<meta property=\"og:site_name\" content=\"The Latest Print and Design News | Solopress\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Solopress\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-16T09:19:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-15T17:55:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/06\/Green-footprint-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jake Ross\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@solopress\" \/>\n<meta name=\"twitter:site\" content=\"@solopress\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jake Ross\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/eco-friendly\\\/carbon-offsetting-v-recycling\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/eco-friendly\\\/carbon-offsetting-v-recycling\\\/\"},\"author\":{\"name\":\"Jake Ross\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/86438061b6921d896a81194a55080684\"},\"headline\":\"Carbon offsetting v recycling: what is the difference?\",\"datePublished\":\"2022-06-16T09:19:12+00:00\",\"dateModified\":\"2023-09-15T17:55:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/eco-friendly\\\/carbon-offsetting-v-recycling\\\/\"},\"wordCount\":1465,\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/eco-friendly\\\/carbon-offsetting-v-recycling\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Green-footprint-1.jpg\",\"articleSection\":[\"Eco Friendly\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/eco-friendly\\\/carbon-offsetting-v-recycling\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/eco-friendly\\\/carbon-offsetting-v-recycling\\\/\",\"name\":\"Carbon Offsetting v Recycling: What Is The Difference? - Solopress UK\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/eco-friendly\\\/carbon-offsetting-v-recycling\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/eco-friendly\\\/carbon-offsetting-v-recycling\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Green-footprint-1.jpg\",\"datePublished\":\"2022-06-16T09:19:12+00:00\",\"dateModified\":\"2023-09-15T17:55:51+00:00\",\"description\":\"Is carbon offsetting just a greenwashing scheme to finesse the public images of big businesses? As a business and as customers which is best?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/eco-friendly\\\/carbon-offsetting-v-recycling\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/eco-friendly\\\/carbon-offsetting-v-recycling\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/eco-friendly\\\/carbon-offsetting-v-recycling\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Green-footprint-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Green-footprint-1.jpg\",\"width\":900,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/eco-friendly\\\/carbon-offsetting-v-recycling\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carbon offsetting v recycling: what is the difference?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"name\":\"The Latest Print and Design News | Solopress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\",\"name\":\"Solopress\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"width\":428,\"height\":88,\"caption\":\"Solopress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Solopress\",\"https:\\\/\\\/x.com\\\/solopress\",\"https:\\\/\\\/instagram.com\\\/solopress\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/solopress\",\"https:\\\/\\\/uk.pinterest.com\\\/solopress\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/solopress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/86438061b6921d896a81194a55080684\",\"name\":\"Jake Ross\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97ff332c68b712fc4f6e179f11f1b65fb3ae3d18ec6c0115eb15220bdbbdf414?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97ff332c68b712fc4f6e179f11f1b65fb3ae3d18ec6c0115eb15220bdbbdf414?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97ff332c68b712fc4f6e179f11f1b65fb3ae3d18ec6c0115eb15220bdbbdf414?s=96&r=g\",\"caption\":\"Jake Ross\"},\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/it\\\/author\\\/jake-ross\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Compensazione delle emissioni di carbonio e riciclaggio: Qual \u00e8 la differenza? - Solopress Italia","description":"La compensazione delle emissioni di carbonio \u00e8 solo uno schema di greenwashing per migliorare l'immagine pubblica delle grandi aziende? Come azienda e come clienti, qual \u00e8 la cosa migliore?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solopress.com\/blog\/it\/ecologico\/compensazione-delle-emissioni-di-carbonio-riciclaggio\/","og_locale":"it_IT","og_type":"article","og_title":"Carbon Offsetting v Recycling: What Is The Difference? - Solopress UK","og_description":"Is carbon offsetting just a greenwashing scheme to finesse the public images of big businesses? As a business and as customers which is best?","og_url":"https:\/\/www.solopress.com\/blog\/it\/ecologico\/compensazione-delle-emissioni-di-carbonio-riciclaggio\/","og_site_name":"The Latest Print and Design News | Solopress","article_publisher":"https:\/\/www.facebook.com\/Solopress","article_published_time":"2022-06-16T09:19:12+00:00","article_modified_time":"2023-09-15T17:55:51+00:00","og_image":[{"width":900,"height":675,"url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/06\/Green-footprint-1.jpg","type":"image\/jpeg"}],"author":"Jake Ross","twitter_card":"summary_large_image","twitter_creator":"@solopress","twitter_site":"@solopress","twitter_misc":{"Scritto da":"Jake Ross","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.solopress.com\/blog\/eco-friendly\/carbon-offsetting-v-recycling\/#article","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/eco-friendly\/carbon-offsetting-v-recycling\/"},"author":{"name":"Jake Ross","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/86438061b6921d896a81194a55080684"},"headline":"Carbon offsetting v recycling: what is the difference?","datePublished":"2022-06-16T09:19:12+00:00","dateModified":"2023-09-15T17:55:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/eco-friendly\/carbon-offsetting-v-recycling\/"},"wordCount":1465,"publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/eco-friendly\/carbon-offsetting-v-recycling\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/06\/Green-footprint-1.jpg","articleSection":["Eco Friendly"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.solopress.com\/blog\/eco-friendly\/carbon-offsetting-v-recycling\/","url":"https:\/\/www.solopress.com\/blog\/eco-friendly\/carbon-offsetting-v-recycling\/","name":"Compensazione delle emissioni di carbonio e riciclaggio: Qual \u00e8 la differenza? - Solopress Italia","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/eco-friendly\/carbon-offsetting-v-recycling\/#primaryimage"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/eco-friendly\/carbon-offsetting-v-recycling\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/06\/Green-footprint-1.jpg","datePublished":"2022-06-16T09:19:12+00:00","dateModified":"2023-09-15T17:55:51+00:00","description":"La compensazione delle emissioni di carbonio \u00e8 solo uno schema di greenwashing per migliorare l'immagine pubblica delle grandi aziende? Come azienda e come clienti, qual \u00e8 la cosa migliore?","breadcrumb":{"@id":"https:\/\/www.solopress.com\/blog\/eco-friendly\/carbon-offsetting-v-recycling\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solopress.com\/blog\/eco-friendly\/carbon-offsetting-v-recycling\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.solopress.com\/blog\/eco-friendly\/carbon-offsetting-v-recycling\/#primaryimage","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/06\/Green-footprint-1.jpg","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/06\/Green-footprint-1.jpg","width":900,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/www.solopress.com\/blog\/eco-friendly\/carbon-offsetting-v-recycling\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.solopress.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Carbon offsetting v recycling: what is the difference?"}]},{"@type":"WebSite","@id":"https:\/\/www.solopress.com\/blog\/#website","url":"https:\/\/www.solopress.com\/blog\/","name":"Le ultime notizie su stampa e design | Solopress","description":"","publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solopress.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.solopress.com\/blog\/#organization","name":"Solopress","url":"https:\/\/www.solopress.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","width":428,"height":88,"caption":"Solopress"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Solopress","https:\/\/x.com\/solopress","https:\/\/instagram.com\/solopress\/","https:\/\/www.linkedin.com\/company\/solopress","https:\/\/uk.pinterest.com\/solopress\/","https:\/\/www.youtube.com\/user\/solopress"]},{"@type":"Person","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/86438061b6921d896a81194a55080684","name":"Jake Ross","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/97ff332c68b712fc4f6e179f11f1b65fb3ae3d18ec6c0115eb15220bdbbdf414?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97ff332c68b712fc4f6e179f11f1b65fb3ae3d18ec6c0115eb15220bdbbdf414?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97ff332c68b712fc4f6e179f11f1b65fb3ae3d18ec6c0115eb15220bdbbdf414?s=96&r=g","caption":"Jake Ross"},"url":"https:\/\/www.solopress.com\/blog\/it\/author\/jake-ross\/"}]}},"jetpack_featured_media_url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/06\/Green-footprint-1.jpg","_links":{"self":[{"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/posts\/72374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/users\/154"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/comments?post=72374"}],"version-history":[{"count":5,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/posts\/72374\/revisions"}],"predecessor-version":[{"id":74501,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/posts\/72374\/revisions\/74501"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/media\/72615"}],"wp:attachment":[{"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/media?parent=72374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/categories?post=72374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/tags?post=72374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}