{"id":73369,"date":"2023-03-17T11:19:32","date_gmt":"2023-03-17T11:19:32","guid":{"rendered":"https:\/\/www.solopress.com\/blog\/?p=73369"},"modified":"2023-11-14T14:27:04","modified_gmt":"2023-11-14T14:27:04","slug":"crescere-con-i-professionisti-nomi-e-tagline","status":"publish","type":"post","link":"https:\/\/www.solopress.com\/blog\/it\/entrepreneurs\/choosing-brand-names-and-taglines\/","title":{"rendered":"Scegliere un marchio e una tagline per un'impresa in fase di avviamento"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p><span style=\"font-weight: 400;\">Una parte emozionante del lancio di un'impresa \u00e8 la definizione del tono di voce e della personalit\u00e0 del marchio. Dopo aver fatto un po' di strada, i nostri imprenditori esperti hanno avuto il tempo di affinare questa personalit\u00e0, di utilizzarla in modi diversi e di testare i limiti della sua identit\u00e0.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Abbiamo incontrato Lorna Minter, Matt Davis e Christine Wyatt per rivivere quei viaggi e parlare delle ragioni alla base delle loro decisioni in merito al nome e allo slogan del marchio.<\/span><\/p>\n<h2><b>Fatevi un nome<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Il nome \u00e8 spesso la prima decisione di branding e la prima impressione che si fa al pubblico. \u00c8 una sfida riassumere il vostro prodotto, il vostro servizio e la vostra filosofia in un nome semplice e veloce. Le nostre tre aziende hanno seguito percorsi diversi per arrivare ai loro nomi, da quelli precisi, a quelli personali, a quelli pratici.<\/span><\/p>\n<h3><b>Biscotti e coni<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Il nostro esempio pi\u00f9 \"evidente\" \u00e8 sicuramente Cookies &amp; Cones. Il nome non lascia dubbi su cosa ci aspetta. \u00c8 un ottimo esempio di linguaggio a basso contesto, di cui ci occupiamo nel nostro <\/span><a href=\"https:\/\/www.solopress.com\/blog\/it\/marketing-aziendale\/6-consigli-su-come-scrivere-slogan-pubblicitari-che-vendano\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">blog sugli slogan<\/span><\/a><span style=\"font-weight: 400;\">. Tuttavia, con il passare del tempo, Matt ha scoperto che il nome \u00e8 diventato un'espressione troppo ristretta della loro offerta:<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">Ad essere brutalmente onesti, il nostro nome non \u00e8 probabilmente l'idea migliore che abbiamo avuto. Pu\u00f2 essere piuttosto limitante, soprattutto quando cerchiamo di vendere caff\u00e8 alla gente e in inverno, quando la gente non ha necessariamente voglia di gelato.<\/span><\/i><\/p>\n<p><i><span style=\"font-weight: 400;\"><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/02\/Cookies-and-Cones-01.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-73360\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/02\/Cookies-and-Cones-01.jpg\" alt=\"\" width=\"900\" height=\"460\" \/><\/a><\/span><\/i><i><span style=\"font-weight: 400;\"><br \/>\n<\/span><\/i><span style=\"font-weight: 400;\">Tuttavia, con il passare del tempo e la crescita della consapevolezza, i marchi possono diventare pi\u00f9 della somma delle loro parti. Il nome Cookies and Cones \u00e8 gi\u00e0 un simbolo di qualcosa di pi\u00f9 di semplici biscotti e gelati.<\/span><\/p>\n<h3><b>Via Latham<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Al contrario, <\/span><a href=\"https:\/\/latham-street.com\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Via Latham<\/span><\/a><span style=\"font-weight: 400;\"> \u00e8 un esempio di linguaggio ad alto contesto. \u00c8 necessario conoscere un po' di storia per apprezzare il nome. Latham Street prende il nome dalla strada di Preston in cui la fondatrice Lorna Minter viveva come studentessa.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La casa di Latham Street divenne un punto di ritrovo per gli appassionati della fiorente scena rave. Sono stati i ricordi di quel periodo a ispirare l'offerta centrale dell'attuale attivit\u00e0 di Lorna: abbigliamento che strizza l'occhio alla cultura dance degli anni '90, dell'anno 2000 e successivi.\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/03\/Screenshot-2023-03-17-at-11.09.42.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-73588\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/03\/Screenshot-2023-03-17-at-11.09.42.png\" alt=\"\" width=\"786\" height=\"374\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Il nome ha successo nonostante la necessit\u00e0 di un contesto, perch\u00e9 \u00e8 unico, ispira curiosit\u00e0 ed \u00e8 personale e significativo per Lorna.<\/span><\/p>\n<h3><b>Creare 98<\/b><\/h3>\n<p><a href=\"http:\/\/create98.co.uk\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Creare 98<\/span><\/a><span style=\"font-weight: 400;\">L'approccio di Christine al branding \u00e8 un po' diverso, in quanto tutto deriva dal luogo stesso. Christine ha acquistato 98 The Broadway Leigh-on-Sea con l'intento di avviare questa attivit\u00e0 artistica e gli aspetti della propriet\u00e0 esistente - il 98 dell'indirizzo, il muro di mattoni a vista - sono stati tutti integrati nel marchio. In definitiva, Create 98 \u00e8 un marchio che si \u00e8 sviluppato intorno ai mattoni e alla malta dove avviene la magia.<\/span><\/p>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/03\/Screenshot-2023-03-17-at-11.17.38.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-73589\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/03\/Screenshot-2023-03-17-at-11.17.38.png\" alt=\"\" width=\"1500\" height=\"886\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Per Christine era anche importante che il nome riassumesse attivit\u00e0 e creativit\u00e0. In origine, aveva intenzione di chiamare l'attivit\u00e0 \"Make 98\", ma aveva scoperto che un'altra azienda locale utilizzava un nome simile. L'essere costretta a tornare al tavolo da disegno si \u00e8 rivelato una benedizione, poich\u00e9 \"Create 98\", con la sua rima interna, \u00e8 un nome perfettamente accattivante che ricorda anche dove trovarlo.<\/span><\/p>\n<h2><b>Creare una tagline<\/b><\/h2>\n<p>Le aziende spesso utilizzano una breve frase per riassumere ci\u00f2 che hanno da offrire. Il nostro <a href=\"https:\/\/www.solopress.com\/blog\/it\/marketing-aziendale\/6-consigli-su-come-scrivere-slogan-pubblicitari-che-vendano\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">blog su slogan e tagline<\/span><\/a> offre alcuni consigli su ci\u00f2 che rende grande una linea, insieme ad esempi di marchi che hanno utilizzato approcci diversi per creare qualcosa di memorabile. Gli approcci delle nostre tre aziende sono molto diversi, ma ognuna di esse \u00e8 riuscita a raggiungere i propri obiettivi.<\/p>\n<h3><b>\"Riutilizzato. Rimosso. Rilanciato\".\u00a0<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Lo slogan di Latham Street \"Reused, remade, reloved\" (Riutilizzare, rifare, amare) ha davvero tutte le carte in regola. In primo luogo, \u00e8 reale. L'azienda riutilizza effettivamente i tessuti, che trasforma in nuovi capi, pronti per essere amati ancora una volta da un nuovo proprietario. Ma \u00e8 la parola \"reloved\" a essere determinante. Non la troverete nel dizionario, ma noi sappiamo esattamente cosa significa in questo contesto. <\/span><\/p>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/03\/Screenshot-2023-03-17-at-10.58.52.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-73585\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/03\/Screenshot-2023-03-17-at-10.58.52.png\" alt=\"\" width=\"1060\" height=\"772\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">I pezzi di Latham Street sono fatti per essere custoditi e apprezzati per la loro unicit\u00e0 - l'antitesi della fast fashion usa e getta. L'accattivante assonanza che lega le tre parole \u00e8 la ciliegina sulla torta.<\/span><\/p>\n<h3><b>\u00a0\"Vivere la vita in modo pi\u00f9 creativo\"<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">A prima vista, lo slogan di Create 98 invita il pubblico a considerare l'idea di incorporare la creativit\u00e0 nella propria routine. Il motivo per cui questa linea risuona pi\u00f9 profondamente, per\u00f2, \u00e8 il suggerimento che coltivare uno sbocco creativo pu\u00f2 anche avere il potere di permeare, migliorare e dare significato a ogni aspetto della nostra vita. Christine ci ha detto:<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">Quando abbiamo spiegato le aspirazioni del nostro marchio ai nostri progettisti, abbiamo detto: \"Vogliamo stimolare le persone a vivere la loro vita in modo pi\u00f9 creativo\", e cos\u00ec, da l\u00ec, \"vivere la vita in modo pi\u00f9 creativo\" \u00e8 diventato il nostro slogan. Lo abbiamo appeso al muro, lo abbiamo scritto nella dichiarazione di missione che si legge scendendo le scale e iniziamo sempre le nostre newsletter con questo messaggio.<\/span><\/i><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/03\/Screenshot-2023-03-17-at-11.05.01.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-73587\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/03\/Screenshot-2023-03-17-at-11.05.01.png\" alt=\"\" width=\"2412\" height=\"920\" \/><\/a><\/p>\n<h3><\/h3>\n<h3><\/h3>\n<h3><\/h3>\n<h3><\/h3>\n<h3><\/h3>\n<h3><b>Varie, tra cui \"Il posto pi\u00f9 cool della citt\u00e0\".<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Cookies and Cones non ha una tagline ufficiale, ma preferisce cambiare, utilizzando vari slogan nei suoi diversi canali. In riferimento ai suoi punti vendita, la frase \"the coolest place in town\" (il posto pi\u00f9 cool della citt\u00e0) compare sul sito di Cookies and Cones. <\/span><a href=\"https:\/\/cookiesandcones.co.uk\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Sito web di Biscotti e Coni<\/span><\/a><span style=\"font-weight: 400;\">Il sito di Cookies and Cones ci fa capire che si tratta di un locale alla moda, accennando alle delizie ghiacciate che ci aspettano. I loro furgoni per le consegne recano la scritta \"Here it crumbs!\", perch\u00e9 chi non ama i giochi di parole?\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/03\/Screenshot-2023-03-17-at-11.01.25.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-73586\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/03\/Screenshot-2023-03-17-at-11.01.25.png\" alt=\"\" width=\"1422\" height=\"716\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Altre volte l'azienda ha usato \"\u00c8 sempre tempo di biscotti\". Quando abbiamo chiesto a Matt Davis se si sentiva in grado di scegliere una tagline, ci ha risposto:<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><i><span style=\"font-weight: 400;\">Penso che sar\u00e0 sempre un'idea in movimento, per evitare di essere troppo restrittivi mentre cresciamo.<\/span><\/i><\/p>\n<h2><strong>Mettere l'immaginario al servizio delle parole<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Dopo aver creato un nome e una tagline, i marchi hanno bisogno di un'identit\u00e0 visiva da presentare al mondo. Nella prossima puntata di \"Crescere con i professionisti\" vedremo come sono nati i loghi e i colori del marchio delle tre aziende.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>An exciting part of launching any business is establishing the tone of voice and personality of the brand. Having gone a way down the track, our experienced entrepreneurs have had time to refine that personality, put it to use in different ways and to test the limits of its identity. We caught up with Lorna [&hellip;]<\/p>\n","protected":false},"author":134,"featured_media":73565,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[955],"tags":[],"class_list":{"0":"post-73369","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-entrepreneurs"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Choosing A Brand Name &amp; Tagline For A Start-up Business - Solopress UK<\/title>\n<meta name=\"description\" content=\"This blog looks at the origins of the brand names and taglines used by three businesses to help start-ups with the process.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solopress.com\/blog\/it\/imprenditori\/crescere-con-i-professionisti-nomi-e-tagline\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Choosing A Brand Name &amp; Tagline For A Start-up Business - Solopress UK\" \/>\n<meta property=\"og:description\" content=\"This blog looks at the origins of the brand names and taglines used by three businesses to help start-ups with the process.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solopress.com\/blog\/it\/imprenditori\/crescere-con-i-professionisti-nomi-e-tagline\/\" \/>\n<meta property=\"og:site_name\" content=\"The Latest Print and Design News | Solopress\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Solopress\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-17T11:19:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-14T14:27:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/03\/Blog-Grow-with-the-pros_03.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Danny Powell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@solopress\" \/>\n<meta name=\"twitter:site\" content=\"@solopress\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Danny Powell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/choosing-brand-names-and-taglines\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/choosing-brand-names-and-taglines\\\/\"},\"author\":{\"name\":\"Danny Powell\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/0937555a256c22f94400f4b7e2329c09\"},\"headline\":\"Choosing a brand name and tagline for a start-up business\",\"datePublished\":\"2023-03-17T11:19:32+00:00\",\"dateModified\":\"2023-11-14T14:27:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/choosing-brand-names-and-taglines\\\/\"},\"wordCount\":1018,\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/choosing-brand-names-and-taglines\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Blog-Grow-with-the-pros_03.jpg\",\"articleSection\":[\"Entrepreneurs\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/choosing-brand-names-and-taglines\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/choosing-brand-names-and-taglines\\\/\",\"name\":\"Choosing A Brand Name & Tagline For A Start-up Business - Solopress UK\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/choosing-brand-names-and-taglines\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/choosing-brand-names-and-taglines\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Blog-Grow-with-the-pros_03.jpg\",\"datePublished\":\"2023-03-17T11:19:32+00:00\",\"dateModified\":\"2023-11-14T14:27:04+00:00\",\"description\":\"This blog looks at the origins of the brand names and taglines used by three businesses to help start-ups with the process.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/choosing-brand-names-and-taglines\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/choosing-brand-names-and-taglines\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/choosing-brand-names-and-taglines\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Blog-Grow-with-the-pros_03.jpg\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Blog-Grow-with-the-pros_03.jpg\",\"width\":900,\"height\":675,\"caption\":\"Grow with the pros 2 brand names and taglines\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/choosing-brand-names-and-taglines\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Choosing a brand name and tagline for a start-up business\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"name\":\"The Latest Print and Design News | Solopress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\",\"name\":\"Solopress\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"width\":428,\"height\":88,\"caption\":\"Solopress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Solopress\",\"https:\\\/\\\/x.com\\\/solopress\",\"https:\\\/\\\/instagram.com\\\/solopress\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/solopress\",\"https:\\\/\\\/uk.pinterest.com\\\/solopress\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/solopress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/0937555a256c22f94400f4b7e2329c09\",\"name\":\"Danny Powell\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"caption\":\"Danny Powell\"},\"description\":\"With over two decades in marketing, Danny Powell is a Senior Copywriter at Solopress, one of the UK\u2019s leading online printers. Having worked on the print buying, agency and sales sides of the industry, he brings a well-rounded perspective to his writing on print, design and sustainability.\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/it\\\/author\\\/danny-powell\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Scegliere il nome del marchio e la tagline per un'impresa in fase di avviamento - Solopress Italia","description":"Questo blog analizza le origini dei nomi dei marchi e delle tagline utilizzati da tre aziende per aiutare le start-up in questo processo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solopress.com\/blog\/it\/imprenditori\/crescere-con-i-professionisti-nomi-e-tagline\/","og_locale":"it_IT","og_type":"article","og_title":"Choosing A Brand Name & Tagline For A Start-up Business - Solopress UK","og_description":"This blog looks at the origins of the brand names and taglines used by three businesses to help start-ups with the process.","og_url":"https:\/\/www.solopress.com\/blog\/it\/imprenditori\/crescere-con-i-professionisti-nomi-e-tagline\/","og_site_name":"The Latest Print and Design News | Solopress","article_publisher":"https:\/\/www.facebook.com\/Solopress","article_published_time":"2023-03-17T11:19:32+00:00","article_modified_time":"2023-11-14T14:27:04+00:00","og_image":[{"width":900,"height":675,"url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/03\/Blog-Grow-with-the-pros_03.jpg","type":"image\/jpeg"}],"author":"Danny Powell","twitter_card":"summary_large_image","twitter_creator":"@solopress","twitter_site":"@solopress","twitter_misc":{"Scritto da":"Danny Powell","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/choosing-brand-names-and-taglines\/#article","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/choosing-brand-names-and-taglines\/"},"author":{"name":"Danny Powell","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/0937555a256c22f94400f4b7e2329c09"},"headline":"Choosing a brand name and tagline for a start-up business","datePublished":"2023-03-17T11:19:32+00:00","dateModified":"2023-11-14T14:27:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/choosing-brand-names-and-taglines\/"},"wordCount":1018,"publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/choosing-brand-names-and-taglines\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/03\/Blog-Grow-with-the-pros_03.jpg","articleSection":["Entrepreneurs"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/choosing-brand-names-and-taglines\/","url":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/choosing-brand-names-and-taglines\/","name":"Scegliere il nome del marchio e la tagline per un'impresa in fase di avviamento - Solopress Italia","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/choosing-brand-names-and-taglines\/#primaryimage"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/choosing-brand-names-and-taglines\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/03\/Blog-Grow-with-the-pros_03.jpg","datePublished":"2023-03-17T11:19:32+00:00","dateModified":"2023-11-14T14:27:04+00:00","description":"Questo blog analizza le origini dei nomi dei marchi e delle tagline utilizzati da tre aziende per aiutare le start-up in questo processo.","breadcrumb":{"@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/choosing-brand-names-and-taglines\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solopress.com\/blog\/entrepreneurs\/choosing-brand-names-and-taglines\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/choosing-brand-names-and-taglines\/#primaryimage","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/03\/Blog-Grow-with-the-pros_03.jpg","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/03\/Blog-Grow-with-the-pros_03.jpg","width":900,"height":675,"caption":"Grow with the pros 2 brand names and taglines"},{"@type":"BreadcrumbList","@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/choosing-brand-names-and-taglines\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.solopress.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Choosing a brand name and tagline for a start-up business"}]},{"@type":"WebSite","@id":"https:\/\/www.solopress.com\/blog\/#website","url":"https:\/\/www.solopress.com\/blog\/","name":"Le ultime notizie su stampa e design | Solopress","description":"","publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solopress.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.solopress.com\/blog\/#organization","name":"Solopress","url":"https:\/\/www.solopress.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","width":428,"height":88,"caption":"Solopress"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Solopress","https:\/\/x.com\/solopress","https:\/\/instagram.com\/solopress\/","https:\/\/www.linkedin.com\/company\/solopress","https:\/\/uk.pinterest.com\/solopress\/","https:\/\/www.youtube.com\/user\/solopress"]},{"@type":"Person","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/0937555a256c22f94400f4b7e2329c09","name":"Danny Powell","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","caption":"Danny Powell"},"description":"Con oltre vent'anni di esperienza nel marketing, Danny Powell \u00e8 Senior Copywriter presso Solopress, uno dei principali stampatori online del Regno Unito. Avendo lavorato nel settore degli acquisti di stampa, delle agenzie e delle vendite, porta una prospettiva a tutto tondo nei suoi scritti su stampa, design e sostenibilit\u00e0.","url":"https:\/\/www.solopress.com\/blog\/it\/author\/danny-powell\/"}]}},"jetpack_featured_media_url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/03\/Blog-Grow-with-the-pros_03.jpg","_links":{"self":[{"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/posts\/73369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/comments?post=73369"}],"version-history":[{"count":5,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/posts\/73369\/revisions"}],"predecessor-version":[{"id":74643,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/posts\/73369\/revisions\/74643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/media\/73565"}],"wp:attachment":[{"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/media?parent=73369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/categories?post=73369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/tags?post=73369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}