{"id":75689,"date":"2025-09-13T08:16:27","date_gmt":"2025-09-13T07:16:27","guid":{"rendered":"https:\/\/www.solopress.com\/blog\/?p=75689"},"modified":"2025-10-13T09:00:50","modified_gmt":"2025-10-13T08:00:50","slug":"storie-di-clienti-che-costruiscono-il-supporto-per-linvio-di-amici","status":"publish","type":"post","link":"https:\/\/www.solopress.com\/blog\/it\/customer-stories\/customer-stories-building-support-for-send-friends\/","title":{"rendered":"Storie di clienti: costruire un supporto per gli amici SEND"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p><span style=\"font-weight: 400;\">Quando si costruisce qualcosa da zero, senza grandi budget o finanziamenti, ogni dettaglio conta. Per Leanne Thompson, fondatrice di <a href=\"https:\/\/www.sendfriends.co.uk\/\" target=\"_blank\" rel=\"noopener\">Inviare gli amici<\/a>Anche un solo striscione ben disegnato \u00e8 diventato un argomento di conversazione, attirando le persone a conoscere un progetto in crescita che affonda le sue radici nell'esperienza vissuta, nell'empatia e nel sostegno pratico.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">SEND Friends \u00e8 un'iniziativa di interesse comunitario con sede a Grimsby, che fornisce supporto tra pari alle famiglie di bambini con bisogni educativi speciali e disabilit\u00e0 (SEND). Ma \u00e8 iniziata con un'idea molto pi\u00f9 semplice: un libro per bambini.<\/span><\/p>\n<h3><b>Storie che parlano di esperienze reali<\/b><\/h3>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-75690 size-full\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-3-e1758118494237.jpg\" alt=\"\" width=\"1512\" height=\"1193\" srcset=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-3-e1758118494237.jpg 1512w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-3-e1758118494237-300x237.jpg 300w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-3-e1758118494237-1024x808.jpg 1024w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-3-e1758118494237-768x606.jpg 768w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-3-e1758118494237-15x12.jpg 15w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-3-e1758118494237-532x420.jpg 532w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-3-e1758118494237-696x549.jpg 696w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-3-e1758118494237-1068x843.jpg 1068w\" sizes=\"auto, (max-width: 1512px) 100vw, 1512px\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Leanne ha originariamente creato SEND Friends come una serie di <a href=\"https:\/\/www.sendfriends.co.uk\/the-book-series\/\" target=\"_blank\" rel=\"noopener\">libri per bambini<\/a>. Le storie in rima, leggere e divertenti, presentano i personaggi neurodivergenti in modo da incoraggiare gli adulti a rivedere le proprie aspettative e ad adattare gli ambienti, anzich\u00e9 vedere il bambino come un problema.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\"Ho scritto i libri nella speranza che i miei figli e altri come loro si vedessero rappresentati in una luce positiva\", spiega Leanne. \"Volevo che si identificassero con i personaggi, che si sentissero convalidati e forse anche autorizzati a difendere se stessi\".<\/span><\/p>\n<p><span style=\"font-weight: 400;\">I libri iniziarono a generare un piccolo reddito attraverso i diritti d'autore e Leanne vide il potenziale per fare di pi\u00f9. Attingendo all'esperienza della sua famiglia e alla sua formazione professionale nel campo del sostegno alle persone con disabilit\u00e0, ha ampliato SEND Friends trasformandolo in un servizio di sostegno tra pari per le famiglie che si sentono sopraffatte o lasciate indietro dal sistema.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\"C'\u00e8 un'enorme lacuna nel sostegno alle famiglie con neurodivergenze\", afferma l'autrice. \"I tempi di attesa per la valutazione sono lunghi, i servizi variano da un'area all'altra e, anche quando si \u00e8 in lista d'attesa, il supporto pu\u00f2 essere discontinuo. Se si \u00e8 nuovi al mondo delle SEND, pu\u00f2 essere completamente travolgente. Sto cercando di offrire il tipo di supporto di cui avevo bisogno ma che non sempre riuscivo a trovare\".<\/span><\/p>\n<h3><b>La stampa che attira le persone<\/b><\/h3>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-75693\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-2.jpg\" alt=\"Invio di banner a rullo e stampa\" width=\"2136\" height=\"2226\" srcset=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-2.jpg 2136w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-2-288x300.jpg 288w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-2-983x1024.jpg 983w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-2-768x800.jpg 768w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-2-1474x1536.jpg 1474w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-2-1965x2048.jpg 1965w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-2-12x12.jpg 12w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-2-403x420.jpg 403w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-2-696x725.jpg 696w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-2-1068x1113.jpg 1068w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/09\/SEND-friends-2-1920x2001.jpg 1920w\" sizes=\"auto, (max-width: 2136px) 100vw, 2136px\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Per diffondere la notizia, Leanne sapeva di aver bisogno di qualcosa di visivo. Lavorando con fondi limitati reinvestiti dalle royalties del suo libro, si \u00e8 rivolta a Solopress per un banner a rullo singolo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\"Volevo far conoscere il mio marchio e iniziare a farmi conoscere. Speravo che avrebbe attirato le persone per una conversazione ed \u00e8 esattamente quello che ha fatto\", dice.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Lo striscione \u00e8 stato progettato da Leanne stessa e stampato con la sua grafica e il suo marchio.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\"Sono rimasta molto colpita dalla semplicit\u00e0 dell'ordinazione online. Avevo gi\u00e0 un disegno, quindi \u00e8 stato fantastico poterlo caricare direttamente. Il processo di correzione delle bozze \u00e8 stato davvero chiaro e lo striscione \u00e8 arrivato cos\u00ec rapidamente che ho potuto portarlo al mio primo evento\".<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La risposta \u00e8 stata incoraggiante ed \u00e8 solo l'inizio.<\/span><\/p>\n<h3><b>Uno striscione, grandi ambizioni<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Sebbene il banner a rullo abbia contribuito a far decollare l'attivit\u00e0, Leanne ha progetti pi\u00f9 grandi per il futuro.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\"Ho gi\u00e0 utilizzato Solopress in un ruolo precedente, quindi conosco la qualit\u00e0 dei prodotti. Appena posso, voglio creare un allestimento completo per gli eventi. Opuscoli, volantini, omaggi promozionali come penne o caramelle che aiutino la gente a ricordarsi chi sei. Alla fine mi piacerebbe avere uno stand espositivo completo dove poter esporre con orgoglio i libri che hanno dato il via a tutto e pubblicizzare gli eventi che sto organizzando. Quello sar\u00e0 il mio momento \"ho fatto questo\"\".<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A breve termine, SEND Friends offre un supporto sia online che faccia a faccia, a costo zero o ridotto per i partecipanti. Leanne si sta inoltre mettendo in contatto con organizzazioni locali per ampliare il proprio raggio d'azione e creare collaborazioni durature.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\"Il sogno \u00e8 quello di avere uno spazio permanente. Un centro per le famiglie neurodivergenti. Un luogo in cui le persone possano sentirsi al sicuro, imparare a capire e a piacersi, trovare una guida pratica e un senso di appartenenza. Autismo, ADHD, OCD, ARFID, Tourette e altro ancora. Tutto sotto un unico tetto di sostegno. Forse un giorno. Ma per ora lo striscione aiuta ad aprire le prime conversazioni\".<\/span><\/p>\n<h3><b>Inizia la tua storia con Solopress<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Se state lanciando un servizio, promuovendo il vostro messaggio o semplicemente facendo conoscere il vostro nome, i banner a rullo sono una soluzione conveniente, portatile e in grado di attirare l'attenzione. Solopress offre un'ampia gamma di <a href=\"https:\/\/www.solopress.com\/blog\/it\/banners\/\" target=\"_blank\" rel=\"noopener\">opzioni per i banner<\/a>tra cui design economici, stand di qualit\u00e0 superiore e alternative eco-compatibili.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Esplorate l'intera gamma e trovate la soluzione giusta per il vostro progetto su <a href=\"https:\/\/www.solopress.com\/blog\/it\/\" target=\"_blank\" rel=\"noopener\">solopress.com<\/a>.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>When you\u2019re building something from the ground up with no big budget or backing, every detail counts. For Leanne Thompson, founder of SEND Friends, even one well-designed roller banner has become a conversation starter, drawing people in to hear about a growing project rooted in lived experience, empathy and practical support. SEND Friends is a [&hellip;]<\/p>\n","protected":false},"author":134,"featured_media":75752,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[557,544],"tags":[],"class_list":{"0":"post-75689","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-customer-stories","8":"category-print-inspiration"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Customer Stories: Building Support For SEND Friends - Solopress<\/title>\n<meta name=\"description\" content=\"Learn how SEND Friends uses print to build awareness and support families navigating the world of special educational needs and disabilities.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solopress.com\/blog\/it\/storie-di-clienti\/storie-di-clienti-che-costruiscono-il-supporto-per-linvio-di-amici\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Customer Stories: Building Support For SEND Friends - Solopress\" \/>\n<meta property=\"og:description\" content=\"Learn how SEND Friends uses print to build awareness and support families navigating the world of special educational needs and disabilities.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solopress.com\/blog\/it\/storie-di-clienti\/storie-di-clienti-che-costruiscono-il-supporto-per-linvio-di-amici\/\" \/>\n<meta property=\"og:site_name\" content=\"The Latest Print and Design News | Solopress\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Solopress\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-13T07:16:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-13T08:00:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/10\/SEND-Friends-Customer-Story-Blog-Header.png\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"338\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Danny Powell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@solopress\" \/>\n<meta name=\"twitter:site\" content=\"@solopress\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Danny Powell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-building-support-for-send-friends\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-building-support-for-send-friends\\\/\"},\"author\":{\"name\":\"Danny Powell\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/0937555a256c22f94400f4b7e2329c09\"},\"headline\":\"Customer Stories: building support for SEND Friends\",\"datePublished\":\"2025-09-13T07:16:27+00:00\",\"dateModified\":\"2025-10-13T08:00:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-building-support-for-send-friends\\\/\"},\"wordCount\":708,\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-building-support-for-send-friends\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/SEND-Friends-Customer-Story-Blog-Header.png\",\"articleSection\":[\"Customer Stories\",\"Print Inspiration\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-building-support-for-send-friends\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-building-support-for-send-friends\\\/\",\"name\":\"Customer Stories: Building Support For SEND Friends - Solopress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-building-support-for-send-friends\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-building-support-for-send-friends\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/SEND-Friends-Customer-Story-Blog-Header.png\",\"datePublished\":\"2025-09-13T07:16:27+00:00\",\"dateModified\":\"2025-10-13T08:00:50+00:00\",\"description\":\"Learn how SEND Friends uses print to build awareness and support families navigating the world of special educational needs and disabilities.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-building-support-for-send-friends\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-building-support-for-send-friends\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-building-support-for-send-friends\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/SEND-Friends-Customer-Story-Blog-Header.png\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/SEND-Friends-Customer-Story-Blog-Header.png\",\"width\":450,\"height\":338,\"caption\":\"SEND Friends Header\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/customer-stories\\\/customer-stories-building-support-for-send-friends\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Customer Stories: building support for SEND Friends\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"name\":\"The Latest Print and Design News | Solopress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\",\"name\":\"Solopress\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"width\":428,\"height\":88,\"caption\":\"Solopress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Solopress\",\"https:\\\/\\\/x.com\\\/solopress\",\"https:\\\/\\\/instagram.com\\\/solopress\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/solopress\",\"https:\\\/\\\/uk.pinterest.com\\\/solopress\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/solopress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/0937555a256c22f94400f4b7e2329c09\",\"name\":\"Danny Powell\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"caption\":\"Danny Powell\"},\"description\":\"With over two decades in marketing, Danny Powell is a Senior Copywriter at Solopress, one of the UK\u2019s leading online printers. Having worked on the print buying, agency and sales sides of the industry, he brings a well-rounded perspective to his writing on print, design and sustainability.\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/it\\\/author\\\/danny-powell\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Storie di clienti: Costruire il sostegno per gli amici SEND - Solopress","description":"Scoprite come SEND Friends utilizza la stampa per creare consapevolezza e sostenere le famiglie nel mondo dei bisogni educativi speciali e delle disabilit\u00e0.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solopress.com\/blog\/it\/storie-di-clienti\/storie-di-clienti-che-costruiscono-il-supporto-per-linvio-di-amici\/","og_locale":"it_IT","og_type":"article","og_title":"Customer Stories: Building Support For SEND Friends - Solopress","og_description":"Learn how SEND Friends uses print to build awareness and support families navigating the world of special educational needs and disabilities.","og_url":"https:\/\/www.solopress.com\/blog\/it\/storie-di-clienti\/storie-di-clienti-che-costruiscono-il-supporto-per-linvio-di-amici\/","og_site_name":"The Latest Print and Design News | Solopress","article_publisher":"https:\/\/www.facebook.com\/Solopress","article_published_time":"2025-09-13T07:16:27+00:00","article_modified_time":"2025-10-13T08:00:50+00:00","og_image":[{"width":450,"height":338,"url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/10\/SEND-Friends-Customer-Story-Blog-Header.png","type":"image\/png"}],"author":"Danny Powell","twitter_card":"summary_large_image","twitter_creator":"@solopress","twitter_site":"@solopress","twitter_misc":{"Scritto da":"Danny Powell","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-building-support-for-send-friends\/#article","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-building-support-for-send-friends\/"},"author":{"name":"Danny Powell","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/0937555a256c22f94400f4b7e2329c09"},"headline":"Customer Stories: building support for SEND Friends","datePublished":"2025-09-13T07:16:27+00:00","dateModified":"2025-10-13T08:00:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-building-support-for-send-friends\/"},"wordCount":708,"publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-building-support-for-send-friends\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/10\/SEND-Friends-Customer-Story-Blog-Header.png","articleSection":["Customer Stories","Print Inspiration"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-building-support-for-send-friends\/","url":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-building-support-for-send-friends\/","name":"Storie di clienti: Costruire il sostegno per gli amici SEND - Solopress","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-building-support-for-send-friends\/#primaryimage"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-building-support-for-send-friends\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/10\/SEND-Friends-Customer-Story-Blog-Header.png","datePublished":"2025-09-13T07:16:27+00:00","dateModified":"2025-10-13T08:00:50+00:00","description":"Scoprite come SEND Friends utilizza la stampa per creare consapevolezza e sostenere le famiglie nel mondo dei bisogni educativi speciali e delle disabilit\u00e0.","breadcrumb":{"@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-building-support-for-send-friends\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-building-support-for-send-friends\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-building-support-for-send-friends\/#primaryimage","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/10\/SEND-Friends-Customer-Story-Blog-Header.png","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/10\/SEND-Friends-Customer-Story-Blog-Header.png","width":450,"height":338,"caption":"SEND Friends Header"},{"@type":"BreadcrumbList","@id":"https:\/\/www.solopress.com\/blog\/customer-stories\/customer-stories-building-support-for-send-friends\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.solopress.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Customer Stories: building support for SEND Friends"}]},{"@type":"WebSite","@id":"https:\/\/www.solopress.com\/blog\/#website","url":"https:\/\/www.solopress.com\/blog\/","name":"Le ultime notizie su stampa e design | Solopress","description":"","publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solopress.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.solopress.com\/blog\/#organization","name":"Solopress","url":"https:\/\/www.solopress.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","width":428,"height":88,"caption":"Solopress"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Solopress","https:\/\/x.com\/solopress","https:\/\/instagram.com\/solopress\/","https:\/\/www.linkedin.com\/company\/solopress","https:\/\/uk.pinterest.com\/solopress\/","https:\/\/www.youtube.com\/user\/solopress"]},{"@type":"Person","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/0937555a256c22f94400f4b7e2329c09","name":"Danny Powell","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","caption":"Danny Powell"},"description":"Con oltre vent'anni di esperienza nel marketing, Danny Powell \u00e8 Senior Copywriter presso Solopress, uno dei principali stampatori online del Regno Unito. Avendo lavorato nel settore degli acquisti di stampa, delle agenzie e delle vendite, porta una prospettiva a tutto tondo nei suoi scritti su stampa, design e sostenibilit\u00e0.","url":"https:\/\/www.solopress.com\/blog\/it\/author\/danny-powell\/"}]}},"jetpack_featured_media_url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2025\/10\/SEND-Friends-Customer-Story-Blog-Header.png","_links":{"self":[{"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/posts\/75689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/comments?post=75689"}],"version-history":[{"count":7,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/posts\/75689\/revisions"}],"predecessor-version":[{"id":75753,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/posts\/75689\/revisions\/75753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/media\/75752"}],"wp:attachment":[{"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/media?parent=75689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/categories?post=75689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/tags?post=75689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}