{"id":76103,"date":"2026-03-31T13:45:18","date_gmt":"2026-03-31T12:45:18","guid":{"rendered":"https:\/\/www.solopress.com\/blog\/?p=76103"},"modified":"2026-04-01T13:03:30","modified_gmt":"2026-04-01T12:03:30","slug":"una-prima-solopress-britannica-investe-in-una-macchina-da-stampa-a-getto-dinchiostro-ad-alta-velocita-ricoh-pro-vc80000","status":"publish","type":"post","link":"https:\/\/www.solopress.com\/blog\/it\/solopress-news\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\/","title":{"rendered":"Una novit\u00e0 nel Regno Unito: Solopress investe nella macchina da stampa a getto d'inchiostro ad alta velocit\u00e0 Ricoh Pro VC80000"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p>Una nuova aggiunta \u00e8 arrivata nel reparto di produzione di Solopress. Il <a style=\"color: #4db2ec; text-decoration-line: underline;\" href=\"https:\/\/www.ricoh.co.uk\/products\/production-printers\/continuous-feed-printers\/pro-vc80000\/\" target=\"_blank\" rel=\"noopener\">Ricoh Pro VC80000<\/a> \u00e8 in fase di installazione presso la nostra sede di Southend-on-Sea, dopo diversi mesi di progettazione, e si prevede che aumenter\u00e0 la nostra capacit\u00e0 di produzione di stampa digitale di ben 80%.<\/p>\n<p><span style=\"font-weight: 400;\">Questo investimento di oltre 2 milioni di sterline si concentra sull'aumento della capacit\u00e0 e sul miglioramento dell'efficienza in aree chiave della nostra produzione digitale. Con l'aumento della domanda, in particolare per le tirature digitali pi\u00f9 lunghe, diventa sempre pi\u00f9 importante mantenere una qualit\u00e0 costante e tempi di consegna affidabili.<\/span><\/p>\n<h2 id=\"why\"><b>Rispondere alla domanda crescente<\/b><\/h2>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Jack-Clifford-and-Andy.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-76104\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Jack-Clifford-and-Andy.png\" alt=\"\" width=\"900\" height=\"675\" srcset=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Jack-Clifford-and-Andy.png 900w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Jack-Clifford-and-Andy-300x225.png 300w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Jack-Clifford-and-Andy-768x576.png 768w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Jack-Clifford-and-Andy-16x12.png 16w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Jack-Clifford-and-Andy-560x420.png 560w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Jack-Clifford-and-Andy-80x60.png 80w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Jack-Clifford-and-Andy-696x522.png 696w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Jack-Clifford-and-Andy-265x198.png 265w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">La domanda di stampa di brochure continua a crescere tra i nostri clienti, in particolare per le tirature digitali pi\u00f9 lunghe che richiedono una qualit\u00e0 costante e tempi di consegna affidabili.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Questi lavori spesso comportano quantit\u00e0 pi\u00f9 elevate, scadenze pi\u00f9 strette e grafica dettagliata che deve essere riprodotta in modo coerente dalla prima all'ultima copia. Per soddisfare queste aspettative \u00e8 necessario un impianto di produzione in grado di gestire sia i volumi che le variazioni senza introdurre ritardi o incongruenze.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ricoh Pro VC80000 \u00e8 stato scelto per rafforzare questa capacit\u00e0. Ci permette di produrre in modo pi\u00f9 efficiente tirature digitali pi\u00f9 lunghe, mantenendo gli standard che i nostri clienti gi\u00e0 si aspettano da noi.<\/span><\/p>\n<p><b>Jack Clifford, direttore operativo di Solopress, ha dichiarato:<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">\u201cAbbiamo registrato una crescita forte e costante nella stampa di brochure, quindi aumentare la capacit\u00e0 in questo settore era una priorit\u00e0. Ricoh Pro VC80000 ci permette di produrre tirature digitali pi\u00f9 lunghe in modo molto pi\u00f9 efficiente, mantenendo la qualit\u00e0 che i nostri clienti si aspettano\u201d.\u201d<\/span><\/p>\n<h2><b>Cosa offre Ricoh Pro VC80000<a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Install.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-76107\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Install.png\" alt=\"\" width=\"900\" height=\"675\" srcset=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Install.png 900w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Install-300x225.png 300w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Install-768x576.png 768w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Install-16x12.png 16w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Install-560x420.png 560w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Install-80x60.png 80w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Install-696x522.png 696w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Install-265x198.png 265w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Ricoh Pro VC80000 \u00e8 una macchina da stampa a getto d'inchiostro ad alimentazione continua. Invece di stampare su singoli fogli, stampa su un rotolo di carta in movimento, consentendo una produzione ininterrotta ad alta velocit\u00e0.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c8 in grado di raggiungere una velocit\u00e0 di 150 metri al minuto, con una risoluzione di stampa fino a 1200 \u00d7 1200 dpi. Ci\u00f2 consente un'elevata produttivit\u00e0 mantenendo dettagli nitidi e colori uniformi, in particolare sulle tirature pi\u00f9 lunghe.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La macchina \u00e8 progettata per mantenere una produzione stabile per lunghi periodi di produzione. I suoi sistemi di asciugatura e di gestione della temperatura aiutano a mantenere le condizioni costanti per tutta la tiratura, il che \u00e8 particolarmente importante quando si trattano progetti con un'elevata copertura di inchiostro o dettagli fini.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Questo ci permette di aumentare la velocit\u00e0 e la capacit\u00e0, mantenendo gli standard di qualit\u00e0 che gi\u00e0 applichiamo per ogni lavoro.<\/span><\/p>\n<p><b>David Farnsworth, Strategic Account Manager di Ricoh UK Graphic Communications, ha commentato:<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">\u201cSolopress \u00e8 esattamente il tipo di ambiente di produzione all'avanguardia in cui la tecnologia Ricoh dimostra il suo valore. La prima installazione di VC80000 nel Regno Unito \u00e8 una pietra miliare significativa, non solo per Solopress, ma anche come dimostrazione di ci\u00f2 che la moderna produzione a getto d'inchiostro pu\u00f2 raggiungere a livello commerciale. \u00c8 anche un segnale della fiducia nelle nostre soluzioni e del valore dei servizi che offriamo\u201d.\u201d<\/span><\/p>\n<h2 id=\"workflow\"><b>Dalla carta bianca alla brochure finita in un unico flusso di lavoro<\/b><\/h2>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Hunkeler-Horizon.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-76108\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Hunkeler-Horizon.png\" alt=\"\" width=\"877\" height=\"436\" srcset=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Hunkeler-Horizon.png 877w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Hunkeler-Horizon-300x149.png 300w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Hunkeler-Horizon-768x382.png 768w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Hunkeler-Horizon-18x9.png 18w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Hunkeler-Horizon-845x420.png 845w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Hunkeler-Horizon-696x346.png 696w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Hunkeler-Horizon-324x160.png 324w\" sizes=\"auto, (max-width: 877px) 100vw, 877px\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">La rotativa \u00e8 stata installata in linea con le apparecchiature di svolgitura e finitura Hunkeler, tra cui la cucitrice Horizon Mark V. In questo modo si crea un flusso di lavoro continuo dalla stampa alla brochure finita.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Man mano che il rotolo stampato si muove nel sistema, viene tagliato, raccolto, cucito e rifilato in sequenza. Ci\u00f2 riduce la necessit\u00e0 di interventi manuali tra le varie fasi e contribuisce a mantenere l'uniformit\u00e0 tra grandi quantit\u00e0.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Inoltre, accorcia i tempi tra la stampa e la finitura, favorendo una maggiore prevedibilit\u00e0 dei tempi di consegna, in particolare per i volumi pi\u00f9 elevati di brochure.<\/span><\/p>\n<h2><b>Aumentare la capacit\u00e0 dove \u00e8 pi\u00f9 necessario<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Si prevede che questo investimento <strong>aumentare la nostra capacit\u00e0 di stampa digitale di circa 80%<\/strong>. Ma soprattutto, ci permette di distribuire il lavoro in modo pi\u00f9 efficace tra i nostri reparti di produzione.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c8 previsto che pi\u00f9 della met\u00e0 della nostra produzione di brochure venga eseguita su questa nuova linea, una volta che sar\u00e0 pienamente operativa. Spostando questo lavoro su un sistema dedicato ad alto volume, possiamo ridurre la pressione sulle altre macchine da stampa digitali e migliorare l'efficienza complessiva del flusso di lavoro.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il risultato \u00e8 un margine di manovra aggiuntivo nella produzione, che aiuta a gestire i picchi di domanda senza compromettere i tempi di consegna o la qualit\u00e0.<\/span><\/p>\n<h2 id=\"expertise\"><b>Preparazione del team<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Parallelamente all'installazione, i membri del nostro team di produzione si sono preparati a utilizzare la nuova macchina da stampa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Gli operatori esperti Tony Sullivan, Jim Wellard, Geoff Holliss e Darren Brown hanno recentemente completato un programma di formazione di tre giorni presso la sede centrale di Ricoh a Telford. Il corso ha riguardato le procedure di sicurezza, il trasporto della carta attraverso la rotativa, i sistemi di asciugatura e raffreddamento, la gestione dell'inchiostro e i controlli su schermo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Questo addestramento assicura che il team sia pienamente preparato a integrare la nuova rotativa nella produzione quotidiana. Come per ogni nuova apparecchiatura, \u00e8 la combinazione di tecnologia ed esperienza dell'operatore a determinarne l'efficacia.<\/span><\/p>\n<h2><b>Un'installazione gestita con cura<\/b><\/h2>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Unload.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-76109\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Unload.png\" alt=\"\" width=\"900\" height=\"675\" srcset=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Unload.png 900w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Unload-300x225.png 300w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Unload-768x576.png 768w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Unload-16x12.png 16w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Unload-560x420.png 560w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Unload-80x60.png 80w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Unload-696x522.png 696w, https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Unload-265x198.png 265w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><span style=\"font-weight: 400;\">L'installazione di una macchina di questa portata \u00e8 un processo dettagliato. La Ricoh Pro VC80000 \u00e8 arrivata in pi\u00f9 sezioni, ognuna delle quali pesa diverse tonnellate, e ha richiesto un'attenta movimentazione per essere posizionata all'interno dello spazio di produzione.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Squadre specializzate hanno lavorato a fianco dei nostri tecnici per scaricare e installare le unit\u00e0 con precisione. Ogni sezione \u00e8 stata posizionata con precisione per garantire l'allineamento su tutta la linea di produzione.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Allo stesso tempo, il flusso di lavoro circostante \u00e8 stato configurato per supportare il nuovo sistema, dalla gestione dei materiali alla finitura e alla spedizione.<\/span><\/p>\n<h2><b>Cosa significa questo per la vostra stampa<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Con l'entrata in funzione della nuova linea, i clienti cominceranno a vedere i vantaggi nel modo in cui il lavoro si svolge durante la produzione.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Questo consente l'introduzione di una tiratura di 24 ore per le brochure A4 e A5 con pinzatura verticale, offrendo un'opzione pi\u00f9 rapida per uno dei nostri prodotti pi\u00f9 richiesti.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Altri formati, orientamenti e supporti cartacei continueranno a seguire i tempi di produzione appropriati a causa dei requisiti di asciugatura e finitura. Tuttavia, l'aumento della capacit\u00e0 va a vantaggio di tutti i lavori di stampa digitale, riducendo la pressione su tutto il programma di produzione.<\/span><\/p>\n<h2><b>Guardare al futuro<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Ricoh Pro VC80000 \u00e8 attualmente in fase di installazione e messa in funzione. Nelle prossime settimane entrer\u00e0 in piena produzione, man mano che verranno completati i test e la calibrazione.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Questo investimento riflette un approccio continuo al miglioramento delle modalit\u00e0 di produzione della stampa. Aumentando la capacit\u00e0 e perfezionando i nostri flussi di lavoro, possiamo continuare a fornire una qualit\u00e0 costante e rispondere in modo pi\u00f9 efficace ai cambiamenti della domanda. Tenete d'occhio il nostro <a href=\"https:\/\/www.solopress.com\/blog\/it\/stapled-brochures\/\" target=\"_blank\" rel=\"noopener\">Opuscoli pinzati<\/a> per ridurre i tempi di consegna e ottenere una stampa di qualit\u00e0 superiore.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>A new addition has arrived on the Solopress production floor. The Ricoh Pro VC80000 is now being installed at our Southend-on-Sea site following several months of planning, and is expected to boost our digital print production capacity by a massive 80%. This \u00a32m+ investment focuses on increasing capacity and improving efficiency in key areas of [&hellip;]<\/p>\n","protected":false},"author":134,"featured_media":76106,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[550,551],"tags":[],"class_list":{"0":"post-76103","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-print-industry-news","8":"category-solopress-news"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Solopress Invests In UK&#039;s First Ricoh Pro VC80000 Inkjet Press<\/title>\n<meta name=\"description\" content=\"Solopress installs Ricoh VC80000 continuous feed press, boosting digital capacity by 80% and improving efficiency in brochure production.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solopress.com\/blog\/it\/notizie-solopress\/una-prima-solopress-britannica-investe-in-una-macchina-da-stampa-a-getto-dinchiostro-ad-alta-velocita-ricoh-pro-vc80000\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Solopress Invests In UK&#039;s First Ricoh Pro VC80000 Inkjet Press\" \/>\n<meta property=\"og:description\" content=\"Solopress installs Ricoh VC80000 continuous feed press, boosting digital capacity by 80% and improving efficiency in brochure production.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solopress.com\/blog\/it\/notizie-solopress\/una-prima-solopress-britannica-investe-in-una-macchina-da-stampa-a-getto-dinchiostro-ad-alta-velocita-ricoh-pro-vc80000\/\" \/>\n<meta property=\"og:site_name\" content=\"The Latest Print and Design News | Solopress\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Solopress\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-31T12:45:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-01T12:03:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Flat.png\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Danny Powell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@solopress\" \/>\n<meta name=\"twitter:site\" content=\"@solopress\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Danny Powell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/solopress-news\\\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/solopress-news\\\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\\\/\"},\"author\":{\"name\":\"Danny Powell\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/0937555a256c22f94400f4b7e2329c09\"},\"headline\":\"A UK first: Solopress invests in Ricoh Pro VC80000 high speed inkjet press\",\"datePublished\":\"2026-03-31T12:45:18+00:00\",\"dateModified\":\"2026-04-01T12:03:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/solopress-news\\\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\\\/\"},\"wordCount\":966,\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/solopress-news\\\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Ricoh-Flat.png\",\"articleSection\":[\"Print Industry News\",\"Solopress News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/solopress-news\\\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/solopress-news\\\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\\\/\",\"name\":\"Solopress Invests In UK's First Ricoh Pro VC80000 Inkjet Press\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/solopress-news\\\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/solopress-news\\\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Ricoh-Flat.png\",\"datePublished\":\"2026-03-31T12:45:18+00:00\",\"dateModified\":\"2026-04-01T12:03:30+00:00\",\"description\":\"Solopress installs Ricoh VC80000 continuous feed press, boosting digital capacity by 80% and improving efficiency in brochure production.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/solopress-news\\\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/solopress-news\\\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/solopress-news\\\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Ricoh-Flat.png\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Ricoh-Flat.png\",\"width\":900,\"height\":675,\"caption\":\"The Ricoh VC80000 installed at Solopress\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/solopress-news\\\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A UK first: Solopress invests in Ricoh Pro VC80000 high speed inkjet press\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"name\":\"The Latest Print and Design News | Solopress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\",\"name\":\"Solopress\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"width\":428,\"height\":88,\"caption\":\"Solopress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Solopress\",\"https:\\\/\\\/x.com\\\/solopress\",\"https:\\\/\\\/instagram.com\\\/solopress\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/solopress\",\"https:\\\/\\\/uk.pinterest.com\\\/solopress\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/solopress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/0937555a256c22f94400f4b7e2329c09\",\"name\":\"Danny Powell\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g\",\"caption\":\"Danny Powell\"},\"description\":\"With over two decades in marketing, Danny Powell is a Senior Copywriter at Solopress, one of the UK\u2019s leading online printers. Having worked on the print buying, agency and sales sides of the industry, he brings a well-rounded perspective to his writing on print, design and sustainability.\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/it\\\/author\\\/danny-powell\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Solopress investe nella prima macchina da stampa a getto d'inchiostro Ricoh Pro VC80000 del Regno Unito","description":"Solopress installa la macchina da stampa ad alimentazione continua Ricoh VC80000, aumentando la capacit\u00e0 digitale di 80% e migliorando l'efficienza nella produzione di brochure.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solopress.com\/blog\/it\/notizie-solopress\/una-prima-solopress-britannica-investe-in-una-macchina-da-stampa-a-getto-dinchiostro-ad-alta-velocita-ricoh-pro-vc80000\/","og_locale":"it_IT","og_type":"article","og_title":"Solopress Invests In UK's First Ricoh Pro VC80000 Inkjet Press","og_description":"Solopress installs Ricoh VC80000 continuous feed press, boosting digital capacity by 80% and improving efficiency in brochure production.","og_url":"https:\/\/www.solopress.com\/blog\/it\/notizie-solopress\/una-prima-solopress-britannica-investe-in-una-macchina-da-stampa-a-getto-dinchiostro-ad-alta-velocita-ricoh-pro-vc80000\/","og_site_name":"The Latest Print and Design News | Solopress","article_publisher":"https:\/\/www.facebook.com\/Solopress","article_published_time":"2026-03-31T12:45:18+00:00","article_modified_time":"2026-04-01T12:03:30+00:00","og_image":[{"width":900,"height":675,"url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Flat.png","type":"image\/png"}],"author":"Danny Powell","twitter_card":"summary_large_image","twitter_creator":"@solopress","twitter_site":"@solopress","twitter_misc":{"Scritto da":"Danny Powell","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.solopress.com\/blog\/solopress-news\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\/#article","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/solopress-news\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\/"},"author":{"name":"Danny Powell","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/0937555a256c22f94400f4b7e2329c09"},"headline":"A UK first: Solopress invests in Ricoh Pro VC80000 high speed inkjet press","datePublished":"2026-03-31T12:45:18+00:00","dateModified":"2026-04-01T12:03:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/solopress-news\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\/"},"wordCount":966,"publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/solopress-news\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Flat.png","articleSection":["Print Industry News","Solopress News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.solopress.com\/blog\/solopress-news\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\/","url":"https:\/\/www.solopress.com\/blog\/solopress-news\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\/","name":"Solopress investe nella prima macchina da stampa a getto d'inchiostro Ricoh Pro VC80000 del Regno Unito","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/solopress-news\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\/#primaryimage"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/solopress-news\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Flat.png","datePublished":"2026-03-31T12:45:18+00:00","dateModified":"2026-04-01T12:03:30+00:00","description":"Solopress installa la macchina da stampa ad alimentazione continua Ricoh VC80000, aumentando la capacit\u00e0 digitale di 80% e migliorando l'efficienza nella produzione di brochure.","breadcrumb":{"@id":"https:\/\/www.solopress.com\/blog\/solopress-news\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solopress.com\/blog\/solopress-news\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.solopress.com\/blog\/solopress-news\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\/#primaryimage","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Flat.png","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Flat.png","width":900,"height":675,"caption":"The Ricoh VC80000 installed at Solopress"},{"@type":"BreadcrumbList","@id":"https:\/\/www.solopress.com\/blog\/solopress-news\/a-uk-first-solopress-invests-in-ricoh-pro-vc80000-high-speed-inkjet-press\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.solopress.com\/blog\/"},{"@type":"ListItem","position":2,"name":"A UK first: Solopress invests in Ricoh Pro VC80000 high speed inkjet press"}]},{"@type":"WebSite","@id":"https:\/\/www.solopress.com\/blog\/#website","url":"https:\/\/www.solopress.com\/blog\/","name":"Le ultime notizie su stampa e design | Solopress","description":"","publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solopress.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.solopress.com\/blog\/#organization","name":"Solopress","url":"https:\/\/www.solopress.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","width":428,"height":88,"caption":"Solopress"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Solopress","https:\/\/x.com\/solopress","https:\/\/instagram.com\/solopress\/","https:\/\/www.linkedin.com\/company\/solopress","https:\/\/uk.pinterest.com\/solopress\/","https:\/\/www.youtube.com\/user\/solopress"]},{"@type":"Person","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/0937555a256c22f94400f4b7e2329c09","name":"Danny Powell","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/61a91dfef0f2540955232e281a9d8dd099c01492bda6e2638fa05db47a9665eb?s=96&r=g","caption":"Danny Powell"},"description":"Con oltre vent'anni di esperienza nel marketing, Danny Powell \u00e8 Senior Copywriter presso Solopress, uno dei principali stampatori online del Regno Unito. Avendo lavorato nel settore degli acquisti di stampa, delle agenzie e delle vendite, porta una prospettiva a tutto tondo nei suoi scritti su stampa, design e sostenibilit\u00e0.","url":"https:\/\/www.solopress.com\/blog\/it\/author\/danny-powell\/"}]}},"jetpack_featured_media_url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2026\/03\/Ricoh-Flat.png","_links":{"self":[{"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/posts\/76103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/comments?post=76103"}],"version-history":[{"count":4,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/posts\/76103\/revisions"}],"predecessor-version":[{"id":76113,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/posts\/76103\/revisions\/76113"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/media\/76106"}],"wp:attachment":[{"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/media?parent=76103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/categories?post=76103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/it\/wp-json\/wp\/v2\/tags?post=76103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}