{"id":72530,"date":"2022-07-06T13:25:54","date_gmt":"2022-07-06T12:25:54","guid":{"rendered":"https:\/\/www.solopress.com\/blog\/?p=72530"},"modified":"2022-08-17T09:52:48","modified_gmt":"2022-08-17T08:52:48","slug":"10-dicas-para-provar-a-leitura-do-seu-trabalho","status":"publish","type":"post","link":"https:\/\/www.solopress.com\/blog\/pt-pt\/copywriting-typography\/10-tips-to-proofreading-your-work\/","title":{"rendered":"10 dicas de especialistas para rever o seu trabalho"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><h2><strong>Revisto, revisto e revisto de novo<\/strong><\/h2>\n<p>J\u00e1 todos pass\u00e1mos por isso.<\/p>\n<p>Horas de pesquisa efectuadas. Horas de palavras escritas. Satisfeito com o trabalho, clica-se em publicar.<\/p>\n<p>Bum. Encontrou um <a href=\"https:\/\/www.solopress.com\/blog\/pt-pt\/tutoriais\/como-evitar-erros-ortograficos-nas-suas-impressoes\/\" target=\"_blank\" rel=\"noopener\">erro ortogr\u00e1fico grave<\/a> na primeira linha. Toda a credibilidade que esperava dar ao seu artigo vai pela janela fora.<\/p>\n<p>Mas como \u00e9 que isso aconteceu? Sem nos apercebermos, a psicologia tem um enorme impacto no nosso corretor ortogr\u00e1fico interno.<\/p>\n<p>H\u00e1 v\u00e1rias dicas que encontr\u00e1mos e utiliz\u00e1mos que podem ajud\u00e1-lo a rever o seu trabalho para que a sua impress\u00e3o seja perfeita!<\/p>\n<h2><strong>N\u00c3O se preocupar com as coisas pequenas<\/strong><\/h2>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/07\/Sweat-the-small-things.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-72537\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/07\/Sweat-the-small-things.jpg\" alt=\"\" width=\"1920\" height=\"1281\" \/><\/a><\/p>\n<p style=\"text-align: left;\"><em><strong>Porque \u00e9 que as gralhas s\u00e3o t\u00e3o \u00f3bvias quando o trabalho de impress\u00e3o est\u00e1 conclu\u00eddo?\u00a0<\/strong><\/em><\/p>\n<p>Mudar a natureza do que se escreveu e o seu aspeto \u00e9 fundamental para a revis\u00e3o.<\/p>\n<p>Os nossos c\u00e9rebros est\u00e3o programados para ler o que pensamos ter escrito e, consequentemente, podem n\u00e3o ver os nossos erros.<\/p>\n<p>Fazer com que o c\u00e9rebro acredite que est\u00e1 a ler o texto pela primeira vez \u00e9 a arte suprema da revis\u00e3o.<\/p>\n<h2><strong>Os princ\u00edpios b\u00e1sicos<\/strong><\/h2>\n<p>Para come\u00e7ar\u00a0<strong>revis\u00e3o de provas<\/strong>Utilize o corretor ortogr\u00e1fico do seu computador, port\u00e1til ou telem\u00f3vel para eliminar erros de digita\u00e7\u00e3o simples.<\/p>\n<p>N\u00e3o se esque\u00e7a de verificar se o seu computador tem a l\u00edngua regional correcta selecionada, ou seja, Reino Unido vs. EUA. Os computadores nem sempre acertam, por isso, ter um dicion\u00e1rio impresso \u00e0 m\u00e3o ser\u00e1 o seu parceiro perfeito.<\/p>\n<p>Tente ler a sua escrita em tr\u00eas fases:<\/p>\n<ul>\n<li>Em primeiro lugar, leia o documento para ver se cont\u00e9m todas as informa\u00e7\u00f5es necess\u00e1rias. Isto pode significar datas e horas para um evento num\u00a0<a href=\"https:\/\/www.solopress.com\/blog\/pt-pt\/folhetos-folhetos\/\" target=\"_blank\" rel=\"noopener\">Folheto <\/a>ou explica\u00e7\u00f5es pormenorizadas dos servi\u00e7os num\u00a0<a href=\"https:\/\/www.solopress.com\/blog\/pt-pt\/brochuras-papeis\/\" target=\"_blank\" rel=\"noopener\">Brochura<\/a>. De qualquer forma, certifique-se de que est\u00e1 tudo l\u00e1.<\/li>\n<li>Em segundo lugar, ler o documento <strong>em voz alta<\/strong> para ouvir como soa e ver se as frases fazem sentido. Aqui, verifique os tempos verbais do passado, presente e futuro e certifique-se de que n\u00e3o est\u00e1 a alternar entre a terceira e a primeira pessoa quando n\u00e3o \u00e9 aplic\u00e1vel.<\/li>\n<li>Em terceiro lugar, verificar se o <strong>pormenores mais finos<\/strong>. Verifique novamente os cabe\u00e7alhos e rodap\u00e9s, uma vez que estes s\u00e3o normalmente formatados para se destacarem. Certifique-se de que os n\u00fameros, as datas ou os nomes est\u00e3o escritos corretamente, uma vez que estes elementos podem facilmente passar despercebidos.<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/07\/Spelling-mistakes.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-72536\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/07\/Spelling-mistakes.jpg\" alt=\"\" width=\"1920\" height=\"1280\" \/><\/a><\/p>\n<h2><strong>Revis\u00e3o de provas para uma impress\u00e3o perfeita<\/strong><\/h2>\n<h3><strong>1<\/strong> Ler mais tarde<\/h3>\n<p>Ler o seu trabalho de tr\u00e1s para a frente \u00e9 uma dica importante para detetar erros ortogr\u00e1ficos. Olhar para o que escreveu numa ordem que n\u00e3o faz qualquer sentido liter\u00e1rio, ajud\u00e1-lo-\u00e1 a detetar se algumas palavras est\u00e3o escritas corretamente ou se se destacam.<\/p>\n<h3><strong>2<\/strong> Conhe\u00e7a a sua kryptonite<\/h3>\n<p>Toda a gente tem os seus pr\u00f3prios erros pessoais que comete repetidamente. Quer se engane no \"tu\" e no \"teu\", ou se esque\u00e7a sempre do \"n\" em \"ambiente\", esteja atento aos erros que sabe que comete.<\/p>\n<h3><strong>3<\/strong> Alterar o tipo de letra<\/h3>\n<p>D\u00ea aos seus olhos uma vis\u00e3o diferente das palavras que tem \u00e0 sua frente. Alterar o desenho ou o tamanho do tipo de letra \u00e9 uma \u00f3ptima forma de detetar erros simples que antes n\u00e3o eram notados.<\/p>\n<h3><strong>4<\/strong> Dois pares de olhos s\u00e3o melhores do que um<\/h3>\n<p>Pe\u00e7a a um amigo ou colega para rever o seu trabalho. Um olhar diferente e fresco \u00e9 a sua melhor ferramenta de revis\u00e3o. Olho por olho melhora sempre o seu texto!<\/p>\n<h3><strong>5<\/strong> Pr\u00e9-visualizar o seu trabalho<\/h3>\n<p>Um truque que funciona muito bem para mim em <a href=\"https:\/\/www.solopress.com\/blog\/pt-pt\/\" target=\"_blank\" rel=\"noopener\">WordPress<\/a>, est\u00e1 a utilizar o <em><strong>Pr\u00e9-visualiza\u00e7\u00e3o<\/strong><\/em> bot\u00e3o. Isto permite-lhe ver o aspeto que o seu trabalho teria se o publicasse. Esta mudan\u00e7a de formato exp\u00f5e sempre alguns pequenos erros que precisam de ser corrigidos rapidamente, antes que algu\u00e9m os veja!<\/p>\n<h3><strong>6<\/strong> Imprimir em papel<\/h3>\n<p>Ler a sua c\u00f3pia numa vers\u00e3o diferente num ecr\u00e3 digital, tal como num papel impresso, pode ser um truque valioso para detetar esses erros indisciplinados. Fazer com que o seu c\u00e9rebro pense que est\u00e1 a ler a c\u00f3pia final pode ajudar a detetar qualquer coisa que permane\u00e7a na p\u00e1gina.<\/p>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/07\/Proofreading.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-72535\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/07\/Proofreading.jpg\" alt=\"\" width=\"1920\" height=\"1044\" \/><\/a><\/p>\n<h3><strong>7<\/strong> Alterar as margens<\/h3>\n<p>Estreite ou alargue as margens da sua p\u00e1gina para que o tamanho e o comprimento dos seus par\u00e1grafos mudem. Ter as palavras ordenadas num novo formato pode ajud\u00e1-lo a ver erros ortogr\u00e1ficos ou erros, uma vez que parece um trabalho diferente.<\/p>\n<h3><strong>8<\/strong> Gram\u00e1tica<\/h3>\n<p>O Grammarly \u00e9 o xeque-mate para a revis\u00e3o de textos se quiser poupar tempo. Transfira a extens\u00e3o e veja-a corrigir todos os erros que comete, evitando que perca tempo a detect\u00e1-los.<\/p>\n<h3><strong>9<\/strong> Tirar uma folga<\/h3>\n<p>Os seus olhos podem estar cansados e o seu c\u00e9rebro pode estar frito. Saia para dar um passeio; tome um duche; v\u00e1 para a cama. Fa\u00e7a algo diferente e volte com uma nova mentalidade. Ficar\u00e1 surpreendido com o facto de ser muito mais produtivo.<\/p>\n<h3><strong>10<\/strong> Agrade\u00e7am aos vossos leitores!<\/h3>\n<p>Os seus leitores s\u00e3o os seus melhores amigos. Eles l\u00eaem os seus erros, esperemos que engra\u00e7ados, e apontam-nos sempre para que os corrija. Agrade\u00e7a-lhes por isso, s\u00e3o revisores gratuitos!<\/p>\n<h3>Eis alguns dos erros mais comuns:<\/h3>\n<ul>\n<li><strong>Hom\u00f3fonos<\/strong>- s\u00e3o palavras que t\u00eam o mesmo som, mas que t\u00eam grafias e significados diferentes. Certo e escrever. Veado e querido.<\/li>\n<li><strong>Omitir letras mudas<\/strong>- fevereiro e fevereiro, ouvir e escutar.<\/li>\n<li><strong>Adicionar um final<\/strong>- Podem ser cometidos erros quando se altera o tempo verbal de uma palavra acrescentando uma termina\u00e7\u00e3o. Hopeing e Hoping ou Submiting e Submitting.<\/li>\n<li><strong>Palavras em falta<\/strong>- mais frequentemente com palavras mais pequenas, to, it, is, of, a, etc. Ou, por vezes, estas palavras s\u00e3o utilizadas incorretamente em substitui\u00e7\u00e3o de outras.<\/li>\n<li><strong>Encomenda de cartas<\/strong>- o mais comum dos erros tipogr\u00e1ficos \u00e9 as letras estarem ao contr\u00e1rio. Por exemplo, \u00e9 estranho escrever \"weird\" como \"wierd\".<\/li>\n<li><strong>Pontua\u00e7\u00e3o<\/strong>- Os ap\u00f3strofos s\u00e3o o erro de pontua\u00e7\u00e3o mais comum. Devem ser utilizados de duas formas: para o possessivo, por exemplo, Peter's ball, e para substituir letras em falta (uma contra\u00e7\u00e3o), por exemplo, it's ou don't.<\/li>\n<li><strong>Am\u00e1lgama de palavras<\/strong>- algumas palavras devem ser separadas. Por exemplo, \"muito\" em vez de<a href=\"http:\/\/hyperboleandahalf.blogspot.co.uk\/2010\/04\/alot-is-better-than-you-at-everything.html\">muito<\/a>'<\/li>\n<li><strong>Verbos<\/strong>- adaptar o verbo a um sujeito singular ou plural, por exemplo, \"I was\" e \"we were\" e n\u00e3o \"I were\" e \"we was\".<\/li>\n<li><strong>Deveria de\/deveria ter<\/strong>- esta \u00faltima est\u00e1 correcta.<\/li>\n<\/ul>\n<p>S\u00f3 depois de o documento estar isento de erros e t\u00e3o correto quanto poss\u00edvel \u00e9 que est\u00e1 pronto para ser impresso. Tudo o que precisa \u00e9 de um <a href=\"https:\/\/www.solopress.com\/blog\/pt-pt\/\" target=\"_blank\" rel=\"noopener\">parceiro de impress\u00e3o<\/a> para corresponder \u00e0 sua revis\u00e3o impec\u00e1vel...<\/p>","protected":false},"excerpt":{"rendered":"<p>Profread, proofreed, and proofread again We\u2019ve all been there. Hours of research done. Hours of words written. Happy with the work, you click publish. Boom. You\u2019ve spotted a major spelling mistake in the first line. Any credibility you\u2019d hoped to bring to your article goes flying out of the window. But how did this happen? [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":72612,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[549],"tags":[890],"class_list":{"0":"post-72530","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-copywriting-typography","8":"tag-branding"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>10 Expert Tips For Proofreading Your Work<\/title>\n<meta name=\"description\" content=\"Here are several tips we\u2019ve found and used that can help your proofreading in order to make your print perfect!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solopress.com\/blog\/pt-pt\/redacao-tipografia\/10-dicas-para-provar-a-leitura-do-seu-trabalho\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 Expert Tips For Proofreading Your Work\" \/>\n<meta property=\"og:description\" content=\"Here are several tips we\u2019ve found and used that can help your proofreading in order to make your print perfect!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solopress.com\/blog\/pt-pt\/redacao-tipografia\/10-dicas-para-provar-a-leitura-do-seu-trabalho\/\" \/>\n<meta property=\"og:site_name\" content=\"The Latest Print and Design News | Solopress\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Solopress\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-06T12:25:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-17T08:52:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/07\/Featured-image-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"902\" \/>\n\t<meta property=\"og:image:height\" content=\"676\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Solopress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@solopress\" \/>\n<meta name=\"twitter:site\" content=\"@solopress\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Solopress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/copywriting-typography\\\/10-tips-to-proofreading-your-work\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/copywriting-typography\\\/10-tips-to-proofreading-your-work\\\/\"},\"author\":{\"name\":\"Solopress\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/f8531403c74fe1b3ef14bcaeec1c8c41\"},\"headline\":\"10 expert tips for proofreading your work\",\"datePublished\":\"2022-07-06T12:25:54+00:00\",\"dateModified\":\"2022-08-17T08:52:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/copywriting-typography\\\/10-tips-to-proofreading-your-work\\\/\"},\"wordCount\":1001,\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/copywriting-typography\\\/10-tips-to-proofreading-your-work\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Featured-image-1.jpg\",\"keywords\":[\"Branding\"],\"articleSection\":[\"Copywriting &amp; Typography\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/copywriting-typography\\\/10-tips-to-proofreading-your-work\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/copywriting-typography\\\/10-tips-to-proofreading-your-work\\\/\",\"name\":\"10 Expert Tips For Proofreading Your Work\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/copywriting-typography\\\/10-tips-to-proofreading-your-work\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/copywriting-typography\\\/10-tips-to-proofreading-your-work\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Featured-image-1.jpg\",\"datePublished\":\"2022-07-06T12:25:54+00:00\",\"dateModified\":\"2022-08-17T08:52:48+00:00\",\"description\":\"Here are several tips we\u2019ve found and used that can help your proofreading in order to make your print perfect!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/copywriting-typography\\\/10-tips-to-proofreading-your-work\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/copywriting-typography\\\/10-tips-to-proofreading-your-work\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/copywriting-typography\\\/10-tips-to-proofreading-your-work\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Featured-image-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Featured-image-1.jpg\",\"width\":902,\"height\":676},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/copywriting-typography\\\/10-tips-to-proofreading-your-work\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"10 expert tips for proofreading your work\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"name\":\"The Latest Print and Design News | Solopress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\",\"name\":\"Solopress\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"width\":428,\"height\":88,\"caption\":\"Solopress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Solopress\",\"https:\\\/\\\/x.com\\\/solopress\",\"https:\\\/\\\/instagram.com\\\/solopress\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/solopress\",\"https:\\\/\\\/uk.pinterest.com\\\/solopress\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/solopress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/f8531403c74fe1b3ef14bcaeec1c8c41\",\"name\":\"Solopress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g\",\"caption\":\"Solopress\"},\"sameAs\":[\"https:\\\/\\\/www.solopress.com\\\/\"],\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/pt-pt\\\/author\\\/solopress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10 dicas de especialistas para a revis\u00e3o do seu trabalho","description":"Eis algumas dicas que encontr\u00e1mos e utiliz\u00e1mos e que podem ajudar a sua revis\u00e3o de forma a tornar a sua impress\u00e3o perfeita!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solopress.com\/blog\/pt-pt\/redacao-tipografia\/10-dicas-para-provar-a-leitura-do-seu-trabalho\/","og_locale":"pt_PT","og_type":"article","og_title":"10 Expert Tips For Proofreading Your Work","og_description":"Here are several tips we\u2019ve found and used that can help your proofreading in order to make your print perfect!","og_url":"https:\/\/www.solopress.com\/blog\/pt-pt\/redacao-tipografia\/10-dicas-para-provar-a-leitura-do-seu-trabalho\/","og_site_name":"The Latest Print and Design News | Solopress","article_publisher":"https:\/\/www.facebook.com\/Solopress","article_published_time":"2022-07-06T12:25:54+00:00","article_modified_time":"2022-08-17T08:52:48+00:00","og_image":[{"width":902,"height":676,"url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/07\/Featured-image-1.jpg","type":"image\/jpeg"}],"author":"Solopress","twitter_card":"summary_large_image","twitter_creator":"@solopress","twitter_site":"@solopress","twitter_misc":{"Escrito por":"Solopress","Tempo estimado de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.solopress.com\/blog\/copywriting-typography\/10-tips-to-proofreading-your-work\/#article","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/copywriting-typography\/10-tips-to-proofreading-your-work\/"},"author":{"name":"Solopress","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/f8531403c74fe1b3ef14bcaeec1c8c41"},"headline":"10 expert tips for proofreading your work","datePublished":"2022-07-06T12:25:54+00:00","dateModified":"2022-08-17T08:52:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/copywriting-typography\/10-tips-to-proofreading-your-work\/"},"wordCount":1001,"publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/copywriting-typography\/10-tips-to-proofreading-your-work\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/07\/Featured-image-1.jpg","keywords":["Branding"],"articleSection":["Copywriting &amp; Typography"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.solopress.com\/blog\/copywriting-typography\/10-tips-to-proofreading-your-work\/","url":"https:\/\/www.solopress.com\/blog\/copywriting-typography\/10-tips-to-proofreading-your-work\/","name":"10 dicas de especialistas para a revis\u00e3o do seu trabalho","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/copywriting-typography\/10-tips-to-proofreading-your-work\/#primaryimage"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/copywriting-typography\/10-tips-to-proofreading-your-work\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/07\/Featured-image-1.jpg","datePublished":"2022-07-06T12:25:54+00:00","dateModified":"2022-08-17T08:52:48+00:00","description":"Eis algumas dicas que encontr\u00e1mos e utiliz\u00e1mos e que podem ajudar a sua revis\u00e3o de forma a tornar a sua impress\u00e3o perfeita!","breadcrumb":{"@id":"https:\/\/www.solopress.com\/blog\/copywriting-typography\/10-tips-to-proofreading-your-work\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solopress.com\/blog\/copywriting-typography\/10-tips-to-proofreading-your-work\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.solopress.com\/blog\/copywriting-typography\/10-tips-to-proofreading-your-work\/#primaryimage","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/07\/Featured-image-1.jpg","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/07\/Featured-image-1.jpg","width":902,"height":676},{"@type":"BreadcrumbList","@id":"https:\/\/www.solopress.com\/blog\/copywriting-typography\/10-tips-to-proofreading-your-work\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.solopress.com\/blog\/"},{"@type":"ListItem","position":2,"name":"10 expert tips for proofreading your work"}]},{"@type":"WebSite","@id":"https:\/\/www.solopress.com\/blog\/#website","url":"https:\/\/www.solopress.com\/blog\/","name":"As \u00faltimas not\u00edcias sobre impress\u00e3o e design | Solopress","description":"","publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solopress.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.solopress.com\/blog\/#organization","name":"Solopress","url":"https:\/\/www.solopress.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","width":428,"height":88,"caption":"Solopress"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Solopress","https:\/\/x.com\/solopress","https:\/\/instagram.com\/solopress\/","https:\/\/www.linkedin.com\/company\/solopress","https:\/\/uk.pinterest.com\/solopress\/","https:\/\/www.youtube.com\/user\/solopress"]},{"@type":"Person","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/f8531403c74fe1b3ef14bcaeec1c8c41","name":"Solopress","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g","caption":"Solopress"},"sameAs":["https:\/\/www.solopress.com\/"],"url":"https:\/\/www.solopress.com\/blog\/pt-pt\/author\/solopress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2022\/07\/Featured-image-1.jpg","_links":{"self":[{"href":"https:\/\/www.solopress.com\/blog\/pt-pt\/wp-json\/wp\/v2\/posts\/72530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solopress.com\/blog\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.solopress.com\/blog\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/pt-pt\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/pt-pt\/wp-json\/wp\/v2\/comments?post=72530"}],"version-history":[{"count":5,"href":"https:\/\/www.solopress.com\/blog\/pt-pt\/wp-json\/wp\/v2\/posts\/72530\/revisions"}],"predecessor-version":[{"id":73642,"href":"https:\/\/www.solopress.com\/blog\/pt-pt\/wp-json\/wp\/v2\/posts\/72530\/revisions\/73642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/pt-pt\/wp-json\/wp\/v2\/media\/72612"}],"wp:attachment":[{"href":"https:\/\/www.solopress.com\/blog\/pt-pt\/wp-json\/wp\/v2\/media?parent=72530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/pt-pt\/wp-json\/wp\/v2\/categories?post=72530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/pt-pt\/wp-json\/wp\/v2\/tags?post=72530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}