{"id":74441,"date":"2023-09-08T14:38:57","date_gmt":"2023-09-08T13:38:57","guid":{"rendered":"https:\/\/www.solopress.com\/blog\/?p=74441"},"modified":"2023-09-08T14:38:57","modified_gmt":"2023-09-08T13:38:57","slug":"os-maiores-obstaculos-ao-empreendedorismo","status":"publish","type":"post","link":"https:\/\/www.solopress.com\/blog\/pt-pt\/entrepreneurs\/the-biggest-barriers-to-entrepreneurship\/","title":{"rendered":"Os maiores obst\u00e1culos ao empreendedorismo"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p><span style=\"font-weight: 400;\">Para muitos brit\u00e2nicos, o sonho \u00e9 trabalhar por conta pr\u00f3pria, quer se trate de um projeto de paix\u00e3o que se transforma em trabalho a tempo inteiro ou de uma vontade s\u00fabita de trabalhar por conta pr\u00f3pria.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Com quase 20.000 brit\u00e2nicos a pesquisar '<strong>como criar uma empresa<\/strong>' todos os meses, \u00e9 evidente que somos uma na\u00e7\u00e3o cheia de empres\u00e1rios em ascens\u00e3o. No entanto, se tantos est\u00e3o a considerar voar sozinhos, que barreiras est\u00e3o potencialmente a impedir a sua excurs\u00e3o?<\/span><\/p>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/pt-pt\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Solopress<\/span><\/a><span style=\"font-weight: 400;\"> efectuou um inqu\u00e9rito <strong>2.000 brit\u00e2nicos<\/strong> para desvendar os sonhos e os desesperos dos nossos aspirantes a empres\u00e1rios e descobrir quais s\u00e3o os maiores obst\u00e1culos ao empreendedorismo que est\u00e3o a travar as suas ambi\u00e7\u00f5es.<\/span><\/p>\n<h2><b>Tr\u00eas quartos dos brit\u00e2nicos empregados sonham em trabalhar por conta pr\u00f3pria<\/b><\/h2>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/09\/Self-employed.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-74473 size-full\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/09\/Self-employed.jpg\" alt=\"Trabalhadores independentes: obst\u00e1culos ao esp\u00edrito empresarial\" width=\"900\" height=\"600\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Imaginar os seus sonhos e viv\u00ea-los s\u00e3o duas perspectivas muito diferentes. Para <strong>74.2%<\/strong> dos brit\u00e2nicos que ainda n\u00e3o t\u00eam uma empresa, a realiza\u00e7\u00e3o do sonho de se tornarem empres\u00e1rios continua a ser uma ambi\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De acordo com o nosso inqu\u00e9rito, iniciar a sua atividade no sector retalhista \u00e9 o sector mais apelativo para os aspirantes a empres\u00e1rios.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dois sectores semelhantes, a sa\u00fade e o bem-estar, e a alimenta\u00e7\u00e3o e as bebidas, seguem de perto o com\u00e9rcio retalhista como as ind\u00fastrias mais populares para os empres\u00e1rios sonhadores iniciarem a sua atividade.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\n<table id=\"tablepress-10\" class=\"tablepress tablepress-id-10\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Os 10 sectores em que as pessoas mais gostariam de abrir uma empresa<\/th><th class=\"column-2\">Percentagem de inquiridos que pretendem abrir uma empresa neste sector (%)<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Retalho<\/td><td class=\"column-2\">6.4%<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Sa\u00fade e bem-estar<\/td><td class=\"column-2\">5.8%<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Alimentos e bebidas<\/td><td class=\"column-2\">5.0%<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">TI<\/td><td class=\"column-2\">4.6%<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">Cuidados com os animais<\/td><td class=\"column-2\">4.5%<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">Hotelaria e turismo<\/td><td class=\"column-2\">3.7%<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">Educa\u00e7\u00e3o e forma\u00e7\u00e3o<\/td><td class=\"column-2\">3.1%<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">Artesanato<\/td><td class=\"column-2\">3.1%<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">Finan\u00e7as<\/td><td class=\"column-2\">2.7%<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">Fabrico e produ\u00e7\u00e3o<\/td><td class=\"column-2\">2.7%<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-10 from cache --><\/span><\/p>\n<p><span style=\"font-weight: 400;\"><br \/>\nO nosso inqu\u00e9rito revela<\/span> <span style=\"font-weight: 400;\">que as finan\u00e7as, a par da ind\u00fastria transformadora e da produ\u00e7\u00e3o, s\u00e3o os sectores menos procurados pelos novos empres\u00e1rios.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c9 interessante notar que existe uma divis\u00e3o not\u00e1vel entre os g\u00e9neros nas pessoas que desejam gerir a sua pr\u00f3pria empresa no futuro. <strong>82.5%<\/strong> dos homens esperam abrir um dia a sua pr\u00f3pria empresa, independentemente do sector em que se insere. Este n\u00famero desce ligeiramente, uma vez que, com 68%, quase um ter\u00e7o das mulheres n\u00e3o tem inten\u00e7\u00e3o de vir a ter a sua pr\u00f3pria empresa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como se previa, jovens, ambiciosos e ing\u00e9nuos em rela\u00e7\u00e3o \u00e0s barreiras ao empreendedorismo, mais de <strong>93%<\/strong> dos jovens entre os 18 e os 24 anos querem um dia abrir o seu pr\u00f3prio neg\u00f3cio.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em compara\u00e7\u00e3o, quase <strong>50%<\/strong> das pessoas com mais de 55 anos n\u00e3o t\u00eam qualquer desejo de virar a p\u00e1gina e mergulhar no estilo de vida empresarial.<\/span><\/p>\n<p><span style=\"color: #111111; font-family: Roboto, sans-serif; font-size: 27px;\">\n<table id=\"tablepress-8\" class=\"tablepress tablepress-id-8\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Faixa et\u00e1ria<\/th><th class=\"column-2\">Percentagem (%) que afirmou que n\u00e3o gostaria de abrir uma empresa em nenhum sector<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">18-24<\/td><td class=\"column-2\">6.4%<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">25-34<\/td><td class=\"column-2\">6.6%<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">35-44<\/td><td class=\"column-2\">11.5%<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">45-54<\/td><td class=\"column-2\">20.9%<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">55+<\/td><td class=\"column-2\">48.6%<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-8 from cache --><\/span><\/p>\n<h2><strong>Cardiff tem a maior popula\u00e7\u00e3o de aspirantes a empres\u00e1rios<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Dizem que nos tornamos naquilo que nos rodeia. Se vive em Cardiff, parece que o seu c\u00edrculo est\u00e1 cheio de aspirantes a empres\u00e1rios.<\/span><\/p>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/09\/Cardiff.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-74474\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/09\/Cardiff.jpg\" alt=\"\" width=\"900\" height=\"600\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Um n\u00famero impressionante de <strong>83.5%<\/strong> de todos os cardiffianos gostariam de abrir uma empresa no futuro. Sem surpresa, s\u00e3o seguidos de perto pelos londrinos, onde <strong>82%<\/strong> das pessoas tamb\u00e9m t\u00eam a ambi\u00e7\u00e3o de gerir o seu pr\u00f3prio neg\u00f3cio.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Curiosamente, cada uma das quatro principais cidades cheias de aspirantes a empres\u00e1rios pertence a um canto diferente da Gr\u00e3-Bretanha. Em Cardiff, Londres, Glasgow e Belfast, \u00e9 evidente que a Gr\u00e3-Bretanha est\u00e1 cheia de potenciais empres\u00e1rios ambiciosos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aqui pode encontrar as 10 cidades com a maior percentagem de aspirantes a empres\u00e1rios:\u00a0<\/span><\/p>\n\n<table id=\"tablepress-13\" class=\"tablepress tablepress-id-13\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Cidade<\/th><th class=\"column-2\">Abriria uma empresa (L\u00edquido)<\/th><th class=\"column-3\">N\/A - Nunca abriria uma empresa em nenhum sector<\/th><th class=\"column-4\">Sector<\/th><th class=\"column-5\">%<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Cardiff<\/td><td class=\"column-2\">83.58%<\/td><td class=\"column-3\">16.42%<\/td><td class=\"column-4\">Retalho<\/td><td class=\"column-5\">10.45%<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Londres<\/td><td class=\"column-2\">81.98%<\/td><td class=\"column-3\">18.02%<\/td><td class=\"column-4\">Sa\u00fade e bem-estar<\/td><td class=\"column-5\">6.68%<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Belfast<\/td><td class=\"column-2\">80.00%<\/td><td class=\"column-3\">20.00%<\/td><td class=\"column-4\">Retalho<\/td><td class=\"column-5\">10.91%<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">Glasgow<\/td><td class=\"column-2\">78.85%<\/td><td class=\"column-3\">21.15%<\/td><td class=\"column-4\">Sa\u00fade e bem-estar<\/td><td class=\"column-5\">9.62%<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">Leeds<\/td><td class=\"column-2\">77.23%<\/td><td class=\"column-3\">22.77%<\/td><td class=\"column-4\">Cuidados com os animais<\/td><td class=\"column-5\">8.91%<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">Newcastle<\/td><td class=\"column-2\">77.11%<\/td><td class=\"column-3\">22.89%<\/td><td class=\"column-4\">Alimentos e bebidas<\/td><td class=\"column-5\">8.43%<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">Southampton<\/td><td class=\"column-2\">77.08%<\/td><td class=\"column-3\">22.92%<\/td><td class=\"column-4\">Retalho<\/td><td class=\"column-5\">8.33%<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">Manchester<\/td><td class=\"column-2\">75.97%<\/td><td class=\"column-3\">24.03%<\/td><td class=\"column-4\">Retalho<\/td><td class=\"column-5\">7.14%<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">Sheffield<\/td><td class=\"column-2\">71.43%<\/td><td class=\"column-3\">28.57%<\/td><td class=\"column-4\">Alimenta\u00e7\u00e3o e bebidas \/ Sa\u00fade e bem-estar<\/td><td class=\"column-5\">7.94%<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">Edimburgo<\/td><td class=\"column-2\">70.49%<\/td><td class=\"column-3\">29.51%<\/td><td class=\"column-4\">Retalho<\/td><td class=\"column-5\">11.48%<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-13 from cache -->\n<p><span style=\"font-weight: 400;\">A definhar no fundo da tabela est\u00e3o as cidades mar\u00edtimas, Bristol e Liverpool. Mais de <strong>40%<\/strong> dos inquiridos em ambas as \u00e1reas n\u00e3o t\u00eam inten\u00e7\u00e3o de criar a sua pr\u00f3pria empresa.\u00a0<\/span><\/p>\n<h2><b>As empresas est\u00e3o a tornar-se demasiado caras para serem criadas?<\/b><\/h2>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/09\/finance.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-74475 size-full\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/09\/finance.jpg\" alt=\"obst\u00e1culos financeiros ao esp\u00edrito empresarial\" width=\"900\" height=\"600\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Quase um ter\u00e7o dos inquiridos (<strong>30.7%<\/strong>) referiram o custo associado como sendo a principal raz\u00e3o que impede ou adia os seus sonhos empresariais.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dependendo do sector, algumas empresas incorrer\u00e3o em custos mais elevados do que outras. No entanto, todas ter\u00e3o inicialmente o mesmo tipo de custos. Os custos de arranque, os honor\u00e1rios legais e o marketing s\u00e3o necess\u00e1rios e indispens\u00e1veis para p\u00f4r a empresa a funcionar.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quase um quarto das pessoas acredita que o medo do fracasso \u00e9 o maior obst\u00e1culo ao empreendedorismo (<strong>23.1%<\/strong>). Expectativas elevadas, pouca confian\u00e7a ou talvez uma mistura das duas podem criar um quadro crescente de d\u00favidas na cabe\u00e7a de algu\u00e9m. Quando esta tela fica demasiado cheia, n\u00e3o \u00e9 de admirar que muitos receiem que o seu futuro neg\u00f3cio possa falhar.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Seguiu-se de perto o clima econ\u00f3mico, que \u00e9 o terceiro maior fator que impede os aspirantes a empres\u00e1rios de iniciarem a sua atividade (<strong>22.2%<\/strong>). A instabilidade p\u00f3s-Brexit, agravada pela pandemia do Coronav\u00edrus, deixou um clima econ\u00f3mico em que muitos est\u00e3o claramente receosos de iniciar um novo cap\u00edtulo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A falta de experi\u00eancia (<strong>20.2%<\/strong>) e a falta de conhecimentos (<strong>16.4%<\/strong>) constituem os dois \u00faltimos obst\u00e1culos ao esp\u00edrito empresarial. Este facto \u00e9 interessante, uma vez que, por outro lado, muitos empres\u00e1rios afirmam sofrer de<\/span><a href=\"https:\/\/www.uschamber.com\/co\/grow\/thrive\/overcoming-imposter-syndrome-at-work#:~:text=Entrepreneurs%20may%20put%20more%20pressure,a%20feeling%20of%20%E2%80%9Cfailure.%E2%80%9D\" target=\"_blank\" rel=\"noopener\"> <span style=\"font-weight: 400;\">s\u00edndrome do impostor<\/span><\/a><span style=\"font-weight: 400;\"> devido \u00e0 falta de conhecimentos ou de experi\u00eancia na sua nova posi\u00e7\u00e3o. Como diz o ditado, o trabalho duro supera o talento quando o talento n\u00e3o trabalha duro.<\/span><\/p>\n\n<table id=\"tablepress-15\" class=\"tablepress tablepress-id-15\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">O maior obst\u00e1culo ao empreendedorismo<\/th><th class=\"column-2\">Percentagem de pessoas que concordam com esta afirma\u00e7\u00e3o (%)<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">O custo associado<\/td><td class=\"column-2\">30.7%<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Medo de falhar<\/td><td class=\"column-2\">23.1%<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">O clima econ\u00f3mico<\/td><td class=\"column-2\">22.2%<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">Falta de experi\u00eancia<\/td><td class=\"column-2\">20.2%<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">Falta de conhecimento<\/td><td class=\"column-2\">16.4%<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-15 from cache -->\n<h2><b>O apoio financeiro encorajaria mais empres\u00e1rios<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">H\u00e1 muitas coisas que poderiam facilitar o esp\u00edrito empresarial. Algumas pessoas t\u00eam os conhecimentos necess\u00e1rios, mas n\u00e3o t\u00eam o dinheiro para apoiar o seu projeto. Para outros, pode ser o contr\u00e1rio. O caminho de cada um para ter o seu neg\u00f3cio de sonho \u00e9 \u00fanico.<\/span><\/p>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/09\/shutterstock_1042524955-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-74476\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/09\/shutterstock_1042524955-1.jpg\" alt=\"empres\u00e1rio\" width=\"900\" height=\"600\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Seguindo a tend\u00eancia demonstrada no nosso inqu\u00e9rito de que a maioria das pessoas (<strong>30%<\/strong>) acreditam que os custos associados s\u00e3o a maior barreira ao empreendedorismo, n\u00e3o \u00e9 surpreendente que receber incentivos monet\u00e1rios encorajaria mais pessoas a dar o salto de f\u00e9. <\/span><\/p>\n<p><span style=\"font-weight: 400;\"><strong>41.8%<\/strong> dos inquiridos citaram o apoio financeiro como o principal fator que reduziria significativamente o seu obst\u00e1culo ao empreendedorismo. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, <strong>60%<\/strong> acreditam que o financiamento e uma maior ajuda governamental s\u00e3o os maiores obst\u00e1culos que poderiam tornar os seus sonhos empresariais uma realidade.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De acordo com o nosso inqu\u00e9rito, um ter\u00e7o das pessoas considera que a falta de conhecimentos e de experi\u00eancia as impede de se tornarem empres\u00e1rios. Um em cada cinco (<strong>20%<\/strong>) consideram que o aconselhamento sobre como elaborar um plano de neg\u00f3cios aumentaria as suas hip\u00f3teses de criar uma empresa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><strong>36%<\/strong> das pessoas acreditam que tanto o aconselhamento sobre como lidar com o risco de criar uma empresa como um maior conhecimento do sector empresarial s\u00e3o os factores importantes que as tornariam mais propensas a iniciar a sua carreira empresarial.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Estas foram as cinco principais respostas quando os nossos inquiridos foram questionados<\/span> <b><i>'<\/i><\/b><i><span style=\"font-weight: 400;\">O que \u00e9 que o ajudaria mais a ultrapassar as barreiras anteriormente mencionadas?<\/span><\/i><span style=\"font-weight: 400;\">:<\/span><\/p>\n\n<table id=\"tablepress-16\" class=\"tablepress tablepress-id-16\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">DECLARA\u00c7\u00c3O<\/th><th class=\"column-2\">%<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Apoio financeiro<\/td><td class=\"column-2\">41.8%<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Conselhos sobre como iniciar um plano de neg\u00f3cios<\/td><td class=\"column-2\">20.8%<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Apoio e pol\u00edticas governamentais<\/td><td class=\"column-2\">20.1%<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">Conselhos sobre como lidar com o risco de iniciar uma nova empresa<\/td><td class=\"column-2\">19.3%<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">Mais conhecimentos sobre o sector empresarial<\/td><td class=\"column-2\">17.8%<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-16 from cache -->\n<h2><b>Os jovens pais s\u00e3o os mais suscept\u00edveis de criar empresas ecol\u00f3gicas<\/b><\/h2>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/09\/Green-business.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-74477\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/09\/Green-business.jpg\" alt=\"\" width=\"900\" height=\"600\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Viver num mundo verde pode ser um sonho para alguns, mas \u00e9 um objetivo comercial fundamental para outros. Com a crescente press\u00e3o sobre as empresas existentes para introduzirem e manterem valores ecol\u00f3gicos, ser\u00e1 que isso influencia a abordagem de potenciais novos propriet\u00e1rios de empresas?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Na esmagadora maioria das vezes, a resposta \u00e9 sim. <strong>81.3%<\/strong> das pessoas acreditam que \u00e9 importante garantir que a sua empresa seja uma empresa ecol\u00f3gica.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No entanto, \u00e9 fascinante ver que, de acordo com os nossos dados, n\u00e3o \u00e9 a Gera\u00e7\u00e3o Z que se preocupa mais com a sustentabilidade ambiental quando cria uma empresa. As pessoas com idades compreendidas entre os 35 e os 44 anos s\u00e3o claramente as que t\u00eam os valores ecol\u00f3gicos mais fortes se quiserem criar a sua empresa de sonho. Isto \u00e9 demonstrado por <strong>88.8%<\/strong> que afirmam que ter uma empresa ecol\u00f3gica \u00e9 importante para eles versus <strong>81%<\/strong> de jovens entre os 18 e os 24 anos.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c9 prov\u00e1vel que muitos dos que t\u00eam entre 35 e 44 anos tenham sido pais recentemente, abrindo os olhos para o mundo em que querem que os seus filhos sejam criados.<\/span><\/p>\n<p><a href=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/09\/Young-parents.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-74478\" src=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/09\/Young-parents.jpg\" alt=\"\" width=\"900\" height=\"600\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Sem surpresa, as pessoas com mais de 55 anos s\u00e3o as que d\u00e3o menos import\u00e2ncia \u00e0 sustentabilidade ambiental, com <strong>25%<\/strong> dos inquiridos que n\u00e3o consideram os valores ecol\u00f3gicos da sua futura atividade.<\/span><\/p>\n\n<table id=\"tablepress-18\" class=\"tablepress tablepress-id-18\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Faixa et\u00e1ria:<\/th><th class=\"column-2\">Percentagem (%) que afirmou que ter uma empresa ecol\u00f3gica \u00e9 importante para eles:<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">18-24<\/td><td class=\"column-2\">81.0%<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">25-34<\/td><td class=\"column-2\">84.2%<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">35-44<\/td><td class=\"column-2\">87.8%<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">45-54<\/td><td class=\"column-2\">80.2%<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">55+<\/td><td class=\"column-2\">75.7%<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-18 from cache -->\n<h2><b>N\u00e3o se meta na sua vida<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Est\u00e1 a planear criar a sua pr\u00f3pria empresa? Qualquer pessoa que crie uma empresa encontrar\u00e1 barreiras \u00fanicas, mas a forma como as ultrapassa \u00e9 o que o distingue.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Depois de ultrapassar as suas barreiras ao empreendedorismo, vai precisar de uma marca de cortar a respira\u00e7\u00e3o para tornar a sua empresa imperd\u00edvel. Explore a gama de produtos oferecidos pela <\/span><a href=\"https:\/\/www.solopress.com\/blog\/pt-pt\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Solopress<\/span><\/a><span style=\"font-weight: 400;\"> para criar impress\u00f5es e marcas irresist\u00edveis.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>For many Brits, the dream is to work for themselves, whether that\u2019s a passion project that flourishes into full-time work or a sudden urge to go it alone. With almost 20,000 Brits searching \u2018how to start a business\u2019 each month, it\u2019s clear we\u2019re a nation full of budding entrepreneurs. However, if so many are considering [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":74472,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[547,955],"tags":[],"class_list":{"0":"post-74441","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-business-marketing","8":"category-entrepreneurs"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Biggest Barriers To Entrepreneurship<\/title>\n<meta name=\"description\" content=\"Solopress surveyed 2,000 British people to uncover their dreams, despairs and biggest barriers to entrepreneurship.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solopress.com\/blog\/pt-pt\/empresarios\/os-maiores-obstaculos-ao-empreendedorismo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Biggest Barriers To Entrepreneurship\" \/>\n<meta property=\"og:description\" content=\"Solopress surveyed 2,000 British people to uncover their dreams, despairs and biggest barriers to entrepreneurship.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solopress.com\/blog\/pt-pt\/empresarios\/os-maiores-obstaculos-ao-empreendedorismo\/\" \/>\n<meta property=\"og:site_name\" content=\"The Latest Print and Design News | Solopress\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Solopress\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-08T13:38:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/09\/blog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"3750\" \/>\n\t<meta property=\"og:image:height\" content=\"2813\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Solopress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@solopress\" \/>\n<meta name=\"twitter:site\" content=\"@solopress\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Solopress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/the-biggest-barriers-to-entrepreneurship\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/the-biggest-barriers-to-entrepreneurship\\\/\"},\"author\":{\"name\":\"Solopress\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/f8531403c74fe1b3ef14bcaeec1c8c41\"},\"headline\":\"The biggest barriers to entrepreneurship\",\"datePublished\":\"2023-09-08T13:38:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/the-biggest-barriers-to-entrepreneurship\\\/\"},\"wordCount\":1173,\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/the-biggest-barriers-to-entrepreneurship\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/blog.jpg\",\"articleSection\":[\"Business &amp; Marketing\",\"Entrepreneurs\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/the-biggest-barriers-to-entrepreneurship\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/the-biggest-barriers-to-entrepreneurship\\\/\",\"name\":\"The Biggest Barriers To Entrepreneurship\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/the-biggest-barriers-to-entrepreneurship\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/the-biggest-barriers-to-entrepreneurship\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/blog.jpg\",\"datePublished\":\"2023-09-08T13:38:57+00:00\",\"description\":\"Solopress surveyed 2,000 British people to uncover their dreams, despairs and biggest barriers to entrepreneurship.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/the-biggest-barriers-to-entrepreneurship\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/the-biggest-barriers-to-entrepreneurship\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/the-biggest-barriers-to-entrepreneurship\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/blog.jpg\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/blog.jpg\",\"width\":3750,\"height\":2813,\"caption\":\"Barriers to entrepreneurship\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/entrepreneurs\\\/the-biggest-barriers-to-entrepreneurship\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The biggest barriers to entrepreneurship\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"name\":\"The Latest Print and Design News | Solopress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#organization\",\"name\":\"Solopress\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/solopress-logo-no-tagline@2x.png\",\"width\":428,\"height\":88,\"caption\":\"Solopress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Solopress\",\"https:\\\/\\\/x.com\\\/solopress\",\"https:\\\/\\\/instagram.com\\\/solopress\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/solopress\",\"https:\\\/\\\/uk.pinterest.com\\\/solopress\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/solopress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/#\\\/schema\\\/person\\\/f8531403c74fe1b3ef14bcaeec1c8c41\",\"name\":\"Solopress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g\",\"caption\":\"Solopress\"},\"sameAs\":[\"https:\\\/\\\/www.solopress.com\\\/\"],\"url\":\"https:\\\/\\\/www.solopress.com\\\/blog\\\/pt-pt\\\/author\\\/solopress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"As maiores barreiras ao empreendedorismo","description":"A Solopress realizou um inqu\u00e9rito a 2.000 brit\u00e2nicos para descobrir os seus sonhos, desesperos e maiores obst\u00e1culos ao empreendedorismo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solopress.com\/blog\/pt-pt\/empresarios\/os-maiores-obstaculos-ao-empreendedorismo\/","og_locale":"pt_PT","og_type":"article","og_title":"The Biggest Barriers To Entrepreneurship","og_description":"Solopress surveyed 2,000 British people to uncover their dreams, despairs and biggest barriers to entrepreneurship.","og_url":"https:\/\/www.solopress.com\/blog\/pt-pt\/empresarios\/os-maiores-obstaculos-ao-empreendedorismo\/","og_site_name":"The Latest Print and Design News | Solopress","article_publisher":"https:\/\/www.facebook.com\/Solopress","article_published_time":"2023-09-08T13:38:57+00:00","og_image":[{"width":3750,"height":2813,"url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/09\/blog.jpg","type":"image\/jpeg"}],"author":"Solopress","twitter_card":"summary_large_image","twitter_creator":"@solopress","twitter_site":"@solopress","twitter_misc":{"Escrito por":"Solopress","Tempo estimado de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/the-biggest-barriers-to-entrepreneurship\/#article","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/the-biggest-barriers-to-entrepreneurship\/"},"author":{"name":"Solopress","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/f8531403c74fe1b3ef14bcaeec1c8c41"},"headline":"The biggest barriers to entrepreneurship","datePublished":"2023-09-08T13:38:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/the-biggest-barriers-to-entrepreneurship\/"},"wordCount":1173,"publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/the-biggest-barriers-to-entrepreneurship\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/09\/blog.jpg","articleSection":["Business &amp; Marketing","Entrepreneurs"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/the-biggest-barriers-to-entrepreneurship\/","url":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/the-biggest-barriers-to-entrepreneurship\/","name":"As maiores barreiras ao empreendedorismo","isPartOf":{"@id":"https:\/\/www.solopress.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/the-biggest-barriers-to-entrepreneurship\/#primaryimage"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/the-biggest-barriers-to-entrepreneurship\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/09\/blog.jpg","datePublished":"2023-09-08T13:38:57+00:00","description":"A Solopress realizou um inqu\u00e9rito a 2.000 brit\u00e2nicos para descobrir os seus sonhos, desesperos e maiores obst\u00e1culos ao empreendedorismo.","breadcrumb":{"@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/the-biggest-barriers-to-entrepreneurship\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solopress.com\/blog\/entrepreneurs\/the-biggest-barriers-to-entrepreneurship\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/the-biggest-barriers-to-entrepreneurship\/#primaryimage","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/09\/blog.jpg","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/09\/blog.jpg","width":3750,"height":2813,"caption":"Barriers to entrepreneurship"},{"@type":"BreadcrumbList","@id":"https:\/\/www.solopress.com\/blog\/entrepreneurs\/the-biggest-barriers-to-entrepreneurship\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.solopress.com\/blog\/"},{"@type":"ListItem","position":2,"name":"The biggest barriers to entrepreneurship"}]},{"@type":"WebSite","@id":"https:\/\/www.solopress.com\/blog\/#website","url":"https:\/\/www.solopress.com\/blog\/","name":"As \u00faltimas not\u00edcias sobre impress\u00e3o e design | Solopress","description":"","publisher":{"@id":"https:\/\/www.solopress.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solopress.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.solopress.com\/blog\/#organization","name":"Solopress","url":"https:\/\/www.solopress.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","contentUrl":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2017\/06\/solopress-logo-no-tagline@2x.png","width":428,"height":88,"caption":"Solopress"},"image":{"@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Solopress","https:\/\/x.com\/solopress","https:\/\/instagram.com\/solopress\/","https:\/\/www.linkedin.com\/company\/solopress","https:\/\/uk.pinterest.com\/solopress\/","https:\/\/www.youtube.com\/user\/solopress"]},{"@type":"Person","@id":"https:\/\/www.solopress.com\/blog\/#\/schema\/person\/f8531403c74fe1b3ef14bcaeec1c8c41","name":"Solopress","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5012622dc5386d65dcc9cba9677e1adb69a824f7e61d6885446076b73d0a2544?s=96&r=g","caption":"Solopress"},"sameAs":["https:\/\/www.solopress.com\/"],"url":"https:\/\/www.solopress.com\/blog\/pt-pt\/author\/solopress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.solopress.com\/blog\/wp-content\/uploads\/2023\/09\/blog.jpg","_links":{"self":[{"href":"https:\/\/www.solopress.com\/blog\/pt-pt\/wp-json\/wp\/v2\/posts\/74441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solopress.com\/blog\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.solopress.com\/blog\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/pt-pt\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/pt-pt\/wp-json\/wp\/v2\/comments?post=74441"}],"version-history":[{"count":5,"href":"https:\/\/www.solopress.com\/blog\/pt-pt\/wp-json\/wp\/v2\/posts\/74441\/revisions"}],"predecessor-version":[{"id":74480,"href":"https:\/\/www.solopress.com\/blog\/pt-pt\/wp-json\/wp\/v2\/posts\/74441\/revisions\/74480"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/pt-pt\/wp-json\/wp\/v2\/media\/74472"}],"wp:attachment":[{"href":"https:\/\/www.solopress.com\/blog\/pt-pt\/wp-json\/wp\/v2\/media?parent=74441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/pt-pt\/wp-json\/wp\/v2\/categories?post=74441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solopress.com\/blog\/pt-pt\/wp-json\/wp\/v2\/tags?post=74441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}